{"id":17011,"date":"2021-07-19T00:27:22","date_gmt":"2021-07-19T03:27:22","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17011"},"modified":"2021-07-19T00:27:22","modified_gmt":"2021-07-19T03:27:22","slug":"becco-ponto-com-45","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-45\/","title":{"rendered":"Becco ponto Com"},"content":{"rendered":"<p><strong>LIVRAI-NOS, SENHOR!<\/strong><br \/>\n01. Dos secadores da \u201cSele\u00e7\u00e3o Brasileira\u201d, via fakes.<br \/>\n02. Dos puxa-sacos de plant\u00e3o com seus mi-mi-mi.<br \/>\n03. Das baladas cheias de infectados nas capitais.<br \/>\n04. Dos novos ricos nos bares papeando lorotas.<br \/>\n05. Da sele\u00e7\u00e3o canarinha cantando tudo: \u2018acabooou\u2019.<br \/>\n06. Das bodegas sociais que viraram faculdades.<br \/>\n07. Da robalheira dos pol\u00edticos de carreiras \u2018eles\u2019.<br \/>\n08. Da s\u00edndrome dos boatos que viram verdades.<br \/>\n09. Da mistura de religi\u00e3o com politica mata povo.<br \/>\nDos bandidos do voto voltando a cena aqui.<\/p>\n<p><strong>NOTICIANDO<\/strong><br \/>\n01. \u00c9 com alegria de vida e paz que neste dia 17 de julho, completo 40 anos de casado em comunh\u00e3o de amor e vida longa a dois. Agrade\u00e7o a Deus, o tempo que partiu nossas almas de emo\u00e7\u00f5es at\u00e9 hoje, cavaleiros de vidas e sonhos bons, uma filha um sonho realizado que marcam nossas conquistas terrenas. S\u00e3o quase quinze mil dias de companheirismo de vida a dois t\u00e3o salutar. Viva os sonhos! Salve a vida de casados a todo custo, am\u00e9m!<br \/>\n02. Dizem por a\u00ed que: o nosso mundo est\u00e1 voltando a respirar paz na vida com a sa\u00edda da Pandemia do medo do Coronavirus. Aqui no Brasil, a pol\u00edtica tem feito um estrago na doen\u00e7a do s\u00e9culo, matando e matando os seres e a esperan\u00e7a de dias melhores para todos n\u00f3s. Salve a medicina do mundo e um povo marcado pela dor!<br \/>\n03. O Centro Cultural marcou a data da entrega neste ano do Trof\u00e9u Dom Jos\u00e9 de cidadania, 24 de setembro. Ser\u00e3o nove homenageados ilustres da cidade Princesa. O Centro completa em dezembro, 35 anos de funda\u00e7\u00e3o com uma festa marcada pela nova diretoria. O amigo Dr. Mendes ser\u00e1 o novo Presidente desta institui\u00e7\u00e3o de Sobral com garbo e compet\u00eancia cultural no fazer.<br \/>\n04. Estive visitando a Secretaria de Finan\u00e7as do nosso municipio, a Dra. Socorro Oliveira, assessorado pelo Dr. C\u00e9lio Vasconcelos, Coordenador Jur\u00eddico da Secretaria. Foi uma visita de cortesia e amizade no servi\u00e7o p\u00fablico. Parab\u00e9ns, a digna secret\u00e1ria executiva, Ana Paula, pela recep\u00e7\u00e3o carinhosa para comigo.<br \/>\n05. Uma turma amiga moradora antiga do Bairro da Rua do Fortaleza, que est\u00e1 articulando um encontro de 50 anos em dezembro para festejar a data magna. Acontecer\u00e1 uma festa na aabb, estilo \u201canos 60\u201d com os antigos amigos na pista puxada \u2018ai\u00ea, i\u00ea, i\u00ea\u2019 e m\u00fasicas do estlilo rom\u00e2ntica no card\u00e1pio. Vai ser uma festa de arromba amigos. Participe voc\u00ea desta saudade.<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17012\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-09.22.26-195x300.jpeg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-09.22.26-195x300.jpeg 195w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-09.22.26.jpeg 381w\" sizes=\"(max-width: 195px) 100vw, 195px\" \/>PERFIL: DR. C\u00c9LIO VASCONCELOS<\/strong><br \/>\nUm cidad\u00e3o com todas as letras, um digno jovem advogado, Coordenador Jur\u00eddico da Secretaria de Finan\u00e7as do munic\u00edpio de Sobral e profissional caro e amigo afeito a fazer o bem na vida. Falo do amigo Dr. C\u00e9lio Vasconcelos, que por m\u00e9ritos ilustra nossa coluna como o perfil da semana neste noticioso da Diocese de Sobral.<\/p>\n<p><strong>LIVRE PENSAR:<\/strong> \u201cO resto de vida de um velho que se sustenta na dor do mundo \u00e9 a esperan\u00e7a do futuro tangida pela for\u00e7a do presente vivendo em paz\u201d. (Poeta Chico Prado &#8211; Presidente do Centro Cultural Dom Jos\u00e9 de Sobral).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIVRAI-NOS, SENHOR! 01. Dos secadores da \u201cSele\u00e7\u00e3o Brasileira\u201d, via fakes. 02. Dos puxa-sacos de plant\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,27],"tags":[],"class_list":["post-17011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-becco-ponto-com"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg","jetpack-related-posts":[{"id":20319,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-91\/","url_meta":{"origin":17011,"position":0},"title":"Becco ponto Com","author":"","date":"Julho 3, 2022","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. Das mamatas pol\u00cdticas na sa\u00fade. 02. Dos gastos com quadrilhas, ufa! 03. Da crise na pol\u00edtica brasileira fede. 04. S\u00f3 Ensino Superior t\u00e3o com\u00e9rcio. 05. Das multas covardes na cidade, ui! 06. Do futebol arte virando drogas. 07. Da Santa Casa virar urnas pol\u00edticas. 08. Do cartel\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20271,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-90\/","url_meta":{"origin":17011,"position":1},"title":"Becco ponto Com","author":"","date":"Junho 27, 2022","format":false,"excerpt":"Livrai-nos, senhor! 01. Das querelas pol\u00edticas dos governos. 02. Da l\u00edngua solta dos pol\u00edticos agora. 03. Do eterno \u201ccartel da gasolina\u201d aqui, ui! 04. Do ensino internetizado e sem nexo. 05. Dos assaltos por hora \u00e0 motos, aqui. 06. Das opera\u00e7\u00f5es levando algemados. 07. Do mi mi mi para escolhas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33340,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-210\/","url_meta":{"origin":17011,"position":2},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Abril 14, 2025","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Dos falsos crist\u00e3os evang\u00e9licos, ufa! Da Medicina virando mesa de neg\u00f3cios. Dos fofoqueiros na onda do mi-mi-mi, ui! Dos ateus pol\u00edticos matando um povo. Dos fg,s voltarem ao poder de Sobral, ui! Do mi-mi-mi pol\u00edtico da Santa Casa, ufa! Da fila dos picaretas h\u00e1 voto na pista. Do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":17120,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-47\/","url_meta":{"origin":17011,"position":3},"title":"Becco ponto Com","author":"","date":"Agosto 2, 2021","format":false,"excerpt":"Livrai-nos, senhor! 01. Da puta pol\u00edtica dos corruptos bandidos do voto. 02. Do mi mi mi da vacina no pa\u00eds fazendo politicagem. 03. Da gana pelo poder dos pol\u00edticos caras de pau, ufa! 04. Das escolas \u2018pagou-passou\u2019 formando seus analfas. 05. Da solid\u00e3o de um mundo c\u00e3o na sua modernidade.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30752,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-184\/","url_meta":{"origin":17011,"position":4},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Setembro 23, 2024","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Das pesquisas encomendadas t\u00e3o cru\u00e9is. Dos novos ricos feios e importantes, ufa! Da revolu\u00e7\u00e3o da taxa do lixo entre n\u00f3s. Do bl\u00e1-bl\u00e1-bl\u00e1 dos pol\u00edticos coron\u00e9is, ui! Do mi-mi-mi da taxa do lixo e que virou meme. Dos ataques calados da oposi\u00e7\u00e3o rude. Das dondocas religiosas por interesses. Do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16789,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-41\/","url_meta":{"origin":17011,"position":5},"title":"Becco ponto Com","author":"","date":"Junho 20, 2021","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Da cpi pol\u00edtica das cloroquinas bolsonarianas, ufa! Das mamatas tocadas como propinas em c\u00e2maras, ui! Do surto nas igrejas evang\u00e9licas sem o tal d\u00edzimo. Do ensino moderno de alunos ao professor analfas. Do mi-mi-mi pol\u00edtico da vacina\u00e7\u00e3o brasileira na rede. Do ca\u00e7a j\u00e1 solta eleitoral de pol\u00edticos corruptos.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/Chico-Prado-22.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17011"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17011\/revisions"}],"predecessor-version":[{"id":17013,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17011\/revisions\/17013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/16178"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}