{"id":17162,"date":"2021-08-09T01:57:17","date_gmt":"2021-08-09T04:57:17","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17162"},"modified":"2021-08-09T01:57:17","modified_gmt":"2021-08-09T04:57:17","slug":"sobral-sobral-50","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-sobral-50\/","title":{"rendered":"Sobral, Sobral"},"content":{"rendered":"<p><strong>MINHAS HIST\u00d3RIAS&#8230;<\/strong><br \/>\n<strong>UM ABSURDO: SAL\u00c1RIOS E MORDOMIAS DOS POL\u00cdTICOS<\/strong><\/p>\n<p>Em janeiro de 2019 o Deputado Federal FRANCISCO EVERARDO TIRIRICA OLIVEIRA SILVA (PL-SP), 57, revelou os valores que auferia na C\u00c2MARA DOS DEPUTADOS (hoje os n\u00fameros e as mordomias s\u00e3o ainda maiores!!!)<br \/>\nVoc\u00ea sabe qual \u00e9 o meu sal\u00e1rio ?<br \/>\nEnt\u00e3o, vamos l\u00e1:<br \/>\nDeputado Federal:<br \/>\n&#8211; Sal\u00e1rio: R$ 26.700,00<br \/>\n&#8211; Verba Gabinete: R$ 94.300,00<br \/>\n&#8211; Aux\u00edlio Palet\u00f3: R$ 53.400,00<br \/>\n&#8211; Combust\u00edvel: R$ 5.000,00<br \/>\n&#8211; Aux\u00edlio Moradia: R$ 22.000,00<br \/>\n&#8211; Passagens A\u00e9reas: R$ 59.000<br \/>\n&#8211; Aux\u00edlio Sa\u00fade: R$ ilimitado<br \/>\n&#8211; Aux\u00edlio Educa\u00e7\u00e3o: R$ 12.100,00<br \/>\n&#8211; Aux\u00edlio Aliment.: R$ 16.400,00<br \/>\n&#8211; Aux\u00edlio Cultural: R$ 13.400,00<br \/>\n&#8211; Aux\u00edlio Dentista: R$ ilimitado<br \/>\n&#8211; Aux\u00edlio Farm\u00e1cia: R$ ilimitado<br \/>\nPortanto, senhores e senhoras brasileiros, este \u00e9 o custo BRASIL que voc\u00eas nos proporcionam:<br \/>\nR$ 302.300,00\/m\u00eas<br \/>\nS\u00e3o 513 Deputados.<br \/>\nR$ 155.079.900,00\/m\u00eas<br \/>\n12 meses<br \/>\nR$ 1.860.958.800,00\/ano<br \/>\nQuase 2 Bilh\u00f5es s\u00f3 com os Deputados.<br \/>\nIsso s\u00f3 para Deputado ainda tem Senador, Presidente e seus Ministros etc.<br \/>\nE o Sal\u00e1rio M\u00ednimo do trabalhador \u00e9 de R$ 998,00 para sustentar a fam\u00edlia.<br \/>\nSer\u00e1 que o problema do Brasil s\u00e3o os assalariados e os aposentados ?<br \/>\nABSURDO!!!<\/p>\n<p><strong>MINHAS <\/strong><br \/>\n<strong>M\u00daSICAS\u2026<\/strong><br \/>\nGET BACK &#8211; PHOLHAS. 1972 Banda de rock progressivo criada em S\u00c3O PAULO em 1969 pelo amigo WAGNER BENATTI (o BIT\u00c3O) (guitarra), H\u00c9LIO SANTISTEBAN (teclado), PAULO FERNANDES (bateria) e OSWALDO MALAGUTTI (baixo). Gravaram m\u00fasicas em ingl\u00eas e se tornaram o maior fen\u00f4meno do g\u00eanero no BRASIL e no exterior. Sua m\u00fasica de maior sucesso MY MISTAKE (MEU ERRO) conta a hist\u00f3ria de um crime passional: o homem mata a esposa e vai para a cadeia. GET BACK (VOLTE ATR\u00c1S) relata conselho para um amigo retomar seu relacionamento. \u201cO amor n\u00e3o se compra e o sentimento n\u00e3o se pode esconder\u201d, diz a letra. No in\u00edcio dos anos 2000 a banda PHOLHAS fez sua \u00faltima apresenta\u00e7\u00e3o em SOBRAL, na AABB, junto com FEVERS e RENATO &amp; SEUS BLUE CAPS. Dos componentes originais dos PHOLHAS, somente H\u00c9LIO SANTISTEBAN n\u00e3o est\u00e1 mais neste plano. Morreu em 2018, aos 69 anos<\/p>\n<p><strong>MINHAS FRASES&#8230;<\/strong><br \/>\nVoc\u00ea na vida obter\u00e1 resultados. Ou desculpas. (autor desconhecido)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINHAS HIST\u00d3RIAS&#8230; UM ABSURDO: SAL\u00c1RIOS E MORDOMIAS DOS POL\u00cdTICOS Em janeiro de 2019 o Deputado&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,75],"tags":[],"class_list":["post-17162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-carolino-soares"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png","jetpack-related-posts":[{"id":17768,"url":"https:\/\/correiodasemana.com\/site\/dia-dos-professores-distrito-federal-e-o-estado-brasileiro-com-a-maior-media-salarial-para-professores\/","url_meta":{"origin":17162,"position":0},"title":"DIA DOS PROFESSORES: Distrito Federal \u00e9 o estado brasileiro com a maior m\u00e9dia salarial para professores","author":"","date":"Outubro 17, 2021","format":false,"excerpt":"Com a retomada das aulas presenciais vagas para professores auxiliares tamb\u00e9m cresceram mais de 300% S\u00e3o Paulo, outubro de 2021\u00a0- Levantamento realizado pela\u00a0Catho,\u00a0marketplace de tecnologia que conecta empresas e candidatos, revela o ranking de estados que oferecem os maiores sal\u00e1rios para professores no Brasil. O Distrito Federal \u00e9 o estado\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/educacao-pos-pandemia-como-preparar-sua-escola-para-a-volta-as-aulas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/educacao-pos-pandemia-como-preparar-sua-escola-para-a-volta-as-aulas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/educacao-pos-pandemia-como-preparar-sua-escola-para-a-volta-as-aulas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22344,"url":"https:\/\/correiodasemana.com\/site\/piso-salarial-de-enfermagem-e-aprovado-em-comissao-especial-da-camara\/","url_meta":{"origin":17162,"position":1},"title":"Piso salarial de enfermagem \u00e9 aprovado em comiss\u00e3o especial da C\u00e2mara","author":"","date":"Dezembro 19, 2022","format":false,"excerpt":"Proposta pode ser votada ainda nesta\u00a0quinta-feira no plen\u00e1rio A comiss\u00e3o especial do piso salarial da enfermagem na C\u00e2mara dos Deputados aprovou nesta\u00a0quinta-feira (15) a proposta de emenda constitucional que prev\u00ea assist\u00eancia financeira complementar da Uni\u00e3o aos estados, ao Distrito Federal, aos munic\u00edpios e \u00e0s entidades filantr\u00f3picas para o pagamento dos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/pis-salarial.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/pis-salarial.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/pis-salarial.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":11661,"url":"https:\/\/correiodasemana.com\/site\/governo-corta-auxilio-de-565-mil-por-pagamento-indevido-diz-tcu\/","url_meta":{"origin":17162,"position":2},"title":"Governo corta aux\u00edlio de 565 mil por pagamento indevido, diz TCU","author":"","date":"Julho 8, 2020","format":false,"excerpt":"H\u00e1 casos em que os benefici\u00e1rios constam do cadastro de mortos da Receita Federal, moram no exterior, integram a popula\u00e7\u00e3o carcer\u00e1ria ou t\u00eam mandado de pris\u00e3o em aberto \u00a0POR FOLHAPRESS Relat\u00f3rio do TCU (Tribunal de Contas da Uni\u00e3o) obtido pela Folha de S.Paulo diz que 565,3 mil benefici\u00e1rios do aux\u00edlio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/naom_5f0595a8af737.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":12191,"url":"https:\/\/correiodasemana.com\/site\/projeto-de-socorro-a-agricultores-familiares-e-aprovado-pela-camara-dos-deputados\/","url_meta":{"origin":17162,"position":3},"title":"Projeto de socorro a agricultores familiares \u00e9 aprovado pela C\u00e2mara dos Deputados","author":"","date":"Julho 25, 2020","format":false,"excerpt":"Texto ainda ser\u00e1 avaliado pelos senadores; PL inclui grupo entre os benefici\u00e1rios do aux\u00edlio emergencial e suspende d\u00edvidas, entre outras medidas A C\u00e2mara dos Deputados aprovou na \u00faltima segunda-feira (20) uma s\u00e9rie de medidas emergenciais que visam ajudar agricultores familiares impactados pela crise econ\u00f4mica em decorr\u00eancia da pandemia da Covid-19.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/agricultores-familiar.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18484,"url":"https:\/\/correiodasemana.com\/site\/contribuicao-do-mei-subira-para-r-6060-em-fevereiro\/","url_meta":{"origin":17162,"position":4},"title":"Contribui\u00e7\u00e3o do MEI subir\u00e1 para R$ 60,60 em fevereiro","author":"","date":"Janeiro 9, 2022","format":false,"excerpt":"Pagamento maior segue aumento do sal\u00e1rio m\u00ednimo A partir de fevereiro, os cerca de 13 milh\u00f5es de microempreendedores individuais (MEI) registrados no pa\u00eds pagar\u00e3o R$ 60,60 para contribu\u00edrem com a Previd\u00eancia Social. O aumento, de 10,18%, segue o reajuste do sal\u00e1rio m\u00ednimo, que passou de R$ 1,1 mil para R$\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/MEI-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/MEI-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/MEI-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/MEI-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/MEI-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12882,"url":"https:\/\/correiodasemana.com\/site\/auxilio-emergencial-impede-que-235-milhoes-caiam-na-pobreza\/","url_meta":{"origin":17162,"position":5},"title":"Aux\u00edlio emergencial impede que 23,5 milh\u00f5es caiam na pobreza","author":"","date":"Agosto 17, 2020","format":false,"excerpt":"Estudo mostra tamb\u00e9m que medidas do governo levam \u00e0 redu\u00e7\u00e3o tempor\u00e1ria da desigualdade Sem o aux\u00edlio emergencial, 63,1 milh\u00f5es de brasileiros teriam renda per capta inferior a R$ 348,33. Ganhar menos de \u2153 do sal\u00e1rio m\u00ednimo \u00e9 o crit\u00e9rio usado para determinar a pobreza no pa\u00eds. Com o benef\u00edcio, 23,5\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/CEF-AuxilioEmergencial-60000-Covid19-Coronavirus-2-868x644-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17162"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17162\/revisions"}],"predecessor-version":[{"id":17163,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17162\/revisions\/17163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15808"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}