{"id":17198,"date":"2021-08-09T02:11:36","date_gmt":"2021-08-09T05:11:36","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17198"},"modified":"2021-08-09T02:15:46","modified_gmt":"2021-08-09T05:15:46","slug":"em-tempo-94","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-94\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Bienal Internacional de Dan\u00e7a do Cear\u00e1<\/strong><br \/>\nManter a dan\u00e7a pr\u00f3xima do p\u00fablico sem a sua presen\u00e7a na plateia. Essa \u00e9 a proposta da 7\u00aa edi\u00e7\u00e3o da\u00a0Bienal Internacional de Dan\u00e7a do Cear\u00e1 \/ De Par Em Par. O resultado \u00e9 a transmiss\u00e3o ao vivo, em realidade virtual, de\u00a013 a 22 de agosto,\u00a0no canal do evento\u00a0no YouTube.<br \/>\nA abertura, dia 13 de agosto, no Theatro Jos\u00e9 de Alencar, ser\u00e1 com o\u00a0Teatro M\u00e1quina\u00a0na remontagem do premiado \u201cO Cantil\u201d (2008), espet\u00e1culo mais antigo do grupo de teatro fundado h\u00e1 18 anos em Fortaleza.\u00a0A programa\u00e7\u00e3o ter\u00e1 22 espet\u00e1culos de artistas cearenses.<\/p>\n<p><strong>Casas de Cultura Estrangeira da UFC<\/strong><br \/>\nEntre os dias 9 e 10 de agosto, as Casas de Cultura Estrangeira da Universidade Federal do Cear\u00e1 (UFC) abrir\u00e3o 236 vagas para cursos de l\u00edngua\u00a0Alem\u00e3,\u00a0Brit\u00e2nica,\u00a0Francesa\u00a0e\u00a0Italiana, bem como de\u00a0Esperanto. Os novos alunos ser\u00e3o admitidos para o per\u00edodo letivo 2021.2.<br \/>\nOs candidatos podem se inscrever para apenas uma Casa de Cultura. Inscri\u00e7\u00f5es\u00a0podem ser realizadas gratuitamente via\u00a0formul\u00e1rio eletr\u00f4nico (https:\/\/docs.google.com). \u00c9 necess\u00e1rio utilizar o\u00a0gmail, comprovar a conclus\u00e3o do Ensino Fundamental e anexar a documenta\u00e7\u00e3o exigida.<\/p>\n<p><strong>Filha de Belchior faz show em Fortaleza<\/strong><br \/>\n<strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17199\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Vannick-Belchior-promete-noite-dedicada-a-memoria-e-legado-do-artista-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Vannick-Belchior-promete-noite-dedicada-a-memoria-e-legado-do-artista-300x169.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Vannick-Belchior-promete-noite-dedicada-a-memoria-e-legado-do-artista-1024x575.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Vannick-Belchior-promete-noite-dedicada-a-memoria-e-legado-do-artista-768x431.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Vannick-Belchior-promete-noite-dedicada-a-memoria-e-legado-do-artista.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Foto \u2013 Divulga\u00e7\u00e3o <\/strong><br \/>\n<strong>Vannick Belchior, 24 anos, graduada em direito, \u00e9 filha do artista cearense Belchior.<\/strong><br \/>\nA m\u00fasica e poesia de\u00a0Belchior\u00a0(1946-2017) continuam causando fasc\u00ednio e admira\u00e7\u00e3o. Homenagens, debates, livros, entre outras iniciativas, buscam decifrar o legado deixado pelo artista. No dia 1\u00ba de agosto, a obra do cantor e compositor foi celebrada por Vannick Belchior.<br \/>\nA filha do cantor fez a estreia da carreira nos palcos, em Fortaleza, com o show\u00a0\u201cCoisas que aprendi nos discos\u201d. Aos 24 anos, Vannick est\u00e1 animada com o come\u00e7o. Graduada em direito, ela tem a mesma idade de Belchior quando este partiu rumo ao Sudeste com o sonho de cantar.<\/p>\n<p><strong>Plano das Artes e da Cidadania Cultural<\/strong><br \/>\nA Secretaria da Cultura do Estado divulgou o Plano Cear\u00e1 das Artes e da Cidadania Cultural. Com or\u00e7amento de R$ 30 milh\u00f5es, a proposta prev\u00ea os relan\u00e7amentos do XIV Edital Cear\u00e1 de Cinema e V\u00eddeo, XII Edital Cear\u00e1 de Incentivo \u00e0s Artes e Edital Cultura Inf\u00e2ncia 2020.<br \/>\nDe acordo com a Secult-CE, 477 projetos que j\u00e1 estavam classificados ou habilitados deixaram de ser realizados. Agora, novos candidatos e quem teve a proposta cancelada deve participar da pr\u00f3xima sele\u00e7\u00e3o. Os tr\u00eas editais sair\u00e3o ainda esse ano.<\/p>\n<p><strong>Teste r\u00e1pido para diagn\u00f3stico da Covid<\/strong><br \/>\nO Laborat\u00f3rio de Biotecnologia e Biologia Molecular da Universidade Estadual do Cear\u00e1 (Uece) desenvolveu teste r\u00e1pido e de baixo custo para diagn\u00f3stico da Covid-19, a partir da saliva ou de secre\u00e7\u00f5es nasais. O resultado do teste sai entre tr\u00eas e cinco minutos.<br \/>\nAtualmente, o teste padr\u00e3o ouro para detec\u00e7\u00e3o da Covid-19 \u00e9 realizado por RT-PCR, cujo processo \u00e9 demorado e de elevado custo. Est\u00e1 comprovado que o teste desenvolvido pela Uece \u00e9 t\u00e3o eficaz quanto o RT-PCR, tendo vantagens econ\u00f4micas e de aplicabilidade.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br). Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienal Internacional de Dan\u00e7a do Cear\u00e1 Manter a dan\u00e7a pr\u00f3xima do p\u00fablico sem a sua&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-17198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/FOTO-EDILSON-SILVA-2.jpg","jetpack-related-posts":[{"id":32436,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-263\/","url_meta":{"origin":17198,"position":0},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Fevereiro 10, 2025","format":false,"excerpt":"XV Bienal Internacional do Livro A XV Bienal Internacional do Livro do Cear\u00e1 ocorre entre os dias 4 a 13 de abril. A programa\u00e7\u00e3o ocorrer\u00e1 no Centro de Eventos, em Fortaleza, com o tema \u201cDas fogueiras ao fogo das palavras: mulheres, resist\u00eancia e literatura\u201d. Iniciativa \u00e9 da Secretaria da Cultura\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/RENATO-ARAGAO-150x150.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/RENATO-ARAGAO-150x150.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/RENATO-ARAGAO-150x150.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/02\/RENATO-ARAGAO-150x150.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35676,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-295\/","url_meta":{"origin":17198,"position":1},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Setembro 28, 2025","format":false,"excerpt":"Curso doutorado em Geografia na UVA A Universidade Estadual Vale do Acara\u00fa (UVA) viveu um momento hist\u00f3rico, no dia 15 de setembro, em Sobral, com aula inaugural do doutorado acad\u00eamico em Geografia, que marca um passo significativo para consolida\u00e7\u00e3o da p\u00f3s-gradua\u00e7\u00e3o stricto sensu na institui\u00e7\u00e3o. O curso conta com a\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Peca-memorias-de-chico-xavier-foto-Valerio-Trabanco-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Peca-memorias-de-chico-xavier-foto-Valerio-Trabanco-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Peca-memorias-de-chico-xavier-foto-Valerio-Trabanco-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/Peca-memorias-de-chico-xavier-foto-Valerio-Trabanco-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":21351,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-156\/","url_meta":{"origin":17198,"position":2},"title":"Em Tempo","author":"","date":"Outubro 24, 2022","format":false,"excerpt":"Cursos de extens\u00e3o IFCE Sobral O Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1 (IFCE) lan\u00e7ou chamada p\u00fablica para cursos de extens\u00e3o na \u00e1rea de modelagem computacional aplicada \u00e0 impress\u00e3o 3D e corte a laser. Objetivo \u00e9 formar profissionais para a ind\u00fastria 4.0, com foco em fabrica\u00e7\u00e3o digital. S\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/10\/show-em-tempo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":28544,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-217\/","url_meta":{"origin":17198,"position":3},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Mar\u00e7o 4, 2024","format":false,"excerpt":"14\u00aa Bienal Internacional de Dan\u00e7a Quem pode dan\u00e7ar? Existe limite de idade para estar em cena? Em \u201cCorpos Velhos \u2013 Pra que servem?\u201d, que teve estreia em 2023, um grupo de grandes bailarinos de uma gera\u00e7\u00e3o pioneira da dan\u00e7a c\u00eanica brasileira vem mostrando que a dan\u00e7a n\u00e3o tem idade, n\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/ednardo_serginho_-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/ednardo_serginho_-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/ednardo_serginho_-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/ednardo_serginho_-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28862,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-221\/","url_meta":{"origin":17198,"position":4},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Abril 2, 2024","format":false,"excerpt":"Inscri\u00e7\u00f5es para Vestibular UECE Universidade Estadual do Cear\u00e1 recebe inscri\u00e7\u00f5es, at\u00e9 o dia 8 de abril, para Vestibular 2024.2, exclusivamente pela internet no site www.uece\/cev. S\u00e3o ofertadas 2.322 vagas, das quais 1.222 para os cursos de Fortaleza e 1.094 para as unidades da Uece no interior do estado. Na ficha\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/1_carlinhos_patriolino_e_choro_cabuloso-26141754-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/1_carlinhos_patriolino_e_choro_cabuloso-26141754-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/1_carlinhos_patriolino_e_choro_cabuloso-26141754-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/1_carlinhos_patriolino_e_choro_cabuloso-26141754-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28779,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-220\/","url_meta":{"origin":17198,"position":5},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Mar\u00e7o 25, 2024","format":false,"excerpt":"Homenagem ao artista Belchior Vai \u00e0 san\u00e7\u00e3o presidencial projeto de lei do deputado federal Le\u00f4nidas Cristino, que denomina Ant\u00f4nio Carlos Belchior o Terminal Mar\u00edtimo de Passageiros do Porto de Fortaleza, no Mucuripe. Belchior morreu em 2017, aos 70 anos, mas suas m\u00fasicas fazem sucesso at\u00e9 hoje. O projeto, aprovado no\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/OSWALD-BARROSO-1_img_6454-26075622-150x150.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17198"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17198\/revisions"}],"predecessor-version":[{"id":17200,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17198\/revisions\/17200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}