{"id":17332,"date":"2021-08-30T00:50:15","date_gmt":"2021-08-30T03:50:15","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17332"},"modified":"2021-08-30T00:55:20","modified_gmt":"2021-08-30T03:55:20","slug":"sobral-sobral-53","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-sobral-53\/","title":{"rendered":"Sobral, Sobral"},"content":{"rendered":"<p><strong>\u201cO DESTINO COLOCA MUITAS PESSOAS EM NOSSAS VIDAS. SOMENTE AS MELHORES FICAM PARA SEMPRE !!\u201d<\/strong><\/p>\n<p><strong>MINHAS HIST\u00d3RIAS&#8230;<\/strong><br \/>\n<strong>PRA\u00c7A DA CUBALA<\/strong><br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17333\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.27-298x300.jpeg\" alt=\"\" width=\"298\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.27-298x300.jpeg 298w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.27-150x150.jpeg 150w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.27.jpeg 552w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/> Era uma linda denomina\u00e7\u00e3o: PRA\u00c7A DA MERUOCA. Significa a casa do mel, na linguagem tupi-guarany. Por d\u00e9cadas assim admiramos a nossa pra\u00e7a mais bonita, no centro da PRINCESA DO NORTE. Homenagem \u00e0 serra que desenha a silhueta de SOBRAL. Nos \u00faltimos meses, alguns vereadores de oposi\u00e7\u00e3o, \u00e0 frente TIAGO RAMOS, 51, do MDB, encetaram um movimento pra retirar o estulto nome PRA\u00c7A DE CUBA. A pra\u00e7a se chamaria DR. RICARDO BARRETO. No entanto, a justa rever\u00eancia ao ex-prefeito, m\u00e9dico amigo e popular, foi abortada imediatamente pelos vereadores tutelados pela Prefeitura Municipal. (quem acompanha a recente hist\u00f3ria pol\u00edtica da terra de D. Jos\u00e9 sabe o porqu\u00ea !!). Para piorar a insatisfa\u00e7\u00e3o das pessoas que amam SOBRAL e seus logradouros, a PRA\u00c7A DA MERUOCA hoje \u00e9 um feir\u00e3o a ce\u00fa aberto. Todavia os pequenos comerciantes fizeram \u00e0 cidade um grande obs\u00e9quio. Esconderam o monumento rid\u00edculo, trazido de Cuba. Ele nada tem a ver com SOBRAL nem com o seu povo, sempre conservador e com princ\u00edpios crist\u00e3os. A nossa PRA\u00c7A DA MERUOCA passou a ser chamada Pra\u00e7a de Cuba, ou melhor \u201cPra\u00e7a da CUBALA\u201d. Para a gargalhada geral dos nossos visitantes, quando conhecem a seguinte hist\u00f3ria: no dia reinaugura\u00e7\u00e3o da PRA\u00c7A, com show do cantor sertanejo LEONARDO, houve tiroteio no meio da multid\u00e3o. Um morto. O povo, na sua profunda sabedoria, rebatizou na hora: A PRA\u00c7A DA MERUOCA virou PRA\u00c7A DA CUBALA. Bem feito. Castigo. Voto no pr\u00f3ximo prefeito que prometer tirar aquela geringon\u00e7a e voltar o nome original: PRA\u00c7A DA MERUOCA !!!!<\/p>\n<p><strong>PRA\u00c7A DA MERUOCA \u00e9 hoje a PRA\u00c7A DE CUBALA.<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\"alignleft size-medium wp-image-17334\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.37-300x221.jpeg\" alt=\"\" width=\"300\" height=\"221\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.37-300x221.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-26-at-14.03.37.jpeg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>MINHAS FRASES&#8230;<\/strong><br \/>\n\u201cNesta vida temos tr\u00eas professores importantes: o MOMENTO FELIZ, o MOMENTO TRISTE e o MOMENTO DIF\u00cdCIL. O Momento Feliz mostra o que n\u00e3o precisamos mudar. O Momento Triste mostra o que precisamos mudar. O Momento Dif\u00edcil mostra que somos capazes de superar.\u201d<br \/>\n\u2015\u00a0ROBERTO SHINYASHIKI, 69, m\u00e9dico, palestrante e psiquiatra de SANTOS-SP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO DESTINO COLOCA MUITAS PESSOAS EM NOSSAS VIDAS. SOMENTE AS MELHORES FICAM PARA SEMPRE !!\u201d&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,75],"tags":[],"class_list":["post-17332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-carolino-soares"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png","jetpack-related-posts":[{"id":11136,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-33\/","url_meta":{"origin":17332,"position":0},"title":"Panorama Pol\u00edtico","author":"","date":"Mar\u00e7o 9, 2020","format":false,"excerpt":"Vereadora Alessandra Ponte solicita constru\u00e7\u00e3o de uma Areninha A vereadora Alessandra Ponte (PDT), enviou ao Plen\u00e1rio da C\u00e2mara Municipal diversos requerimentos e indica\u00e7\u00f5es solicitando benef\u00edcios para o povo de Sobral e distritos. Tendo indicado a constru\u00e7\u00e3o de uma miniareninha, atrav\u00e9s do projeto Campinho da Galera no terreno localizado na Rua\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10592,"url":"https:\/\/correiodasemana.com\/site\/panorama-politica\/","url_meta":{"origin":17332,"position":1},"title":"Panorama Pol\u00edtica","author":"","date":"Janeiro 27, 2020","format":false,"excerpt":"Prefeito Ivo Gomes visita casas construidas pelo projeto Jo\u00e3o de Barro O prefeito Ivo Gomes esteve no Bairro Sumar\u00e9 para visitar as 14 fam\u00edlias que tiveram suas casas de taipas substitu\u00eddas por alvenarias. A a\u00e7\u00e3o \u00e9 fruto do Projeto Jo\u00e3o de Bairro do Centro de Forma\u00e7\u00e3o Humana Padre Ibiapina, coordenado\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9674,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-18\/","url_meta":{"origin":17332,"position":2},"title":"Panorama Pol\u00edtico","author":"","date":"Novembro 4, 2019","format":false,"excerpt":"Reforma da Pra\u00e7a da Sa\u00fade chega aos 47% de conclus\u00e3o A Pra\u00e7a da Sa\u00fade est\u00e1 passando por reforma desde julho deste ano. Os servi\u00e7os j\u00e1 chegaram aos 47% de conclus\u00e3o e a previs\u00e3o \u00e9 que ela seja entregue a popula\u00e7\u00e3o no in\u00edcio de 2020, com uma \u00e1rea total de 956m\u00b2.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9623,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-17\/","url_meta":{"origin":17332,"position":3},"title":"Panorama Pol\u00edtico","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"Adutora da Serra do Ros\u00e1rio est\u00e1 em plena execu\u00e7\u00e3o e vai beneficiar 2.300 habitantes O t\u00e3o esperado sistema de abastecimento de \u00e1gua da Serra do Ros\u00e1rio est\u00e1 em dias de ser conclu\u00eddo. Desde fevereiro as obras da adutora daquela regi\u00e3o est\u00e3o em pleno execu\u00e7\u00e3o. Com previs\u00e3o de ser conclu\u00edda at\u00e9\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10875,"url":"https:\/\/correiodasemana.com\/site\/panorama-politica-2\/","url_meta":{"origin":17332,"position":4},"title":"Panorama Pol\u00edtica","author":"","date":"Fevereiro 17, 2020","format":false,"excerpt":"Prefeito Ivo Gomes apresentou novo projeto do Aeroporto de Sobral O prefeito Ivo Gomes recebeu o secret\u00e1rio da Infraestrutura do Estado, L\u00facio Gomes, para discutir sobre o novo aeroporto de Sobral. O projeto foi apresentado em uma audi\u00eancia p\u00fablica realizada pela secretaria do Detran. \u201cEnxergamos que esse empreendimento vai de\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10168,"url":"https:\/\/correiodasemana.com\/site\/panorama-politico-24\/","url_meta":{"origin":17332,"position":5},"title":"Panorama Pol\u00edtico","author":"","date":"Dezembro 16, 2019","format":false,"excerpt":"Prefeito Ivo Gomes inaugura pra\u00e7a em Santa Luzia e Posto de Sa\u00fade em Jaibaras O prefeito Ivo Gomes inaugurou quarta-feira, 11, a Pra\u00e7a Manoel Rodrigues de Lima na localidade de Santa Luzia - Baracho e anunciou que vai fazer o complemento da pavimenta\u00e7\u00e3o da estrada e disse sobre as obras\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/camara-de-sobral.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17332"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17332\/revisions"}],"predecessor-version":[{"id":17335,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17332\/revisions\/17335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15808"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}