{"id":17498,"date":"2021-09-12T23:49:09","date_gmt":"2021-09-13T02:49:09","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17498"},"modified":"2021-09-12T23:49:09","modified_gmt":"2021-09-13T02:49:09","slug":"abrir-se-ao-mundo-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/abrir-se-ao-mundo-2\/","title":{"rendered":"\u201cABRIR-SE AO MUNDO\u201d"},"content":{"rendered":"<p>Esta \u00e9 uma interpelante express\u00e3o evocada na Carta Enc\u00edclica Fratelli Tutti \u2013 sobre a fraternidade e a amizade social, do Papa Francisco, em refer\u00eancia \u00e0 busca por din\u00e2micas que superem os sombrios sinais de um \u201cmundo fechado\u201d. N\u00e3o \u00e9 exagero e nem pessimismo: os fechamentos da civiliza\u00e7\u00e3o contempor\u00e2nea mostram que a humanidade est\u00e1 na contram\u00e3o de progressos alcan\u00e7ados no campo tecnol\u00f3gico-cient\u00edfico. Torna-se dif\u00edcil encontrar raz\u00f5es para a atual configura\u00e7\u00e3o pol\u00edtica, social, econ\u00f4mica e cultural do planeta, com a hist\u00f3ria dando sinais de regress\u00e3o. Conflitos anacr\u00f4nicos \u2013 com o surgimento de nacionalismos fechados, ressentidos e agressivos \u2013 ressurgem em diferentes lugares. Medidas que buscam superar determinadas ideologias fazem surgir outras igualmente perigosas. Diante desses e de tantos outros problemas, os cidad\u00e3os est\u00e3o desafiados: \u00e9 necess\u00e1ria lucidez m\u00ednima para ir al\u00e9m de interesses pol\u00edtico-partid\u00e1rios enraizados em determinadas ideologias. Vencer, assim, os limites de fechamentos obscurantistas e os interesses mercadol\u00f3gicos ego\u00edstas \u2013 que levam poucos ao enriquecimento enquanto alimentam a exclus\u00e3o social de muitos, com cen\u00e1rios de desola\u00e7\u00e3o agravados pela pandemia da COVID-19. Torna-se inadi\u00e1vel um esfor\u00e7o de todos para que a sociedade adote o paradigma da fraternidade social, por um permanente e fecundo investimento na amizade social.<br \/>\nO Papa Francisco lembra que o bem deve ser conquistado a cada dia. N\u00e3o \u00e9 poss\u00edvel, pois, contentar-se com o que j\u00e1 se obteve no passado \u2013 \u201cmuitos dos nossos irm\u00e3os ainda sofrem situa\u00e7\u00f5es de injusti\u00e7a que nos interpelam a todos\u201d. Acatar a interpela\u00e7\u00e3o que vem dos cen\u00e1rios de injusti\u00e7as, viol\u00eancias e desigualdades sociais \u00e9 contribuir na indispens\u00e1vel e urgente din\u00e2mica de \u201cabrir-se ao mundo\u201d, mas de modo bem diferente da atual concep\u00e7\u00e3o de um modelo econ\u00f4mico question\u00e1vel. No \u00e2mbito da economia e das finan\u00e7as, h\u00e1 uma equivocada compreens\u00e3o a respeito do que significa \u201cabrir-se ao mundo\u201d. Essa express\u00e3o, no contexto dos interesses econ\u00f4micos, muitas vezes se restringe \u00e0 busca por novos mercados globalizados, visando ac\u00famulo de poder. Esse exclusivo compromisso com o lucro forma um tipo de cultura que acentua divis\u00f5es entre na\u00e7\u00f5es e pessoas. Prejudica avan\u00e7os indispens\u00e1veis na promo\u00e7\u00e3o da amizade social, sem a qual n\u00e3o se alcan\u00e7ar\u00e1 a paz no mundo.<br \/>\nCada pessoa deve buscar superar a l\u00f3gica do mercado que reduz o ser humano \u00e0 condi\u00e7\u00e3o de consumidor ou espectador. A humanidade precisa reagir a esse \u201cglobalismo\u201d que tenta estabelecer uma cultura dominante, com a valoriza\u00e7\u00e3o da identidade dos mais fortes e a dissolu\u00e7\u00e3o da identidade dos mais fr\u00e1geis \u2013 um genoc\u00eddio cultural. Lament\u00e1vel \u00e9 a incapacidade da pol\u00edtica para promover essa rea\u00e7\u00e3o, pois, cada vez mais, se submete aos poderes econ\u00f4micos transnacionais. Sob o controle desses poderes, a pol\u00edtica torna-se instrumento de interesses que propiciam a negocia\u00e7\u00e3o de tudo, sem escr\u00fapulos. Essa falta de escr\u00fapulos n\u00e3o raramente tem sido camuflada pela defesa de alguns valores, sacrificando tantos outros que s\u00e3o inegoci\u00e1veis \u2013 determinantes para reequilibrar a civiliza\u00e7\u00e3o contempor\u00e2nea.<br \/>\n\u201cAbrir-se ao mundo\u201d na busca pela consolida\u00e7\u00e3o da amizade social \u00e9 tarefa que exige amadurecimento nos campos antropol\u00f3gico-cultural e da espiritualidade. O momento atual, consideradas as escaladas de retrocessos, precisa de l\u00edderes e do envolvimento cidad\u00e3o para que se torne poss\u00edvel encontrar novas respostas e configurar novos cen\u00e1rios. Nesse processo, uma situa\u00e7\u00e3o merece urgente tratamento: os direitos humanos n\u00e3o s\u00e3o suficientemente universais, n\u00e3o s\u00e3o iguais para todos, e o respeito a esses direitos \u00e9 condi\u00e7\u00e3o b\u00e1sica para o progresso socioecon\u00f4mico da humanidade. O Papa Francisco sublinha que o respeito \u00e0 dignidade e aos direitos humanos fortalece a criatividade e a aud\u00e1cia, possibilitando que mais pessoas se tornem, efetivamente, protagonistas na promo\u00e7\u00e3o do bem comum. Assim, a cidadania est\u00e1 desafiada a se fortalecer construindo um mundo que seja para todos. Deve ir al\u00e9m de paix\u00f5es, alimentadas por diferentes ideologias, para efetivar uma agenda de di\u00e1logo, reflex\u00f5es e entendimentos. Ao inv\u00e9s de antecipar discuss\u00f5es partid\u00e1rias ou idolatrar determinados nomes, o caminho deveria ser o investimento nas pr\u00e1ticas culturais e sociopol\u00edticas capazes de superar o atual \u201cmundo fechado\u201d, isto \u00e9, injusto e desigual.<br \/>\n\u00c9 hora de inaugurar, indicar e trilhar percursos de esperan\u00e7a \u2013 a esperan\u00e7a que est\u00e1 enraizada profundamente no cora\u00e7\u00e3o humano. Seja alimentada a sede por um tempo novo, alicer\u00e7ado na grandeza imbat\u00edvel da amizade social, fecundada pela vitalidade \u00fanica da f\u00e9. \u00a0Um caminho para deixar o cora\u00e7\u00e3o repleto de alegria fraterna e emoldurar os sonhos da humanidade a partir do compromisso com o bem comum \u2013 cada pessoa vivendo e trabalhando n\u00e3o somente para si, mas para o bem de todos os irm\u00e3os e irm\u00e3s.<\/p>\n<p>Dom Walmor Oliveira de Azevedo &#8211; Arcebispo de Belo Horizonte (MG)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta \u00e9 uma interpelante express\u00e3o evocada na Carta Enc\u00edclica Fratelli Tutti \u2013 sobre a fraternidade&#8230;<\/p>\n","protected":false},"author":1,"featured_media":79,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[24],"tags":[],"class_list":["post-17498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-300x167.jpg",300,167,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-768x427.jpg",640,356,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",640,356,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",540,300,false]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/\" rel=\"category tag\">A voz do Pastor<\/a>","tag_info":"A voz do Pastor","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":17373,"url":"https:\/\/correiodasemana.com\/site\/abrir-se-ao-mundo\/","url_meta":{"origin":17498,"position":0},"title":"\u201cABRIR-SE AO MUNDO\u201d","author":"","date":"Agosto 30, 2021","format":false,"excerpt":"Esta \u00e9 uma interpelante express\u00e3o evocada na Carta Enc\u00edclica Fratelli Tutti \u2013 sobre a fraternidade e a amizade social, do Papa Francisco, em refer\u00eancia \u00e0 busca por din\u00e2micas que superem os sombrios sinais de um \u201cmundo fechado\u201d. N\u00e3o \u00e9 exagero e nem pessimismo: os fechamentos da civiliza\u00e7\u00e3o contempor\u00e2nea mostram que\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20775,"url":"https:\/\/correiodasemana.com\/site\/arquitetar-um-mundo-aberto\/","url_meta":{"origin":17498,"position":1},"title":"Arquitetar um mundo aberto","author":"","date":"Agosto 21, 2022","format":false,"excerpt":"Arquitetar um \u201cmundo aberto\u201d \u00e9 tarefa mission\u00e1ria, abrangente, que pede o envolvimento de todos os cidad\u00e3os, para dissipar as sombras de um \u201cmundo fechado\u201d. A express\u00e3o \u201cAs sombras de um mundo fechado\u201d \u00e9 titula\u00e7\u00e3o do primeiro cap\u00edtulo da Carta Enc\u00edclica\u00a0Fratelli Tutti, do Papa Francisco, chamando aten\u00e7\u00e3o para algumas tend\u00eancias atuais\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15156,"url":"https:\/\/correiodasemana.com\/site\/luz-a-um-mundo-fechado\/","url_meta":{"origin":17498,"position":2},"title":"Luz a um mundo fechado","author":"","date":"Dezembro 21, 2020","format":false,"excerpt":"Ouvir o profeta Isa\u00edas, em sua sabedoria e maestria, contribui para adotar medidas que podem trazer o novo esperado \u2013 o brilho da nova luz. O profeta chama a aten\u00e7\u00e3o para a urg\u00eancia de se vivenciar um despertar da consci\u00eancia mission\u00e1ria e assumir a responsabilidade cidad\u00e3. O ponto de partida\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19811,"url":"https:\/\/correiodasemana.com\/site\/recomecos-cidadaos\/","url_meta":{"origin":17498,"position":3},"title":"Recome\u00e7os cidad\u00e3os","author":"","date":"Maio 16, 2022","format":false,"excerpt":"Cl\u00e1ssico, consagrado e bem atual \u00e9 o que expressa o imortal Rui Barbosa, ao referir-se sobre o triunfo das nulidades e o crescimento das injusti\u00e7as. Ante essa constata\u00e7\u00e3o, a cidadania \u00e9 interpelada a n\u00e3o abrir m\u00e3o de virtudes, a superar a desconsidera\u00e7\u00e3o da honra e a eleger como prioridade a\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19875,"url":"https:\/\/correiodasemana.com\/site\/recomecos-cidadaos-2\/","url_meta":{"origin":17498,"position":4},"title":"Recome\u00e7os cidad\u00e3os","author":"","date":"Maio 26, 2022","format":false,"excerpt":"Cl\u00e1ssico, consagrado e bem atual \u00e9 o que expressa o imortal Rui Barbosa, ao referir-se sobre o triunfo das nulidades e o crescimento das injusti\u00e7as. Ante essa constata\u00e7\u00e3o, a cidadania \u00e9 interpelada a n\u00e3o abrir m\u00e3o de virtudes, a superar a desconsidera\u00e7\u00e3o da honra e a eleger como prioridade a\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":26295,"url":"https:\/\/correiodasemana.com\/site\/a-prisao-das-mentes-fechadas\/","url_meta":{"origin":17498,"position":5},"title":"A pris\u00e3o das mentes fechadas","author":"adminredacao","date":"Agosto 27, 2023","format":false,"excerpt":"Existem diversas formas de aprisionar algu\u00e9m fisicamente. Bem mais diversas s\u00e3o as maneiras de aprisionar mentes, cora\u00e7\u00f5es e intelectos. Estas, sem d\u00favida, s\u00e3o as piores formas de pris\u00e3o. De mentes fechadas, forma-se uma sociedade e um mundo fechados. No contexto atual, corremos o s\u00e9rio risco de cairmos nesse fechamento, em\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17498"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17498\/revisions"}],"predecessor-version":[{"id":17499,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17498\/revisions\/17499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/79"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}