{"id":17562,"date":"2021-09-19T22:08:47","date_gmt":"2021-09-20T01:08:47","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17562"},"modified":"2021-09-19T22:08:47","modified_gmt":"2021-09-20T01:08:47","slug":"setembro-dom-jose-3","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/setembro-dom-jose-3\/","title":{"rendered":"Setembro Dom Jos\u00e9"},"content":{"rendered":"<p>Neste m\u00eas de Setembro, vivencia-se um tempo favor\u00e1vel para enaltecer os grandes feitos de Dom Jos\u00e9 Tupinamb\u00e1 da Frota e divulgar a valorosa figura deste homem de Deus, considerado o maior benfeitor de Sobral. Ele nasceu a 10 de setembro de 1882 e faleceu a 25 de setembro de 1959. Por isso, este m\u00eas \u00e9 chamado Setembro de Dom Jos\u00e9.<br \/>\nNa ocasi\u00e3o das homenagens feitas a Dom Jos\u00e9 no centen\u00e1rio de seu nascimento, em 1982, Mons. Ximenes de Arag\u00e3o publicou neste jornal um brilhante paneg\u00edrico sobre o referido bispo, no qual se l\u00ea o seguinte trecho: \u201cA caminhada de liberta\u00e7\u00e3o de um povo tem sempre um Abra\u00e3o pela frente, tem um Mois\u00e9s, um Messias, e Dom Jos\u00e9 representou todos eles na Israel de Sobral. Foi o maior profeta. Aquele que apareceu com uma luz e uma vis\u00e3o que ningu\u00e9m teve\u201d.<br \/>\nDe fato, a Hist\u00f3ria comprova as palavras de Mons. Ximenes ao demonstrar que Dom Jos\u00e9 tinha uma capacidade incomum de enxergar o futuro no presente, caracter\u00edstica dos homens vision\u00e1rios. Foi com esta vis\u00e3o que ele projetou suas obras nos campos da sa\u00fade, da educa\u00e7\u00e3o e da forma\u00e7\u00e3o eclesi\u00e1stica na cidade de Sobral. Devemos, pois, valorizar mais a Hist\u00f3ria n\u00e3o deixando com que seus protagonistas caiam no esquecimento. Se, hoje, Sobral \u00e9 um dos maiores polos urban\u00edsticos do Nordeste, deve-se muito a Dom Jos\u00e9!<br \/>\nEle soube, como ningu\u00e9m, zelar pela educa\u00e7\u00e3o cat\u00f3lica em Sobral. Esse s\u00f3lido alicerce, talvez, explique o fato de Sobral ter-se tornado refer\u00eancia em educa\u00e7\u00e3o no pa\u00eds. Deve-se muito ao nosso primeiro bispo.<br \/>\nQuem o conheceu de perto afirma que nada escapava ao olhar penetrante do bispo que observava a tudo e a todos. Enaltecia os acertos e denunciava os erros. Muitos testemunham que, nas grandes solenidades, Dom Jos\u00e9 conseguia trazer os ares de Roma para estes sert\u00f5es, na execu\u00e7\u00e3o dos atos lit\u00fargicos e das grandes festividades. Quando entrava na igreja, revestido de seus paramentos, o povo tinha a impress\u00e3o de que aparecera uma figura sobrenatural e todos diziam consigo: \u201ccomo \u00e9 grande um Bispo\u201d!<br \/>\nUma marca do primeiro bispo de Sobral foi a promo\u00e7\u00e3o vocacional. Uma de suas primeiras edifica\u00e7\u00f5es foi o Semin\u00e1rio S\u00e3o Jos\u00e9, na Bet\u00e2nia. Ele fazia quest\u00e3o de estar presente no Semin\u00e1rio e acompanhar pessoalmente o processo formativo. Demonstrava uma profunda afei\u00e7\u00e3o de pai aos seus padres e seminaristas, de quem fazia cobran\u00e7as, dizia conselhos e dava ensinamentos. Semear as voca\u00e7\u00f5es sacerdotais era prioridade de Dom Jos\u00e9, que queria ver o Povo de Deus guiado por bons sacerdotes.<br \/>\nPor estas e outras benfeitorias prestadas \u00e0 Igreja e \u00e0 sociedade, conv\u00e9m que, neste Setembro de Dom Jos\u00e9, exaltemos a vida e a obra deste homem t\u00e3o ilustre. Enquanto o tempo faz o seu papel de imperdo\u00e1vel apagador, insistamos em traz\u00ea-lo \u00e0 lembran\u00e7a. Deixemos com que suas obras materiais e espirituais testemunhem seu valor \u00e0queles que o admiram, mesmo sem o terem conhecido. Salve o Bispo Conde de Sobral!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste m\u00eas de Setembro, vivencia-se um tempo favor\u00e1vel para enaltecer os grandes feitos de Dom&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,20],"tags":[],"class_list":["post-17562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg","jetpack-related-posts":[{"id":21114,"url":"https:\/\/correiodasemana.com\/site\/setembro-dom-jose-4\/","url_meta":{"origin":17562,"position":0},"title":"Setembro Dom Jos\u00e9","author":"","date":"Setembro 26, 2022","format":false,"excerpt":"Neste m\u00eas de Setembro, vivencia-se um tempo favor\u00e1vel para enaltecer os grandes feitos de Dom Jos\u00e9 Tupinamb\u00e1 da Frota e divulgar a valorosa figura deste homem de Deus, considerado o maior benfeitor de Sobral. Ele nasceu a 10 de setembro de 1882 e faleceu a 25 de setembro de 1959.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13555,"url":"https:\/\/correiodasemana.com\/site\/setembro-dom-jose-2\/","url_meta":{"origin":17562,"position":1},"title":"Setembro Dom Jos\u00e9","author":"","date":"Setembro 15, 2020","format":false,"excerpt":"Neste m\u00eas de Setembro, vivencia-se um tempo favor\u00e1vel para enaltecer os grandes feitos de Dom Jos\u00e9 Tupinamb\u00e1 da Frota e divulgar a valorosa figura deste homem de Deus, considerado o maior benfeitor de Sobral. Na ocasi\u00e3o das homenagens feitas a Dom Jos\u00e9 no centen\u00e1rio de seu nascimento, em 1982, Mons.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9072,"url":"https:\/\/correiodasemana.com\/site\/setembro-dom-jose\/","url_meta":{"origin":17562,"position":2},"title":"Setembro Dom Jos\u00e9","author":"","date":"Setembro 8, 2019","format":false,"excerpt":"Neste m\u00eas de Setembro, vivencia-se um tempo favor\u00e1vel para enaltecer os grandes feitos de Dom Jos\u00e9 Tupinamb\u00e1 da Frota e divulgar a valorosa figura deste homem de Deus, considerado o maior benfeitor de Sobral. Na ocasi\u00e3o das homenagens feitas a Dom Jos\u00e9 no centen\u00e1rio de seu nascimento, em 1982, Mons.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":26684,"url":"https:\/\/correiodasemana.com\/site\/centro-cultural-dom-jose-destaca-a-importancia-do-mes-de-setembro\/","url_meta":{"origin":17562,"position":3},"title":"Centro Cultural Dom Jos\u00e9 destaca a import\u00e2ncia do m\u00eas de setembro","author":"adminredacao","date":"Outubro 1, 2023","format":false,"excerpt":"Na ocasi\u00e3o, a Faculdade Via Sapiens entregou placa de Dr. Honoris Causa ao empres\u00e1rio Expedito Vasconcelos, pelos 70 anos de exist\u00eancia do Caf\u00e9 Jaibaras O Presidente do Centro Cultural Dom Jos\u00e9, Francisco Prado, se dedica a vida e a obra do primeiro bispo de Sobral. H\u00e1 34 anos o Centro\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/DSC5826.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/DSC5826.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/DSC5826.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/DSC5826.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34777,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-223\/","url_meta":{"origin":17562,"position":4},"title":"Becco ponto Com","author":"adminredacao","date":"Julho 22, 2025","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Do mercad\u00e3o que virou o Becco do Cotovelo. Das festas p\u00e3o e circo dos pol\u00edticos nossos. Da ruma de faculdades prometendo ensino. Da pol\u00edcia motorizada vagando no Becco, ui! Da novela Trump x Lula na taxa\u00e7\u00e3o imposta. Do medo do pt de Ciro \u201cl\u00edngua ferina\u201d Gomes. Da oposi\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28256,"url":"https:\/\/correiodasemana.com\/site\/poucas-e-boas-25\/","url_meta":{"origin":17562,"position":5},"title":"POUCAS E BOAS","author":"adminredacao","date":"Fevereiro 6, 2024","format":false,"excerpt":"Zuleika Viana parte deixando exemplo de f\u00e9, dedica\u00e7\u00e3o e trabalho Na quarta-feira (31), por volta das 22h, faleceu no Hospital do Cora\u00e7\u00e3o de Sobral Zuleika Ximenes Viana, de 94 anos, em decorr\u00eancia de problemas card\u00edacos. Inupta e de imenso talento profissional, a distinta senhorita prestou relevantes servi\u00e7os \u00e0 sociedade sobralense\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17562"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17562\/revisions"}],"predecessor-version":[{"id":17563,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17562\/revisions\/17563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7865"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}