{"id":17678,"date":"2021-10-04T01:13:35","date_gmt":"2021-10-04T04:13:35","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17678"},"modified":"2021-10-04T01:13:35","modified_gmt":"2021-10-04T04:13:35","slug":"oh-santo-de-deus-muito-amado","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/oh-santo-de-deus-muito-amado\/","title":{"rendered":"OH SANTO DE DEUS MUITO AMADO!\u00a0"},"content":{"rendered":"<p>S\u00e3o Francisco Louvado Sejais!, assim cantamos na ladainha de S\u00e3o Francisco de Assis. Setecentos e noventa e cinco anos nos separam de morte por quem louvou ao Senhor Deus, chamando-a \u201cnossa irm\u00e3 a Morte corporal,\/ da qual homem algum pode escapar\u201d. Conforme seus bi\u00f3grafos, sentindo a morte pr\u00f3xima, Francisco solicitou \u00e0 nobre Jacopa de\u2019 Settesoli, uma amiga romana, que trouxesse o necess\u00e1rio para seu sepultamento. Foi despedir-se da Irm\u00e3 Clara e das irm\u00e3s, em S\u00e3o Dami\u00e3o e voltou \u00e0 Porci\u00fancula, deu instru\u00e7\u00f5es para ser sepultado nu, e no p\u00f4r do sol de 3 de outubro de 1226, depois de ler algumas passagens do Evangelho, faleceu rodeado de seus companheiros, nobres amigos e outras personalidades.<br \/>\nMenos de dois anos depois, o Papa Greg\u00f3rio IX foi a Assis para canoniz\u00e1-lo, em 06\/07\/1228. Em 1230, foi inaugurada uma nova bas\u00edlica em Assis, dedicada ao Santo, abrigando suas rel\u00edquias e o seu t\u00famulo definitivo.<br \/>\nDante Alighieri (1265-1321) escreveu que Francisco foi uma \u201cluz que brilhou sobre o mundo\u201d. Francisco foi um poeta existencial. Na juventude, como todo rapaz de sua \u00e9poca, aventureiro, namorador&#8230; Em 1202, alistou-se na guerra que Assis desenvolvia contra Peruggia, mas foi capturado e permaneceu preso por cerca de um ano. Em 1205, engajou-se no ex\u00e9rcito papal que lutava contra Frederico II, tornando-se Cavaleiro. Deixando o campo de batalha, voltou \u00e0 sua cidade. Ali, ao passar por uma igreja em ru\u00ednas, ouviu o chamado: \u201cFrancisco, reconstr\u00f3i a minha Igreja\u201d e fez uma revolu\u00e7\u00e3o na Santa Madre Igreja.<br \/>\nO martirol\u00f3gio romano registra em 4 de outubro, um dia ap\u00f3s seu encontro com Deus: \u201cMem\u00f3ria de S\u00e3o Francisco, que, depois de uma vida despreocupada, se converteu \u00e0 vida evang\u00e9lica em Assis, na \u00dambria, regi\u00e3o da It\u00e1lia, encontrando Jesus Cristo especialmente nos pobres e tornando-se ele mesmo pobre ao servi\u00e7o dos necessitados. Reuniu em comunidade consigo os Frades Menores, pregou o amor de Deus a todos nas suas caminhadas, inclusivamente na peregrina\u00e7\u00e3o \u00e0 Terra Santa, mostrando com as suas palavras e atitudes o desejo de seguir a Cristo, e quis morrer deitado sobre a terra nua\u201d.<br \/>\nO maior local de devo\u00e7\u00e3o ao Santo \u00e9 sua terra, Assisi, na Peruggia, It\u00e1lia, onde um dia percorri seus caminhos. No Cear\u00e1 est\u00e1 o segundo maior santu\u00e1rio franciscano do mundo: Canind\u00e9. O in\u00edcio de tudo se deu no s\u00e9culo XVIII, quando foi constru\u00edda uma capela dedicada a S\u00e3o Francisco, vindo, da It\u00e1lia, sua primeira imagem. A capela deu origem \u00e0 bela Bas\u00edlica Menor de S\u00e3o Francisco, da qual tive a honra de relatar o Parecer de Tombamento, no Conselho Estadual de Preserva\u00e7\u00e3o do Patrim\u00f4nio Cultural do Cear\u00e1.<br \/>\nEm 2018, pelo Decreto Legislativo N\u00b0 020\/2018, publicado no Di\u00e1rio Oficial do Munic\u00edpio de Canind\u00e9, de 1\u00b0\/11\/2018, foi concedido o \u201cT\u00edtulo Honor\u00edfico de CIDAD\u00c3O CANINDEENSE, ao PADROEIRO da Cidade, S\u00e3o Francisco (in memoriam)\u201d. N\u00e3o encontrei, em lugar nenhum, tributo semelhante a um santo padroeiro. O Vereador Carlos Anast\u00e1cio, autor do projeto, em justificativa, relatou a biografia do Santo e destacou: \u201cse algu\u00e9m merece tal honraria de cidadania canindeense, esse \u00e9 S\u00e3o Francisco\u201d.<br \/>\nS\u00e3o Francisco \u00e9 irm\u00e3o de todos os crist\u00e3os e de n\u00f3s, cearenses, muito pr\u00f3ximo, pela cidadania canindeense!<br \/>\nS\u00e3o Francisco nos aben\u00e7oai!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Francisco Louvado Sejais!, assim cantamos na ladainha de S\u00e3o Francisco de Assis. Setecentos e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,41],"tags":[],"class_list":["post-17678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-jose-luis-lira"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose\u0301-1.jpg","jetpack-related-posts":[{"id":15835,"url":"https:\/\/correiodasemana.com\/site\/de-poeta-para-poeta-santo-sao-francisco-de-assis-por-augusto-de-lima\/","url_meta":{"origin":17678,"position":0},"title":"DE POETA PARA POETA SANTO: S\u00c3O FRANCISCO DE ASSIS POR AUGUSTO DE LIMA\u00a0","author":"","date":"Fevereiro 28, 2021","format":false,"excerpt":"Em dezembro, encaminhei um cart\u00e3o personalizado de feliz ano de 2021 ao nobre irm\u00e3o na Nobre e Pontif\u00edcia Ordem Equestre do Santo Sepulcro de Jerusal\u00e9m, Comendador Arist\u00f3teles Drummond. O nobre Comendador e conceituado jornalista me pediu o endere\u00e7o. Dias depois recebi livro de seu bisav\u00f4, de quem seu av\u00f4, Augusto\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":13900,"url":"https:\/\/correiodasemana.com\/site\/os-santos-em-nossos-dias\/","url_meta":{"origin":17678,"position":1},"title":"OS SANTOS EM NOSSOS DIAS\u00a0","author":"","date":"Outubro 4, 2020","format":false,"excerpt":"Em 3 de outubro, no long\u00ednquo ano de 1226, acontecia o tr\u00e2nsito da terra para o c\u00e9u, a morte, de S\u00e3o Francisco de Assis, Giovanni di Pietro di Bernardone, simplesmente Francesco. Ele foi uma dessas figuras que se fazem \u00fanicas. De jovem rico e aventureiro como qualquer um outro, cavaleiro,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30829,"url":"https:\/\/correiodasemana.com\/site\/sao-francisco-louvado-sejas-5\/","url_meta":{"origin":17678,"position":2},"title":"\u201cS\u00e3o Francisco, louvado sejas!\u201d","author":"adminredacao","date":"Outubro 2, 2024","format":false,"excerpt":"Na pr\u00f3xima sexta-feira, dia 4, o santo do povo ser\u00e1 celebrado em nossas par\u00f3quias e comunidades. Nas serras, praias e sert\u00f5es, S\u00e3o Francisco \u00e9 lembrado e festejado a cada ano. O seu testemunho alcan\u00e7ou, ao longo dos s\u00e9culos, uma grande popularidade na Igreja. \u00c9 por isso que se afirma que\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22946,"url":"https:\/\/correiodasemana.com\/site\/padre-ronaldo-marques-e-apresentado-como-novo-vigario-paroquial-da-area-pastoral-de-sao-francisco-de-assis-em-parapui\/","url_meta":{"origin":17678,"position":3},"title":"Padre Ronaldo Marques \u00e9 apresentado como novo Vig\u00e1rio Paroquial da \u00c1rea Pastoral de S\u00e3o Francisco de Assis, em Parapu\u00ed","author":"adminredacao","date":"Janeiro 22, 2023","format":false,"excerpt":"A quarta-feira (18\/01) foi de muita festa para a comunidade paroquial da \u00c1rea Pastoral de S\u00e3o Francisco de Assis em Parapu\u00ed - Santana do Acara\u00fa. Os paroquianos acolheram seu novo Vig\u00e1rio Paroquial, Pe. Ronaldo Marques da Costa, durante a Santa Missa presidida por Dom Jos\u00e9 Luiz Gomes de Vasconcelos. Ap\u00f3s\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/novo-paroco-diocese-de-sobral-8.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":9402,"url":"https:\/\/correiodasemana.com\/site\/sao-francisco-louvado-sejas\/","url_meta":{"origin":17678,"position":4},"title":"\u201cS\u00e3o Francisco, louvado sejas!\u201d","author":"","date":"Outubro 14, 2019","format":false,"excerpt":"Por: Ygor Leonardo Sampaio - Seminarista da Diocese de Sobral No \u00faltimo dia 4, o santo do povo foi celebrado em nossas par\u00f3quias e comunidades. Nas serras, praias e sert\u00f5es, S\u00e3o Francisco \u00e9 lembrado e festejado a cada ano. Muito encanta a popularidade que o seu testemunho alcan\u00e7ou ao longo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_6217.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":13910,"url":"https:\/\/correiodasemana.com\/site\/sao-francisco-louvado-sejas-2\/","url_meta":{"origin":17678,"position":5},"title":"\u201cS\u00e3o Francisco, louvado sejas!\u201d","author":"","date":"Outubro 4, 2020","format":false,"excerpt":"Neste domingo, dia 4, o santo do povo \u00e9 celebrado em nossas par\u00f3quias e comunidades. Nas serras, praias e sert\u00f5es, S\u00e3o Francisco \u00e9 lembrado e festejado a cada ano. Muito encanta a popularidade que o seu testemunho alcan\u00e7ou ao longo dos s\u00e9culos. \u00c9 por isso que se afirma que Francisco\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17678"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17678\/revisions"}],"predecessor-version":[{"id":17679,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17678\/revisions\/17679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7874"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}