{"id":17745,"date":"2021-10-17T23:46:52","date_gmt":"2021-10-18T02:46:52","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17745"},"modified":"2021-10-17T23:46:52","modified_gmt":"2021-10-18T02:46:52","slug":"valor-fixo-do-icms-e-aprovado-pela-camara-para-impacto-no-preco-dos-combustiveis","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/valor-fixo-do-icms-e-aprovado-pela-camara-para-impacto-no-preco-dos-combustiveis\/","title":{"rendered":"Valor fixo do ICMS \u00e9 aprovado pela c\u00e2mara para impacto no pre\u00e7o dos combust\u00edveis"},"content":{"rendered":"<p>Por Samuel Carvalho<br \/>\nReda\u00e7\u00e3o Correio da Semana<br \/>\nFoi aprovado na noite da \u00faltima quarta-feira (13) um projeto de lei no plen\u00e1rio da C\u00e2mara que estabelece um valor fixo para a cobran\u00e7a do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS) sobre os combust\u00edveis. A proposta foi aprovada por 392 votos a favor, 71 contra e 2 absten\u00e7\u00f5es. O texto parte agora para an\u00e1lise do Senado.<br \/>\nO substitutivo do relator, deputado Dr Jaziel (PL-CE), obriga estados e o Distrito Federal a especificar a al\u00edquota cobrada do ICMS de cada produto pela unidade de medida adotada (litro, quilo ou volume) e n\u00e3o mais sobre o valor da mercadoria, como ocorre atualmente. Na pr\u00e1tica o projeto de lei ir\u00e1 tornar o ICMS invari\u00e1vel frente a oscila\u00e7\u00f5es no pre\u00e7o dos combust\u00edveis e de mudan\u00e7as do c\u00e2mbio.<br \/>\nDe acordo com a avalia\u00e7\u00e3o apresentada pelo relator, as mudan\u00e7as estabelecidas pela proposta que ir\u00e1 ao Senado deve levar a uma redu\u00e7\u00e3o do pre\u00e7o final praticado ao consumidor de, em m\u00e9dia, 8% para a gasolina comum, 7% para o etanol hidratado e 3,7% para o diesel B. \u201cA medida colaborar\u00e1 para a simplifica\u00e7\u00e3o do modelo de exig\u00eancia do imposto, bem como para uma maior estabilidade nos pre\u00e7os desses produtos\u201d, explicou o deputado Dr Jaziel.<br \/>\nO presidente da C\u00e2mara, Arthur Lira (PP-AL), disse que a aprova\u00e7\u00e3o do projeto foi resultado de um acordo com os l\u00edderes partid\u00e1rios. Segundo o presidente, a proposta \u201ccircula desde o in\u00edcio da legislatura\u201d, esteve em debate nas reuni\u00f5es do Col\u00e9gio de L\u00edderes e se chegou a um acordo de procedimento com a oposi\u00e7\u00e3o para que n\u00e3o houvesse obstru\u00e7\u00e3o na sess\u00e3o desta quarta-feira.<br \/>\n\u201cO governo prop\u00f4s unificar as tarifas de ICMS no Brasil em todos os estados \u2013 o que todos n\u00f3s n\u00e3o concord\u00e1vamos \u2013 e o que n\u00f3s estamos votando \u00e9 um projeto que cria uma m\u00e9dia dos \u00faltimos dois anos e, sobre esta m\u00e9dia, se multiplica pelo imposto estadual de cada estado, com total liberdade para cada estado\u201d, apontou Arthur Lira.<br \/>\nHoje, o tributo \u00e9 devido por substitui\u00e7\u00e3o tribut\u00e1ria para frente, sendo a sua base de c\u00e1lculo pressuposta a partir dos pre\u00e7os m\u00e9dios ponderados ao consumidor final, ponderados por quinzena pelos governos estaduais. As al\u00edquotas de ICMS para gasolina, por exemplo, variam entre 25% e 34%, dependendo do estado.<br \/>\nNo novo c\u00e1lculo, as al\u00edquotas ser\u00e3o definidas pelos estados e Distrito Federal para cada produto a partir da unidade de medida adotada, no caso o litro para os combust\u00edveis. As al\u00edquotas espec\u00edficas ser\u00e3o fixadas anualmente e vigorar\u00e3o por 12 meses a partir da data de sua publica\u00e7\u00e3o, mas n\u00e3o poder\u00e3o exceder, em reais por litro, o valor da m\u00e9dia dos pre\u00e7os ao consumidor final usualmente praticados no mercado considerado ao longo dos dois exerc\u00edcios imediatamente anteriores, multiplicada pela al\u00edquota ad valorem (percentual fixado em lei que ser\u00e1 aplicado sobre a base de c\u00e1lculo do tributo) aplic\u00e1vel ao combust\u00edvel em 31 de dezembro do exerc\u00edcio imediatamente anterior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Foi aprovado na noite da \u00faltima quarta-feira (13)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-17745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",652,408,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos-300x188.jpg",300,188,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",640,400,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",640,400,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",652,408,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",652,408,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg",652,408,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos-652x380.jpg",540,315,true]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/gasolina-nos-postos.jpg","jetpack-related-posts":[{"id":18868,"url":"https:\/\/correiodasemana.com\/site\/presidente-da-camara-defende-congelar-icms-em-preco-de-combustivel\/","url_meta":{"origin":17745,"position":0},"title":"Presidente da C\u00e2mara defende congelar ICMS em pre\u00e7o de combust\u00edvel","author":"","date":"Fevereiro 14, 2022","format":false,"excerpt":"Lira defende a redu\u00e7\u00e3o do imposto para baixar os pre\u00e7o Por Heloisa Cristaldo* - Bras\u00edlia O presidente da C\u00e2mara, deputado Arthur Lira (PP-AL), afirmou\u00a0hoje\u00a0(10) que o Parlamento deve votar uma proposta para reduzir os tributos dos combust\u00edveis no pa\u00eds. O congressista tem defendido o\u00a0projeto\u00a0j\u00e1 aprovado na C\u00e2mara, que estabelece um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/monumentos_brasilia_3103201323.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/monumentos_brasilia_3103201323.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/monumentos_brasilia_3103201323.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/monumentos_brasilia_3103201323.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/monumentos_brasilia_3103201323.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20172,"url":"https:\/\/correiodasemana.com\/site\/camara-conclui-votacao-de-projeto-que-limita-icms-dos-combustiveis\/","url_meta":{"origin":17745,"position":1},"title":"C\u00e2mara conclui vota\u00e7\u00e3o de projeto que limita ICMS dos combust\u00edveis","author":"","date":"Junho 19, 2022","format":false,"excerpt":"Por Heloisa Cristaldo - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia A C\u00e2mara dos Deputados concluiu h\u00e1 pouco a vota\u00e7\u00e3o do Projeto de Lei Complementar (PLP) 18\/2022, que limita a aplica\u00e7\u00e3o de al\u00edquota do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS) sobre combust\u00edveis. O texto segue para san\u00e7\u00e3o presidencial. Na\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/img202205051111199831.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/img202205051111199831.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/img202205051111199831.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/img202205051111199831.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/img202205051111199831.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24963,"url":"https:\/\/correiodasemana.com\/site\/tributos-sobre-combustiveis-sobem-em-junho-e-julho\/","url_meta":{"origin":17745,"position":2},"title":"Tributos sobre combust\u00edveis sobem em junho e julho","author":"","date":"Maio 29, 2023","format":false,"excerpt":"A partir de junho, haver\u00e1 mudan\u00e7as na al\u00edquota do ICMS (Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os) sobre a gasolina, e uma das principais altera\u00e7\u00f5es \u00e9 volta de tributos federais sobre gasolina e etanol. Essas mudan\u00e7as ter\u00e3o impacto nos pre\u00e7os para os consumidores. Com a nova regra, o imposto passar\u00e1\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/COMBUSTIVEL-ILUSTRACAO-AUMENTO-DE-PRECOS.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/COMBUSTIVEL-ILUSTRACAO-AUMENTO-DE-PRECOS.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/COMBUSTIVEL-ILUSTRACAO-AUMENTO-DE-PRECOS.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/COMBUSTIVEL-ILUSTRACAO-AUMENTO-DE-PRECOS.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/COMBUSTIVEL-ILUSTRACAO-AUMENTO-DE-PRECOS.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19156,"url":"https:\/\/correiodasemana.com\/site\/senado-aprova-projeto-para-reduzir-preco-dos-combustiveis\/","url_meta":{"origin":17745,"position":3},"title":"Senado aprova projeto para reduzir pre\u00e7o dos combust\u00edveis","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"Projeto segue para C\u00e2mara dos Deputados Por Marcelo Brand\u00e3o \u2013 Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O Senado aprovou, na quinta-feira (10), o Projeto de Lei (PL) 1.472\/2021, que altera a forma de c\u00e1lculo do pre\u00e7o dos combust\u00edveis, al\u00e9m de criar uma Conta de Estabiliza\u00e7\u00e3o. Esse fundo funcionar\u00e1 como um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/preco-da-gasolina.-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":18577,"url":"https:\/\/correiodasemana.com\/site\/senadores-criticam-reajustes-nos-combustiveis-e-defendem-projetos-para-conter-precos\/","url_meta":{"origin":17745,"position":4},"title":"Senadores criticam reajustes nos combust\u00edveis e defendem projetos para conter pre\u00e7os","author":"","date":"Janeiro 16, 2022","format":false,"excerpt":"Ap\u00f3s sucessivos reajustes em 2021, que elevaram o pre\u00e7o dos combust\u00edveis nos postos em cerca de 44%, a Petrobras subiu esta semana os valores para a gasolina (4,85%) e o diesel (8,08%) para as distribuidoras. O an\u00fancio assusta os brasileiros diante de mais um aumento do principal vil\u00e3o da infla\u00e7\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/senadores.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/senadores.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/senadores.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17195,"url":"https:\/\/correiodasemana.com\/site\/aprovado-projeto-que-regulamenta-cobranca-de-icms-no-comercio-interestadual\/","url_meta":{"origin":17745,"position":5},"title":"Aprovado projeto que regulamenta cobran\u00e7a de ICMS no com\u00e9rcio interestadual","author":"","date":"Agosto 9, 2021","format":false,"excerpt":"Fonte: Ag\u00eancia Senado Foi aprovado pelo Senado Federal o projeto de lei complementar (PLP 32\/2021), de autoria do senador Cid Gomes (PDT-CE), que regulamenta a cobran\u00e7a do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS) sobre vendas de produtos e presta\u00e7\u00e3o de servi\u00e7os a consumidor final localizado em outro estado.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/icms-estadual.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/icms-estadual.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/icms-estadual.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/icms-estadual.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17745"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17745\/revisions"}],"predecessor-version":[{"id":17746,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17745\/revisions\/17746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/12973"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}