{"id":17790,"date":"2021-10-18T00:05:28","date_gmt":"2021-10-18T03:05:28","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17790"},"modified":"2021-10-18T00:05:28","modified_gmt":"2021-10-18T03:05:28","slug":"patria-amada-nao-pode-ser-patria-armada-exorta-arcebispo-de-aparecida-durante-feriado-nacional-da-padroeira-do-brasil","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/patria-amada-nao-pode-ser-patria-armada-exorta-arcebispo-de-aparecida-durante-feriado-nacional-da-padroeira-do-brasil\/","title":{"rendered":"\u201cP\u00e1tria Amada n\u00e3o pode ser P\u00e1tria armada\u201d, exorta arcebispo de Aparecida durante feriado nacional da Padroeira do Brasil"},"content":{"rendered":"<p>Por Samuel Carvalho<br \/>\nReda\u00e7\u00e3o Correio da Semana<br \/>\nDom Orlando Brandes, arcebispo de Aparecida, em S\u00e3o Paulo, durante o feriado de 12 de outubro, Dia de Nossa Senhora Aparecida, padroeira do Brasil, fez um apelo ao n\u00e3o armamento da popula\u00e7\u00e3o no Pa\u00eds. \u201cP\u00e1tria amada n\u00e3o pode ser p\u00e1tria armada\u201d, disse o p\u00e1roco durante o serm\u00e3o da missa das 9 horas, no santu\u00e1rio da Arquidiocese.<br \/>\nNas palavras do Bispo do santur\u00e1rio da Arquidiocese, para ser p\u00e1tria amada, \u00e9 preciso ser \u201cp\u00e1tria sem \u00f3dio\u201d. \u201cPara ser p\u00e1tria amada, uma rep\u00fablica sem mentira e fake news. P\u00e1tria amada sem corrup\u00e7\u00e3o. E p\u00e1tria amada com fraternidade. Todos os irm\u00e3os construindo a grande fam\u00edlia brasileira\u201d, afirmou Dom Orlando Brandes.<br \/>\nDurante o serm\u00e3o o bispo tamb\u00e9m lamentou as perdas pela pandemia do coronav\u00edrus, lamentou a marca de 600 mil mortes por Covid-19 no Pa\u00eds e defendeu a vacina\u00e7\u00e3o e a ci\u00eancia. \u201cM\u00e3e Aparecida, muito obrigado porque, na pandemia, a senhora foi consoladora, conselheira, mestra, companheira e guia do povo brasileiro que hoje te agradece de cora\u00e7\u00e3o porque vacina, sim, ci\u00eancia, sim, e Nossa Senhora Aparecida junto salvando o povo brasileiro\u201d, celebrou. Al\u00e9m dessas falas, o aumento da pobreza e da fome nos \u00faltimos anos tamb\u00e9m foram pautas da hom\u00edlia de Dom Orlando Brandes. \u201cQuero pedir que cada um de n\u00f3s abrace o Brasil. Abrace o nosso povo\u201d, pediu o arcebispo.<br \/>\nAp\u00f3s as cr\u00edticas indiretas de Dom Orlando ao Governo Federal, o presidente Jair Bolsonaro (sem partido) compareceu ao santu\u00e1rio de Aparecida. Segundo o G1, o presidente estava de m\u00e1scara e s\u00f3 retirou o item para fazer uma leitura diante da igreja.<br \/>\nA imprensa tamb\u00e9m questionou ao arcebispo se o serm\u00e3o era um recado para Bolsonaro. Ao que ele respondeu ser uma mensagem para todos os brasileiros. \u201cRespeitamos as autoridades mesmo discordando e falamos com a doutrina da igreja. N\u00f3s estamos quebrando a alian\u00e7a com o \u00f3dio e a corrup\u00e7\u00e3o e para confirmarmos a nossa Rep\u00fablica e a democracia\u201d, disse o religioso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Dom Orlando Brandes, arcebispo de Aparecida, em S\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-17790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Dom-Orlando-Brandes-1024x654-1.jpg","jetpack-related-posts":[{"id":21010,"url":"https:\/\/correiodasemana.com\/site\/um-sonho-de-200-anos\/","url_meta":{"origin":17790,"position":0},"title":"Um sonho de 200 anos","author":"","date":"Setembro 11, 2022","format":false,"excerpt":"Ao celebrarmos o bicenten\u00e1rio da Independ\u00eancia do Brasil, precisamos pensar na grande na\u00e7\u00e3o que formamos. Grande em todos os aspectos, em territ\u00f3rio, em popula\u00e7\u00e3o, em riquezas, em potenciais, em bens naturais. Mas o que mais carecemos, no atual contexto, \u00e9 de grandes ideais. Isso porque a dignidade do povo brasileiro\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9065,"url":"https:\/\/correiodasemana.com\/site\/patria-amada-brasil\/","url_meta":{"origin":17790,"position":1},"title":"P\u00e1tria Amada Brasil!","author":"","date":"Setembro 8, 2019","format":false,"excerpt":"O Pa\u00eds celebra os 197 anos de Independ\u00eancia do Brasil. Nossa P\u00e1tria \u00e9 jovem e sua independ\u00eancia foi promovida por gente mais jovem ainda, posto que tinha 24 anos incompletos, o jovem Pr\u00edncipe Regente do Brasil e herdeiro do trono de Portugal, cidad\u00e3o portugu\u00eas, Dom Pedro, que chegara ao Brasil\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17399,"url":"https:\/\/correiodasemana.com\/site\/dom-walmor-abre-mes-da-biblia-e-deseja-que-a-luz-da-palavra-de-deus-ilumine-a-semana-da-patria\/","url_meta":{"origin":17790,"position":2},"title":"DOM WALMOR ABRE M\u00caS DA B\u00cdBLIA E DESEJA QUE A LUZ DA PALAVRA DE DEUS ILUMINE A SEMANA DA P\u00c1TRIA","author":"","date":"Setembro 6, 2021","format":false,"excerpt":"Fonte: CNBB A Igreja no Brasil abriu, nesta quarta-feira, 1\u00ba de setembro, o M\u00eas da B\u00edblia, com uma Celebra\u00e7\u00e3o Eucar\u00edstica presida pelo arcebispo de Belo Horizonte (MG) e presidente da CNBB, dom Walmor Oliveira de Azevedo, no Santu\u00e1rio de Nossa Senhora da Piedade. Em sua homilia, dom Walmor manifestou alegria\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/dom-walmor-abertura-mes-biblia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/dom-walmor-abertura-mes-biblia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/dom-walmor-abertura-mes-biblia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/dom-walmor-abertura-mes-biblia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/dom-walmor-abertura-mes-biblia.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9070,"url":"https:\/\/correiodasemana.com\/site\/patria-e-ecologia\/","url_meta":{"origin":17790,"position":3},"title":"P\u00e1tria e ecologia","author":"","date":"Setembro 8, 2019","format":false,"excerpt":"A p\u00e1tria \u00e9 raz\u00e3o de amor e de respeito, \u00e9 a terra natal com suas tradi\u00e7\u00f5es, culturas, hist\u00f3rias e sua l\u00edngua. Espa\u00e7o e heran\u00e7a cultural, miss\u00e3o a cumprir. A p\u00e1tria \u00e9 um projeto sempre em constru\u00e7\u00e3o que ultrapassa qualquer sentido de posse partid\u00e1ria e deve estar livre dos estreitamentos impostos\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-Em-entrevista-concedida-%C3%A0-Pascom-Diocesana-Foto-Jo%C3%A3o-Pauloo.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26848,"url":"https:\/\/correiodasemana.com\/site\/padre-cicero-entra-para-o-livro-dos-herois-e-heroinas-da-patria\/","url_meta":{"origin":17790,"position":4},"title":"Padre C\u00edcero entra para o Livro dos Her\u00f3is e Hero\u00ednas da P\u00e1tria","author":"adminredacao","date":"Outubro 17, 2023","format":false,"excerpt":"Ele nasceu em 1844 e morreu em 1934, aos 90 anos Por Fab\u00edola Sinimb\u00fa - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia O nome de C\u00edcero Rom\u00e3o Batista - mais conhecido como padre C\u00edcero - foi inscrito no Livro dos Her\u00f3is e Hero\u00ednas da P\u00e1tria, atrav\u00e9s da lei 14.693\/2023, sancionada pelo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/alta_9e433e57-cf28-4194-a3e3-a91bb10198a8_jv.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/alta_9e433e57-cf28-4194-a3e3-a91bb10198a8_jv.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/alta_9e433e57-cf28-4194-a3e3-a91bb10198a8_jv.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/alta_9e433e57-cf28-4194-a3e3-a91bb10198a8_jv.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/10\/alta_9e433e57-cf28-4194-a3e3-a91bb10198a8_jv.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21239,"url":"https:\/\/correiodasemana.com\/site\/aparecida-nas-aguas-2\/","url_meta":{"origin":17790,"position":5},"title":"Aparecida nas \u00e1guas","author":"","date":"Outubro 10, 2022","format":false,"excerpt":"No pr\u00f3ximo dia 12, feriado nacional, a Igreja do Brasil celebra a festa da Rainha e Padroeira desta na\u00e7\u00e3o, Nossa Senhora Aparecida. Tal devo\u00e7\u00e3o, hoje t\u00e3o popularizada, surgiu na simplicidade da devo\u00e7\u00e3o de um povo pobre e humilde. A Virgem Maria, a partir daquela pequenina imagem aparecida nas \u00e1guas, mais\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17790"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17790\/revisions"}],"predecessor-version":[{"id":17792,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17790\/revisions\/17792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17791"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}