{"id":17819,"date":"2021-10-24T19:22:27","date_gmt":"2021-10-24T22:22:27","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17819"},"modified":"2021-10-24T19:23:27","modified_gmt":"2021-10-24T22:23:27","slug":"sobral-sobral-61","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/sobral-sobral-61\/","title":{"rendered":"Sobral, Sobral"},"content":{"rendered":"<p><strong>MINHAS HIST\u00d3RIAS&#8230;<\/strong><br \/>\n<strong>Z\u00c9 PREGUIM E O JUIZ VILA NOVA<\/strong><br \/>\nNum passado n\u00e3o t\u00e3o recente jogou no GUARANY DE SOBRAL o zagueiro central Z\u00c9 PREGUIM. Natural de QUIXAD\u00c1, time pelo qual jogou quase toda sua carreira esportiva. Era aquele tipo de zagueiro estilo FERREIRA ARAG\u00c3O: do pesco\u00e7o pra baixo era canela. Foi trazido para o CACIQUE DO VALE atrav\u00e9s do seu eterno presidente LUIZ TORQUATO. Por\u00e9m, Seu LUIZ j\u00e1 conhecendo o \u00abgabarito t\u00e9cnico\u00bb do Z\u00c9 PREGUIM, fez com ele um trato. A cada expuls\u00e3o de campo, multa de 25 por cento do sal\u00e1rio. Logo na estreia do \u201cbec\u00e3o\u201d, cl\u00e1ssico GUARANY \u00d7 FERROVI\u00c1RIO, no Est\u00e1dio do Junco. \u00c1rbitro escalado: LUIZ VIEIRA VILA NOVA, velho conhecido de todos por sua toler\u00e2ncia zero com a viol\u00eancia. Z\u00c9 PREGUIM invariavelmente era expulso em todo jogo apitado por aquele juiz. Lembrando da cl\u00e1usula no contrato, Z\u00c9 PREGUIM bolou um plano. Chegou para o VILA NOVA antes do apito inicial e tascou:<br \/>\n&#8212; Dr. VILA NOVA, por favor n\u00e3o me bote pra fora do jogo hoje. Domingo que vem vamos jogar em JUAZEIRO contra o ICASA. Minha m\u00e3e t\u00e1 revendendo MICHELIN e eu queria comprar um ourim pra ajudar minha velha !!<br \/>\nSem olhar para o zagueiro, o \u00e1rbitro, respondeu na bucha:<br \/>\n<img decoding=\"async\" class=\"alignleft size-full wp-image-17822\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/Jornal-Correio-da-Semana-No-896-4-2.jpg\" alt=\"\" width=\"262\" height=\"153\" \/>&#8212; Jogue direito, na bola. Pense que a sua m\u00e3e \u00e9 o atacante do outro time.<br \/>\nMas logo na sua primeira disputa, Z\u00c9 PREGUIM deu uma voadora num atacante coral. O juiz j\u00e1 ia expulsar (n\u00e3o havia ainda os cart\u00f5es) quando o zagueiro juntou as m\u00e3os e suplicou clem\u00eancia, pela necessidade de comprar o \u201couro\u201d para a m\u00e3e. O juiz atendeu, j\u00e1 contrariado. Todavia, antes dos 20 minutos do tempo inicial, Z\u00c9 PREGUIM esqueceu de novo a bola e quase acerta o rosto de outro atacante do FERRIM. Foi quando o juiz VILA NOVA assoprou estridente o seu apito e, com o dedo apontando o t\u00fanel do GUARANY, soltou a frase que ningu\u00e9m comprendeu:<br \/>\n&#8212; FORA, FORA! VOC\u00ca L\u00c1 QUER COMPRAR OURO EM JUAZEIRO, RAPAZ!!!<br \/>\n\u2022 Luiz Vieira Vilanova, ex-jogador e ex-\u00e1rbitro de futebol<\/p>\n<p><strong>MINHAS FRASES&#8230;<img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17820\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/col-9-300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/col-9-300x226.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/col-9.jpg 542w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/strong><\/p>\n<p><strong>S\u00d3 PENSE NO PASSADO SE AS LEMBRAN\u00c7AS FOREM BOAS!!<\/strong><br \/>\n(JANE AUSTEN, 1775-1817, de STEVENTON, INGLATERRA, escreveu o romance ORGULHO E PRECONCEITO, roteiro para v\u00e1rios filmes e seriados na)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINHAS HIST\u00d3RIAS&#8230; Z\u00c9 PREGUIM E O JUIZ VILA NOVA Num passado n\u00e3o t\u00e3o recente jogou&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,75],"tags":[],"class_list":["post-17819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-carolino-soares"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png","jetpack-related-posts":[{"id":29753,"url":"https:\/\/correiodasemana.com\/site\/poucas-e-boas-38\/","url_meta":{"origin":17819,"position":0},"title":"Poucas e Boas","author":"adminredacao","date":"Junho 24, 2024","format":false,"excerpt":"Jogando conversa fora Pensando que eu n\u00e3o tinha conhecimento do registro de um encontro de tr\u00eas gigantes da nossa Cultura e da nossa Religiosidade, h\u00e1 poucos dias um internauta amigo enviou-me uma fotografia \u201chist\u00f3rica e rara\u201d, segundo ele. Durante algum tempo essa foto, que representa a perspic\u00e1cia de quem a\u2026","rel":"","context":"In &quot;Poucas e Boas&quot;","block_context":{"text":"Poucas e Boas","link":"https:\/\/correiodasemana.com\/site\/category\/poucas-e-boas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16984,"url":"https:\/\/correiodasemana.com\/site\/a-santa-casa-pelo-padre-ze-linhares\/","url_meta":{"origin":17819,"position":1},"title":"A Santa Casa pelo Padre Z\u00e9 Linhares\u00a0","author":"","date":"Julho 12, 2021","format":false,"excerpt":"O t\u00edtulo desta coluna que hoje ser\u00e1 maior que o habitual, tem sentido amplo. Referiremos \u00e0 publica\u00e7\u00e3o do livro enciclop\u00e9dico e hist\u00f3rico em dois volumes escrito pelo Padre Jos\u00e9 Linhares Ponte, nosso querido Padre Z\u00e9: \u201cA Hist\u00f3ria da Santa Casa de Miseric\u00f3rdia de Sobral: Sonho, Saga, Sacramental (Mist\u00e9rio e Milagre)\u201d.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16876,"url":"https:\/\/correiodasemana.com\/site\/padre-jose-linhares-ponte-lanca-livros-sobre-historia-da-santa-casa-de-misericordia-de-sobral\/","url_meta":{"origin":17819,"position":2},"title":"Padre Jos\u00e9 Linhares Ponte lan\u00e7a livros sobre hist\u00f3ria da Santa Casa de Miseric\u00f3rdia de Sobral","author":"","date":"Julho 5, 2021","format":false,"excerpt":"Padre Z\u00e9 ainda recebeu uma comenda de agradecimento pelos 33 anos de dedica\u00e7\u00e3o ao desenvolvimento do hospital, pelas m\u00e3os do bispo da Diocese de Sobral e provedor do Complexo Santa Casa de Sobral, Dom Jos\u00e9 Luiz Gomes de Vasconcelos. Por Henrique Brito \u201cDedico esta obra a todos os pacientes que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/padre-ze-lanca-livro-sobre-a-historia-da-santa-casa-de-sobral-4.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15292,"url":"https:\/\/correiodasemana.com\/site\/sobral-sobral-22\/","url_meta":{"origin":17819,"position":3},"title":"Sobral, Sobral","author":"","date":"Janeiro 10, 2021","format":false,"excerpt":"GENTILEZA \u00c9 O JEITO MAIS BONITO DE SER O SOL NO DIA NUBLADO E TRISTE DE ALGU\u00c9M !! (AN\u00d4NIMO) MINHAS HIST\u00d3RIAS\u2026 ACONTECEU EM SOBRAL (Por LUC\u00cdDIO CARNEIRO) WALDICK NO BAILE BRANCO DA DOZINHA!! Nos anos 1980 o BNB CLUBE de SOBRAL recebe WALDICK SORIANO para uma noite de gala (\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/02.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/02.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/02.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/02.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9342,"url":"https:\/\/correiodasemana.com\/site\/washington-luiz-e-o-nome-da-nova-aposta-do-guarany-de-sobral\/","url_meta":{"origin":17819,"position":4},"title":"Washington Luiz \u00e9 o nome da nova aposta do Guarany de Sobral","author":"","date":"Outubro 7, 2019","format":false,"excerpt":"O t\u00e9cnico j\u00e1 passou pelo Caucaia, Barbalha, Icasa e Guarani de Juazeiro. Atualmente, o Guarany disputa a Ta\u00e7a Fares Lopes, mas precisa de uma vit\u00f3ria no s\u00e1bado (05) para seguir em frente. Correio da Semana: Como voc\u00ea analisa a sua trajet\u00f3ria? Washington: Se avaliar \u00e9 muito dif\u00edcil, n\u00e3o \u00e9? Desde\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Washington-Luiz-768x432-750x375.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Washington-Luiz-768x432-750x375.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Washington-Luiz-768x432-750x375.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/Washington-Luiz-768x432-750x375.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15109,"url":"https:\/\/correiodasemana.com\/site\/sobral-sobral-20\/","url_meta":{"origin":17819,"position":5},"title":"Sobral, Sobral","author":"","date":"Dezembro 21, 2020","format":false,"excerpt":"ESTAR PERTO \u00c9 UMA QUEST\u00c3O GEOGR\u00c1FICA. ESTAR PR\u00d3XIMO \u00c9 UMA ESCOLHA !! (autor desconhecido) MINHAS HIST\u00d3RIAS\u2026 A PUREZA DO CENTROAVANTE CABE\u00c7\u00c3O Ele mora na avenida Desembargador Moreira da Rocha. Quase esquina com a Pericentral, onde corre o VLT em SOBRAL. Se algu\u00e9m perguntar pelo senhor RAIMUNDO SILVA FERREIRA, 79 anos,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-15.08.24.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-15.08.24.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-15.08.24.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-19-at-15.08.24.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17819"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17819\/revisions"}],"predecessor-version":[{"id":17823,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17819\/revisions\/17823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/15808"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}