{"id":17881,"date":"2021-10-31T23:50:00","date_gmt":"2021-11-01T02:50:00","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17881"},"modified":"2021-10-31T23:50:00","modified_gmt":"2021-11-01T02:50:00","slug":"bispos-do-regional-ne-i-reunem-se-para-aprofundar-e-encaminhar-as-atividades-pastorais","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/bispos-do-regional-ne-i-reunem-se-para-aprofundar-e-encaminhar-as-atividades-pastorais\/","title":{"rendered":"Bispos do Regional NE I re\u00fanem-se para aprofundar e encaminhar as atividades pastorais"},"content":{"rendered":"<p>Por Thais Helena (Portal de Comunica\u00e7\u00e3o \u2013 Diocese de Sobral)<br \/>\nCom o tema \u201cCelebrando a vida e a esperan\u00e7a\u201d, o Regional Nordeste I celebrou 40 anos de funda\u00e7\u00e3o. Para celebrar essa data o CONSER foi realizado presencialmente, obedecendo todas as regras estabelecidas pelos \u00f3rg\u00e3os sanit\u00e1rios, entre os dias 25 e 27 de outubro, na Casa de Retiro \u2013 Maria Aux\u00edlio dos Crist\u00e3os. O tema abordado foi: \u201cEnt\u00e3o, os disc\u00edpulos foram anunciar por toda parte\u201d. (Mc 16, 20), e o Lema: \u201cMiss\u00e3o: compromisso da vida e da f\u00e9!\u201d<br \/>\nO encontro houve motiva\u00e7\u00f5es como: espiritualidade, pain\u00e9is de mem\u00f3ria, celebra\u00e7\u00e3o eucar\u00edstica, apresenta\u00e7\u00e3o cultural com o cantor Z\u00e9 Vicente; e debate sobre as a\u00e7\u00f5es encaminhadas no \u00faltimo CONSER.<br \/>\nDe acordo com o site do Regional, O Regional NE 1 era composto pelos estados do Maranh\u00e3o, Piau\u00ed e Cear\u00e1, em 1980 e foi aprovado o desmembramento, com isso o Cear\u00e1 comp\u00f5e o regional, composto pela Arquidiocese de Fortaleza e as Dioceses de: Crato, Sobral, Limoeiro, Crate\u00fas, Quixad\u00e1, Tiangu\u00e1, Itapipoca e Iguatu. Celebrando esse momento foi realizado uma abordagem hist\u00f3rica por Pe. Marcelino Sivinski e tamb\u00e9m uma mesa redonda, composta por: Dom Jos\u00e9 Antonio, Arcebispo de Fortaleza; Dom Vasconcelos, Presidente do Regional; Pe. Ivan Sousa, Comiss\u00e3o de Liturgia; Pe. Lopes, COMIRE; Pe. Silvio Scopel, Comunidade Shalom; Regilv\u00e2nia Mateus, Pastorais Sociais; Erivan Silva, Catequese; Elza Braga, ex membro da Pastoral Urbana; e Elisian de Carvalho, subsecret\u00e1ria 1996-2000.<br \/>\n\u00c0s 18 horas do dia 27 de outubro, foi celebrada solenemente a Santa Missa, tendo como presidente da celebra\u00e7\u00e3o, Dom Vasconcelos e foi concelebrada pelos demais bispos e padres. Estavam presentes leigos e leigas das Comiss\u00f5es, Pastorais, Movimentos e Organismos. O coral da catedral de Quixad\u00e1 foram os respons\u00e1veis pelos c\u00e2nticos da celebra\u00e7\u00e3o.<br \/>\nE para finalizar as comemora\u00e7\u00f5es, ao final da celebra\u00e7\u00e3o houve o momento cultural com Z\u00e9 Vicente e foram apresentadas as a\u00e7\u00f5es encaminhadas pelo CONSER de novembro\/2020 e junho\/2021, sobre a Escola Regional e Plano de Comunica\u00e7\u00e3o, referentes ao Pilar da Palavra e do P\u00e3o.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-17875\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0040-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0040-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0040-1024x682.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0040-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0040.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-17874\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038-1024x682.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-17873\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0037-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0037-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0037-1024x682.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0037-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0037.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-17872\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/FB_IMG_1635469888182-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/FB_IMG_1635469888182-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/FB_IMG_1635469888182.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Thais Helena (Portal de Comunica\u00e7\u00e3o \u2013 Diocese de Sobral) Com o tema \u201cCelebrando a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-17881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/IMG-20211028-WA0038.jpg","jetpack-related-posts":[{"id":17893,"url":"https:\/\/correiodasemana.com\/site\/cnbb-nordeste-1-realiza-assembleia-do-conselho-episcopal-regional-conser-2021\/","url_meta":{"origin":17881,"position":0},"title":"CNBB NORDESTE 1 realiza assembleia do Conselho Episcopal Regional \u2013 CONSER 2021","author":"","date":"Outubro 31, 2021","format":false,"excerpt":"\u2022 Algumas fotos acima do ano de 1999: (In memoriam) Dom Aldo di Cillo\u00a0Pagotto, 4\u00ba bispo da Diocese Sobral; Monsenhor Jos\u00e9 Edison Magalh\u00e3es, por v\u00e1rios anos foi coordenador de Pastoral; Pe. Raimundo Cleano Tavares Moreira. Memoria saud\u00e1vel aos vivos que est\u00e3o entre os participantes da Diocese; Pe. Jo\u00e3o Batista Frota,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-21.46.34.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-21.46.34.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-21.46.34.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-28-at-21.46.34.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34094,"url":"https:\/\/correiodasemana.com\/site\/conser-reune-clerigos-e-leigos-em-fortaleza\/","url_meta":{"origin":17881,"position":1},"title":"CONSER re\u00fane cl\u00e9rigos e leigos em Fortaleza","author":"adminredacao","date":"Junho 9, 2025","format":false,"excerpt":"Os bispos das nove dioceses do Cear\u00e1, incluindo o arcebispo de Fortaleza, participaram do Conselho Episcopal Regional (CONSER), realizado na Casa de Retiro S\u00e3o Jos\u00e9, na capital cearense, nos dias 2 e 3 de junho. Dom Vasconcelos, vice-presidente do Regional Nordeste 1 e bispo da Diocese de Sobral, esteve presente\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-17.18.03-1-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":29555,"url":"https:\/\/correiodasemana.com\/site\/conselho-episcopal-regional-reune-bispos-do-ceara-em-fortaleza\/","url_meta":{"origin":17881,"position":2},"title":"Conselho Episcopal Regional re\u00fane bispos do Cear\u00e1 em Fortaleza","author":"adminredacao","date":"Junho 10, 2024","format":false,"excerpt":"De 3 a 5 de junho aconteceu o Conselho Episcopal Regional (CONSER) no Semin\u00e1rio de Teologia S\u00e3o Jos\u00e9 em Fortaleza. O encontro que reuniu os bispos do Cear\u00e1 \u00e9 o primeiro deste ano em curso. Com o tema: \u201cIgreja no Cear\u00e1, caminhando na esperan\u00e7a\u201d, e o lema: \u201cEnsina-nos a rezar\u201d.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-06-at-08.41.21.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-06-at-08.41.21.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-06-at-08.41.21.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-06-at-08.41.21.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-06-at-08.41.21.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20065,"url":"https:\/\/correiodasemana.com\/site\/reuniao-do-conser-pilar-da-caridade-e-a-principal-tematica-abordada\/","url_meta":{"origin":17881,"position":3},"title":"Reuni\u00e3o do CONSER: Pilar da Caridade \u00e9 a principal tem\u00e1tica abordada","author":"","date":"Junho 12, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Durante os dias 6, 7 e 8 de junho foi realizado em Fortaleza\/CE na casa de retiro das irm\u00e3s josefinas, o Conselho Episcopal Regional NE1 (CONSER). O tema abordado este ano foi: \u201cCaridade, a servi\u00e7o a vida plena\u201d, e o lema: \u201cViu, sentiu\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/conser-em-Fortaleza-5.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/conser-em-Fortaleza-5.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/conser-em-Fortaleza-5.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/conser-em-Fortaleza-5.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/conser-em-Fortaleza-5.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19962,"url":"https:\/\/correiodasemana.com\/site\/congresso-das-novas-comunidades-do-regional-ne-1-reuniu-diversos-dons-e-carismas-no-ultimo-fim-de-semana\/","url_meta":{"origin":17881,"position":4},"title":"Congresso das Novas Comunidades do Regional NE 1 reuniu diversos dons e carismas no \u00faltimo fim de semana","author":"","date":"Junho 6, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) A Sede da Comunidade Cat\u00f3lica Rainha da Paz, em Sobral, recebeu diversas comunidades pertencentes ao regional nordeste 1 e de outras regi\u00f5es para o I Congresso das Novas Comunidades. Foi um momento onde estiveram reunidos diversos dons e carismas. A Santa Missa de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220417207.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220417207.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220417207.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220417207.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24369,"url":"https:\/\/correiodasemana.com\/site\/cnbb-regional-ne-1-bispos-do-ceara-elegem-nova-presidencia-para-o-quadrienio-2023-2027\/","url_meta":{"origin":17881,"position":5},"title":"CNBB &#8211; Regional NE 1: Bispos do Cear\u00e1 elegem nova presid\u00eancia para o quadri\u00eanio 2023-2027","author":"adminredacao","date":"Maio 1, 2023","format":false,"excerpt":"O episcopado cearense elegeu na noite desta quinta-feira, 27\/04, durante a 60\u00aa Assembleia Geral da CNBB a nova presid\u00eancia para o quadri\u00eanio 2023-2027. A s\u00e9tima presid\u00eancia foi eleita de acordo com o regulamento do CONSER. O mandato da presid\u00eancia \u00e9 de quatro anos na qual \u00e9 realizado o acompanhamento para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/cnbb-regional-1-destaque.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/cnbb-regional-1-destaque.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/cnbb-regional-1-destaque.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/cnbb-regional-1-destaque.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17881"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17881\/revisions"}],"predecessor-version":[{"id":17882,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17881\/revisions\/17882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}