{"id":17909,"date":"2021-11-01T00:04:53","date_gmt":"2021-11-01T03:04:53","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17909"},"modified":"2021-11-01T00:04:53","modified_gmt":"2021-11-01T03:04:53","slug":"finados-e-dia-de-todos-os-santos-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/finados-e-dia-de-todos-os-santos-2\/","title":{"rendered":"FINADOS E DIA DE TODOS OS SANTOS"},"content":{"rendered":"<p>O m\u00eas de novembro se inicia com duas celebra\u00e7\u00f5es bem marcantes no calend\u00e1rio lit\u00fargico da Igreja: o dia de Finados e a Festa de Todos os Santos. Ambas nos fazem relembrar aqueles que nos precederam e que j\u00e1 conclu\u00edram a sua peregrina\u00e7\u00e3o neste plano terrestre da vida. Entendemos, assim, que h\u00e1 uma profunda comunh\u00e3o entre a Igreja do c\u00e9u e da terra.<br \/>\nA cada 2 de novembro, quando muitas pessoas visitam os cemit\u00e9rios, rezamos por todos os fi\u00e9is defuntos, particularmente pelos nossos entes queridos que j\u00e1 est\u00e3o junto de Deus. Fazemos mem\u00f3ria de nossos antepassados, parentes e amigos, que nos precederam e nos transmitiram a f\u00e9. N\u00e3o como uma celebra\u00e7\u00e3o da morte, mas sim celebrando a esperan\u00e7a na vida eterna.<br \/>\nDe fato, quando pensamos assim, a nossa condi\u00e7\u00e3o de finitude e o mist\u00e9rio da morte ganham um outro sentido, pois n\u00f3s cremos e professamos que existe uma vida eterna para al\u00e9m deste mundo temporal. Por isso, \u00e9 um pensamento santo e salutar venerar com piedade a mem\u00f3ria dos defuntos e rezar pelas suas almas.<br \/>\nNossa ora\u00e7\u00e3o por eles pode n\u00e3o somente ajud\u00e1-los, mas tamb\u00e9m tornar eficaz sua intercess\u00e3o por n\u00f3s. S\u00e3o Domingos de Gusm\u00e3o, em seu leito de morte, disse aos seus irm\u00e3os: \u201cN\u00e3o choreis! Ser-vos-ei mais \u00fatil ap\u00f3s a minha morte e ajudar-vos-ei mais eficazmente do que durante a minha vida.\u201d<br \/>\nDentre estes que j\u00e1 partiram, muitos deles, a Igreja nos aponta como modelos de crist\u00e3os. S\u00e3o aqueles que n\u00f3s chamamos de santos. Eles comp\u00f5em uma multid\u00e3o incont\u00e1vel de homens e mulheres que se decidiram seguir Jesus de um modo fiel e radical, e fizeram do amor a maior lei de seus cora\u00e7\u00f5es.<br \/>\nN\u00f3s tamb\u00e9m cremos e professamos a nossa comunh\u00e3o com os santos, e celebramos todos em \u00fanico dia como uma recorda\u00e7\u00e3o da nossa voca\u00e7\u00e3o \u00e0 santidade. Certa vez, Santo In\u00e1cio de Loyola, ao terminar de ler um livro sobre a vida dos santos, fez-se o seguinte questionamento: \u201cSe eles conseguiram, por que tamb\u00e9m eu n\u00e3o posso conseguir ser santo?\u201d. E, a partir disso, ele foi moldando sua vida \u00e0 pr\u00e1tica do Evangelho.<br \/>\nIsso quer dizer que n\u00e3o se nasce santo. Al\u00e9m disso, os santos n\u00e3o s\u00e3o pessoas privilegiadas, com feitos extraordin\u00e1rios, mas a santidade \u00e9 uma constru\u00e7\u00e3o di\u00e1ria, um processo de convers\u00e3o que se d\u00e1 na busca de encarnar o Evangelho na pr\u00f3pria vida, na simplicidade do cotidiano. E n\u00e3o foram poucos os que trilharam esse caminho: homens e mulheres, sacerdotes e religiosos, jovens e crian\u00e7as, oper\u00e1rios, militares, pais e m\u00e3es de fam\u00edlia que, ao longo dos s\u00e9culos, forma canonizados. S\u00e3o os nossos \u201cher\u00f3is\u201d da f\u00e9.<br \/>\nAl\u00e9m disso, os santos s\u00e3o s\u00f3lidas refer\u00eancias para o nosso agir moral e marcaram profundamente o ontem e o hoje da Igreja. Neste mundo escurecido pelo pecado, devemos olhar para o alto e contemplar esses luzeiros que brilham no firmamento como uma bela e reluzente constela\u00e7\u00e3o.<br \/>\nQue a Igreja triunfante do c\u00e9u esteja sempre a rogar pela Igreja militante sobre a terra!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00eas de novembro se inicia com duas celebra\u00e7\u00f5es bem marcantes no calend\u00e1rio lit\u00fargico da&#8230;<\/p>\n","protected":false},"author":1,"featured_media":75,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,20],"tags":[],"class_list":["post-17909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg","jetpack-related-posts":[{"id":9731,"url":"https:\/\/correiodasemana.com\/site\/finados-e-dia-de-todos-os-santos\/","url_meta":{"origin":17909,"position":0},"title":"Finados e Dia de Todos os Santos","author":"","date":"Novembro 4, 2019","format":false,"excerpt":"O m\u00eas de novembro se inicia com duas celebra\u00e7\u00f5es bem marcantes no calend\u00e1rio lit\u00fargico da Igreja: o dia de Finados e a Festa de Todos os Santos. Ambas nos fazem relembrar aqueles que nos precederam e que j\u00e1 conclu\u00edram a sua peregrina\u00e7\u00e3o neste plano terrestre da vida. Entendemos, assim, que\u2026","rel":"","context":"In &quot;Editorial&quot;","block_context":{"text":"Editorial","link":"https:\/\/correiodasemana.com\/site\/category\/editorial\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27108,"url":"https:\/\/correiodasemana.com\/site\/finados-e-dia-de-todos-os-santos-3\/","url_meta":{"origin":17909,"position":1},"title":"Finados e Dia de Todos os Santos","author":"adminredacao","date":"Novembro 6, 2023","format":false,"excerpt":"O m\u00eas de novembro inicia-se com duas celebra\u00e7\u00f5es bem marcantes no calend\u00e1rio lit\u00fargico da Igreja: o dia de Finados e a Festa de Todos os Santos. Ambas nos fazem relembrar aqueles que nos precederam e que j\u00e1 conclu\u00edram a sua peregrina\u00e7\u00e3o neste plano terrestre da vida. Entendemos, assim, que h\u00e1\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9726,"url":"https:\/\/correiodasemana.com\/site\/finados\/","url_meta":{"origin":17909,"position":2},"title":"FINADOS","author":"","date":"Novembro 4, 2019","format":false,"excerpt":"O quarto Pr\u00edncipe dos Poetas Cearenses, Artur Eduardo Benevides, disse em poema que, \u201cem poesia, o que n\u00e3o for saudade \u00e9 liturgia\u201d. A data religiosa e c\u00edvica que se vivencia neste s\u00e1bado, une saudade e liturgia, posto que todos temos algu\u00e9m que j\u00e1 faleceu e de quem sentimos saudades e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31334,"url":"https:\/\/correiodasemana.com\/site\/no-inicio-de-novembro-celebracoes-de-finados-e-todos-os-santos-apontam-para-a-eternidade-e-o-chamado-a-santidade\/","url_meta":{"origin":17909,"position":3},"title":"No in\u00edcio de novembro, celebra\u00e7\u00f5es de Finados e Todos os Santos apontam para a eternidade e o chamado \u00e0 santidade","author":"adminredacao","date":"Novembro 3, 2024","format":false,"excerpt":"A Igreja inicia o m\u00eas de novembro com duas grandes celebra\u00e7\u00f5es, no primeiro final de semana. No s\u00e1bado, 2, a Comemora\u00e7\u00e3o dos Fi\u00e9is Defuntos e, no domingo, dia 3, a Solenidade de Todos os Santos. Essas duas celebra\u00e7\u00f5es apontam para a eternidade e para o chamado universal \u00e0 santidade. Fi\u00e9is\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Dom-Jose-Luiz-Gomes-Vasconcelos-bispo-diocesano-de-Sobral.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Dom-Jose-Luiz-Gomes-Vasconcelos-bispo-diocesano-de-Sobral.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Dom-Jose-Luiz-Gomes-Vasconcelos-bispo-diocesano-de-Sobral.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Dom-Jose-Luiz-Gomes-Vasconcelos-bispo-diocesano-de-Sobral.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/Dom-Jose-Luiz-Gomes-Vasconcelos-bispo-diocesano-de-Sobral.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21639,"url":"https:\/\/correiodasemana.com\/site\/na-solenidade-de-todos-os-santos-dom-vasconcelos-reitera-a-importancia-em-abrir-o-coracao-para-deus\/","url_meta":{"origin":17909,"position":4},"title":"Na Solenidade de todos os Santos, Dom Vasconcelos reitera a import\u00e2ncia em abrir o cora\u00e7\u00e3o para Deus","author":"","date":"Novembro 13, 2022","format":false,"excerpt":"A solene celebra\u00e7\u00e3o eucar\u00edstica que faz mem\u00f3ria a vida e santidade de todos os santos foi celebrada no \u00faltimo domingo (06\/11) por Dom Vasconcelos na majestosa Catedral da S\u00e9. O dia de todos os Santos \u00e9 celebrado no dia primeiro de novembro, mas \u00e9 transferida para o domingo seguinte, a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/diocese-mestres.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/diocese-mestres.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/diocese-mestres.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/diocese-mestres.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/diocese-mestres.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24757,"url":"https:\/\/correiodasemana.com\/site\/a-festa-da-ascensao-2\/","url_meta":{"origin":17909,"position":5},"title":"A festa da Ascens\u00e3o","author":"adminredacao","date":"Maio 21, 2023","format":false,"excerpt":"Neste domingo, o s\u00e9timo da P\u00e1scoa, a Igreja celebra a festa da Ascens\u00e3o do Senhor. 40 dias ap\u00f3s a Ressurrei\u00e7\u00e3o, Jesus \u00e9 elevado ao c\u00e9u e nos deixa a garantia da presen\u00e7a do Esp\u00edrito Santo, que doravante conduziria os passos da Igreja e de todos os disc\u00edpulos. Conclui-se, assim, a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17909"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17909\/revisions"}],"predecessor-version":[{"id":17910,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17909\/revisions\/17910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}