{"id":17927,"date":"2021-11-07T23:31:44","date_gmt":"2021-11-08T02:31:44","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17927"},"modified":"2021-11-07T23:31:44","modified_gmt":"2021-11-08T02:31:44","slug":"no-ceara-mortes-por-covid-19-caem-85-no-mes-de-outubro-em-comparacao-ao-ano-passado","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/no-ceara-mortes-por-covid-19-caem-85-no-mes-de-outubro-em-comparacao-ao-ano-passado\/","title":{"rendered":"No Cear\u00e1 mortes por Covid-19 caem 85% no m\u00eas de Outubro em compara\u00e7\u00e3o ao ano passado"},"content":{"rendered":"<p>Por Samuel Carvalho<br \/>\nReda\u00e7\u00e3o Correio da Semana<br \/>\nO n\u00famero de mortes por Covid-19 regritradas no m\u00eas de outubro deste ano \u00e9 85% inferior em rela\u00e7\u00e3o ao mesmo m\u00eas de 2020, segundo os dados apurados na \u00faltima segunda-feira (01) pelo IntegraSUS, plataforma da Secret\u00e1ria de Sa\u00fade do Cear\u00e1 (Sesa). Em rela\u00e7\u00e3o a setembro deste ano, a marca de outubro de 2021 tamb\u00e9m apresentou uma queda, passando de 93 para 52 registros. Os casos mais recentes, no entanto, podem ainda n\u00e3o ter entrado no sistema devido ao atraso nas notifica\u00e7\u00f5es.<br \/>\nQuanto ao n\u00famero de casos de infec\u00e7\u00e3o por covid-19 confirmados no Cear\u00e1, tamb\u00e9m \u00e9 percept\u00edvel uma redu\u00e7\u00e3o ao longo dos \u00faltimos meses. O pico de registros neste ano aconteceu em abril, com mais de 136 mil mortes, e em outubro essa estat\u00edstica atingiu 2,4 mil \u00f3bitos. Segundo os \u00faltimos regristro do boletim epidemiol\u00f3gico publicado pela Sesa, no dia 18 de outubro, a pasta apontou redu\u00e7\u00e3o de 29% no n\u00famero de casos confirmados e 45% dos \u00f3bitos em decorr\u00eancia da crise na sa\u00fade.<br \/>\nOs indicadores rela\u00e7\u00e3o \u00e0 ocupa\u00e7\u00e3o da rede hospitalar tamb\u00e9m apresentam sinais de melhora em rela\u00e7\u00e3o ao mesmo per\u00edodo. No \u00faltimo domingo (31) eram 183 leitos de Unidade de Terapia Intensiva (UTI) ativos, com 40,44% de ocupa\u00e7\u00e3o, em compra\u00e7\u00e3o ao in\u00edcio de setembro onde o n\u00famero de equipamentos ativos superou 300 e a ocupa\u00e7\u00e3o tamb\u00e9m se aproximava de 40%. Nas enfermarias, tamb\u00e9m h\u00e1 um quadro parecido onde a quantidade de leitos ativos no fim de outubro era quase a metade do registrado no in\u00edcio de setembro \u2014 caindo de 844 para 423.<br \/>\nDesde o in\u00edcio da pandemia, 24.497 cearenses morreram e 943.675 foram infectados em decorr\u00eancia da Covid-19, conforme dados consolidados \u00e0s 13h01min desta segunda-feira, 1\u00ba, pela Secretaria de Sa\u00fade do Estado. Em rela\u00e7\u00e3o ao avan\u00e7o da vacina\u00e7\u00e3o, j\u00e1 s\u00e3o 4.885.843 pessoas que completaram o ciclo vacinal, com as duas doses ou dose \u00fanica da vacina contra a Covid-19 \u2014 o n\u00famero representa 52% da popula\u00e7\u00e3o do Cear\u00e1, segundo proje\u00e7\u00e3o para 2021 do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Com pelo menos uma das doses, 71% dos cearenses est\u00e3o imunizados contra a doen\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O n\u00famero de mortes por Covid-19 regritradas no&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-17927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg","jetpack-related-posts":[{"id":18598,"url":"https:\/\/correiodasemana.com\/site\/mais-de-5-mil-casos-de-covid-19-sao-confirmados-no-ceara-em-2022-sobral-ja-registra-2-obitos-para-a-doenca\/","url_meta":{"origin":17927,"position":0},"title":"Mais de 5 mil casos de Covid-19 s\u00e3o confirmados no Cear\u00e1 em 2022; Sobral j\u00e1 registra 2 \u00f3bitos para a doen\u00e7a","author":"","date":"Janeiro 16, 2022","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo com dados da plataforma IntegraSUS, de 1\u00ba a 11 de janeiro de 2022, 5.263 cearenses tiveram diagn\u00f3stico confirmado para Covid-19. A plataforma foi atualizada \u00e0s 10h36 desta quinta-feira, 13. Ainda de acordo com a plataforma, Sobral est\u00e1 entre as cinco cidades com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/000-1r0382-easy-resize.com_.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16235,"url":"https:\/\/correiodasemana.com\/site\/quase-metade-dos-obitos-registrados-em-marco-foi-causada-por-covid-19\/","url_meta":{"origin":17927,"position":1},"title":"Quase metade dos \u00f3bitos registrados em Mar\u00e7o foi causada por covid-19","author":"","date":"Abril 18, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana Segundo a notifica\u00e7\u00e3o dos Cart\u00f3rios de Registro Civil cearenses no \u00faltimo m\u00eas, 6.930 \u00f3bitos por causas naturais (doen\u00e7as respirat\u00f3rias e card\u00edacas), dos quais 3.202 decorreram da infec\u00e7\u00e3o causada pelo novo coronav\u00edrus. Esse n\u00famero \u00e9 equivalente a 46% do total do n\u00famero de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/internac-o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/internac-o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/internac-o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/internac-o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/internac-o.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":11537,"url":"https:\/\/correiodasemana.com\/site\/brasil-registra-1-022-mortes-por-covid-19-e-se-aproxima-de-50-mil-obitos\/","url_meta":{"origin":17927,"position":2},"title":"Brasil registra 1.022 mortes por Covid-19 e se aproxima de 50 mil \u00f3bitos","author":"","date":"Junho 21, 2020","format":false,"excerpt":"O Brasil registrou neste s\u00e1bado 1.022 mortes por Covid-19 e se aproximou dos 50 mil \u00f3bitos pelo v\u00edrus \u2014alcan\u00e7ou exatamente 49.976 nas \u00faltimas 24 horas, segundo dados do Minist\u00e9rio da Sa\u00fade. O pa\u00eds chegou a 1.067.579 casos confirmados, registrando o terceiro maior \u00edndice di\u00e1rio de novos casos do coronav\u00edrus, com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/recuperados-coronavirus-minas-gerais.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/recuperados-coronavirus-minas-gerais.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/recuperados-coronavirus-minas-gerais.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/recuperados-coronavirus-minas-gerais.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14773,"url":"https:\/\/correiodasemana.com\/site\/taxa-de-transmissao-da-covid-19-no-pais-e-a-maior-desde-maio-sobral-passa-de-doze-mil-curados\/","url_meta":{"origin":17927,"position":3},"title":"Taxa de transmiss\u00e3o da Covid-19 no pa\u00eds \u00e9 a maior desde maio; Sobral passa de doze mil curados","author":"","date":"Novembro 30, 2020","format":false,"excerpt":"Por Joc\u00e9lio Tavares. A taxa de transmiss\u00e3o do novo coronav\u00edrus voltou a subir no Brasil e j\u00e1 \u00e9 a maior desde maio, de acordo com os dados divulgados nesta ter\u00e7a-feira (24) pelo Centro de Controle de Epidemias do Imperial College, de Londres. A taxa passou de 1,10 no \u00faltimo balan\u00e7o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/covid-em-sobral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16939,"url":"https:\/\/correiodasemana.com\/site\/ceara-registra-queda-de-93-em-casos-de-obitos-por-covid-19-em-um-mes\/","url_meta":{"origin":17927,"position":4},"title":"Cear\u00e1 registra queda de 93% em casos de \u00f3bitos por covid-19 em um m\u00eas","author":"","date":"Julho 12, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana O Cear\u00e1 registrou uma queda de 93,3% nas mortes di\u00e1rias por Covid-19 entre os dias 6 de junho e 6 de julho de 2021. Foram contabilizados 60 \u00f3bitos por coronav\u00edrus h\u00e1 um m\u00eas, enquanto quatro falecimentos foram anotados nesta ter\u00e7a-feira (6). Apesar\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/covid-19.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":21746,"url":"https:\/\/correiodasemana.com\/site\/fiocruz-identifica-nova-variante-da-omicron-no-amazonas\/","url_meta":{"origin":17927,"position":5},"title":"Fiocruz identifica nova variante da \u00f4micron no Amazonas","author":"","date":"Novembro 21, 2022","format":false,"excerpt":"Estudo para determinar causas da explos\u00e3o de novos casos no Amazonas revela variante da \u00f4micron denominada BE.9. Por enquanto n\u00e3o h\u00e1 aumento relevante de hospitaliza\u00e7\u00f5es ou mortes. Um grupo de cientistas da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) identificou o surgimento de uma nova variante do coronav\u00edrus no estado do Amazonas. Trata-se\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/0303-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/0303-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/0303-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/0303-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17927"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17927\/revisions"}],"predecessor-version":[{"id":17928,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17927\/revisions\/17928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/16940"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}