{"id":17999,"date":"2021-11-14T23:01:23","date_gmt":"2021-11-15T02:01:23","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=17999"},"modified":"2021-11-14T23:02:31","modified_gmt":"2021-11-15T02:02:31","slug":"de-olho-na-lingua-37","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-37\/","title":{"rendered":"De Olho na L\u00edngua"},"content":{"rendered":"<p>MEDICAMENTO E REM\u00c9DIO S\u00c3O A MESMA COISA?<br \/>\nN\u00e3o. Medicamento\u00a0\u00e9 qualquer droga ou subst\u00e2ncia aplicada em algu\u00e9m como rem\u00e9dio.<br \/>\nRem\u00e9dio\u00a0\u00e9 tudo o que serve para aliviar ou curar um mal. Uma boa massagem \u00e9 um rem\u00e9dio para o desgaste f\u00edsico, assim como um banho, depois de uma longa ou dura jornada de trabalho. Observe que todo medicamento \u00e9 rem\u00e9dio, mas nem todo rem\u00e9dio \u00e9 medicamento.<\/p>\n<p>O MORAL \/ A MORAL (DIFEREN\u00c7A)<br \/>\n\u00c9 muito frequente a confus\u00e3o entre\u00a0o moral\u00a0(substantivo masculino), que significa \u00e2nimo disposi\u00e7\u00e3o, firmeza, e\u00a0a moral\u00a0(substantivo feminino) significando conjunto de preceitos de conduta considerada digna. Ex.: Uma vit\u00f3ria no campo do advers\u00e1rio deixa os jogadores com o moral elevado; A moral crist\u00e3; Moral ilibada; Qual a moral da hist\u00f3ria?<\/p>\n<p>\u00c0 FAM\u00cdLIA ENLUTADA, OS NOSSO SENTIDOS P\u00caSAMES<br \/>\n\u201cSentidos p\u00easames\u201d \u00e9 coisa de \u201cdoente mental\u201d. Na palavra p\u00easames j\u00e1 existe a ideia de sentidos, doloridos, etc. Trata-se, portanto, de redund\u00e2ncia clara.<\/p>\n<p>VIM, VIR, VIER OU VER<br \/>\n\u00c9 comum fazer confus\u00e3o e ouvir esta frase: \u201cSe ela n\u00e3o vim vai ser demitida. E se tu v\u00ea ela por a\u00ed, pode avisar\u201d.<\/p>\n<p>Em primeiro lugar, vamos analisar o \u201cSe ela n\u00e3o vim\u201d. A frase est\u00e1 exigindo o futuro do subjuntivo do verbo VIR. Deveria ser: \u201cSe ela n\u00e3o vier, vai ser demitida\u201d. \u00c9 importante lembrar que a forma \u201cvim\u201d vem sendo muito mal empregada. E a primeira pessoa do pret\u00e9rito perfeito do indicativo (Eu vim, tu vieste, ele veio, n\u00f3s viemos, v\u00f3s viestes, ele vieram): Ontem eu n\u00e3o vim trabalhar.<\/p>\n<p>Outro erro frequente \u00e9 o famoso \u201cEu vou vim\u201d.<\/p>\n<p>Para quem n\u00e3o entendeu, esse erro ocorre quando o falante quer dizer \u201cEu vou vir\u201d. Nesse caso, confunde-se o infinitivo (vir) com o pret\u00e9rito perfeito do indicativo (vim). O melhor mesmo seria dizer \u201cEu irei\u201d (= Futuro do presente do indicativo do verbo vir).<\/p>\n<p>Quanto ao verbo VER, o erro mais frequente ocorre no futuro do subjuntivo: Se eu vir, se tu vires, se ele vir, se n\u00f3s virmos, se v\u00f3s virdes, se eles virem. Portanto, na frase \u201cSe tu v\u00ea ela\u201d temos dois erros: Primeiro, o verbo VER deveria estar no futuro do subjuntivo, concordando com o sujeito (Tu): Se tu vires&#8230; Tamb\u00e9m est\u00e1 correto: Se voc\u00ea vir (= Na terceira pessoa).<\/p>\n<p>Segundo, o problema pessoal reto (ela) deveria ser substitu\u00eddo pelo pronome obl\u00edquo, porque se trata de objeto direto: \u201cSe tu a vires\u201d ou \u201cSe voc\u00ea a vir\u201d. O que nos cabe, como seres inteligentes que somos, \u00e9 adequar a linguagem. Em situa\u00e7\u00f5es informais, geralmente usamos um registro popular \u2013 coloquial, que n\u00e3o se caracteriza pelo respeito total \u00e0s normas da gram\u00e1tica.<\/p>\n<p>(*) Professor Ant\u00f4nio da Costa \u00e9 graduado em Letras Plenas, com Especializa\u00e7\u00e3o em L\u00edngua Portuguesa e Literatura, na Universidade Estadual Vale do Acara\u00fa (UVA). Aposentado, escreve esta Coluna todo s\u00e1bado no Jornal Correio da Semana e Blog Artem\u00edsio da Costa. Contatos: (088) 99868-2517.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEDICAMENTO E REM\u00c9DIO S\u00c3O A MESMA COISA? N\u00e3o. Medicamento\u00a0\u00e9 qualquer droga ou subst\u00e2ncia aplicada em&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,12],"tags":[],"class_list":["post-17999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-de-olho-na-lingua"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg","jetpack-related-posts":[{"id":37091,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-147\/","url_meta":{"origin":17999,"position":0},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Janeiro 17, 2026","format":false,"excerpt":"Que curiosidade traz a palavra aula? A palavra aula significava antigamente pal\u00e1cio, corte, assim como \u00e1ulico, ainda hoje, significa cortes\u00e3o, palaciano. Como veio a tomar o sentido que hoje possui, qual seja o de li\u00e7\u00e3o de uma disciplina? \u00c9 que antigamente os filhos dos nobres eram educados nos pal\u00e1cios, nas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26858,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-68\/","url_meta":{"origin":17999,"position":1},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Outubro 17, 2023","format":false,"excerpt":"Meio e meia Meio, quando adv\u00e9rbio, significa \u201cum pouco\u201d, \u201cum tanto\u201d, \u2018quase\u201d, \u201cmais ou menos\u201d. Por isso, \u00e9 invari\u00e1vel. Esta \u00e9 a raz\u00e3o pela qual se deve dizer: Maria est\u00e1 meio cansada. Isto \u00e9: Maria est\u00e1 um tanto, um pouco, mais ou menos cansada. Quando, por\u00e9m, meio \u00e9 adjetivo, com\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24511,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-51\/","url_meta":{"origin":17999,"position":2},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"De Olho na L\u00edngua Prof. Ant\u00f4nio da Costa Reverter o quadro A frase em ep\u00edgrafe est\u00e1 na moda. M\u00e9dicos, economistas, tecnocratas de todas as \u00e1reas e principalmente cronistas esportivos est\u00e3o a inventar uma l\u00edngua pr\u00f3pria: A asinina. Entre tantas asnices que se notam em linguagem desses profissionais, salienta-se o emprego\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":18356,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-41\/","url_meta":{"origin":17999,"position":3},"title":"De Olho na L\u00edngua","author":"","date":"Dezembro 20, 2021","format":false,"excerpt":"Posso dizer que os jogadores se\u00a0confraternizam\u00a0ap\u00f3s o final da partida N\u00e3o. O verbo \u00e9 simplesmente\u00a0confraternizar. E n\u00e3o:\u00a0confraternizar-se. Por isso use sempre: Os jogadores confraternizaram ap\u00f3s o final da partida. No Natal ou no dia 31 de dezembro \u00e9 comum as pessoas confraternizarem. Afinal, a grafia correta do nome \u00e9\u00a0Luiz\u00a0ou\u00a0Lu\u00eds? Lu\u00eds.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":29850,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-92\/","url_meta":{"origin":17999,"position":4},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Julho 8, 2024","format":false,"excerpt":"Eu disse \u201cde que\u201d este jogo seria dif\u00edcil!? N\u00e3o; Nada disso; Dif\u00edcil, e muito, \u00e9 de ouvi asneiras desse jaez. E quem gosta de esportes est\u00e1 fadado, inevitavelmente, a ouvir muito esse tipo de absurdo. Alguns radialistas esportivos costumam usar \u201cde que\u201d com qualquer verbo: transitivo direto, transitivo indireto, intransitivo,\u2026","rel":"","context":"In &quot;De olho na l\u00edngua&quot;","block_context":{"text":"De olho na l\u00edngua","link":"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":35141,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-132\/","url_meta":{"origin":17999,"position":5},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Agosto 17, 2025","format":false,"excerpt":"\u201cEM P\u00c9\u201d OU \u201cDE P\u00c9\u201d \u201cH\u00e1 dias, em uma cerim\u00f4nia lit\u00fargica, ao dizer a frase \u2018fiquemos todos de p\u00e9 para a aclama\u00e7\u00e3o ao Santo Evangelho\u2019, fui contestada por algu\u00e9m que me disse que o certo \u00e9 \u2018fiquemos todo em p\u00e9...\u2019 Quem, ent\u00e3o, est\u00e1 com a raz\u00e3o?\u201d, perguntou-me uma leitora desta\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=17999"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17999\/revisions"}],"predecessor-version":[{"id":18000,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/17999\/revisions\/18000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17923"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=17999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=17999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=17999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}