{"id":18184,"date":"2021-11-28T21:28:27","date_gmt":"2021-11-29T00:28:27","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18184"},"modified":"2021-11-28T21:28:27","modified_gmt":"2021-11-29T00:28:27","slug":"diocese-de-itapipoca-celebra-jubileu-de-ouro-pelos-50-anos-de-criacao","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/diocese-de-itapipoca-celebra-jubileu-de-ouro-pelos-50-anos-de-criacao\/","title":{"rendered":"Diocese de Itapipoca celebra Jubileu de Ouro pelos 50 anos de cria\u00e7\u00e3o"},"content":{"rendered":"<p>Por Thais Helena<br \/>\nReda\u00e7\u00e3o Jornal Correio da Semana<\/p>\n<p>No dia 21 de novembro, \u00faltimo dia do ano lit\u00fargico, tamb\u00e9m dia em que a Igreja celebrou solenemente o Dia de Cristo Rei do Universo, a Diocese de Itapipoca festejou com j\u00fabilo 50 anos de cria\u00e7\u00e3o. A grande festa foi marcada por um tr\u00edduo celebrativo por todas as par\u00f3quias, em prepara\u00e7\u00e3o ao Jubileu de Ouro. No dia festivo, todos os bispos que fazem parte do Regional Nordeste 1 fizeram-se presente para celebrar este momento, os que n\u00e3o puderam enviaram seus respectivos representantes.<br \/>\nDe acordo com o site Wikip\u00e9dia, a Diocese de Itapipoca \u00e9 uma\u00a0circunscri\u00e7\u00e3o eclesi\u00e1stica\u00a0da\u00a0Igreja Cat\u00f3lica\u00a0no estado do\u00a0Cear\u00e1, foi criada em 21 de novembro de 1971. \u00c9 sufrag\u00e2nea da\u00a0Arquidiocese de Fortaleza. Est\u00e1 situada no norte do Estado do Cear\u00e1, fazendo limites com as seguintes circunscri\u00e7\u00f5es eclesi\u00e1sticas: Arquidiocese de Fortaleza e a Diocese de Sobral, abrangendo os seguintes munic\u00edpios ou distritos:\u00a0Itapipoca,\u00a0Itapaj\u00e9,\u00a0Trairi,\u00a0Amontada,\u00a0Itarema,\u00a0Pentecoste,\u00a0Uruburetama,\u00a0Tururu,\u00a0Umirim,\u00a0Paraipaba,\u00a0Mira\u00edma,\u00a0Paracuru,\u00a0Irau\u00e7uba,\u00a0Teju\u00e7uoca,\u00a0S\u00e3o Lu\u00eds do Curu,\u00a0Icara\u00ed de Amontada,\u00a0Apuiar\u00e9s,\u00a0Munda\u00fa,\u00a0Juritianha\u00a0e\u00a0General Sampaio.<br \/>\nNo dia festivo, houve o ter\u00e7o mission\u00e1rio, organizado pelo COMIDI (Conselho Mission\u00e1rio Diocesano), al\u00e9m de anima\u00e7\u00e3o na pra\u00e7a da Catedral de Itapipoca com a banda de m\u00fasica local. O Bispo Diocesano de Sobral e Presidente do Regional NE1, Dom Vasconcelos, esteve presente e manifestou a sua alegria por estar presente neste momento importante e festivo para a Diocese de Itapipoca. Cumprimentou os bispos que estiveram presente, sacerdotes, autoridades civis e judiciais, e todo o povo de Deus. E disse: \u201cComo \u00e9 bom estarmos aqui nesta terra dos tr\u00eas climas dedicada \u00e0 Nossa Senhora das Merc\u00eas para celebrar o Jubileu de Ouro da Diocese de Itapipoca, inteiramente voltada desde a sua origem ao servi\u00e7o do reino, cujo rei, Senhor do universo n\u00f3s celebramos em comunh\u00e3o com toda a igreja nesta data solene. Completou: \u201cO Jubileu serve primeiramente para tocar a trombeta em a\u00e7\u00e3o de gra\u00e7as por tudo o que Deus realizou na vida desta por\u00e7\u00e3o do povo de Deus, por sua presen\u00e7a vivificante e santificadora por sermos por ele criados e chamados para no seu filho sermos membros de sua fam\u00edlia pela a\u00e7\u00e3o do esp\u00edrito santo. Em segundo lugar, para oferecer a Deus o sacrif\u00edcio das vidas doadas, dos pastores, religiosos e religiosas, mission\u00e1rios, leigos e leigas que se ofereceram como h\u00f3stias vivas para que esta igreja particular se tornasse ao longo destes 50 anos essa igreja viva, f\u00e9rtil, rede de comunidades. Escola de espiritualidade, centralizada na divina eucaristia. Casa de instru\u00e7\u00e3o e exerc\u00edcio da viv\u00eancia da palavra de Deus que tanto preza e ama. Igreja samaritana, comprometida com a causa da vida, especialmente com a vida plena dos mais pobres e abandonados. Igreja aberta para acolher os exclu\u00eddos para dar-lhes dignidade de filhos e filhas de Deus; igreja mission\u00e1ria, portadora do an\u00fancio do reino, reino eterno e universal, reino da verdade e da vida, reino da santidade e da gra\u00e7a, reino da justi\u00e7a, do amor e da gra\u00e7a como proclama o pref\u00e1cio da liturgia de hoje. Finalmente o jubileu serve para revigorar as energias neste ano sab\u00e1tico porque grandes desafios nos esperam e temos um longo caminho a percorrer. Sempre fortalecidos pelo p\u00e3o vivo descido do c\u00e9u, e sob a prote\u00e7\u00e3o da Sant\u00edssima Virgem Maria, Nossa Senhora das Merc\u00eas que nunca nos abandonar\u00e1\u201d. E finalizou o seu discurso parabenizando a Diocese e aben\u00e7oou todo os diocesanos.<br \/>\nEm seguida, houve a Celebra\u00e7\u00e3o Solene presidida por Dom Rosalvo Cordeiro de Lima, bispo diocesano de Itapipoca e concelebrada pelos demais bispos presentes.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-18189\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-300x210.jpeg\" alt=\"\" width=\"300\" height=\"210\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-300x210.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-18188\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.11-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.11-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.11.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-18187\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-2-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-2-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-2.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-18186\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-1-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-1.jpeg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-18185\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-3-204x300.jpeg\" alt=\"\" width=\"204\" height=\"300\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-3-204x300.jpeg 204w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-3-696x1024.jpeg 696w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-3.jpeg 720w\" sizes=\"(max-width: 204px) 100vw, 204px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Thais Helena Reda\u00e7\u00e3o Jornal Correio da Semana No dia 21 de novembro, \u00faltimo dia&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-18184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-25-at-08.43.10-3.jpeg","jetpack-related-posts":[{"id":17355,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-preside-missa-de-conclusao-do-ano-jubilar-na-diocese-de-tiangua-ce\/","url_meta":{"origin":18184,"position":0},"title":"Dom Vasconcelos preside missa de conclus\u00e3o do Ano Jubilar na Diocese de Tiangu\u00e1-CE","author":"","date":"Agosto 30, 2021","format":false,"excerpt":"Por Thais Helena - Colaboradora No \u00faltimo domingo, 22 de agosto, a Diocese de Tiangu\u00e1 celebrou 50 anos de exist\u00eancia, mais precisamente, o Jubileu de Ouro. O Bispo Diocesano e Presidente do Regional Nordeste 1, Dom Jos\u00e9 Luiz Gomes de Vasconcelos presidiu \u00e0 Solenidade de Conclus\u00e3o do Ano Jubilar. Estiveram\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/240444718_4352288464838330_2384680404297278745_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/240444718_4352288464838330_2384680404297278745_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/240444718_4352288464838330_2384680404297278745_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/240444718_4352288464838330_2384680404297278745_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20794,"url":"https:\/\/correiodasemana.com\/site\/pastoral-carceraria-celebra-jubileu-de-ouro-pelos-50-anos-de-criacao-no-brasil\/","url_meta":{"origin":18184,"position":1},"title":"Pastoral Carcer\u00e1ria celebra Jubileu de Ouro pelos 50 anos de cria\u00e7\u00e3o no Brasil","author":"","date":"Agosto 29, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) A pastoral carcer\u00e1ria da Diocese de Sobral celebrou no \u00faltimo domingo (21), na Catedral da S\u00e9 o Jubileu de Ouro pelos 50 anos de cria\u00e7\u00e3o da Pastoral Carcer\u00e1ria no Brasil. Neste domingo tamb\u00e9m a igreja celebrou a Solenidade da Assun\u00e7\u00e3o de Nossa Senhora.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/pastoral-carceraria-sobral-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/pastoral-carceraria-sobral-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/pastoral-carceraria-sobral-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/pastoral-carceraria-sobral-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17318,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-tiangua-jubileu-de-ouro\/","url_meta":{"origin":18184,"position":2},"title":"DIOCESE DE TIANGU\u00c1: JUBILEU DE OURO","author":"","date":"Agosto 23, 2021","format":false,"excerpt":"A Diocese de Tiangu\u00e1 foi criada por S\u00e3o Paulo VI, Papa, juntamente com as Dioceses de Itapipoca e Quixad\u00e1, a 13\/03\/1971 e foi desmembrada da Diocese de Sobral, em todo o seu territ\u00f3rio. \u00c9 interessante, nesse Jubileu, destacar a import\u00e2ncia de Dom Walfrido Teixeira Vieira, Bispo de Sobral (1965-1998), na\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31373,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-sobral-realiza-42a-assembleia-diocesana-de-evangelizacao\/","url_meta":{"origin":18184,"position":3},"title":"Diocese de Sobral realiza 42\u00aa Assembleia Diocesana de Evangeliza\u00e7\u00e3o","author":"adminredacao","date":"Novembro 18, 2024","format":false,"excerpt":"Nos dias 8 e 9 de novembro, aconteceu a 42\u00aa Assembleia Diocesana de Evangeliza\u00e7\u00e3o no Centro de Treinamento de Sobral Dom Aldo Di Cillo Pagotto (Cetreso), com o tema: \u201cPeregrinos da Esperan\u00e7a\u201d, e o lema: \u201cEnsinai-nos a rezar\u201d. (Lc 11, 1). Nesta edi\u00e7\u00e3o, o intuito foi de favorecer espa\u00e7o para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/42-assembleia-diocesana-de-sobral-4.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29606,"url":"https:\/\/correiodasemana.com\/site\/diaconos-participam-da-v-assembleia-formativa-e-eletiva-da-comissao-dos-diaconos\/","url_meta":{"origin":18184,"position":4},"title":"Di\u00e1conos participam da V Assembleia Formativa e Eletiva da Comiss\u00e3o dos Di\u00e1conos","author":"adminredacao","date":"Junho 10, 2024","format":false,"excerpt":"No \u00faltimo dia 25 de maio, os di\u00e1conos das dioceses que fazem parte do Regional NE1, participaram da V Assembleia Formativa e Eletiva da Comiss\u00e3o dos Di\u00e1conos na Casa de Forma\u00e7\u00e3o Arquidiocesana Maria m\u00e3e da Igreja em Fortaleza\/CE. Da diocese de Sobral, participaram os di\u00e1conos: Alex Te\u00f3filo, par\u00f3quia de S\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Diaconos-da-Diocese-de-Sobral-Alex-Teofilo-Edmar-Filho-Candido-Aguiar-e-Luis-Gonzaga-2.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":36197,"url":"https:\/\/correiodasemana.com\/site\/diocese-de-sobral-celebra-110-anos-de-criacao-com-missa-em-acao-de-gracas-na-se-catedral\/","url_meta":{"origin":18184,"position":5},"title":"Diocese de Sobral celebra 110 anos de cria\u00e7\u00e3o com Missa em A\u00e7\u00e3o de Gra\u00e7as na S\u00e9 Catedral","author":"adminredacao","date":"Novembro 12, 2025","format":false,"excerpt":"A Diocese de Sobral celebrou, nesta segunda-feira (10\/11), os 110 anos de sua cria\u00e7\u00e3o. A Missa em A\u00e7\u00e3o de Gra\u00e7as foi presidida pelo bispo diocesano, Dom Jos\u00e9 Luiz Gomes de Vasconcelos, na S\u00e9 Catedral de Nossa Senhora da Concei\u00e7\u00e3o, e concelebrada pelos presb\u00edteros da diocese. A Igreja Particular de Sobral\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/11\/DSC_9390-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18184"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18184\/revisions"}],"predecessor-version":[{"id":18190,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18184\/revisions\/18190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18185"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}