{"id":18364,"date":"2021-12-20T00:51:40","date_gmt":"2021-12-20T03:51:40","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18364"},"modified":"2021-12-20T00:51:40","modified_gmt":"2021-12-20T03:51:40","slug":"mudanca-de-habito-durante-a-pandemia","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/mudanca-de-habito-durante-a-pandemia\/","title":{"rendered":"Mudan\u00e7a de H\u00e1bito Durante a Pandemia"},"content":{"rendered":"<p>Durante essa pandemia muitas coisas mudaram na nossa vida. Com o isolamento social e o distanciamento das pessoas fomos obrigados a fazer coisas que n\u00e3o estavam no nosso cotidiano. Como n\u00e3o t\u00ednhamos secret\u00e1ria do lar, minha esposa aprendeu a fazer e criar v\u00e1rios tipos de comidas para nossas refei\u00e7\u00f5es di\u00e1rias. E, diga-se de passagem, comidas deliciosas.<br \/>\nMinha parte ficou com a limpeza da casa. Barrer, passar o pano, lavar aparelhos sanit\u00e1rios, limpar espelhos e divis\u00f3rias dos banheiros, cuidar das plantas e botar comida para os meus gatos, Poetisa e Poeta. Claro, que entre uma coisa e outra, como educador orientava meus alunos remotamente, usando o WhatsApp e reuni\u00f5es de planejamento atrav\u00e9s do meet.<br \/>\nComo sou uma pessoa muito organizada, meticulosa, detalhista e perfeccionista comecei a retirar tudo dos guarda roupas e arm\u00e1rios para limpar e colocar de volta. Essa tarefa substitu\u00eda a minha caminhada de dois quil\u00f4metros que fa\u00e7o de segunda a sexta feira.<br \/>\nPor ser muito met\u00f3dico, comecei a perceber detalhadamente algumas coisas que me chamaram a aten\u00e7\u00e3o. No escorredor de pratos deve-se colocar ao fundo primeiro os pratos grandes, depois os menores e por fim os pires. No escorredor de talheres deve-se colocar facas, garfos e colheres sempre com os cabos para cima. J\u00e1 vi em muitas casas ao contr\u00e1rio, que afirmo que \u00e9 uma maneira errada de se usar. Ou ainda pior, colheres com os cabos para baixo e garfos e facas com os cabos para cima, que afirmo que \u00e9 uma maneira atrapalhada de se usar.<br \/>\nOutra coisa que me chamou a aten\u00e7\u00e3o foram as formiguinhas e as aranhas pequenas. Estas, se voc\u00ea passar dois dias sem limpar elas aparecem do nada e as formigas voc\u00ea tem que ter algumas precau\u00e7\u00f5es porque elas (n\u00e3o fazem bem \u00e0 vista como se dizia antigamente) est\u00e3o sempre onde tem restos de comidas e doces e comem baratas. Por isso, tenho o cuidado de n\u00e3o deixar no dep\u00f3sito de lixo os ossos de carne e peixe, pele de frango e outras sobras de comida. Pego esse material, boto dentro de um saco pl\u00e1stico e coloco na geladeira. Quando for o dia do carro do lixo passar levo para a cal\u00e7ada junto com os outros lixos. Assim, evito que elas apare\u00e7am com mais frequ\u00eancia. E quando aparecem fa\u00e7o a seguinte mistura venenosa para elas: 100ml de \u00e1gua + 100ml de vinagre de \u00e1lcool + 50ml de detergente transparente. Junto todos esses ingredientes e aplico com um borrifador durante alguns dias nos locais mais estrat\u00e9gicos at\u00e9 elas desaparecerem. Morrem de imediato.<br \/>\nTenha cuidado com a esponja de lavar lou\u00e7as. Quando for lavar algum utens\u00edlio que tenha muita gordura, passe primeiro um papel higi\u00eanico limpando at\u00e9 tirar toda a gordura. Dessa maneira voc\u00ea preserva mais a esponja e fa\u00e7a uma higieniza\u00e7\u00e3o quando for necess\u00e1rio. Ferva \u00e1gua, coloque uma colher de sopa de vinagre e descanse por cinco minutos.<br \/>\n\u00c9, meus caros amigos, vivendo e aprendendo.<br \/>\nPor Salmito Campos \u2013 (salmitocamposs@gmail.com).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante essa pandemia muitas coisas mudaram na nossa vida. Com o isolamento social e o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,81],"tags":[],"class_list":["post-18364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-salmito-campos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg","jetpack-related-posts":[{"id":13299,"url":"https:\/\/correiodasemana.com\/site\/no-late-zap-com-mabel-15\/","url_meta":{"origin":18364,"position":0},"title":"NO LATE-ZAP COM MABEL","author":"","date":"Agosto 31, 2020","format":false,"excerpt":"Mabel, minha miga, como est\u00e1? Como foi seu final de semana? Certamente bem melhor que o Witzel, n\u00e3o \u00e9 mesmo? Verdade, aquele coitado est\u00e1 mais acuado que barata em sal\u00e3o de festa. Mas \u00e9 essa mesmo a paga de quem n\u00e3o crer proceder. Coitado do Rio de Janeiro, que n\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/silveira-rocha.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/silveira-rocha.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/silveira-rocha.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/silveira-rocha.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24713,"url":"https:\/\/correiodasemana.com\/site\/cachorro-mais-velho-do-mundo-completa-mais-um-ano-de-vida-31-anos\/","url_meta":{"origin":18364,"position":1},"title":"Cachorro mais velho do mundo completa mais um ano de vida, 31 anos","author":"","date":"Maio 16, 2023","format":false,"excerpt":"Bobi, um cachorro portugu\u00eas, foi reconhecido pelo Guinness Book of World Records como o c\u00e3o mais velho do mundo. Ele celebrou na \u00faltima quinta-feira, 11, seu 31\u00aa anivers\u00e1rio, e chocou at\u00e9 mesmo seus donos que n\u00e3o esperavam ter um animal que vivesse mais que 30 anos. \u201cO Bobi \u00e9 especial\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/bobi-cachorro-mais-velho-do-mundo-750x450-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/bobi-cachorro-mais-velho-do-mundo-750x450-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/bobi-cachorro-mais-velho-do-mundo-750x450-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/bobi-cachorro-mais-velho-do-mundo-750x450-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8511,"url":"https:\/\/correiodasemana.com\/site\/flanelas-da-solidao-historias-de-pessoas-em-situacao-de-rua-na-cidade-de-sobral\/","url_meta":{"origin":18364,"position":2},"title":"Flanelas da solid\u00e3o: Hist\u00f3rias de pessoas em situa\u00e7\u00e3o de rua na cidade de Sobral","author":"","date":"Julho 30, 2019","format":false,"excerpt":"Vindas de outras cidades ou filhas da mesma Sobral, pessoas em situa\u00e7\u00e3o de rua encontram no servi\u00e7o de \u201cflanelinha\u201d um meio para sobreviver. Fome, frio e solid\u00e3o s\u00e3o sentimentos di\u00e1rios nas vidas desses seres humanos Ao caminhar pelas ruas de Sobral \u00e9 comum deparar-se no meio da beleza de sua\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Foto-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Foto-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Foto-1.png?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12455,"url":"https:\/\/correiodasemana.com\/site\/coluna-silveira-rocha-publicacao-diaria\/","url_meta":{"origin":18364,"position":3},"title":"COLUNA SILVEIRA ROCHA &#8211; PUBLICA\u00c7\u00c3O DI\u00c1RIA","author":"","date":"Agosto 3, 2020","format":false,"excerpt":"NO LATE-ZAP COM MABEL Mabel, eu sabia que mais cedo ou mais tarde eu flagraria voc\u00ea batendo papo nas redes sociais. Como eu a descobri? Ora bolas, quem n\u00e3o reconhece esse seu papo de comunista. Tome muito cuidado com o que fala, sen\u00e3o o Alex Imorais manda voc\u00ea para a\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/117163962_290238355633639_4284614535297516281_n-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/117163962_290238355633639_4284614535297516281_n-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/117163962_290238355633639_4284614535297516281_n-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/117163962_290238355633639_4284614535297516281_n-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22059,"url":"https:\/\/correiodasemana.com\/site\/droga-experimental-obtem-avanco-inedito-contra-alzheimer\/","url_meta":{"origin":18364,"position":4},"title":"Droga experimental obt\u00e9m avan\u00e7o in\u00e9dito contra Alzheimer","author":"","date":"Dezembro 5, 2022","format":false,"excerpt":"Medicamento ataca prote\u00ednas no c\u00e9rebro associadas \u00e0 doen\u00e7a, reduzindo decl\u00ednio cognitivo de pacientes em 27%, mas pode causar s\u00e9rios efeitos colaterais. Este \u00e9 o maior avan\u00e7o em 30 anos do combate \u00e0 enfermidade. Um medicamento experimental se tornou o primeiro avan\u00e7o inovador em 30 anos na pesquisa sobre a doen\u00e7a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/ff3063_d564cbc6d98a4f99a6e1a21725f24e56_mv2-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/ff3063_d564cbc6d98a4f99a6e1a21725f24e56_mv2-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/12\/ff3063_d564cbc6d98a4f99a6e1a21725f24e56_mv2-1.webp?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":27379,"url":"https:\/\/correiodasemana.com\/site\/educacao-e-cidadania-25\/","url_meta":{"origin":18364,"position":5},"title":"EDUCA\u00c7\u00c3O E CIDADANIA \u2022","author":"adminredacao","date":"Novembro 27, 2023","format":false,"excerpt":"A Fome Est\u00e1 no Bairro, na Cidade, no Mundo, ao Nosso Lado Esse di\u00e1logo abaixo tem o mesmo sentimento de uma poesia minha:\u00a0\u201cEle Entende de Fome\u201d.\u00a0Encontrei-o na internet. \u00c9 pura realidade. Vamos direto ao texto. \u201cEntrei apressado e com fome no restaurante. Escolhi uma mesa bem afastada, pois queria aproveitar\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18364"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18364\/revisions"}],"predecessor-version":[{"id":18365,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18364\/revisions\/18365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17116"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}