{"id":18512,"date":"2022-01-10T00:18:30","date_gmt":"2022-01-10T03:18:30","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18512"},"modified":"2022-01-10T00:18:30","modified_gmt":"2022-01-10T03:18:30","slug":"santa-casa-de-sobral-recebe-doacao-de-conjuntos-de-nebulizacao-da-secretaria-municipal-de-saude-de-catunda","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-recebe-doacao-de-conjuntos-de-nebulizacao-da-secretaria-municipal-de-saude-de-catunda\/","title":{"rendered":"Santa Casa de Sobral recebe doa\u00e7\u00e3o de conjuntos de Nebuliza\u00e7\u00e3o da Secretaria Municipal de Sa\u00fade de Catunda"},"content":{"rendered":"<p><em><strong>A doa\u00e7\u00e3o foi recebida pelo gerente de enfermagem da Emerg\u00eancia, Hobber Kildare e ser\u00e1 encaminhada para o servi\u00e7o de Almoxarifado para distribui\u00e7\u00e3o nos demais servi\u00e7os.<\/strong><\/em><\/p>\n<p>Ascom Complexo SCMS<br \/>\nRefer\u00eancia em sa\u00fade para toda a zona noroeste do estado do Cear\u00e1, a Santa Casa de Miseric\u00f3rdia de Sobral atende a uma popula\u00e7\u00e3o de aproximadamente 1,9 milh\u00e3o de pessoas, oriundas de 56 munic\u00edpios. A Institui\u00e7\u00e3o \u00e9 porta aberta para toda a Regi\u00e3o e conta com o apoio dos gestores municipais para garantir mais oportunidades de aten\u00e7\u00e3o e cuidado \u00e0 popula\u00e7\u00e3o.<br \/>\nNa quinta-feira (06\/01), o servi\u00e7o de Emerg\u00eancia da Santa Casa recebeu a doa\u00e7\u00e3o de 300 conjuntos de Nebuliza\u00e7\u00e3o do Secret\u00e1rio Municipal de Sa\u00fade de Catunda, Rog\u00e9rio Rodrigues de Mendon\u00e7a. O conjunto para nebuliza\u00e7\u00e3o possibilita a oxigena\u00e7\u00e3o direta ao paciente atrav\u00e9s das atividades de inala\u00e7\u00e3o e aplica\u00e7\u00e3o de medicamentos vaporizados e umidificados com o objetivo de enriquecer o g\u00e1s inalado pelo paciente.<br \/>\nA doa\u00e7\u00e3o foi recebida pelo gerente de enfermagem da Emerg\u00eancia, Hobber Kildare e ser\u00e1 encaminhada para o servi\u00e7o de Almoxarifado para distribui\u00e7\u00e3o nos demais servi\u00e7os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A doa\u00e7\u00e3o foi recebida pelo gerente de enfermagem da Emerg\u00eancia, Hobber Kildare e ser\u00e1 encaminhada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-18512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/Doacao-catunda.jpg","jetpack-related-posts":[{"id":11506,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-recebe-visita-do-secretario-da-saude-do-ceara\/","url_meta":{"origin":18512,"position":0},"title":"Santa Casa de Miseric\u00f3rdia de Sobral recebe visita do secret\u00e1rio da Sa\u00fade do Cear\u00e1","author":"","date":"Junho 21, 2020","format":false,"excerpt":"A Santa Casa de Miseric\u00f3rdia de Sobral recebeu, neste s\u00e1bado (20\/06), a visita do secret\u00e1rio da Sa\u00fade do Cear\u00e1, Carlos Roberto Martins Rodrigues Sobrinho, Dr. Cabeto. Em parceria com o Governo do Estado e Prefeitura Municipal, o Hospital implantou no m\u00eas de maio, uma Unidade de Interna\u00e7\u00e3o com 16 leitos\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/103767577_1130736103979853_5070669222588337650_o-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/103767577_1130736103979853_5070669222588337650_o-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/103767577_1130736103979853_5070669222588337650_o-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/06\/103767577_1130736103979853_5070669222588337650_o-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33657,"url":"https:\/\/correiodasemana.com\/site\/prefeito-oscar-rodrigues-recebe-comitiva-do-ministerio-da-saude-para-dialogar-solucoes-para-a-santa-casa-de-sobral\/","url_meta":{"origin":18512,"position":1},"title":"Prefeito Oscar Rodrigues recebe comitiva do Minist\u00e9rio da Sa\u00fade para dialogar solu\u00e7\u00f5es para a Santa Casa de Sobral","author":"adminredacao","date":"Maio 5, 2025","format":false,"excerpt":"Sobral recebeu nesta sexta-feira, 2 de maio, uma comitiva do Minist\u00e9rio da Sa\u00fade e da Secretaria de Sa\u00fade do Estado, recepcionada pelo prefeito de Sobral, Oscar Rodrigues. O objetivo \u00e9 encontrar solu\u00e7\u00f5es para a crise enfrentada pela Santa Casa de Miseric\u00f3rdia de Sobral, um cen\u00e1rio deixado pela gest\u00e3o anterior. Foram\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/1ok-SANTA-CASA-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10784,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-recebe-visita-do-prefeito-da-cidade\/","url_meta":{"origin":18512,"position":2},"title":"Santa Casa de Miseric\u00f3rdia de Sobral recebe visita do prefeito da cidade","author":"","date":"Fevereiro 10, 2020","format":false,"excerpt":"Visita teve como objetivo conhecer o funcionamento de alguns setores do Hospital e desenvolver planos para melhorar a qualidade da sa\u00fade em Sobral e regi\u00e3o Assessoria de Comunica\u00e7\u00e3o do Complexo SCMS A Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) recebeu, na quarta-feira (05\/02), a visita do prefeito de Sobral, Ivo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Visita-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Visita-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Visita-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Visita-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34846,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-sobral-retoma-gestao-pela-diocese-sob-nova-direcao\/","url_meta":{"origin":18512,"position":3},"title":"Santa Casa de Sobral retoma gest\u00e3o pela Diocese sob nova dire\u00e7\u00e3o","author":"adminredacao","date":"Julho 28, 2025","format":false,"excerpt":"A Associa\u00e7\u00e3o Santa Casa de Miseric\u00f3rdia de Sobral (ASCMS) informa que foi oficialmente revogado o decreto de interven\u00e7\u00e3o municipal que vigorava sobre o hospital Santa Casa de Miseric\u00f3rdia de Sobral. Com o fim da interven\u00e7\u00e3o municipal, o hospital retorna \u00e0 gest\u00e3o da sua associa\u00e7\u00e3o mantenedora. A decis\u00e3o resulta de um\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/07\/foto-da-santa-casa-1200x603-1.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18333,"url":"https:\/\/correiodasemana.com\/site\/coordenadora-da-responsabilidade-social-da-santa-casa-de-sobral-e-homenageada-pelo-hemoce-com-o-trofeu-gente-que-inspira-a-salvar-vidas\/","url_meta":{"origin":18512,"position":4},"title":"Coordenadora da Responsabilidade Social da Santa Casa de Sobral \u00e9 homenageada pelo Hemoce com o trof\u00e9u \u2018Gente que Inspira a Salvar Vidas\u2019","author":"","date":"Dezembro 12, 2021","format":false,"excerpt":"A homenagem aconteceu na\u00a0comemora\u00e7\u00e3o do Hemoce\u00a0em alus\u00e3o ao Dia Nacional do Doador Volunt\u00e1rio de Sangue. Ascom Complexo SCMS A coordenadora do Servi\u00e7o de Responsabilidade Social do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, Ana Helena Vasconcelos, recebeu na quinta-feira (25\/11) o trof\u00e9u \u2018Gente que Inspira a Salvar Vidas\u2019 do\u00a0Centro de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/Hemoce-trofeu.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/Hemoce-trofeu.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/Hemoce-trofeu.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/Hemoce-trofeu.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/12\/Hemoce-trofeu.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":12405,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-recebe-doacao-de-protetores-faciais-de-parceria-entre-ifce-e-sindicato-dos-engenheiros-do-ceara\/","url_meta":{"origin":18512,"position":5},"title":"Santa Casa de Miseric\u00f3rdia de Sobral recebe doa\u00e7\u00e3o de protetores faciais de parceria entre IFCE e Sindicato dos Engenheiros do Cear\u00e1","author":"","date":"Agosto 2, 2020","format":false,"excerpt":"O equipamento de prote\u00e7\u00e3o \u00e9 indicado no combate ao novo coronav\u00edrus como complemento \u00e0s m\u00e1scaras do tipo N95. Assessoria de Comunica\u00e7\u00e3o do Complexo SCMS Desde o in\u00edcio da pandemia da Covid-19, o Complexo Santa Casa de Miseric\u00f3rdia de Sobral vem recebendo doa\u00e7\u00f5es de Equipamentos de Prote\u00e7\u00e3o Individual (EPIs), itens essenciais\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/IFCE-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18512"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18512\/revisions"}],"predecessor-version":[{"id":18514,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18512\/revisions\/18514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18513"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}