{"id":18527,"date":"2022-01-10T00:31:09","date_gmt":"2022-01-10T03:31:09","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18527"},"modified":"2022-01-10T00:31:09","modified_gmt":"2022-01-10T03:31:09","slug":"em-tempo-115","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-115\/","title":{"rendered":"Em Tempo"},"content":{"rendered":"<p><strong>Exame Nacional do Ensino M\u00e9dio<\/strong><br \/>\nNos pr\u00f3ximos domingos, dias 9 e 16 de janeiro, o Exame Nacional do Ensino M\u00e9dio (Enem) ser\u00e1 reaplicado para os candidatos faltosos na data regular. O candidato deve acessar a\u00a0P\u00e1gina do Participante\u00a0e conferir se o cart\u00e3o de confirma\u00e7\u00e3o est\u00e1 dispon\u00edvel.<br \/>\nA replica\u00e7\u00e3o foi liberada pelo Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira. Entre as justificativas est\u00e3o sintomas de doen\u00e7as infectocontagiosas, como a Covid-19, ou problemas log\u00edsticos, de infraestrutura ou por outras ocorr\u00eancias espec\u00edficas.<\/p>\n<p><strong>Cen\u00e1rio dos a\u00e7udes no Cear\u00e1<\/strong><br \/>\nDos 115 a\u00e7udes cearenses, apenas 14 est\u00e3o com 70% da capacidade de aporte total no come\u00e7o de 2022 e 79 t\u00eam menos de 30% armazenados. Os dados s\u00e3o do Portal Hidrol\u00f3gico, referentes ao dia 1\u00ba de janeiro. O Estado come\u00e7a o ano com 20,73% do volume total poss\u00edvel.<br \/>\nO Castanh\u00e3o, maior a\u00e7ude do Cear\u00e1, est\u00e1 com apenas 8,18% de sua capacidade. Por outro lado, j\u00e1 existem alguns reservat\u00f3rios alcan\u00e7ando os 90% de volume, como \u00e9 o caso do Caldeir\u00f5es, no Alto Jaguaribe. Com capacidade de 1,24 hm\u00b3 (um bilh\u00e3o de litros), o a\u00e7ude marcou 89,77%.<\/p>\n<p><strong>Giuliano Eriston vence The Voice <\/strong><br \/>\n<strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-18528\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/bla-9859-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/bla-9859-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/bla-9859-768x512.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/bla-9859.jpg 1008w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Foto: Isabella Pinheiro\/Gshow<\/strong><br \/>\n<strong>Giuliano Eriston \u00e9 o campe\u00e3o da d\u00e9cima temporada do The Voice Brasil<\/strong><br \/>\nCom 33,98%, o artista cearense Giuliano Eriston, de 24 anos, foi o grande vencedor da d\u00e9cima temporada de The Voice Brasil, da TV Globo, na noite de 23 de dezembro de 2021. Natural de Bela Cruz, munic\u00edpio da regi\u00e3o Norte do Estado, Giuliano representou o Time Tel\u00f3.<br \/>\nAl\u00e9m de cantor e multi-instrumentista, Giuliano tamb\u00e9m \u00e9 compositor, por\u00e9m, s\u00f3 come\u00e7ou a estudar para aperfei\u00e7oar sua voz durante a sele\u00e7\u00e3o para o programa. Participando de festivais e convivendo com artistas do ramo, ele tem como influ\u00eancias grandes nomes da MPB.<\/p>\n<p><strong>Incentivo ao setor audiovisual<\/strong><br \/>\nO governador\u00a0Camilo Santana\u00a0sancionou lei que permite a cria\u00e7\u00e3o de\u00a0um programa de incentivo ao setor audiovisual. Agora, ser\u00e3o institu\u00eddos o\u00a0Cear\u00e1 Filmes\u00a0\u2013 Programa Estadual de Desenvolvimento do Cinema e Audiovisual e o Sistema Estadual de Cinema e Audiovisual.<br \/>\nO primeiro tem o objetivo de fomentar o desenvolvimento da produ\u00e7\u00e3o do Estado. A a\u00e7\u00e3o de pol\u00edtica p\u00fablica ser\u00e1 dividida em sete eixos: produ\u00e7\u00e3o, distribui\u00e7\u00e3o, exibi\u00e7\u00e3o, preserva\u00e7\u00e3o, forma\u00e7\u00e3o, rede institucional e legisla\u00e7\u00e3o. A lei foi sancionada no dia 29 de dezembro de 2021.<\/p>\n<p><strong>Concurso para professor Unilab<\/strong><br \/>\nO curso de Medicina da Universidade da Integra\u00e7\u00e3o Internacional da Lusofonia Afro-Brasileira (Unilab) est\u00e1 com inscri\u00e7\u00f5es abertas at\u00e9 27 de janeiro\u00a0para concurso p\u00fablico no Cear\u00e1. Est\u00e3o dispon\u00edveis duas vagas de professor, com remunera\u00e7\u00e3o total de\u00a0R$ 9.616,18\u00a0cada.<br \/>\nAs oportunidades de\u00a040 horas semanais\u00a0s\u00e3o destinadas para\u00a0as \u00e1reas de Ci\u00eancias Morfol\u00f3gicas e Semiologia m\u00e9dica e Ci\u00eancias Fisiol\u00f3gicas e Semiologia m\u00e9dica.\u00a0Os interessados devem possuir\u00a0t\u00edtulo de doutor\u00a0e desembolsar um valor de R$ 240 na inscri\u00e7\u00e3o.<\/p>\n<p><strong>Dica da Coluna<\/strong><br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br): Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica. Feliz e aben\u00e7oado Ano Novo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exame Nacional do Ensino M\u00e9dio Nos pr\u00f3ximos domingos, dias 9 e 16 de janeiro, o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-18527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg","jetpack-related-posts":[{"id":28821,"url":"https:\/\/correiodasemana.com\/site\/sobe-para-25-o-numero-de-acudes-sangrando-no-ceara\/","url_meta":{"origin":18527,"position":0},"title":"Sobe para 25 o n\u00famero de a\u00e7udes sangrando no Cear\u00e1","author":"adminredacao","date":"Mar\u00e7o 25, 2024","format":false,"excerpt":"Subiu para 25 a quantidade de a\u00e7udes monitorados pela Cogerh sangrando no Cear\u00e1. Os dados s\u00e3o desta sexta-feira (22). Outros onze reservat\u00f3rios registram mais de 90% da capacidade total. Os a\u00e7udes Itapaj\u00e9, Batalh\u00e3o, em Crate\u00fas, e Missi, em Mira\u00edma, foram os \u00faltimos a atingir a capacidade m\u00e1xima. O acumulado total\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-15-at-9.49.16-AM-768x418-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-15-at-9.49.16-AM-768x418-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-15-at-9.49.16-AM-768x418-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-15-at-9.49.16-AM-768x418-1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15434,"url":"https:\/\/correiodasemana.com\/site\/mec-divulga-selecionados-na-primeira-chamada-do-prouni-2021\/","url_meta":{"origin":18527,"position":1},"title":"MEC divulga selecionados na primeira chamada do Prouni 2021","author":"","date":"Janeiro 19, 2021","format":false,"excerpt":"Candidatos t\u00eam at\u00e9 27 de janeiro para comprovar informa\u00e7\u00f5es O Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) divulgou, hoje (19), a rela\u00e7\u00e3o dos candidatos aprovados na primeira chamada do Programa Universidade para Todos (Prouni) de 2021. Os selecionados ter\u00e3o at\u00e9 o dia 27 de janeiro para comprovar as informa\u00e7\u00f5es prestadas na inscri\u00e7\u00e3o. O\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/10_07_2020_ministerio_educacao-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/10_07_2020_ministerio_educacao-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/10_07_2020_ministerio_educacao-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/10_07_2020_ministerio_educacao-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/10_07_2020_ministerio_educacao-2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23076,"url":"https:\/\/correiodasemana.com\/site\/ceara-ja-tem-quatro-acudes-sangrando\/","url_meta":{"origin":18527,"position":2},"title":"Cear\u00e1 j\u00e1 tem quatro a\u00e7udes sangrando","author":"","date":"Janeiro 24, 2023","format":false,"excerpt":"O quarto reservat\u00f3rio a sangrar \u00e9 o a\u00e7ude Ros\u00e1rio, no munic\u00edpio de Lavras da Mangabeira. O a\u00e7ude Ros\u00e1rio, no munic\u00edpio de Lavras da Mangabeira, no Cariri cearense, atingiu 100% de capacidade h\u00eddrica total. O volume foi atingido nesta segunda-feira, 23. Agora s\u00e3o quatro a\u00e7udes que sangraram neste ano no Cear\u00e1,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/COCO17.jfif_-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":37540,"url":"https:\/\/correiodasemana.com\/site\/acudes-do-ceara-tiveram-o-maior-aporte-de-2026-nesta-quinta-feira-19\/","url_meta":{"origin":18527,"position":3},"title":"A\u00e7udes do Cear\u00e1 tiveram o maior aporte de 2026 nesta quinta-feira (19)","author":"adminredacao","date":"Fevereiro 23, 2026","format":false,"excerpt":"Regi\u00f5es do Salgado e dos Sert\u00f5es de Crate\u00fas tiveram boa recarga\u00a0de volume Fonte: Ascom Cogerh - texto e fotos A semana do Carnaval trouxe ao Cear\u00e1 um cen\u00e1rio h\u00eddrico mais animador. Conforme dados do monitoramento di\u00e1rio da Companhia de Gest\u00e3o de Recursos H\u00eddricos (Cogerh), nesta quinta-feira (19) os 144 a\u00e7udes\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/acude-Sao-Jose-III-Ipaporanga-foto-tirada-dia-14.06.2023-1024x576-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/acude-Sao-Jose-III-Ipaporanga-foto-tirada-dia-14.06.2023-1024x576-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/acude-Sao-Jose-III-Ipaporanga-foto-tirada-dia-14.06.2023-1024x576-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/02\/acude-Sao-Jose-III-Ipaporanga-foto-tirada-dia-14.06.2023-1024x576-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23837,"url":"https:\/\/correiodasemana.com\/site\/acude-paulo-sarasate-araras-comeca-a-sangrar\/","url_meta":{"origin":18527,"position":4},"title":"A\u00e7ude Paulo Sarasate &#8211; Araras come\u00e7a a sangrar","author":"","date":"Abril 10, 2023","format":false,"excerpt":"Quarto maior reservat\u00f3rio h\u00eddrico do Cear\u00e1, o a\u00e7ude Paulo Sarasate, mais conhecido como Araras, come\u00e7ou a sangrar na noite deste domingo de P\u00e1scoa, 9. Localizado em Varjota, a 262 quil\u00f4metros de Fortaleza, o a\u00e7ude tem capacidade para armazenar at\u00e9 859 milh\u00f5es de metros c\u00fabicos de \u00e1gua. A barragem havia vertido\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/1_araras_2-14528307.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/1_araras_2-14528307.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/1_araras_2-14528307.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/1_araras_2-14528307.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17415,"url":"https:\/\/correiodasemana.com\/site\/maioria-dos-acudes-do-ceara-esta-em-situacao-critica-de-reserva-de-agua-com-niveis-abaixo-de-30\/","url_meta":{"origin":18527,"position":5},"title":"Maioria dos a\u00e7udes do Cear\u00e1 est\u00e1 em situa\u00e7\u00e3o cr\u00edtica de reserva de \u00e1gua com n\u00edveis abaixo de 30%","author":"","date":"Setembro 6, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo dados do Portal Hidrol\u00f3gico do Estado, gerenciado pela Companhia de Gest\u00e3o dos Recursos H\u00eddricos (Cogerh), extra\u00eddos na \u00faltima quarta-feira (01) a maioria dos reservat\u00f3rios do Cear\u00e1 est\u00e3o em n\u00edvel cr\u00edtico de volume h\u00eddrico. De acordo com a plataforma, dos 66 a\u00e7udes monitorados,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/acude-ceara.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18527"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18527\/revisions"}],"predecessor-version":[{"id":18529,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18527\/revisions\/18529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18025"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}