{"id":18567,"date":"2022-01-16T23:25:01","date_gmt":"2022-01-17T02:25:01","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18567"},"modified":"2022-01-16T23:25:01","modified_gmt":"2022-01-17T02:25:01","slug":"inmet-emite-aviso-amarelo-para-chuvas-e-vento-no-estado-do-ceara","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/inmet-emite-aviso-amarelo-para-chuvas-e-vento-no-estado-do-ceara\/","title":{"rendered":"Inmet emite aviso amarelo para chuvas e vento no Estado do Cear\u00e1"},"content":{"rendered":"<p>Por Samuel Carvalho<br \/>\nReda\u00e7\u00e3o Correio da Semana<br \/>\nO Instituto Nacional de Meteorologia (Inmet) emitiu avisos de chuva intensa com ventos fortes para algumas regi\u00f5es do Cear\u00e1 nesta quarta-feira (12). A designa\u00e7\u00e3o significa perigo em potencial em consequ\u00eancia das chuvas onde pelo menos quatro regi\u00f5es do Estado, incluindo o munic\u00edpio de Sobral, receberam o alerta da institui\u00e7\u00e3o.<br \/>\nA determina\u00e7\u00e3o de Perigo potencial (amarelo) \u00e9 definida pela situa\u00e7\u00e3o meteorol\u00f3gica potencialmente perigosa com riscos de chuva entre 20 mm\/h e 30 mm\/h ou at\u00e9 50 mm\/dia; Ventos intensos, de 40km\/h a 60 km\/h e Baixo risco de corte de energia el\u00e9trica, queda de galhos de \u00e1rvores, alagamentos e de descargas el\u00e9tricas. O aviso de maior destaque \u00e9 o \u201camarelo\u201d, que cobre todo o litoral-leste, o de Fortaleza, parte do litoral-oeste e regi\u00f5es norte, da Ibiapaba, al\u00e9m do Maci\u00e7o do Baturit\u00e9 e Vale do Jaguaribe.<br \/>\nApenas na \u00faltima quinta-feira (13) Choveu em 44 munic\u00edpios em todo o Estado entre as 7 horas de quarta e 7 horas com destaques para maior n\u00famero de precipita\u00e7\u00f5es nas cidades de Cedro (82 mm), seguido dos munic\u00edpios de Morada Nova (75 mm) e de Santa Quit\u00e9ria (46.2 mm). No entanto, ap\u00f3s precipita\u00e7\u00f5es mais intensas, os registros devem diminuir de volume neste fim de semana. As informa\u00e7\u00f5es s\u00e3o da Funceme.<br \/>\nAs chuvas esperadas para o fim de semana dever\u00e3o ter intensidade variada. As precipita\u00e7\u00f5es s\u00e3o oriundas de \u00e1reas de instabilidades que est\u00e3o se formando devido a efeitos locais, como relevo, temperatura e disponibilidade de umidade. Al\u00e9m disso, na costa leste do Nordeste encontra-se atuando o v\u00f3rtice cicl\u00f4nico de altos n\u00edveis (VCAN), que colabora por intensificar tais \u00e1reas de instabilidades sobre a regi\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O Instituto Nacional de Meteorologia (Inmet) emitiu avisos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-18567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/imagem_padarao.jpg","jetpack-related-posts":[{"id":22855,"url":"https:\/\/correiodasemana.com\/site\/veja-cidades-que-tem-risco-de-deslizamentos-e-alagamentos-no-ceara\/","url_meta":{"origin":18567,"position":0},"title":"Veja cidades que t\u00eam risco de deslizamentos e alagamentos no Cear\u00e1","author":"","date":"Janeiro 18, 2023","format":false,"excerpt":"Instituto Nacional de Meteorologia (Inmet) listou 22 cidades cearenses sob sinal de alerta sobre as chuvas. Um aviso do Instituto Nacional de Meteorologia (Inmet) publicado nesta ter\u00e7a-feira, 17, aponta que h\u00e1 perigo de pequenos deslizamentos e alagamentos no Cear\u00e1. Ao todo, 22 munic\u00edpios cearenses est\u00e3o sob o sinal de alerta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/leomar-chuva.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/leomar-chuva.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/leomar-chuva.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/leomar-chuva.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22902,"url":"https:\/\/correiodasemana.com\/site\/ceara-amanhece-sob-fortes-chuvas-nesta-quinta-feira-19\/","url_meta":{"origin":18567,"position":1},"title":"Cear\u00e1 amanhece sob fortes chuvas nesta quinta-feira, 19","author":"","date":"Janeiro 19, 2023","format":false,"excerpt":"Precipita\u00e7\u00e3o \u00e9 cont\u00ednua desde a noite da quarta-feira, 18; chuvas na madrugada desta quinta-feira aconteceram em quase todas as macrorregi\u00f5es do Cear\u00e1. O Cear\u00e1 amanheceu novamente sob fortes chuvas nesta quinta-feira, 19. As informa\u00e7\u00f5es s\u00e3o da Funda\u00e7\u00e3o Cearense de Meteorologia e Recursos H\u00eddricos (Funceme). Segundo dados de radar da Funda\u00e7\u00e3o,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/1__mg_4987-20857522.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/1__mg_4987-20857522.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/1__mg_4987-20857522.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/1__mg_4987-20857522.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":26322,"url":"https:\/\/correiodasemana.com\/site\/ondas-de-calor-resultam-de-mudancas-climaticas-nos-ultimos-60-anos\/","url_meta":{"origin":18567,"position":2},"title":"Ondas de calor resultam de mudan\u00e7as clim\u00e1ticas nos \u00faltimos 60 anos","author":"adminredacao","date":"Agosto 27, 2023","format":false,"excerpt":"Nordeste, Norte e Centro-Oeste foram regi\u00f5es com mais altera\u00e7\u00f5es Por Sabrina Craide - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia Ondas de calor como as registradas em diversas regi\u00f5es do pa\u00eds nesta semana s\u00e3o resultados das altera\u00e7\u00f5es clim\u00e1ticas nos \u00faltimos 60 anos. Um levantamento do Instituto Nacional de Meteorologia (Inmet) mostra\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/trbr5828.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/trbr5828.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/trbr5828.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/trbr5828.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/trbr5828.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":27205,"url":"https:\/\/correiodasemana.com\/site\/brasil-registra-recorde-da-temperatura-media-pelo-quarto-mes-seguido\/","url_meta":{"origin":18567,"position":3},"title":"Brasil registra recorde da temperatura m\u00e9dia pelo quarto m\u00eas seguido","author":"adminredacao","date":"Novembro 13, 2023","format":false,"excerpt":"INMET emite alerta para nova onda de calor Por Pedro Peduzzi - Rep\u00f3rter da Ag\u00eancia Brasil - Bras\u00edlia A temperatura m\u00e9dia no Brasil atingiu n\u00edvel recorde pelo quarto m\u00eas seguido em outubro. De acordo com o Instituto Nacional de Meteorologia (Inmet), entre julho e outubro, a diferen\u00e7a entre o valor\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/11\/img_6343.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/11\/img_6343.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/11\/img_6343.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/11\/img_6343.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/11\/img_6343.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18210,"url":"https:\/\/correiodasemana.com\/site\/pre-estacao-chuvosa-tem-inicio-no-ceara-previsoes-para-o-bimestre-sao-divulgadas\/","url_meta":{"origin":18567,"position":4},"title":"Pr\u00e9-esta\u00e7\u00e3o chuvosa tem in\u00edcio no Cear\u00e1; Previs\u00f5es para o bimestre s\u00e3o divulgadas","author":"","date":"Dezembro 6, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Com a chegada dos meses de dezembro e janeiro, tamb\u00e9m inicia a pr\u00e9-esta\u00e7\u00e3o chuvosa no Cear\u00e1. Como o pr\u00f3prio nome diz, esses dois meses antecedem o principal per\u00edodo de chuvas no Estado, que vai de fevereiro a maio. Para este ano a previs\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/chuva-5_mini.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/chuva-5_mini.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/chuva-5_mini.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/chuva-5_mini.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/chuva-5_mini.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":23079,"url":"https:\/\/correiodasemana.com\/site\/media-de-chuvas-no-ceara-em-2023-e-de-828-mm\/","url_meta":{"origin":18567,"position":5},"title":"M\u00e9dia de chuvas no Cear\u00e1 em 2023 \u00e9 de 82,8 mm","author":"","date":"Janeiro 24, 2023","format":false,"excerpt":"O \u00edndice pluviom\u00e9trico, no entanto, j\u00e1 \u00e9 o quinto maior dos \u00faltimos 10 anos, ficando atr\u00e1s apenas de 2016, 2019, 2020 e 2022. Os n\u00fameros podem ser ainda maiores a depender das chuvas dos \u00faltimos dias do m\u00eas. At\u00e9 o momento, o Cear\u00e1 registra 82,8 mm de chuvas em janeiro.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/161788461_1206455566474424_8300505492091169090_n-768x576-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/161788461_1206455566474424_8300505492091169090_n-768x576-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/161788461_1206455566474424_8300505492091169090_n-768x576-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/161788461_1206455566474424_8300505492091169090_n-768x576-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18567"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18567\/revisions"}],"predecessor-version":[{"id":18569,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18567\/revisions\/18569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18568"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}