{"id":18611,"date":"2022-01-16T23:45:41","date_gmt":"2022-01-17T02:45:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18611"},"modified":"2022-01-16T23:45:41","modified_gmt":"2022-01-17T02:45:41","slug":"o-martirio-de-ontem-e-de-hoje-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/o-martirio-de-ontem-e-de-hoje-2\/","title":{"rendered":"O mart\u00edrio de ontem e de hoje"},"content":{"rendered":"<p>Nesta semana, a 2\u00aa do Tempo Comum, a Igreja celebrar\u00e1 a mem\u00f3ria de alguns m\u00e1rtires. Dentre estes, alguns s\u00e3o bem populares, como S\u00e3o Sebasti\u00e3o e Santa In\u00eas. Nesse sentido, cabe-nos fazer uma reflex\u00e3o sobre o tema do mart\u00edrio, ainda bastante atual e presente na vida da Igreja. O Papa Francisco frequentemente traz tal reflex\u00e3o em suas homilias e audi\u00eancias gerais.<br \/>\nEngana-se quem pensa que o mart\u00edrio \u00e9 uma realidade dos primeiros s\u00e9culos, quando o Imp\u00e9rio Romano perseguiu e matou muitos dos santos m\u00e1rtires que hoje conhecemos. Para o Santo Padre, hoje existem mais m\u00e1rtires que no in\u00edcio da vida da Igreja, e eles est\u00e3o por todos os lugares. Vale salientar tamb\u00e9m que o mart\u00edrio tem acompanhado a Igreja ao longo dos s\u00e9culos e h\u00e1 quem diga que ele renova e d\u00e1 vida \u00e0 Igreja de Cristo.<br \/>\nDe fato, n\u00e3o h\u00e1 como discordar da frase de Tertuliano, bispo do terceiro s\u00e9culo, que dizia: \u201co sangue dos m\u00e1rtires \u00e9 a semente de novos crist\u00e3os\u201d. Quanto mais se perseguia os crist\u00e3os, maior era o n\u00famero daqueles que aderiam \u00e0 f\u00e9 crist\u00e3. Era um testemunho que fecundava a palavra de Deus nos cora\u00e7\u00f5es.<br \/>\nA pr\u00f3pria palavra m\u00e1rtir vem de uma palavra grega, martirion, que significa testemunho. O m\u00e1rtir \u00e9 aquele que d\u00e1 testemunho. No cristianismo, a pessoa martirizada entrega a pr\u00f3pria vida, dando testemunho de sua f\u00e9 em Cristo. E, apesar do horr\u00edvel que possa parecer o mart\u00edrio, \u00e9 justamente nisso que consiste a beleza desse testemunho.<br \/>\nAtualmente, essa realidade acompanha a Igreja no Oriente M\u00e9dio, na \u00c1sia e em muitas regi\u00f5es da \u00c1frica. Mas tamb\u00e9m na Am\u00e9rica Latina e no Brasil, h\u00e1 relatos de crist\u00e3os mortos por defenderem os valores do Evangelho e as causas dos mais pobres. Como exemplos temos Santo Oscar Romero, Ir. Dorothy, Pe. J\u00f3simo Tavares, Pe. Ezequiel Ramim, que inspiraram a composi\u00e7\u00e3o do bel\u00edssimo Pai-nosso dos m\u00e1rtires.<br \/>\nAl\u00e9m disso, h\u00e1 tamb\u00e9m o mart\u00edrio branco de cada dia, como definiu o Papa Bento XVI. \u00c9 o testemunho de f\u00e9 que devemos dar nas realidades mais cotidianas de nossas vidas, como nas dificuldades de relacionamento com o outro, em suportar uma enfermidade e em abra\u00e7ar com serenidade as cruzes do dia-a-dia.<br \/>\nOutro mart\u00edrio da atualidade \u00e9 o mart\u00edrio da fidelidade. Todos os crist\u00e3os, que professam a f\u00e9 cat\u00f3lica, n\u00e3o podem abrir m\u00e3o dos valores do evangelho e daquilo que \u00e9 princ\u00edpio de f\u00e9. \u00c9 defender a vida quando ela \u00e9 amea\u00e7ada e quando se defende o aborto, \u00e9 defender a fam\u00edlia diante de tantas ideologias contr\u00e1rias, \u00e9 defender a fraternidade em um mundo cada vez mais ego\u00edsta e excludente.<br \/>\nPortanto, a marca da fidelidade tem caracterizado o mart\u00edrio de ontem e de hoje, com ou sem derramamento de sangue. Em um mundo de princ\u00edpios cada vez menos crist\u00e3os e de ideais cada vez mais fr\u00e1geis, precisamos ser perseverantes na f\u00e9 e fieis ao evangelho. Tal \u00e9 o mart\u00edrio que nos faz imitar o m\u00e1rtir maior Jesus Cristo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta semana, a 2\u00aa do Tempo Comum, a Igreja celebrar\u00e1 a mem\u00f3ria de alguns m\u00e1rtires&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":7865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,20],"tags":[],"class_list":["post-18611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg","jetpack-related-posts":[{"id":15521,"url":"https:\/\/correiodasemana.com\/site\/o-martirio-de-ontem-e-de-hoje\/","url_meta":{"origin":18611,"position":0},"title":"O mart\u00edrio de ontem e de hoje","author":"","date":"Janeiro 24, 2021","format":false,"excerpt":"Nessa semana, a 2\u00aa do Tempo Comum, a Igreja celebrou a mem\u00f3ria de alguns m\u00e1rtires. Dentre estes, alguns s\u00e3o bem populares, como S\u00e3o Sebasti\u00e3o e Santa In\u00eas. Nesse sentido, cabe-nos fazer uma reflex\u00e3o sobre o tema do mart\u00edrio, ainda bastante atual e presente na vida da Igreja. O Papa Francisco\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16988,"url":"https:\/\/correiodasemana.com\/site\/martirios-e-perseguicoes-de-hoje\/","url_meta":{"origin":18611,"position":1},"title":"Mart\u00edrios e persegui\u00e7\u00f5es de hoje","author":"","date":"Julho 12, 2021","format":false,"excerpt":"\u201cO sangue dos m\u00e1rtires \u00e9 a semente de novos crist\u00e3os\u201d. Essa frase de Tertuliano, t\u00e3o conhecida, nos remonta ao terceiro s\u00e9culo da era crist\u00e3, em uma realidade de mart\u00edrios e persegui\u00e7\u00f5es constantes ao povo crist\u00e3o. Mas essa realidade n\u00e3o ficou apenas no passado. Segundo um diagn\u00f3stico feito pelo Papa Francisco,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9595,"url":"https:\/\/correiodasemana.com\/site\/romaria-das-criancas-faz-homenagem-a-menina-benigna-no-ceara\/","url_meta":{"origin":18611,"position":2},"title":"Romaria das Crian\u00e7as faz homenagem \u00e0 Menina Benigna no Cear\u00e1","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"Centenas de crian\u00e7as participaram da caminhada em prepara\u00e7\u00e3o \u00e0 tradicional Romaria em honra \u00e0 jovem m\u00e1rtir Benigna Cardoso, a pr\u00f3xima Beata brasileira, marcada para esta quinta-feira, dia 24 de outubro, dia do mart\u00edrio da Serva de Deus. Vatican News S\u00e3o 10 dias de prepara\u00e7\u00e3o \u00e0 16\u00aa Romaria da Menina Benigna\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_0823-1-750x375.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_0823-1-750x375.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_0823-1-750x375.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/DSC_0823-1-750x375.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27044,"url":"https:\/\/correiodasemana.com\/site\/menina-benigna\/","url_meta":{"origin":18611,"position":3},"title":"MENINA BENIGNA","author":"adminredacao","date":"Outubro 30, 2023","format":false,"excerpt":"\u201cEu te bendigo, Pai, Senhor do c\u00e9u e da terra, porque escondestes estas coisas aos s\u00e1bios e entendidos e as revelastes aos pequenos. Sim, Pai, eu te bendigo, porque assim foi do teu agrado\u201d (Mt 11, 25-26). No \u00faltimo dia 24, a Igreja celebrou a primeira festa em honra \u00e0\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":36113,"url":"https:\/\/correiodasemana.com\/site\/a-festa-de-todos-os-santos-3\/","url_meta":{"origin":18611,"position":4},"title":"A festa de todos os Santos","author":"adminredacao","date":"Novembro 3, 2025","format":false,"excerpt":"Neste primeiro dia do m\u00eas de novembro, a Igreja celebra a festa de todos os santos e santas de Deus. E celebr\u00e1-los todos em um \u00fanico dia \u00e9 recordar a voca\u00e7\u00e3o \u00e0 santidade para a qual n\u00f3s crist\u00e3os somos chamados. Tal venera\u00e7\u00e3o e recorda\u00e7\u00e3o da vida dos santos v\u00eam desde\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":21500,"url":"https:\/\/correiodasemana.com\/site\/a-festa-de-todos-os-santos-2\/","url_meta":{"origin":18611,"position":5},"title":"A festa de todos os Santos","author":"","date":"Novembro 6, 2022","format":false,"excerpt":"Neste primeiro domingo do m\u00eas de novembro, a Igreja celebra a festa de todos os santos e santas de Deus. E celebr\u00e1-los todos em um \u00fanico dia \u00e9 recordar a voca\u00e7\u00e3o \u00e0 santidade para a qual n\u00f3s crist\u00e3os somos chamados. Tal venera\u00e7\u00e3o e recorda\u00e7\u00e3o da vida dos santos v\u00eam desde\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18611"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18611\/revisions"}],"predecessor-version":[{"id":18612,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18611\/revisions\/18612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7865"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}