{"id":18872,"date":"2022-02-14T02:50:41","date_gmt":"2022-02-14T05:50:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18872"},"modified":"2022-02-14T02:50:41","modified_gmt":"2022-02-14T05:50:41","slug":"um-fato-comico-no-sertao-cearense","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/um-fato-comico-no-sertao-cearense\/","title":{"rendered":"Um fato c\u00f4mico no sert\u00e3o cearense"},"content":{"rendered":"<p>Entre algumas reminisc\u00eancias que tenho, apresento o casal Sr. Manoel Carvalho da Frota e a Sra. V\u00e2nia Lima Carvalho da Frota. O Sr. Manoel Carvalho era um homem de pele branca, estatura mediana, calvo, olhos amarelados, usava \u00f3culos com graus muito elevados, (\u00f3culos fundo de garrafa), n\u00e3o escutava bem, mas muito bem sucedido comercialmente no munic\u00edpio de Varjota Cear\u00e1.<br \/>\nDona V\u00e2nia Carvalho, branca, estatura mediana, olhos pretos, cabelos louros, lisos e muito bem cuidados. Muito vaidosa, andava sempre bem vestida, simp\u00e1tica e divertida. Conversava com todas as pessoas que encontrava, principalmente sobre pol\u00edtica. N\u00e3o foi \u00e0 toa que fez seu marido vereador, vice-prefeito e por fim prefeito do munic\u00edpio.<br \/>\nAs duas filhas, (Vanessa e Viviane, hoje casadas), olhos verdes, simp\u00e1ticas, muito bonitas, tempos atr\u00e1s chamava a aten\u00e7\u00e3o de qualquer rapaz.<br \/>\nQuem n\u00e3o queria \u00e0 \u00e9poca, ter uma namorada: bonita, educada, universit\u00e1ria, filha de um empres\u00e1rio bem sucedido e pol\u00edtico, participante da aristocracia local? Claro, uma jovem desta origem estava aos olhos dos mais diversos rapazes da cidade e daqueles que a visitavam na \u00e9poca dos festejos da padroeira Nossa Sra. Santana.<br \/>\nChegando o m\u00eas de julho a cidade ficava repleta de universit\u00e1rios, filhos da \u201cterrinha\u201d que estavam em S\u00e3o Paulo, Rio de Janeiro e turistas das cidades circunvizinhas.<br \/>\nA casa do Sr. Manoel ficava lotada de amigos e amigas das filhas. Embora com seis quartos para abrigar a rapaziada nas camas e redes, ainda tinha gente que dormia em colch\u00f5es improvisados estendidos ao ch\u00e3o. Isso n\u00e3o era problema para aquela juventude entusiasmada.<br \/>\nDona V\u00e2nia, com tanta gente assim, teria a necessidade de encontrar mais uma secret\u00e1ria para os servi\u00e7os gerais da casa.<br \/>\nAssim, Dona V\u00e2nia disse ao marido que precisava ir a uma localidade do munic\u00edpio a procura de mais uma pessoa para ajudar nos afazeres da casa. O Sr. Manoel disse: mas V\u00e2nia, j\u00e1 s\u00e3o mais de cinco e meia da tarde, como \u00e9 que eu vou dirigir sem enxergar bem? Dona V\u00e2nia sem titubear responde: Manoel, o tempo ainda est\u00e1 claro, outra coisa, \u00e9 muito perto a casa da Tereza. A casa do pai dela, Seu Chico Antonio, \u00e9 aqui nas Moitinhas.<br \/>\nNuma estrada de ch\u00e3o com pi\u00e7arra poeirenta, Sr. Manoel come\u00e7a a dirigir. De repente ele p\u00e1ra no meio da estrada, j\u00e1 um pouco confuso com a vis\u00e3o e pergunta: meu senhor, por gentileza, o senhor sabe onde \u00e9 que fica a casa do Seu Chico Ant\u00f4nio? Dona V\u00e2nia imediatamente diz para o marido em voz alta: Manoel, isso \u00e9 um t\u00f4co! O marido responde: cala a boca V\u00e2nia, se n\u00e3o o \u201chomi\u201d vai ouvir. E a\u00ed Dona V\u00e2nia continua: Manoel, isso \u00e9 um t\u00f4co. O marido continua: V\u00e2nia, deixa eu perguntar ao \u201chomi\u201d se ele sabe. Manoel, isso \u00e9 um t\u00f4co, ele n\u00e3o sabe n\u00e3o. Vamos mais adiante.<br \/>\nO que sabemos \u00e9 que o casal acabou por encontrar a casa do Seu Chico Antonio e contratar a Tereza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre algumas reminisc\u00eancias que tenho, apresento o casal Sr. Manoel Carvalho da Frota e a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,81],"tags":[],"class_list":["post-18872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-salmito-campos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg","jetpack-related-posts":[{"id":16493,"url":"https:\/\/correiodasemana.com\/site\/edital-para-concurso-da-guarda-municipal-de-sobral-esta-previsto-para-segundo-semestre-segundo-secretaria\/","url_meta":{"origin":18872,"position":0},"title":"Edital para concurso da Guarda Municipal de Sobral est\u00e1 previsto para segundo semestre segundo secret\u00e1ria","author":"","date":"Maio 17, 2021","format":false,"excerpt":"Por Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana Segundo a secret\u00e1ria de Seguran\u00e7a e Cidadania Emanuela Leite novo concurso para a Guarda Civil Municipal ir\u00e1 acontecer ainda em 2021. A not\u00edcia foi anunciada em programa de r\u00e1dio durante entrevista ao radialista Ara\u00fajo Pachelli na Tupinamb\u00e1 FM de Sobral Na \u00faltima segunda-feira\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Prefeitura-de-Sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Prefeitura-de-Sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Prefeitura-de-Sobral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Prefeitura-de-Sobral.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24511,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-51\/","url_meta":{"origin":18872,"position":1},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"De Olho na L\u00edngua Prof. Ant\u00f4nio da Costa Reverter o quadro A frase em ep\u00edgrafe est\u00e1 na moda. M\u00e9dicos, economistas, tecnocratas de todas as \u00e1reas e principalmente cronistas esportivos est\u00e3o a inventar uma l\u00edngua pr\u00f3pria: A asinina. Entre tantas asnices que se notam em linguagem desses profissionais, salienta-se o emprego\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":24136,"url":"https:\/\/correiodasemana.com\/site\/quando-os-pais-se-vao\/","url_meta":{"origin":18872,"position":2},"title":"Quando os Pais se V\u00e3o","author":"adminredacao","date":"Abril 17, 2023","format":false,"excerpt":"Quando os nossos pais se v\u00e3o eles nunca v\u00e3o sozinhos... Vai junto com eles as m\u00e3os estendidas, o colo para as horas dif\u00edceis, o carinho, a aten\u00e7\u00e3o e o amor incondicional. Quando Pai e M\u00e3e se v\u00e3o... Vai junto a mesa cheia, as conversas fiadas, as gargalhadas, as piadas e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Salmito-Campos.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":35879,"url":"https:\/\/correiodasemana.com\/site\/poucas-e-boas-68\/","url_meta":{"origin":18872,"position":3},"title":"POUCAS E BOAS","author":"adminredacao","date":"Outubro 13, 2025","format":false,"excerpt":"Deverzinho de casa Qu\u00e3o bom \u00e9 voc\u00ea correr os olhos sobre estas linhas e conseguir decifrar as palavras que, juntas, traduzem as ideias que tento repassar. Pena que presumo que dificilmente vem \u00e0 sua mente reconhecer a import\u00e2ncia de tamanha fa\u00e7anha: a comunica\u00e7\u00e3o atrav\u00e9s da escrita. Tamb\u00e9m \u00e9 rar\u00edssimo, nesta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12831,"url":"https:\/\/correiodasemana.com\/site\/politica-em-evidencia-33\/","url_meta":{"origin":18872,"position":4},"title":"Pol\u00edtica em Evid\u00eancia","author":"","date":"Agosto 17, 2020","format":false,"excerpt":"A partir deste s\u00e1bado dia 15 de agosto, agentes p\u00fablicos de todo o Pa\u00eds v\u00e3o estar proibidos de praticar diversas condutas devido \u00e0s elei\u00e7\u00f5es municipais, marcadas para o dia 15 de novembro. O prazo de tr\u00eas meses que antecede o primeiro turno est\u00e1 de acordo com a legisla\u00e7\u00e3o eleitoral e\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21653,"url":"https:\/\/correiodasemana.com\/site\/estatura-cidada\/","url_meta":{"origin":18872,"position":5},"title":"Estatura cidad\u00e3","author":"","date":"Novembro 13, 2022","format":false,"excerpt":"A democracia brasileira, afirma-se em consenso, \u00e9 jovem. Precisa, pois, amadurecer, consolidar conquistas, deixando-se passar pelo \u201ccadinho\u201d da purifica\u00e7\u00e3o e do crescimento, com o aprendizado de li\u00e7\u00f5es e experi\u00eancias vividas. O horizonte largo e cidad\u00e3o da Constitui\u00e7\u00e3o Federal, uma conquista nesse processo de amadurecimento, parametriza compreens\u00f5es e deve emoldurar escolhas,\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/12\/homilia-dom-vasconcelos.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18872"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18872\/revisions"}],"predecessor-version":[{"id":18873,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18872\/revisions\/18873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17116"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}