{"id":18886,"date":"2022-02-14T02:57:06","date_gmt":"2022-02-14T05:57:06","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18886"},"modified":"2022-02-14T02:57:06","modified_gmt":"2022-02-14T05:57:06","slug":"depois-da-mae-sofrer-um-ataque-cardiaco-filho-agradece-assistencia-segura-e-humanizada-do-hospital-do-coracao-de-sobral","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/depois-da-mae-sofrer-um-ataque-cardiaco-filho-agradece-assistencia-segura-e-humanizada-do-hospital-do-coracao-de-sobral\/","title":{"rendered":"Depois da m\u00e3e sofrer um ataque card\u00edaco, filho agradece assist\u00eancia segura e humanizada do Hospital do Cora\u00e7\u00e3o de Sobral"},"content":{"rendered":"<p>A paciente passou por um procedimento de cateterismo no final de janeiro, e j\u00e1 teve alta hospitalar.<\/p>\n<p>Ascom Complexo SCMS<br \/>\nA sobralense Elizete Ara\u00fajo, 60, sofreu um ataque card\u00edaco no final de janeiro, e orientado a procurar imediatamente o Hospital do Cora\u00e7\u00e3o de Sobral, seu filho, Eraldo J\u00fanior, levou a m\u00e3e at\u00e9 a institui\u00e7\u00e3o onde foi assistida pela equipe multiprofissional que proporcionou o tratamento adequado. Elizete passou por um procedimento de cateterismo, e j\u00e1 teve alta hospitalar. Eraldo agora agradece os cuidados e assist\u00eancia humanizada direcionada \u00e0 m\u00e3e.\u00a0\u201cEmbora n\u00e3o estivesse com ela, todos os dias recebia o boletim m\u00e9dico e not\u00edcias sobre sua alimenta\u00e7\u00e3o. S\u00f3 tenho a agradecer a equipe do hospital pela seguran\u00e7a que nos fortaleceu em momentos delicados. Minha m\u00e3e est\u00e1 viva, recuperada e eu e minha fam\u00edlia somos imensamente gratos por isso\u201d, destaca Eraldo.<br \/>\n\u201cMinha m\u00e3e vem passando por v\u00e1rios problemas de sa\u00fade, e por \u00faltimo, com esse infarto, busquei o Hospital do Cora\u00e7\u00e3o e fui muito bem recebido pela Dra. Fabiene Parente, que me instruiu com clareza.\u00a0 Fui recebido pela equipe do enfermeiro Carlos Leone, e agrade\u00e7o o cuidado e aten\u00e7\u00e3o em um momento t\u00e3o delicado. Sei que s\u00e3o muitos profissionais envolvidos, mas quero agradecer todos em nome da Sandra, da Brena, e do Dr. Thomas Filho, pela sua humanidade e comunica\u00e7\u00e3o clara. Ela teve de fazer cateterismo e os cuidados foram com a mesma excel\u00eancia, em nenhum momento nenhum fiquei sem not\u00edcias\u201d, relata Eraldo.<br \/>\nPara a diretora de Enfermagem da institui\u00e7\u00e3o, Dra. Fabiene Parente, o reconhecimento de pacientes e familiares, al\u00e9m de motivar a equipe, enfatiza o cumprimento da miss\u00e3o do hospital de proporcionar uma assist\u00eancia de qualidade, segura e humanizada para a popula\u00e7\u00e3o de Sobral e toda regi\u00e3o norte do estado do Cear\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A paciente passou por um procedimento de cateterismo no final de janeiro, e j\u00e1 teve&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-18886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/saude-stacasa.jpg","jetpack-related-posts":[{"id":14945,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-atinge-a-marca-de-40-mil-procedimentos-de-cateterismo-cardiaco\/","url_meta":{"origin":18886,"position":0},"title":"Hospital do Cora\u00e7\u00e3o de Sobral atinge a marca de 40 mil procedimentos de cateterismo card\u00edaco","author":"","date":"Dezembro 7, 2020","format":false,"excerpt":"A marca vem sendo computada desde 1996, ano de inaugura\u00e7\u00e3o da unidade O Hospital do Cora\u00e7\u00e3o, unidade de sa\u00fade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, chegou a 40 mil procedimentos de cateterismo card\u00edaco no m\u00eas de novembro. O \u201cpaciente n\u00famero 40 mil\u201d foi um homem de 70 anos,\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Cateterismo2.jpg.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Cateterismo2.jpg.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Cateterismo2.jpg.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Cateterismo2.jpg.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16434,"url":"https:\/\/correiodasemana.com\/site\/chanceler-do-uninta-dr-oscar-spindola-rodrigues-junior-passa-por-procedimento-cirurgico-no-hospital-do-coracao\/","url_meta":{"origin":18886,"position":1},"title":"Chanceler do UNINTA, Dr. Oscar Sp\u00edndola Rodrigues Junior passa por procedimento cir\u00fargico no Hospital do Cora\u00e7\u00e3o","author":"","date":"Maio 10, 2021","format":false,"excerpt":"Por Samuel Carvalho - Reda\u00e7\u00e3o Correio da Semana O Oscar Sp\u00edndola Rodrigues Junior, Chanceler e Fundador do UNINTA passou por procedimento cir\u00fargico bem sucedido no Hospital do Cora\u00e7\u00e3o essa semana. Em nota disponibilizada pela assessoria do Chanceler, o Reitor do Centro Universit\u00e1rio Inta (UNINTA), Prof. Dr. Daniel Rontgen Melo Sp\u00edndola\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Osca-Rodrigues.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Osca-Rodrigues.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/Osca-Rodrigues.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":10521,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-inova-no-tratamento-de-doencas-coronarianas\/","url_meta":{"origin":18886,"position":2},"title":"Hospital do Cora\u00e7\u00e3o de Sobral inova no tratamento de doen\u00e7as coronarianas","author":"","date":"Janeiro 22, 2020","format":false,"excerpt":"Na quarta-feira (15\/01), um paciente foi submetido ao procedimento, o qual comprovou que a placa de gordura, avaliada pelos m\u00e9dicos como intermedi\u00e1ria, em uma regi\u00e3o importante do cora\u00e7\u00e3o n\u00e3o ocasionava isquemia. Com o objetivo de promover uma assist\u00eancia segura e de qualidade para seus pacientes, o Hospital do Cora\u00e7\u00e3o, unidade\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/FRR-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/FRR-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/FRR-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/FRR-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14361,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-amplia-capacidade-para-realizacao-de-procedimentos-nao-cardiacos-2\/","url_meta":{"origin":18886,"position":3},"title":"Hospital do Cora\u00e7\u00e3o de Sobral amplia capacidade para realiza\u00e7\u00e3o de procedimentos n\u00e3o card\u00edacos","author":"","date":"Novembro 2, 2020","format":false,"excerpt":"A unidade tem buscado ampliar e qualificar ainda mais seus servi\u00e7os para ofertar assist\u00eancia de excel\u00eancia tamb\u00e9m aos pacientes de conv\u00eanios e particulares. Assessoria de Comunica\u00e7\u00e3o do Complexo SCMS O Hospital do Cora\u00e7\u00e3o, unidade de sa\u00fade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, concluiu neste m\u00eas a reforma em\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/padre-joao-Frota-esta-internado.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/padre-joao-Frota-esta-internado.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/padre-joao-Frota-esta-internado.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/padre-joao-Frota-esta-internado.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/padre-joao-Frota-esta-internado.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14337,"url":"https:\/\/correiodasemana.com\/site\/hospital-do-coracao-de-sobral-amplia-capacidade-para-realizacao-de-procedimentos-nao-cardiacos\/","url_meta":{"origin":18886,"position":4},"title":"Hospital do Cora\u00e7\u00e3o de Sobral amplia capacidade para realiza\u00e7\u00e3o de procedimentos n\u00e3o card\u00edacos","author":"","date":"Outubro 29, 2020","format":false,"excerpt":"O Hospital do Cora\u00e7\u00e3o, unidade de sa\u00fade do Complexo Santa Casa de Miseric\u00f3rdia de Sobral, concluiu neste m\u00eas a reforma em uma de suas salas de cirurgia. A inten\u00e7\u00e3o foi ampliar o espa\u00e7o, possibilitando assim a realiza\u00e7\u00e3o de procedimentos cir\u00fargicos e cl\u00ednicos n\u00e3o card\u00edacos, como: cirurgia pl\u00e1stica, urol\u00f3gica, vascular, tor\u00e1cica,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/2.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17247,"url":"https:\/\/correiodasemana.com\/site\/em-visita-ao-hospital-do-coracao-de-sobral-ministro-da-saude-participa-de-procedimento-no-servico-de-hemodinamica-da-instituicao\/","url_meta":{"origin":18886,"position":5},"title":"Em visita ao Hospital do Cora\u00e7\u00e3o de Sobral, Ministro da Sa\u00fade participa de procedimento no servi\u00e7o de Hemodin\u00e2mica da Institui\u00e7\u00e3o","author":"","date":"Agosto 15, 2021","format":false,"excerpt":"Em toda a hist\u00f3ria da unidade,\u00a0\u00a0Marcelo Queiroga foi o primeiro Ministro da Sa\u00fade a visitar a Institui\u00e7\u00e3o. O Hospital do Cora\u00e7\u00e3o de Sobral recebeu, nesta quinta-feira (12\/08), o Ministro da Sa\u00fade Dr. Marcelo Queiroga. O gestor conheceu os servi\u00e7os prestados pela Institui\u00e7\u00e3o que \u00e9 refer\u00eancia em procedimentos cardiol\u00f3gicos para 55\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/08\/Foto-2-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18886"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18886\/revisions"}],"predecessor-version":[{"id":18888,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18886\/revisions\/18888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18887"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}