{"id":18914,"date":"2022-02-14T03:09:00","date_gmt":"2022-02-14T06:09:00","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=18914"},"modified":"2022-02-14T03:09:00","modified_gmt":"2022-02-14T06:09:00","slug":"a-igreja-perante-o-mundo-atual-3","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/a-igreja-perante-o-mundo-atual-3\/","title":{"rendered":"A Igreja perante o mundo atual"},"content":{"rendered":"<p>N\u00e3o \u00e9 novidade para ningu\u00e9m que a humanidade est\u00e1 em um tempo novo. S\u00e3o in\u00fameras as mudan\u00e7as e revolu\u00e7\u00f5es tecnol\u00f3gicas, acompanhadas tamb\u00e9m de desafios e problemas a serem resolvidos. Diante de tantas crises, surgem novas exig\u00eancias para a Igreja, chamada a interpretar os sinais dos tempos sem abandonar aquilo que comp\u00f5em a sua identidade.<br \/>\nA mensagem do Evangelho \u00e9 sempre antiga e sempre nova. O desafio \u00e9 atualiz\u00e1-la \u00e0 luz da modernidade sem descaracteriz\u00e1-la ou torn\u00e1-la menos exigente. J\u00e1 que o mundo est\u00e1 se tornando plural, a Igreja de Cristo deve permanecer fiel ao seu divino Fundador, enfrentando o mart\u00edrio da ridiculariza\u00e7\u00e3o e tornando-se, muitas vezes, inconveniente para a maioria.<br \/>\nIsso foi muito bem compreendido pelo Papa Jo\u00e3o XXIII ao convocar o Conc\u00edlio Vaticano II, entendendo que a Igreja n\u00e3o deve permanecer, e nunca permaneceu, inerte aos acontecimentos do mundo. Tanto ontem como hoje, a Igreja ergue sua voz prof\u00e9tica, marcando a coer\u00eancia da pr\u00f3pria f\u00e9, sofrendo persegui\u00e7\u00f5es e revelando o hero\u00edsmo de muitos crist\u00e3os.<br \/>\nN\u00e3o se pode construir uma ordem temporal prescindindo-se de Deus. A sociedade moderna caracteriza-se por um grande progresso material ao qual n\u00e3o corresponde igual progresso no campo moral. Por isso, devemos trazer sempre as for\u00e7as vivificantes e renovadoras do Evangelho.<br \/>\n\u00c9 consolador perceber que, ao passo que o mundo aparece profundamente mudado, a comunidade crist\u00e3 tamb\u00e9m ficou em grande parte renovada e transformada e em momento algum deixou de ser aquilo que ela \u00e9. Nunca abandonou o seu apostolado.<br \/>\nTal fato foi definido pelo Papa Jo\u00e3o XXIII, ao convocar o conc\u00edlio, de um duplo espet\u00e1culo: \u201cum mundo que revela um grave estado de indig\u00eancia espiritual, e a Igreja de Cristo, t\u00e3o vibrante de vitalidade\u201d. \u00c9 o pr\u00f3prio Cristo que constantemente injeta sangue novo nas veias de sua Igreja.<br \/>\nPortanto, a Igreja, dialogando com a humanidade atual, permanece a mesma, santificando o mundo e consolidando suas estruturas. As Sagradas Escrituras, a santa Tradi\u00e7\u00e3o e o venerado Magist\u00e9rio continuam a enriquecer a f\u00e9 e a doutrina cat\u00f3licas. Bendita seja esta miss\u00e3o: antiga, jovial e eterna!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o \u00e9 novidade para ningu\u00e9m que a humanidade est\u00e1 em um tempo novo. S\u00e3o in\u00fameras&#8230;<\/p>\n","protected":false},"author":1,"featured_media":75,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,20],"tags":[],"class_list":["post-18914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg","jetpack-related-posts":[{"id":10978,"url":"https:\/\/correiodasemana.com\/site\/a-igreja-perante-o-mundo-atual-2\/","url_meta":{"origin":18914,"position":0},"title":"A Igreja perante o mundo atual","author":"","date":"Fevereiro 25, 2020","format":false,"excerpt":"N\u00e3o \u00e9 novidade para ningu\u00e9m que a humanidade est\u00e1 em um tempo novo. S\u00e3o in\u00fameras as mudan\u00e7as e revolu\u00e7\u00f5es tecnol\u00f3gicas, acompanhadas tamb\u00e9m de desafios e problemas a serem resolvidos. Diante de tantas crises, surgem novas exig\u00eancias para a Igreja, chamada a interpretar os sinais dos tempos sem abandonar aquilo que\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9155,"url":"https:\/\/correiodasemana.com\/site\/a-igreja-perante-o-mundo-atual\/","url_meta":{"origin":18914,"position":1},"title":"A Igreja perante o mundo atual","author":"","date":"Setembro 15, 2019","format":false,"excerpt":"N\u00e3o \u00e9 novidade para ningu\u00e9m que a humanidade est\u00e1 em um tempo novo. S\u00e3o in\u00fameras as mudan\u00e7as e revolu\u00e7\u00f5es tecnol\u00f3gicas, acompanhadas tamb\u00e9m de desafios e problemas a serem resolvidos. Diante de tantas crises, surgem novas exig\u00eancias para a Igreja, chamada a interpretar os sinais dos tempos sem abandonar aquilo que\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23984,"url":"https:\/\/correiodasemana.com\/site\/ressurreicao-e-vida\/","url_meta":{"origin":18914,"position":2},"title":"RESSURREI\u00c7\u00c3O E VIDA","author":"adminredacao","date":"Abril 11, 2023","format":false,"excerpt":"\u201cD\u00e1-me de beber uma \u00e1gua viva!\u201d \u201cEu sou a luz do mundo!\u201d \u201cEu sou a ressurrei\u00e7\u00e3o e a vida!\u201d Todos n\u00f3s, envolvidos na prepara\u00e7\u00e3o da P\u00e1scoa, somos chamados ao novo encontro com Jesus Cristo, nossa P\u00e1scoa, nossa esperan\u00e7a. A partir de \u00e2ngulos diferentes, todos caminhamos para ele, a fim de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33753,"url":"https:\/\/correiodasemana.com\/site\/a-missao-da-igreja\/","url_meta":{"origin":18914,"position":3},"title":"A miss\u00e3o da Igreja","author":"adminredacao","date":"Maio 12, 2025","format":false,"excerpt":"Dois mil\u00eanios se passaram desde a Encarna\u00e7\u00e3o do Verbo de Deus, e a Igreja permanece fiel ao mandato mission\u00e1rio de seu Mestre e Senhor. No transcorrer dos s\u00e9culos, ela continua a atualizar a mensagem do Evangelho, sendo um sinal da salva\u00e7\u00e3o que Deus oferece ao mundo. O discipulado se destaca\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":33955,"url":"https:\/\/correiodasemana.com\/site\/leao-xiv-inicia-seu-ministerio-e-a-hora-do-amor-olhem-para-cristo-e-aproximem-se-dele\/","url_meta":{"origin":18914,"position":4},"title":"Le\u00e3o XIV inicia seu minist\u00e9rio: \u201c\u00c9 a hora do amor! Olhem para Cristo e aproximem-se Dele\u201d","author":"adminredacao","date":"Junho 3, 2025","format":false,"excerpt":"\u201cFui escolhido sem qualquer m\u00e9rito e, com temor e tremor, venho at\u00e9 voc\u00eas como um irm\u00e3o que deseja fazer-se servo da f\u00e9 e da alegria\u201d, disse Le\u00e3o XIV na missa de in\u00edcio de pontificado. O Santo Padre expressou o desejo de uma Igreja unida, que seja fermento para um mundo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/primeira-missa-Papa-Leao-XIV-4.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/primeira-missa-Papa-Leao-XIV-4.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/primeira-missa-Papa-Leao-XIV-4.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/primeira-missa-Papa-Leao-XIV-4.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/primeira-missa-Papa-Leao-XIV-4.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":33595,"url":"https:\/\/correiodasemana.com\/site\/tempo-de-discernimento-e-obediencia\/","url_meta":{"origin":18914,"position":5},"title":"Tempo de discernimento e obedi\u00eancia","author":"adminredacao","date":"Maio 5, 2025","format":false,"excerpt":"Ap\u00f3s a Ressurrei\u00e7\u00e3o e Ascens\u00e3o de Jesus e a descida do Esp\u00edrito Santo, no Pentecostes, come\u00e7ou a maravilhosa aventura da Igreja, chamada por Deus e atuar como sal, luz e fermento na sociedade. Os Atos dos Ap\u00f3stolos retratam a vida das primeiras Comunidades, com os percal\u00e7os havidos no confronto com\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=18914"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18914\/revisions"}],"predecessor-version":[{"id":18915,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/18914\/revisions\/18915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=18914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=18914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=18914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}