{"id":19149,"date":"2022-03-14T00:47:28","date_gmt":"2022-03-14T03:47:28","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19149"},"modified":"2022-03-14T00:47:28","modified_gmt":"2022-03-14T03:47:28","slug":"de-olho-na-lingua-49","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-49\/","title":{"rendered":"De Olho na L\u00edngua"},"content":{"rendered":"<p><strong>Cliente ou fregu\u00eas (Qual a diferen\u00e7a?)<\/strong><br \/>\nCliente \u00e9 a pessoa que utiliza os servi\u00e7os de um profissional liberal. Fregu\u00eas \u00e9 aquele que frequentemente compra coisas numa mesma loja, num mesmo armaz\u00e9m, num mesmo supermercado, etc. ou aquele que costuma ir sempre ao mesmo bar, restaurante, etc. A palavra \u00e9 estrita ao com\u00e9rcio, seja legal, seja ilegal.<\/p>\n<p><strong>Dolo (\u00f3) \u2013 Incesto (\u00e9)<\/strong><br \/>\nA palavra dolo (\u00f3), a qual significa ato consciente, ou inten\u00e7\u00e3o, com que se induz, mant\u00e9m ou confirma outrem num erro, m\u00e1-f\u00e9, tem o primeiro \u201c\u00f3\u201d bem aberto. Ex.: N\u00e3o houve dolo (\u00f3) naquela atitude. Incesto (\u00e9) significa uni\u00e3o il\u00edcita&#8230; A pron\u00fancia do \u2018e\u2019 aberta. N\u00e3o tem nada a ver com cesto. No Portugu\u00eas contempor\u00e2neo essas pron\u00fancias n\u00e3o s\u00e3o seguidas \u00e0 risca.<\/p>\n<p><strong>Missa de S\u00e9timo Dia (Texto completo)<\/strong><br \/>\nApesar de ser assim anunciada, a express\u00e3o casti\u00e7a \u00e9: Missa do s\u00e9timo dia. Quando o substantivo \u00e9 determinado, usa-se o artigo obrigatoriamente. Ademais, antes de numeral ordinal n\u00e3o se deixa de empregar o artigo. Exs.: Comi o segundo bife; Estamos no s\u00e9timo andar; Procure ler o quarto cap\u00edtulo. Por isso \u00e9 que temos de usar o artigo, ainda nessas express\u00f5es: Comemora\u00e7\u00f5es do primeiro anivers\u00e1rio; Missa do trig\u00e9simo dia; Supletivo do Primeiro e do Segundo Graus (Grau), al\u00e9m de outras. Pois, ent\u00e3o, n\u00e3o se diz \u201cmissa do primeiro anivers\u00e1rio, missa do s\u00e9timo anivers\u00e1rio?\u2019\u2019 Por que, ent\u00e3o, dizer \u201cmissa de s\u00e9timo dia?\u201d Deixemos, contudo, esses acontecimentos do s\u00e9timo dia e passemos a outro, menos triste.<\/p>\n<p><strong>Goleada (O que \u00e9 exatamente?)<\/strong><br \/>\nGoleada \u00e9 uma vit\u00f3ria por diferen\u00e7a igual ou superior a tr\u00eas gols. Por exemplo, quando o Santos vence o S\u00e3o Paulo por 4 a 1. Outro exemplo, quando o Palmeiras vence o Corinthians por 4 a 1; quando o Palmeiras \u00e9 derrotado pelo Vit\u00f3ria por 2 a 7. Mas uma vit\u00f3ria por 4 a 3 do Corinthians n\u00e3o \u00e9 goleada, nem uma de 5 a 4. Muitos jornalistas esportivos pensam que goleada \u00e9 a feitura de muitos gois numa partida, independentemente da diferen\u00e7a no placar. Est\u00e1 certo que pensar n\u00e3o ofende, mas que aborrece, ah!, isso aborrece! A goleada, senhores jornalistas esportivos, est\u00e1 na diferen\u00e7a, e n\u00e3o na quantidade.<\/p>\n<p><strong>Qual a pron\u00fancia correta de Watt?<\/strong><br \/>\n\u00c9 \u201cu\u00f3t\u201d, embora muitos insistam em dizer \u201cv\u00e1t\u201d. Estamos cansados de ouvir locutores e rep\u00f3rteres dizerem que suas emissoras possuem pot\u00eancia de mil v\u00e1ts. Alguns t\u00eam a coragem de dizer \u201cu\u00e1ts\u201d.<\/p>\n<p><strong>Chocalhar &#8211; Chacoalhar<\/strong><br \/>\nChocalhar vem de chocalho. Quem diz \u201cchacoalhar\u201d (Ou: Dar uma chacoalhada) est\u00e1 usando uma forma variante coloquial. A forma original \u00e9 chocalhar (Agitar, sacudir, aborrecer). Deriva-se de chocalho e significa tamb\u00e9m \u201ctocar chocalho\u201d.<\/p>\n<p><strong>\u201cEu pare\u00e7o muito com voc\u00ea\u201d (H\u00e1 impropriedade na frase?)<\/strong><br \/>\nH\u00e1, sim. O verbo parecer, nesse caso, \u00e9 pronominal, por isso n\u00e3o dispensa a companhia do pronome obl\u00edquo. Assim, sem impropriedade a frase fica desta forma: Eu me pare\u00e7o muito com voc\u00ea. Veja que constru\u00edmos assim: \u201cN\u00f3s nos parecemos muito\u201d, sempre usando o pronome.<\/p>\n<p>(*)\u00a0Professor Ant\u00f4nio da Costa \u00e9 graduado em Letras Plenas, com Especializa\u00e7\u00e3o em L\u00edngua Portuguesa e Literatura, na Universidade Estadual Vale do Acara\u00fa (UVA). Contatos: (88) 99373-7724.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cliente ou fregu\u00eas (Qual a diferen\u00e7a?) Cliente \u00e9 a pessoa que utiliza os servi\u00e7os de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,12],"tags":[],"class_list":["post-19149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-de-olho-na-lingua"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg","jetpack-related-posts":[{"id":24511,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-51\/","url_meta":{"origin":19149,"position":0},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"De Olho na L\u00edngua Prof. Ant\u00f4nio da Costa Reverter o quadro A frase em ep\u00edgrafe est\u00e1 na moda. M\u00e9dicos, economistas, tecnocratas de todas as \u00e1reas e principalmente cronistas esportivos est\u00e3o a inventar uma l\u00edngua pr\u00f3pria: A asinina. Entre tantas asnices que se notam em linguagem desses profissionais, salienta-se o emprego\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":32582,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-116\/","url_meta":{"origin":19149,"position":1},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Fevereiro 18, 2025","format":false,"excerpt":"Caso hajam (ou haja?) problemas, chamaremos o diretor. A constru\u00e7\u00e3o correta \u00e9: Caso haja problemas, chamaremos o diretor. O verbo haver, quando empregado na acep\u00e7\u00e3o de existir, ocorrer ou acontecer, \u00e9 impessoal, n\u00e3o admite flex\u00e3o. Exs.: Ci\u00fames havia na rela\u00e7\u00e3o deles; Diverg\u00eancias jamais haver\u00e1 entre n\u00f3s; Costuma haver situa\u00e7\u00f5es delicadas;\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9762,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-19\/","url_meta":{"origin":19149,"position":2},"title":"De Olho na L\u00edngua","author":"","date":"Novembro 11, 2019","format":false,"excerpt":"Utiliza\u00e7\u00e3o do adjetivo \u201cmesmo\u201d O adjetivo mesmo concorda ou flexiona-se de acordo com o g\u00eanero e n\u00famero das pessoas por ele representadas. Ele modifica os pronomes pessoais eu, tu, n\u00f3s e v\u00f3s. Exs.: Eu mesmo fiz (afirma\u00e7\u00e3o do homem); Ela mesma fez (afirma\u00e7\u00e3o de mulher); N\u00f3s mesmos publicamos (v\u00e1rios homens);\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":32084,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-112\/","url_meta":{"origin":19149,"position":3},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Janeiro 15, 2025","format":false,"excerpt":"Mandato e mandado As duas palavras v\u00eam do Latim \u201cmandatum\u201d, ordem, mas t\u00eam significados diferentes. MANDADO - ordem escrita emanada de autoridade judicial ou administrativa: Mandado de busca e apreens\u00e3o; mandado de cita\u00e7\u00e3o; mandado de pris\u00e3o. MANDATO - autoriza\u00e7\u00e3o que uma pessoa (o mandante) confere a outra (mandat\u00e1rio, procurador, advogado)\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":33655,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-120\/","url_meta":{"origin":19149,"position":4},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Maio 5, 2025","format":false,"excerpt":"Minha opini\u00e3o \u201cpessoal\u201d Frase comu m e corriqueira na imprensa e at\u00e9 usada por pessoas formadas. Mas \u00e9 vis\u00edvel a redund\u00e2ncia. Ora, se a opini\u00e3o \u00e9 minha, s\u00f3 pode ser pessoal. Dolo (Como se pronuncia?) \u00c9 aberto o timbre da vogal t\u00f4nica dessa palavra: D\u00d3LO. Com a conclus\u00e3o do inqu\u00e9rito\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27845,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-74\/","url_meta":{"origin":19149,"position":5},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Dezembro 26, 2023","format":false,"excerpt":"Cateter \u00c9 palavra ox\u00edtona, isto \u00e9, a s\u00edlaba t\u00f4nica \u00e9 a \u00faltima (ter). N\u00e3o leva acento porque \u00e9 palavra ox\u00edtona terminada em \u201cr\u201d. \u00c9 termo de medicina que designa tubo de baixo calibre que se introduz no corpo, especialmente em a\u00e7\u00f5es diagn\u00f3sticas ou terap\u00eauticas. Ex.: N\u00e3o se usa gaze na\u2026","rel":"","context":"In &quot;De olho na l\u00edngua&quot;","block_context":{"text":"De olho na l\u00edngua","link":"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19149"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19149\/revisions"}],"predecessor-version":[{"id":19150,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19149\/revisions\/19150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17923"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}