{"id":19176,"date":"2022-03-14T01:05:59","date_gmt":"2022-03-14T04:05:59","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19176"},"modified":"2022-03-14T01:08:35","modified_gmt":"2022-03-14T04:08:35","slug":"becco-ponto-com-76","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-76\/","title":{"rendered":"Becco ponto Com"},"content":{"rendered":"<p><strong>Livrai-nos, Senhor!<\/strong><br \/>\nDesta guerra globalizada econ\u00f4mica.<br \/>\nDa f\u00e1brica de fazer loucuras internet.<br \/>\nDas mil\u00edcias movendo as drogas no CE.<br \/>\nDos petistas voltando luladr\u00f5es, ufa!<br \/>\nDos mitos fabricados em gabinetes.<br \/>\nDo cartel da gasolina atacando aqui.<br \/>\nDas faculdades formando analfas, ui!<br \/>\nDos puxas-sacos de plant\u00e3o na cidade.<br \/>\nDa invas\u00e3o de drogados na cidade, ui!<br \/>\nDa volta da pol\u00edtica do medo aqui e j\u00e1!<\/p>\n<p><strong>Noticiando<\/strong><br \/>\nFoi uma perda irrepar\u00e1vel a morte do caro Paulo Roberto Arag\u00e3o, um digno profissional do r\u00e1dio nesta semana. A fam\u00edlia enlutada e boa conforma\u00e7\u00e3o em nome de Deus.<br \/>\nFoi sucesso total da festa da Revista Alternativa que homenageou dia 08, treze mulheres de fibra da cidade. As dignas, parab\u00e9ns, por seu dia especial!<br \/>\nEstarei estreando o programa \u201cBecco do Cotovelo\u201d neste domingo das 7 \u00e0s 08h da manh\u00e3 no prefixo Educadora do Nordeste FM 107,5, com aval do grande Padre Lucas, diretor maior da Emissora cat\u00f3lica de Sobral. Ser\u00e1 de responsabilidade do Centro Cultural Dom Jos\u00e9 de Sobral. Ou\u00e7am amigos!<br \/>\nQuem esteve mudando de idade foi o caro Chanceler Oscar Rodrigues, dia 08, comemorado em grande estilo nas Faculdades UNinta, por m\u00e9ritos. Ao caro, felicidades e muitos anos de vida.<br \/>\nDia 21, vem a Inaugura\u00e7\u00e3o da nova FM de Sobral (Educadora 107,5) com o Pe. Lucas na dire\u00e7\u00e3o desta emissora de f\u00e9 e coragem na cidade. Salve o r\u00e1dio!<\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-19178\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/DR-AZEVEDO2-300x278.png\" alt=\"\" width=\"300\" height=\"278\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/DR-AZEVEDO2-300x278.png 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/DR-AZEVEDO2-768x712.png 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/DR-AZEVEDO2.png 782w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>PERFIL: DR. FRANCISCO AZEVEDO<\/strong><br \/>\nUm cidad\u00e3o com todas as letras, digno m\u00e9dico sobralense, cirurgi\u00e3o de m\u00e3o cheia, um bom car\u00e1ter e amado amante da cidade. Falo do caro amigo do Becco, Dr. Azevedo, que hoje, por m\u00e9ritos e figura como o perfil da semana.<br \/>\nLivre pensar: \u201cA mulher \u00e9 o sal do mundo, como a flor a do\u00e7ura da vida\u201d. (Chico Prado &#8211; Poeta e escritor)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Livrai-nos, Senhor! Desta guerra globalizada econ\u00f4mica. Da f\u00e1brica de fazer loucuras internet. Das mil\u00edcias movendo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg","jetpack-related-posts":[{"id":18376,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-66\/","url_meta":{"origin":19176,"position":0},"title":"Becco ponto Com","author":"","date":"Dezembro 20, 2021","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Das faculdades ca\u00e7a-n\u00edqueis pagou passou as bodegas de candos. Dos bab\u00f5es contumazes na pol\u00edtica\u00a0t\u00e3o nossa\u00a0os z\u00e9s bolachinhas. Dos forasteiros do voto invadindo\u00a0Sobral\u00a0no papo na hora do voto. Das figuras importadas e importantes sem import\u00e2ncia alguma aqui. Da viol\u00eancia\u00a0matando todos\u00a0os dias na escalada\u00a0da droga pol\u00edtica. Do filhos da puta\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23994,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-117\/","url_meta":{"origin":19176,"position":1},"title":"Becco ponto com","author":"adminredacao","date":"Abril 11, 2023","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Dos bazares chiques vendendo molambos na pista. Das ruas invadidas por sem tetos e drogados, ui! Da moda na pol\u00edtica (faz um l e se lasca). Ufa, Brasil Da ruma de trof\u00e9us entregues na cidade. O festival! Do Becco invadido por drogas e drogados doidos! Dos puxa-sacos bab\u00f5es\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":28191,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-155\/","url_meta":{"origin":19176,"position":2},"title":"Becco Ponto Com","author":"adminredacao","date":"Janeiro 29, 2024","format":false,"excerpt":"LIVRAI-NOS, SENHOR! Do Guarany ser vendido como banana. Da gula por impostos: \u201csubiram a \u00e1gua\u201d. Da ruma de forasteiros na pista 2024. Do choro falso dos pol\u00edticos camilos. Das f\u00e1bricas de fabricarem doutores. Da fila dos ex-vereadores: \u201cvou voltar\u201d. Do Becco, virando uma cracol\u00e2ndia, ui! Dos gatunos da pol\u00edtica dando\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":23796,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-116\/","url_meta":{"origin":19176,"position":3},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Abril 5, 2023","format":false,"excerpt":"Livrai-nos, senhor! Das investidas pol\u00edticas de ocasi\u00e3o com acordos esp\u00farios. Das famosas festas hits puxados a drogas e drogados, ui! Das falas falsas dos peitistas buscando a volta ao poder. Do abandono eterno do famoso Becco do Cotovelo, aqui. Do festival de molambos nas cal\u00e7adas e nas butiques, ufa! Do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26087,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-133\/","url_meta":{"origin":19176,"position":4},"title":"Becco Ponto Com","author":"adminredacao","date":"Agosto 14, 2023","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. dos candidatos buchas dos distritos. 02. Da ruma de cursos modernos hoje, ui! 03. Da matan\u00e7a de \u00edndios na Amaz\u00f4nia, ui! 04. Da f\u00e1brica de diplomas nos governos. 05. Da invas\u00e3o de sem tetos na cidade, Ufa! 06. Do Lulismo invadindo a democracia. 07. Do abandono do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26219,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-134\/","url_meta":{"origin":19176,"position":5},"title":"Becco Ponto Com","author":"adminredacao","date":"Agosto 21, 2023","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. dos candidatos buchas dos distritos. 02. Da ruma de cursos modernos hoje, ui! 03. Da matan\u00e7a de \u00edndios na Amaz\u00f4nia, ui! 04. Da f\u00e1brica de diplomas nos governos. 05. Da invas\u00e3o de sem tetos na cidade, ufa! 06. Do Lulismo invadindo a democracia. 07. Do abandono do\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19176"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19176\/revisions"}],"predecessor-version":[{"id":19179,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19176\/revisions\/19179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17508"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}