{"id":19265,"date":"2022-03-20T23:46:14","date_gmt":"2022-03-21T02:46:14","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19265"},"modified":"2022-03-20T23:46:14","modified_gmt":"2022-03-21T02:46:14","slug":"a-igreja-e-a-educacao-integral","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/a-igreja-e-a-educacao-integral\/","title":{"rendered":"A Igreja e a educa\u00e7\u00e3o integral"},"content":{"rendered":"<p>\u201cA educa\u00e7\u00e3o \u00e9 um ato de amor e esperan\u00e7a no ser humano\u201d. Essa frase retirada do texto-base da Campanha da Fraternidade (CF) 2022, produzido pela CNBB, aponta-nos para o car\u00e1ter humanizador da educa\u00e7\u00e3o, defendido pela Igreja nesta Campanha. Em uma sociedade, muitas vezes violenta e injusta, surge a necessidade de uma educa\u00e7\u00e3o que deposite amor e esperan\u00e7a no ser humano.<br \/>\nDesse modo, o princ\u00edpio de uma educa\u00e7\u00e3o integral diz respeito ao valor da pessoa, orientando-a no caminho de uma vida transformada. Da mesma forma que a f\u00e9 da Igreja apregoa uma salva\u00e7\u00e3o integral do homem, que atinge a pessoa no seu todo, em todas as suas dimens\u00f5es na concretude da hist\u00f3ria, a educa\u00e7\u00e3o tamb\u00e9m deve assumir esse papel de formar o homem todo.<br \/>\nIsso supera o fato de que muitas vezes o ensino \u00e9 oferecido com meros objetivos utilit\u00e1rios. Nesse sentido, o diagn\u00f3stico que se faz \u00e9 que o sistema de ensino muitas vezes objetiva apenas transformar o aluno em algu\u00e9m \u00fatil para o mercado de trabalho. N\u00e3o \u00e9 uma forma\u00e7\u00e3o voltada para o desenvolvimento de potencialidades, amadurecimento de rela\u00e7\u00f5es e para a\u00e7\u00f5es concretas de transforma\u00e7\u00e3o.<br \/>\n\u00c9 por isso que, nesta CF, a Igreja reflete sobre a educa\u00e7\u00e3o e sobre o curr\u00edculo do nosso tempo. \u201cN\u00e3o devemos perceb\u00ea-lo como algo que deve ser transformado somente em conte\u00fado escolar, provas e testes, mas em um conte\u00fado de vida\u201d (Texto-base). Esse conte\u00fado da vida inclui a cidadania, as rela\u00e7\u00f5es sociais, o trabalho pela justi\u00e7a e pela paz.<br \/>\nAssim, a educa\u00e7\u00e3o n\u00e3o deve ser entendida como um ato isolado do ambiente escolar, mas \u00e9 tarefa e miss\u00e3o da fam\u00edlia, da Igreja, das organiza\u00e7\u00f5es sociais, da pr\u00f3pria pessoa. A educa\u00e7\u00e3o integral abarca a integralidade da pessoa e a integralidade da sociedade, trazendo quest\u00f5es econ\u00f4micas, sociais, culturais e religiosas. A escola deve ser um ambiente de abertura e de integra\u00e7\u00e3o entre as v\u00e1rias esferas da sociedade.<br \/>\nAl\u00e9m disso, a educa\u00e7\u00e3o integral enriquece o horizonte existencial das pessoas e desenvolve sua capacidade criativa. S\u00e3o diversos os meios que elevam o esp\u00edrito humano, como as artes, a literatura, o teatro, a m\u00fasica, a dan\u00e7a, as diversas express\u00f5es da cultura de cada lugar. Desprezar esses meios e sua linguagem, na educa\u00e7\u00e3o, \u00e9 o mesmo que desprezar as capacidades humanas em seus diversos potenciais.<br \/>\nPortanto, a Igreja deseja promover e apoiar uma educa\u00e7\u00e3o humanizadora, que forme o ser humano em todas as suas dimens\u00f5es e inserido em sua realidade social. Isso se faz com pr\u00e1ticas pedag\u00f3gicas que coloquem a pessoa no centro das rela\u00e7\u00f5es, acolhendo as necessidades de todas as crian\u00e7as, jovens e adultos, apontando-lhes orienta\u00e7\u00f5es de vida, de fraternidade, de empatia e de solidariedade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA educa\u00e7\u00e3o \u00e9 um ato de amor e esperan\u00e7a no ser humano\u201d. Essa frase retirada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":75,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,20],"tags":[],"class_list":["post-19265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-editorial"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg","jetpack-related-posts":[{"id":19398,"url":"https:\/\/correiodasemana.com\/site\/educacao-catolica\/","url_meta":{"origin":19265,"position":0},"title":"Educa\u00e7\u00e3o cat\u00f3lica","author":"","date":"Abril 3, 2022","format":false,"excerpt":"A Igreja Cat\u00f3lica convida a sociedade, com a Campanha da Fraternidade 2022, a discernir sobre novos caminhos para a educa\u00e7\u00e3o, pilar fundamental da paz e do desenvolvimento integral. Esta \u00e9 a terceira vez em quase seis d\u00e9cadas que reflex\u00f5es sobre Fraternidade e Educa\u00e7\u00e3o inspiram a viv\u00eancia da Quaresma. O tempo\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18912,"url":"https:\/\/correiodasemana.com\/site\/educacao-pilar-da-paz\/","url_meta":{"origin":19265,"position":1},"title":"EDUCA\u00c7\u00c3O, PILAR DA PAZ","author":"","date":"Fevereiro 14, 2022","format":false,"excerpt":"A educa\u00e7\u00e3o \u00e9 pilar da paz, sublinha o Papa Francisco, na oportuna mensagem para o Dia Mundial da Paz. O reconhecimento da import\u00e2ncia do campo educacional leva, imediatamente, a um lamento: no Brasil e em outros pa\u00edses, os investimentos na educa\u00e7\u00e3o t\u00eam diminu\u00eddo consideravelmente.\u00a0 N\u00e3o priorizar esses investimentos \u00e9 sinal\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19205,"url":"https:\/\/correiodasemana.com\/site\/a-igreja-no-caminho-da-educacao\/","url_meta":{"origin":19265,"position":2},"title":"A Igreja no caminho da educa\u00e7\u00e3o","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"A Quaresma \u00e9 o tempo lit\u00fargico, por excel\u00eancia, do convite \u00e0 convers\u00e3o. Um convite \u00e0 transforma\u00e7\u00e3o interior que possui uma dimens\u00e3o pessoal e social, individual e, ao mesmo tempo, coletiva. \u00c9 nesse sentido que a espiritualidade quaresmal \u00e9 enriquecida, no contexto brasileiro, com a viv\u00eancia da Campanha da Fraternidade (CF).\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":25242,"url":"https:\/\/correiodasemana.com\/site\/junho-verde-pela-vida-da-mae-terra\/","url_meta":{"origin":19265,"position":3},"title":"Junho Verde: pela vida da M\u00e3e Terra","author":"adminredacao","date":"Junho 19, 2023","format":false,"excerpt":"O m\u00eas de junho em nosso pa\u00eds, al\u00e9m de ser caracterizado pelas tradicionais festividades dos santos juninos, \u00e9 tamb\u00e9m o per\u00edodo de uma campanha de suma import\u00e2ncia: a Campanha Junho Verde. O objetivo \u00e9 desenvolver o entendimento da popula\u00e7\u00e3o acerca da conserva\u00e7\u00e3o dos ecossistemas naturais e do combate a toda\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19263,"url":"https:\/\/correiodasemana.com\/site\/fala-com-sabedoria\/","url_meta":{"origin":19265,"position":4},"title":"Fala com sabedoria","author":"","date":"Mar\u00e7o 20, 2022","format":false,"excerpt":"\u201cFala com sabedoria\u201d, preciosa indica\u00e7\u00e3o da literatura sapiencial na tradi\u00e7\u00e3o da Sagrada Escritura, \u00e9 uma arte espiritual e humana que requer dedica\u00e7\u00e3o \u00e0 sua aprendizagem. Uma express\u00e3o que inspira, especialmente, o caminho quaresmal deste ano com a Campanha da Fraternidade 2022, de tema Fraternidade e Educa\u00e7\u00e3o. \u00a0A aprendizagem necess\u00e1ria para\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19473,"url":"https:\/\/correiodasemana.com\/site\/fala-com-sabedoria-2\/","url_meta":{"origin":19265,"position":5},"title":"Fala com sabedoria","author":"","date":"Abril 10, 2022","format":false,"excerpt":"\u201cFala com sabedoria\u201d, preciosa indica\u00e7\u00e3o da literatura sapiencial na tradi\u00e7\u00e3o da Sagrada Escritura, \u00e9 uma arte espiritual e humana que requer dedica\u00e7\u00e3o \u00e0 sua aprendizagem. Uma express\u00e3o que inspira, especialmente, o caminho quaresmal deste ano com a Campanha da Fraternidade 2022, de tema Fraternidade e Educa\u00e7\u00e3o. \u00a0A aprendizagem necess\u00e1ria para\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19265"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19265\/revisions"}],"predecessor-version":[{"id":19266,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19265\/revisions\/19266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}