{"id":19333,"date":"2022-04-03T19:41:58","date_gmt":"2022-04-03T22:41:58","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19333"},"modified":"2022-04-03T19:41:58","modified_gmt":"2022-04-03T22:41:58","slug":"cerimonia-de-transmissao-de-cargo-de-camilo-santana-para-izolda-cela-acontece-neste-sabado-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/cerimonia-de-transmissao-de-cargo-de-camilo-santana-para-izolda-cela-acontece-neste-sabado-2\/","title":{"rendered":"Cerim\u00f4nia de transmiss\u00e3o de cargo de Camilo Santana para Izolda Cela acontece neste s\u00e1bado (2)"},"content":{"rendered":"<p>A solenidade de transmiss\u00e3o de cargo do governador Camilo Santana (PT) para a vice-governadora Izolda Cela (PDT) ocorre neste s\u00e1bado (2), \u00e0s 17 horas, no Pal\u00e1cio Aboli\u00e7\u00e3o, no Bairro Meireles, em Fortaleza. Antes da transmiss\u00e3o, Camilo Santana e Izolda Cela ir\u00e3o \u00e0 Assembleia Legislativa do Cear\u00e1 para as formalidades de ren\u00fancia e posse. Izolda ser\u00e1 a primeira mulher a comandar o Executivo do Cear\u00e1.<br \/>\nCamilo vai deixar o cargo de governador para concorrer a uma vaga no Senado nas elei\u00e7\u00f5es 2022. Conforme estabelecido pela Justi\u00e7a Eleitoral, ele s\u00f3 pode se candidatar se abrir m\u00e3o do cargo seis meses antes da elei\u00e7\u00e3o. No \u00faltimo dia como governador, Camilo inaugurou o novo aeroporto regional de Sobral, o Centro Integrado de Seguran\u00e7a P\u00fablica e a est\u00e1tua de Santo Ant\u00f4nio em Barbalha.<br \/>\nNesta quarta-feira (30), durante entrevista ao Bom Dia Cear\u00e1, Camilo Santana disse que a vice Izolda Cela \u201cest\u00e1 preparada para continuar todas as a\u00e7\u00f5es\u201d ap\u00f3s a ren\u00fancia dele do governo.<br \/>\n\u201cA Izolda \u00e9 uma pessoa maravilhosa, uma vice-governadora discreta, mas sempre muito firme, esteve ao meu lado ao longo desses 7 anos e 3 meses, nos momentos de avan\u00e7os, mas tamb\u00e9m nos momentos desafiadoras, sempre ao meu lado. Conhece bem o governo, est\u00e1 preparada pra continuar todas as a\u00e7\u00f5es que est\u00e3o planejadas at\u00e9 o final de 2022, quando termina o nosso mandato\u201d, disse Camilo.<br \/>\nAp\u00f3s mais de sete anos no comando Executivo, Camilo enfrentou crises como os atentados de 2019, o desabamento do Edif\u00edcio Andrea, o motim da Pol\u00edcia Militar, a pandemia da Covid-19, entre outros.<br \/>\nDe acordo com a Legisla\u00e7\u00e3o Eleitoral, os ocupantes de cargos p\u00fablicos que queiram se candidatar a outro posto nas Elei\u00e7\u00f5es de outubro precisam se desincompatibilizar at\u00e9 o pr\u00f3ximo dia 2 de abril, data citada pelo governador. Camilo deve ser candidato a senador na chapa majorit\u00e1ria governista, cujo candidato ao governo deve ser do PDT e um vice-governador cuja articula\u00e7\u00e3o ainda est\u00e1 em andamento.<br \/>\nSer\u00e1 a primeira vez na hist\u00f3ria que uma mulher assumir\u00e1, de maneira efetiva, o cargo de governadora do Estado, conforme j\u00e1 abordamos nesta coluna. \u201cUma pessoa extraordin\u00e1ria, discreta, mas firme e forte que esteve ao meu lado, nas decis\u00f5es mais dif\u00edceis\u201d, disse Camilo sobre a vice.<br \/>\nFonte: g1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A solenidade de transmiss\u00e3o de cargo do governador Camilo Santana (PT) para a vice-governadora Izolda&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela.jpeg","jetpack-related-posts":[{"id":19462,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-128\/","url_meta":{"origin":19333,"position":0},"title":"Em Tempo","author":"","date":"Abril 10, 2022","format":false,"excerpt":"Pr\u00eamio Jabuti 2022 abre inscri\u00e7\u00f5es Respons\u00e1vel por reconhecer e divulgar a produ\u00e7\u00e3o nacional, o\u00a0Pr\u00eamio Jabuti recebe inscri\u00e7\u00f5es at\u00e9 26 de maio para a sua 64\u00aa edi\u00e7\u00e3o, com homenagem \u00e0 Semana de Arte Moderna. O Pr\u00eamio traz a escritora Sueli Carneiro como\u00a0\u201cPersonalidade Liter\u00e1ria\u201d desse ano. O vencedor da\u00a0categoria \u201cLivro no Ano\u201d\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela-300x200.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":29153,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-165\/","url_meta":{"origin":19333,"position":1},"title":"Becco Ponto Com","author":"adminredacao","date":"Maio 6, 2024","format":false,"excerpt":"Aliada de Cid Gomes, bra\u00e7o direito de Camilo deve deixar o MEC e mira disputa \u00e0 prefeitura de Sobral Ex-governadora do Cear\u00e1, Izolda Cela ainda n\u00e3o decidiu se estar\u00e1 na disputa, mas ficar\u00e1 a disposi\u00e7\u00e3o do PSB. Secret\u00e1ria foi uma das respons\u00e1veis por transformar cidade em refer\u00eancia no ensino nos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29236,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-166\/","url_meta":{"origin":19333,"position":2},"title":"BECCO PONTO.COM","author":"adminredacao","date":"Maio 13, 2024","format":false,"excerpt":"Cid afirma que Ivo Gomes decide em Sobral Cid Gomes afirmou que o prefeito, seu irm\u00e3o, Ivo Gomes (PSB) conduzir\u00e1 o processo da escolha. O senador tamb\u00e9m disse que defende a manuten\u00e7\u00e3o da alian\u00e7a entre o seu partido e o PT. De acordo com o ex-governador, Sobral e Fortaleza s\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10363,"url":"https:\/\/correiodasemana.com\/site\/novo-alto-do-cristo-em-sobral-e-inaugurado-pelo-governo-do-estado\/","url_meta":{"origin":19333,"position":3},"title":"Novo Alto do Cristo em Sobral \u00e9 inaugurado pelo Governo do Estado","author":"","date":"Janeiro 5, 2020","format":false,"excerpt":"O Governo do Estado do Cear\u00e1 entregou, nesta quinta-feira (26), a urbaniza\u00e7\u00e3o de um dos principais cart\u00f5es postais da cidade de Sobral, o Alto do Cristo. Entre outras autoridades, a inaugura\u00e7\u00e3o contou com a presen\u00e7a da vice-governadora Izolda Cela, representando o governador Camilo Santana; do prefeito de Sobral, Ivo Gomes;\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":18832,"url":"https:\/\/correiodasemana.com\/site\/camilo-santana-se-posiciona-sobre-carnaval-no-estado-nao-e-hora-de-fazer-festa\/","url_meta":{"origin":19333,"position":4},"title":"Camilo Santana se posiciona sobre carnaval no estado: \u201cN\u00e3o \u00e9 hora de fazer festa\u201d","author":"","date":"Fevereiro 7, 2022","format":false,"excerpt":"Samuel Carvalho Reda\u00e7\u00e3o Correio da Semana O governador Camilo Santana (PT) pediu que a popula\u00e7\u00e3o aja de forma consciente em rela\u00e7\u00e3o ao Carnaval de 2022 e evite realizar e participar de festas e celebra\u00e7\u00f5es. A fala busca conscientizar a popula\u00e7\u00e3o diante da terceira onda de Covid-19, puxada pela variante \u00d4micron,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/camilo-santana.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29011,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-164\/","url_meta":{"origin":19333,"position":5},"title":"Becco Ponto Com","author":"adminredacao","date":"Abril 22, 2024","format":false,"excerpt":"Governador do Cear\u00e1, Elmano de Freitas perde a paci\u00eancia com a Enel e disse que a empresa pode n\u00e3o mais permanecer no Estado O governador Elmano de Freitas voltou a criticar a presta\u00e7\u00e3o de servi\u00e7os da Enel no Cear\u00e1. A fala do chefe do Executivo ocorreu ap\u00f3s reuni\u00e3o com presidente\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19333"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19333\/revisions"}],"predecessor-version":[{"id":19335,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19333\/revisions\/19335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/19334"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}