{"id":19361,"date":"2022-04-03T20:43:03","date_gmt":"2022-04-03T23:43:03","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19361"},"modified":"2022-04-03T20:43:03","modified_gmt":"2022-04-03T23:43:03","slug":"dom-vasconcelos-preside-missa-em-acao-de-gracas-pela-radio-educadora-fm-1075-e-realiza-bencao-em-novo-estudio","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-preside-missa-em-acao-de-gracas-pela-radio-educadora-fm-1075-e-realiza-bencao-em-novo-estudio\/","title":{"rendered":"Dom Vasconcelos preside Missa em A\u00e7\u00e3o de Gra\u00e7as pela R\u00e1dio Educadora FM 107,5 e realiza ben\u00e7\u00e3o em novo est\u00fadio"},"content":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Nesta quinta-feira, 31 de mar\u00e7o, na Capela do Abrigo em Sobral, Dom Jos\u00e9 Luiz Gomes de Vasconcelos presidiu a Santa Missa em A\u00e7\u00e3o de Gra\u00e7as pela R\u00e1dio Educadora FM 107,5 e realizou a ben\u00e7\u00e3o nas instala\u00e7\u00f5es do novo est\u00fadio na C\u00faria Diocesana. Na data tamb\u00e9m \u00e9 comemorado 104 anos do Jornal Correio da Semana.<br \/>\nConcelebrou com Dom Vasconcelos, os Padres: Pe. Lucas Moreira, Diretor da R\u00e1dio Educadora e Jornal Correio da Semana; Pe. Eufr\u00e1zio Filho, Capel\u00e3o da Igreja do Menino Deus; Pe. F\u00e1bio Mota, Capel\u00e3o da Igreja do Abrigo e Pe. Zen\u00f3bio. A Santa Missa contou com a presen\u00e7a de diversos radialistas e imprensa sobralense, entre eles os radialistas da R\u00e1dio Educadora que prestigiaram o momento.<br \/>\nNa homilia, Dom Vasconcelos enfatizou a sua felicidade pelo novo momento em que a r\u00e1dio est\u00e1 vivendo, onde tudo foi feito com muito trabalho e dedica\u00e7\u00e3o dos colaboradores e recursos da Diocese. \u201cDomingo passado S\u00e3o Paulo falou para n\u00f3s e continua falando: N\u00e3o deixemos passar esse tempo, esse tempo oportuno, tempo de gra\u00e7a. Aproximemo-nos de Deus, abramos os nossos cora\u00e7\u00f5es, a nossa mente, os nossos ouvidos. N\u00f3s estamos em uma \u00e9poca de muita polui\u00e7\u00e3o sonora, e estamos proporcionando meios para que voc\u00ea possa escutar uma boa m\u00fasica, uma bela mensagem, para que voc\u00ea possa refletir sobre a palavra de Deus. O objetivo desses meios de comunica\u00e7\u00f5es, desse jornal que completa 104 anos, dessa r\u00e1dio que de AM passa para FM, muito investimento, trabalho, esfor\u00e7o e luta para que a palavra de Deus possa chegar \u00e0 sua casa. E n\u00f3s fazemos um apelo a voc\u00ea: abra os seus ouvidos, sintonize 107,5. Ao inv\u00e9s de voc\u00ea ficar escutando asneiras, barulhos, programas que s\u00f3 trazem m\u00e1s not\u00edcias e derramamento de sangue, brigas pol\u00edticas, sintonize na R\u00e1dio Educadora e escute a palavra de Deus para que voc\u00ea possa chegar \u00e0 P\u00e1scoa eterna,\u201d disse o Bispo Diocesano.<br \/>\nDurante as homenagens, esteve presente com muita espontaneidade o Monsenhor Assis Rocha, que contribuiu por muito tempo com a R\u00e1dio Educadora e mesmo a com idade avan\u00e7ada esteve presente na celebra\u00e7\u00e3o e ao final prestou uma bela homenagem a r\u00e1dio com texto prescrito por ele. O diretor da r\u00e1dio, Pe. Lucas, agradeceu a todos os diversos colaboradores tanto da r\u00e1dio quando do jornal, a confian\u00e7a de Dom Vasconcelos e a todos que colaboraram para este dia memor\u00e1vel, sobretudo o seu desejo cont\u00ednuo de que a r\u00e1dio a cada dia mais seja um meio evangelizador. Ap\u00f3s a celebra\u00e7\u00e3o houve a ben\u00e7\u00e3o no est\u00fadio da emissora e nas novas instala\u00e7\u00f5es, na ocasi\u00e3o, Dom Vasconcelos agradeceu profundamente o trabalho prof\u00edcuo de Pe. Lucas e t\u00e3o majestoso sil\u00eancio e dedica\u00e7\u00e3o com que ele levou esta miss\u00e3o \u00e1rdua.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-19362\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-1-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-1-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-1-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-1.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-19363\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-2-300x226.jpeg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-2-300x226.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-2-1024x770.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-2-768x578.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-2.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-19364\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19365\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-4-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-4-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-4-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-4-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-4.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19366\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-5-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-5-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-5-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-5-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-5.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19367\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-6-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-6-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-6-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-6-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-6.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19368\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-7-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-7-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-7-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-7-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-7.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19369\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-8-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-8-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-8-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-8-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-8.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19370\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-9-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-9-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-9-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-9-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-9.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Nesta quinta-feira, 31 de mar\u00e7o, na Capela do&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/bencao-da-radio-educadora-sobral-3.jpeg","jetpack-related-posts":[{"id":19299,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-realiza-bencao-da-torre-e-do-novo-transmissor-da-radio-educadora-fm-1075\/","url_meta":{"origin":19361,"position":0},"title":"Dom Vasconcelos realiza b\u00ean\u00e7\u00e3o da torre e do novo transmissor da R\u00e1dio Educadora FM 107,5","author":"","date":"Mar\u00e7o 27, 2022","format":false,"excerpt":"Thais Helena (Reda\u00e7\u00e3o Correio da Semana) \u2013 A torre e o novo transmissor da R\u00e1dio Educadora FM 107,5 foi aben\u00e7oado no \u00faltimo s\u00e1bado (19) dia dedicado a S\u00e3o Jos\u00e9, por Dom Jos\u00e9 Luiz Gomes de Vasconcelos durante o final dos festejos na Par\u00f3quia do Sumar\u00e9. Sendo um grande marco para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/paroquia-sumare-4-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/paroquia-sumare-4-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/paroquia-sumare-4-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/paroquia-sumare-4-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19151,"url":"https:\/\/correiodasemana.com\/site\/no-ar-a-mais-nova-radio-de-sobral-fm-educadora-1075\/","url_meta":{"origin":19361,"position":1},"title":"No ar, a mais nova r\u00e1dio de Sobral: FM Educadora 107,5","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"Desde sua funda\u00e7\u00e3o h\u00e1 62 anos, a R\u00e1dio Educadora do Nordeste AM 950, al\u00e9m de permanecer evangelizando, educando e entretendo sadiamente, tamb\u00e9m tem como meta constante a renova\u00e7\u00e3o e a inova\u00e7\u00e3o para acompanhar o avan\u00e7o tecnol\u00f3gico. Por conta disso, depois de longo processo e muito trabalho, a Diocese de Sobral\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/Jornal-Correio-da-Semana-No-906-capa2-300x203.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":19201,"url":"https:\/\/correiodasemana.com\/site\/fm-educadora-no-ar-em-107-5\/","url_meta":{"origin":19361,"position":2},"title":"FM EDUCADORA NO AR EM 107.5","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"Uma boa novidade no r\u00e1dio sobralense. Est\u00e1 no ar desde \u00e0s 14h30min do \u00faltimo dia 4 de mar\u00e7o a mais nova esta\u00e7\u00e3o de frequ\u00eancia modulada do Estado do Cear\u00e1: R\u00c1DIO EDUCADORA DO NORDESTE FM 107,5. A autoriza\u00e7\u00e3o da AG\u00caNCIA NACIONAL DE TELECOMUNICA\u00c7\u00d5ES (Anatel) inclui a nova emissora na categoria A2,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/Jornal-Correio-da-Semana-No-906-capa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/Jornal-Correio-da-Semana-No-906-capa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/Jornal-Correio-da-Semana-No-906-capa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/Jornal-Correio-da-Semana-No-906-capa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17614,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-preside-missa-solene-na-catedral-da-se-marcando-os-62-anos-de-falecimento-de-dom-jose-tupinamba-da-frota\/","url_meta":{"origin":19361,"position":3},"title":"Dom Vasconcelos preside missa solene na Catedral da S\u00e9 marcando os 62 anos de falecimento de Dom Jos\u00e9 Tupinamb\u00e1 da Frota","author":"","date":"Outubro 4, 2021","format":false,"excerpt":"Por Thais Helena (Portal de Comunica\u00e7\u00e3o) Antes da celebra\u00e7\u00e3o foi proferido um texto alusivo aos 62 anos de falecimento de Dom Jos\u00e9 Tupinamb\u00e1 da Frota, pelo comentarista. Os c\u00e2nticos da missa foram m\u00fasicas escolhidas especialmente para este momento saudoso. As celebra\u00e7\u00f5es que marcaram os 62 anos de falecimento de Dom\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/missa-aos-62-anos-de-falecimento-de-dom-jose-5.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/missa-aos-62-anos-de-falecimento-de-dom-jose-5.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/missa-aos-62-anos-de-falecimento-de-dom-jose-5.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/10\/missa-aos-62-anos-de-falecimento-de-dom-jose-5.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23257,"url":"https:\/\/correiodasemana.com\/site\/padre-lucas-do-nascimento-ficara-por-mais-tres-anos-a-frente-da-radio-educadora-e-jornal-correio-da-semana\/","url_meta":{"origin":19361,"position":4},"title":"Padre Lucas do Nascimento ficar\u00e1 por mais tr\u00eas anos \u00e0 frente da R\u00e1dio Educadora e Jornal Correio da Semana","author":"adminredacao","date":"Janeiro 31, 2023","format":false,"excerpt":"O bispo diocesano de Sobral, dom Jos\u00e9 Luiz Gomes, renovou por mais um tri\u00eanio as provis\u00f5es can\u00f4nicas do Pe. Lucas do Nascimento Moreira, respectivamente diretor do centen\u00e1rio jornal Correio da Semana e da R\u00e1dio Educadora do Nordeste FM 107,5. O jovem sacerdote assumiu a dire\u00e7\u00e3o do Jornal e da R\u00e1dio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/PADRE-LUCAS-MOREIRA.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":20273,"url":"https:\/\/correiodasemana.com\/site\/radio-educadora-fm-1075-celebra-63-anos-de-criacao\/","url_meta":{"origin":19361,"position":5},"title":"R\u00e1dio Educadora FM 107,5 celebra 63 anos de cria\u00e7\u00e3o","author":"","date":"Junho 27, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Para celebrar o 63\u00ba anivers\u00e1rio da R\u00e1dio Educadora FM 107,5 houve uma programa\u00e7\u00e3o especial no p\u00e1tio da C\u00faria Diocesana na manh\u00e3 da \u00faltima ter\u00e7a-feira, dia 21 de junho, com o Show do Ivan Frota, homenagens, momento musical e anima\u00e7\u00e3o com Rosinha do Acordeon.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19361"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19361\/revisions"}],"predecessor-version":[{"id":19371,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19361\/revisions\/19371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/19364"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}