{"id":19435,"date":"2022-04-10T21:08:16","date_gmt":"2022-04-11T00:08:16","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19435"},"modified":"2022-04-10T21:08:16","modified_gmt":"2022-04-11T00:08:16","slug":"lbv-busca-apoio-de-parceiros-para-acao-solidaria-de-pascoa","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/lbv-busca-apoio-de-parceiros-para-acao-solidaria-de-pascoa\/","title":{"rendered":"LBV busca apoio de parceiros para a\u00e7\u00e3o solid\u00e1ria de P\u00e1scoa"},"content":{"rendered":"<p>Segundo estudo feito pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), a preval\u00eancia global de ansiedade e depress\u00e3o subiu para 25% no primeiro ano da pandemia do novo coronav\u00edrus. Preocupa\u00e7\u00f5es financeiras tamb\u00e9m foram citadas como fatores estressantes. Ali\u00e1s, enquanto h\u00e1 pesquisas que indicam que os brasileiros est\u00e3o consumindo uma maior quantidade de chocolates e com uma frequ\u00eancia significativa durante este per\u00edodo pand\u00eamico, h\u00e1 aqueles brasileiros que n\u00e3o possuem condi\u00e7\u00f5es de manter uma alimenta\u00e7\u00e3o saud\u00e1vel e cujo consumo de chocolates nesse per\u00edodo de P\u00e1scoa \u00e9 invi\u00e1vel.<br \/>\nPor esse motivo, a Legi\u00e3o da Boa Vontade (LBV) iniciou uma mobiliza\u00e7\u00e3o a fim de arrecadar bombons, doces e chocolates para distribuir a crian\u00e7as e jovens atendidos pela Institui\u00e7\u00e3o em seu Centro Comunit\u00e1rio de Assist\u00eancia Social localizado na Vila Manoel S\u00e1tiro, em Fortaleza. A Institui\u00e7\u00e3o continua sua mobiliza\u00e7\u00e3o de amparo \u00e0s pessoas que vivem em situa\u00e7\u00e3o de vulnerabilidade social e convida todos a participar dessa iniciativa para ajudar. A campanha solid\u00e1ria visa presentear cerca de 200 crian\u00e7as nesta P\u00e1scoa.<br \/>\nFa\u00e7a parte desse time solid\u00e1rio e leve sua doa\u00e7\u00e3o, at\u00e9 dia 11\/4 (segunda-feira), ao seguinte endere\u00e7o: Rua Alziro Zarur, 275 \u2013 Vila Manoel S\u00e1tiro \u2013 Fortaleza. Informa\u00e7\u00f5es pelo telefone: (85) 3484-3533.<br \/>\nConhe\u00e7a as a\u00e7\u00f5es da Entidade em prol da inf\u00e2ncia brasileira acessando o site www.lbv.org ou @lbvBrasil nas redes sociais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo estudo feito pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS), a preval\u00eancia global de ansiedade e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-19435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/lbv-post.jpg","jetpack-related-posts":[{"id":16805,"url":"https:\/\/correiodasemana.com\/site\/lbv-leva-amparo-ao-sertao-cearense\/","url_meta":{"origin":19435,"position":0},"title":"LBV leva amparo ao sert\u00e3o cearense","author":"","date":"Junho 21, 2021","format":false,"excerpt":"Em Irau\u00e7uba, LBV beneficia centenas de fam\u00edlias em situa\u00e7\u00e3o de pobreza. A sua doa\u00e7\u00e3o chegou! O Minist\u00e9rio da Cidadania informa que 33% da popula\u00e7\u00e3o do Cear\u00e1 encontra-se em situa\u00e7\u00e3o de extrema pobreza, vivendo com cerca de 89 reais por m\u00eas. Se \u00e9 dif\u00edcil para quem vive nas grandes metr\u00f3poles, para\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/lbv-amparo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/lbv-amparo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/lbv-amparo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/lbv-amparo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/lbv-amparo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14798,"url":"https:\/\/correiodasemana.com\/site\/celebrar-o-natal-e-tambem-ajudar-as-familias-mais-vulneraveis-que-sofrem-com-os-efeitos-da-pandemia-do-novo-coronavirus\/","url_meta":{"origin":19435,"position":1},"title":"Celebrar o Natal \u00e9 tamb\u00e9m ajudar as fam\u00edlias mais vulner\u00e1veis que sofrem com os efeitos da pandemia do novo coronav\u00edrus","author":"","date":"Novembro 30, 2020","format":false,"excerpt":"Campanha de Natal da LBV no estado do Cear\u00e1 pretende arrecadar\u00a056 toneladas de doa\u00e7\u00f5es A fome voltou a crescer no Brasil, segundo a \u201cPesquisa de Or\u00e7amentos Familiares 2017-2018: An\u00e1lise da Seguran\u00e7a Alimentar no Brasil\u201d, do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), divulgada em 17\/9\/2020. De acordo com o documento,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20401,"url":"https:\/\/correiodasemana.com\/site\/lbv-destina-alimentos-as-familias-em-situacao-de-pobreza-e-vulnerabilidade-social-no-ceara\/","url_meta":{"origin":19435,"position":2},"title":"LBV destina alimentos \u00e0s fam\u00edlias em situa\u00e7\u00e3o de pobreza e vulnerabilidade social no Cear\u00e1","author":"","date":"Julho 11, 2022","format":false,"excerpt":"Por Suyane Lopes Oliveira - Assessora de comunica\u00e7\u00e3o da LBV A fome continua avan\u00e7ando no Brasil: cerca de 15% das fam\u00edlias enfrentam esse mal atualmente. O\u00a0n\u00famero de brasileiros sem ter o que comer quase dobrou em dois anos de pandemia. O levantamento faz parte do 2\u00ba Inqu\u00e9rito Nacional sobre Inseguran\u00e7a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/dsc0668-800_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/dsc0668-800_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/dsc0668-800_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/dsc0668-800_0.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16148,"url":"https:\/\/correiodasemana.com\/site\/lbv-continua-o-trabalho-de-combate-aos-impactos-do-novo-coronavirus-no-ceara\/","url_meta":{"origin":19435,"position":3},"title":"LBV continua o trabalho de combate aos impactos do novo Coronav\u00edrus no Cear\u00e1","author":"","date":"Abril 12, 2021","format":false,"excerpt":"Desde mar\u00e7o de 2020 a institui\u00e7\u00e3o vem amparando milhares de fam\u00edlias brasileiras Segundo dados da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Agricultura e Alimenta\u00e7\u00e3o (FAO), a fome no mundo se agravou, devido \u00e0s consequ\u00eancias da pandemia. Com essa situa\u00e7\u00e3o se desdobrando e trazendo alta criticidade em muitos estados brasileiros, a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/LBV.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/LBV.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/LBV.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/LBV.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/04\/LBV.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15398,"url":"https:\/\/correiodasemana.com\/site\/combater-a-fome-conter-a-covid-19-e-levar-esperanca-a-milhares-de-familias-sao-algumas-das-realizacoes-da-lbv-em-2020\/","url_meta":{"origin":19435,"position":4},"title":"Combater a fome, conter a Covid-19 e levar esperan\u00e7a a milhares de fam\u00edlias s\u00e3o algumas das realiza\u00e7\u00f5es da LBV em 2020","author":"","date":"Janeiro 18, 2021","format":false,"excerpt":"Mais de tr\u00eas milh\u00f5es de quilos em doa\u00e7\u00f5es foram entregues pela Institui\u00e7\u00e3o nas cinco regi\u00f5es do pa\u00eds 2020: um ano de grandes desafios para pessoas no mundo inteiro. No Brasil, n\u00e3o foi diferente. Al\u00e9m de causar milhares de mortes, a pandemia do novo coronav\u00edrus tamb\u00e9m afetou fortemente a vida das\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23395,"url":"https:\/\/correiodasemana.com\/site\/o-futuro-que-queremos-se-constroi-hoje\/","url_meta":{"origin":19435,"position":5},"title":"O futuro que queremos se constr\u00f3i hoje","author":"","date":"Fevereiro 5, 2023","format":false,"excerpt":"LBV inicia campanha nacional em prol da Educa\u00e7\u00e3o para incentivar estudos e combater inseguran\u00e7a alimentar de estudantes Sabemos que alimenta\u00e7\u00e3o saud\u00e1vel e material escolar s\u00e3o fortes aliados na melhora do desempenho escolar. Por isso, olhar para a Educa\u00e7\u00e3o nesse momento em que o pa\u00eds ainda se recupera dos reflexos causados\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-01-31-at-13.27.50.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19435"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19435\/revisions"}],"predecessor-version":[{"id":19437,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19435\/revisions\/19437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/19436"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}