{"id":19875,"date":"2022-05-26T01:12:17","date_gmt":"2022-05-26T04:12:17","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19875"},"modified":"2022-05-26T01:12:17","modified_gmt":"2022-05-26T04:12:17","slug":"recomecos-cidadaos-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/recomecos-cidadaos-2\/","title":{"rendered":"Recome\u00e7os cidad\u00e3os"},"content":{"rendered":"<p>Cl\u00e1ssico, consagrado e bem atual \u00e9 o que expressa o imortal Rui Barbosa, ao referir-se sobre o triunfo das nulidades e o crescimento das injusti\u00e7as. Ante essa constata\u00e7\u00e3o, a cidadania \u00e9 interpelada a n\u00e3o abrir m\u00e3o de virtudes, a superar a desconsidera\u00e7\u00e3o da honra e a eleger como prioridade a honestidade. A\u00ed est\u00e1 o exigente programa, em cada etapa da hist\u00f3ria e em todos os momentos da (re)constru\u00e7\u00e3o da sociedade, buscando edificar \u201cum mundo aberto\u201d, isto \u00e9, sem fechamentos que comprometem o humanismo integral. A grande mudan\u00e7a civilizat\u00f3ria em curso n\u00e3o permite relativiza\u00e7\u00f5es ou solu\u00e7\u00f5es que podem parecer f\u00e1ceis, mas conduzem a fracassos que s\u00e3o consequ\u00eancias de escolhas equivocadas, de respostas que contemplam parte dos anseios de uma parcela da popula\u00e7\u00e3o, em um contexto que exige mais compromisso com a solidariedade universal.<br \/>\nEssenciais s\u00e3o valores e princ\u00edpios iluminadores, a exemplo daqueles que integram a doutrina crist\u00e3, com propriedades para configurar respostas adequadas a este tempo. Por isso mesmo, o desafio partilhado por todos inclui o adequado exerc\u00edcio da cidadania, alicer\u00e7ando-o sobre valores e princ\u00edpios insubstitu\u00edveis. Esse desafio pede o reconhecimento das consequ\u00eancias de \u201cum mundo fechado\u201d, para que sejam geradas mudan\u00e7as. \u00a0\u00a0Adverte o Papa Francisco: as sombras de \u201cum mundo fechado\u201d trazem o risco de preju\u00edzos pesados. Isso se comprova quando s\u00e3o observadas as guerras que mancham a hist\u00f3ria da humanidade. Mesmo diante de tantos sofrimentos registrados no passado, os conflitos permanecem, com focos de guerra mundo afora. Os anseios por integra\u00e7\u00e3o n\u00e3o t\u00eam alcan\u00e7ado seus bons prop\u00f3sitos, que s\u00e3o necess\u00e1rios e urgentes. Ao inv\u00e9s disso, sinais apontam para um processo de regress\u00e3o da humanidade, indicando ser essencial investir no cultivo de envergadura humana, moral e pol\u00edtica para inspirar recome\u00e7os cidad\u00e3os.<br \/>\nO atual contexto pede mais intelig\u00eancia e generosidade solid\u00e1ria da civiliza\u00e7\u00e3o contempor\u00e2nea, para que sejam efetivadas mudan\u00e7as alicer\u00e7adas no bem, no amor, na justi\u00e7a e na paz. Trata-se de um processo exigente, que inclui consci\u00eancia individual e coletiva, na constru\u00e7\u00e3o de um caminho que efetivamente seja recome\u00e7o cidad\u00e3o.\u00a0 Oportuno lembrar que a grave crise sanit\u00e1ria enfrentada por todo o mundo vem produzindo grandes perdas, a morte de muitas pessoas, trazendo no seu reverso uma s\u00e9rie de li\u00e7\u00f5es que precisam ser aprendidas, a exemplo da ado\u00e7\u00e3o de um novo estilo de vida e de novas din\u00e2micas. Mas, infelizmente, o que se verifica \u00e9 a pouca disponibilidade para mudar, conforme revelam certas a\u00e7\u00f5es que ignoram a inadi\u00e1vel necessidade de se respeitar o meio ambiente. Privilegia-se a l\u00f3gica do lucro, que cega, fazendo tantos acreditarem que o dinheiro r\u00e1pido na m\u00e3o \u00e9 o que mais vale, sem considerar que logo vir\u00e3o as perdas arrasadoras, a exemplo da escassez de \u00e1gua pot\u00e1vel.<br \/>\nNeste tempo de grandes possibilidades ainda se convive com a discrimina\u00e7\u00e3o crescente, desconsiderando a fraternidade, endurecendo cora\u00e7\u00f5es, incapacitando-os para vencer situa\u00e7\u00f5es de injusti\u00e7a. O ant\u00eddoto para esses males \u00e9 recuperar o sentido de fam\u00edlia, reconhecendo-se parte de um grupo marcado por la\u00e7os sangu\u00edneos, mas tamb\u00e9m integrante de um conjunto maior, a fam\u00edlia humana. Importam os recome\u00e7os cidad\u00e3os para dissipar as sombras de \u201cum mundo fechado\u201d.<br \/>\n\u00c9 preciso vencer o des\u00e2nimo, conforme alimenta e alicer\u00e7a a esperan\u00e7a crist\u00e3. O Papa Francisco, na Carta Enc\u00edclica Fratelli Tutti, adverte, de modo simples e muito assertivo, a respeito deste tempo, apresentando tr\u00eas perigosos verbos: exasperar, exacerbar e polarizar. As atitudes conceituadas por esses tr\u00eas verbos obscurecem a sociedade e o horizonte urgente que inspira recome\u00e7os cidad\u00e3os. Pertinente e sempre interpeladora \u00e9 a interroga\u00e7\u00e3o do Papa: \u201cNesta luta de interesses que nos coloca todos contra todos, onde vencer se torna sin\u00f4nimo de destruir, como se pode levantar a cabe\u00e7a para reconhecer o vizinho ou ficar do lado de quem est\u00e1 ca\u00eddo na estrada?\u201d<br \/>\nO que se verifica \u00e9 um conjunto de consequ\u00eancias desastrosas, capazes de enfraquecer at\u00e9 mesmo o sentido de fam\u00edlia, afrontando seus valores e princ\u00edpios intoc\u00e1veis. Debelam tamb\u00e9m os sentimentos de solidariedade, desprezando a disposi\u00e7\u00e3o para o di\u00e1logo e a capacidade para reconhecer a nobreza da dignidade humana de cada pessoa. Dentre essas situa\u00e7\u00f5es graves que causam um verdadeiro terremoto social est\u00e1 a pol\u00edtica que deixa de ser debate saud\u00e1vel, buscando o desenvolvimento de todos e o bem comum. Essa pol\u00edtica, conforme bem sublinha o Papa Francisco, limita-se a receitas ef\u00eameras de marketing, cujo recurso mais eficaz est\u00e1 na destrui\u00e7\u00e3o do outro. \u00c9 preciso reagir evocando um sentimento amplo e irrestrito para emoldurar a cidadania e iluminar a consci\u00eancia coletiva pela luz da humildade, pelo mecanismo do di\u00e1logo e pelo sentido imprescind\u00edvel de solidariedade. \u00a0Todos, tecendo riquezas a partir das muitas diferen\u00e7as, s\u00e3o convocados a contribuir: com a for\u00e7a do respeito, \u00e9 hora de importantes recome\u00e7os cidad\u00e3os.<\/p>\n<p>Dom Walmor Oliveira de Azevedo<br \/>\nArcebispo metropolitano de Belo Horizonte<br \/>\nPresidente da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cl\u00e1ssico, consagrado e bem atual \u00e9 o que expressa o imortal Rui Barbosa, ao referir-se&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,11],"tags":[],"class_list":["post-19875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":9272,"url":"https:\/\/correiodasemana.com\/site\/chega-a-festa-de-sao-francisco\/","url_meta":{"origin":19875,"position":0},"title":"Chega a Festa de S\u00e3o Francisco","author":"","date":"Setembro 30, 2019","format":false,"excerpt":"Todo final de setembro, em Sobral \u00e9 assim: os frades da Ordem Capuchinho a exemplo de Canind\u00e9, tratam logo de cuidar de todas as instala\u00e7\u00f5es da igreja para receber um expressivo n\u00famero de fi\u00e9is, em especial, dos bairros perif\u00e9ricos e de munic\u00edpios circunvizinhos para os nove dias da festa dedicada\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/Programa%C3%A7%C3%A3o-da-festa-S%C3%A3o-Francisco.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/Programa%C3%A7%C3%A3o-da-festa-S%C3%A3o-Francisco.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/Programa%C3%A7%C3%A3o-da-festa-S%C3%A3o-Francisco.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/09\/Programa%C3%A7%C3%A3o-da-festa-S%C3%A3o-Francisco.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29094,"url":"https:\/\/correiodasemana.com\/site\/nordestinos-negros-e-mulheres-sao-maioria-entre-jovens-que-nao-estudam-nem-trabalham-no-brasil\/","url_meta":{"origin":19875,"position":1},"title":"Nordestinos, negros e mulheres s\u00e3o maioria entre jovens que n\u00e3o estudam nem trabalham no Brasil","author":"adminredacao","date":"Abril 29, 2024","format":false,"excerpt":"Especialistas destacam vulnerabilidade e falta de oportunidade para jovens dentro deste perfil A maioria dos jovens brasileiros entre 15 a 29 anos que n\u00e3o estudam e n\u00e3o trabalham \u00e9 formada por mulheres nordestinas pretas ou pardas. Os dados de 2023 do IBGE revelam que mais de 3,7 milh\u00f5es de jovens\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14333,"url":"https:\/\/correiodasemana.com\/site\/associacao-lanca-campanha-contra-transporte-irregular-de-passageiros\/","url_meta":{"origin":19875,"position":2},"title":"Associa\u00e7\u00e3o lan\u00e7a campanha contra transporte irregular de passageiros","author":"","date":"Outubro 28, 2020","format":false,"excerpt":"Meta \u00e9 conscientizar sobre os riscos do transporte pirata A Associa\u00e7\u00e3o Brasileira das Empresas de Transporte Terrestre de Passageiros (Abrati) lan\u00e7ou hoje (28), no Rio de Janeiro, a campanha nacional \u201cSua vida vale mais. Diga n\u00e3o ao transporte clandestino\u201d. \u00c0s v\u00e9speras do feriado do dia de finados (2 de novembro),\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/onimus-pirata.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/onimus-pirata.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/onimus-pirata.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/onimus-pirata.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/10\/onimus-pirata.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":38403,"url":"https:\/\/correiodasemana.com\/site\/sao-jose-operario-5\/","url_meta":{"origin":19875,"position":3},"title":"S\u00e3o Jos\u00e9 Oper\u00e1rio","author":"adminredacao","date":"Maio 13, 2026","format":false,"excerpt":"Celebramos, neste 1\u00ba de maio, a festa lit\u00fargica de S\u00e3o Jos\u00e9 Oper\u00e1rio. Temos a gra\u00e7a de celebrar S\u00e3o Jos\u00e9 duas vezes ao ano: em 19 de mar\u00e7o, recordamos S\u00e3o Jos\u00e9 como esposo da Virgem Maria e pai adotivo de Jesus, bem como patrono universal da Igreja; e, no dia 1\u00ba\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16815,"url":"https:\/\/correiodasemana.com\/site\/pula-a-fogueira\/","url_meta":{"origin":19875,"position":4},"title":"PULA A FOGUEIRA&#8230;","author":"","date":"Junho 21, 2021","format":false,"excerpt":"Pr\u00f3xima semana teremos a fogueira de S\u00e3o Jo\u00e3o. Domingo passado foi Santo Ant\u00f4nio, amado em todo o Brasil. At\u00e9 concedi entrevista \u00e0 BBC sobre o Santo. Os tempos s\u00e3o estranhos. Em torno das fogueiras (fazemos as tr\u00eas), costumamos reunir al\u00e9m da fam\u00edlia, amigos e os amigos destes, l\u00e1 no Monte\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Jose%CC%81-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16339,"url":"https:\/\/correiodasemana.com\/site\/sao-joao-batista-o-santo-de-devocao-do-catolicismo-popular\/","url_meta":{"origin":19875,"position":5},"title":"S\u00e3o Jo\u00e3o Batista, o santo de devo\u00e7\u00e3o do catolicismo popular!","author":"","date":"Maio 3, 2021","format":false,"excerpt":"Francisco Silas Lopes Sim\u00e3o\/ Historiador J\u00e1 se aproxima o m\u00eas de junho, m\u00eas dedicado a festa em honra ao nascimento de S\u00e3o Jo\u00e3o Batista, que celebramos as festas a Santo Ant\u00f4nio, S\u00e3o Pedro e S\u00e3o Paulo. Junho \u00e9 marcado pelas festas juninas, festas de car\u00e1ter popular que marcam a identidade\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/sao-joao-batista-FotoCNBB.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/sao-joao-batista-FotoCNBB.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/sao-joao-batista-FotoCNBB.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/sao-joao-batista-FotoCNBB.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/05\/sao-joao-batista-FotoCNBB.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19875"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19875\/revisions"}],"predecessor-version":[{"id":19876,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19875\/revisions\/19876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7687"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}