{"id":19943,"date":"2022-06-06T00:29:39","date_gmt":"2022-06-06T03:29:39","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=19943"},"modified":"2022-06-06T00:29:39","modified_gmt":"2022-06-06T03:29:39","slug":"coroacao-de-nossa-senhora-encerra-mes-mariano-na-diocese-de-sobral","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/coroacao-de-nossa-senhora-encerra-mes-mariano-na-diocese-de-sobral\/","title":{"rendered":"Coroa\u00e7\u00e3o de Nossa Senhora encerra m\u00eas mariano na Diocese de Sobral"},"content":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana)<br \/>\nCom a Solenidade da Visita\u00e7\u00e3o de Nossa Senhora no dia 31 de maio, a Diocese de Sobral finalizou o m\u00eas mariano com o rito da Coroa\u00e7\u00e3o de Nossa Senhora no Arco de Nossa Senhora de F\u00e1tima, em Sobral.<br \/>\nInicialmente houve o Santo Ter\u00e7o meditado pelas fam\u00edlias que fazem parte das novas comunidades, em seguida iniciou a celebra\u00e7\u00e3o eucar\u00edstica que foi presidida pelo bispo diocesano de Sobral, Dom Jos\u00e9 Luiz Gomes de Vasconcelos e concelebrada pelos Padres: Pe. Denilson de Sousa, Pe. Eufr\u00e1zio Filho, Pe. Edinardo Gomes, Pe. Jo\u00e3o Paulo , Pe. Livandro, Pe. Uli Endres e Pe. Valdir Braga. Tamb\u00e9m esteve presente o Prefeito em exerc\u00edcio, Paulo. Assim como, seminaristas, movimentos marianos, ter\u00e7o dos homens, e todo o povo de Deus.<br \/>\nAp\u00f3s dois os devotos e devotas de Nossa Senhora tiveram a alegria de estarem reunidos mais uma vez para homenagear a m\u00e3e do c\u00e9u. \u201cTodos n\u00f3s crist\u00e3os cat\u00f3licos aprendemos desde crian\u00e7a a honrar e venerar Maria\u201d. Disse Dom Vasconcelos. O Bispo Diocesano tamb\u00e9m relembrou momentos especiais de sua caminhada sacerdotal quando assumiu sua primeira par\u00f3quia dedicada a Imaculada Concei\u00e7\u00e3o, e al\u00ed havia uma tribo ind\u00edgena que falava portugu\u00eas, mas tamb\u00e9m falava sua pr\u00f3pria l\u00edngua e aqueles \u00edndios eram devotos de Nossa Senhora, rezavam durante todo o m\u00eas de maio. Continuou: \u201cEram cerca de tr\u00eas mil \u00edndios, nunca encontrei um \u00edndio protestante. Os irm\u00e3os evang\u00e9licos chegavam l\u00e1 e iam falar mal de Nossa Senhora e os \u00edndios diziam: \u201cAqui n\u00e3o! Voc\u00ea pode falar mal da m\u00e3e de quem quiser l\u00e1 fora, mas aqui voc\u00ea n\u00e3o fala mal da minha m\u00e3e, e n\u00e3o \u00e9 s\u00f3 minha m\u00e3e, \u00e9 m\u00e3e de nosso Senhor Jesus Cristo\u201d, portanto, n\u00f3s n\u00e3o vamos brigar com ningu\u00e9m por causa de Maria porque ela \u00e9 m\u00e3e de toda a humanidade, n\u00f3s temos a felicidade de reconhec\u00ea-la como m\u00e3e mas ela n\u00e3o deixa de ser m\u00e3e daqueles que n\u00e3o a reconhecem\u201d.<br \/>\nO momento da Coroa\u00e7\u00e3o de Nossa Senhora foi realizado ap\u00f3s a celebra\u00e7\u00e3o. Na ocasi\u00e3o, representantes da Comunidade M\u00e3e da Divina Provid\u00eancia adentraram no meio do povo trazendo as bandeiras das na\u00e7\u00f5es, e logo ap\u00f3s, o grupo do Ter\u00e7o dos Homens fizeram a entroniza\u00e7\u00e3o da imagem de Nossa Senhora.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-19944\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219813192-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219813192-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219813192.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-19945\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219908236-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219908236-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219908236.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-19946\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219918265-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219918265-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219918265.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19947\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219946859-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219946859-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654219946859.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19948\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220058208-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220058208-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220058208.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19949\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220065176-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220065176-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220065176.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-19950\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924-300x200.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Com a Solenidade da Visita\u00e7\u00e3o de Nossa Senhora&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-19943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",720,480,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924-300x200.jpg",300,200,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",640,427,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",640,427,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",720,480,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",720,480,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg",720,480,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924-540x340.jpg",540,340,true]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/FB_IMG_1654220102924.jpg","jetpack-related-posts":[{"id":34032,"url":"https:\/\/correiodasemana.com\/site\/em-sobral-coroacao-de-nossa-senhora-marca-encerramento-do-mes-mariano-na-boulevard-do-arco\/","url_meta":{"origin":19943,"position":0},"title":"Em Sobral, Coroa\u00e7\u00e3o de Nossa Senhora marca encerramento do M\u00eas Mariano na Boulevard do Arco","author":"adminredacao","date":"Junho 4, 2025","format":false,"excerpt":"Centenas de devotos reuniram-se no final da tarde do \u00faltimo s\u00e1bado, 31, para a tradicional Coroa\u00e7\u00e3o da imagem de Nossa Senhora na Boulevard do Arco, em Sobral. A 41\u00aa edi\u00e7\u00e3o deste ano contou com uma programa\u00e7\u00e3o especial em honra \u00e0 Virgem Maria. As atividades iniciaram com a apresenta\u00e7\u00e3o da Banda\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/coroacao-de-nossa-senhora-em-sobral-10.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24503,"url":"https:\/\/correiodasemana.com\/site\/mes-mariano-grupos-rezam-o-santo-terco-no-arco-de-nossa-senhora-de-fatima-durante-o-mes-de-maio\/","url_meta":{"origin":19943,"position":1},"title":"M\u00eas Mariano: Grupos rezam o Santo Ter\u00e7o no Arco de Nossa Senhora de F\u00e1tima durante o m\u00eas de maio","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"A S\u00c9 Catedral de Nossa Senhora da Concei\u00e7\u00e3o juntamente com toda a par\u00f3quia, iniciou no dia 01\/05 o Santo Ter\u00e7o na Boullevard do Arco com a participa\u00e7\u00e3o dos grupos, pastorais, movimentos, novas comunidades e par\u00f3quias da Regi\u00e3o Sede, bem como devotos de Nossa Senhora. Maio \u00e9 o M\u00eas Mariano, dedicado\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-05-at-18.07.31.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29486,"url":"https:\/\/correiodasemana.com\/site\/em-sobral-multidao-participa-da-40a-coroacao-da-imagem-de-nossa-senhora-na-boullevard-do-arco\/","url_meta":{"origin":19943,"position":2},"title":"Em Sobral, multid\u00e3o participa da 40\u00aa Coroa\u00e7\u00e3o da imagem de Nossa Senhora na Boullevard do Arco","author":"adminredacao","date":"Junho 3, 2024","format":false,"excerpt":"Os cat\u00f3licos sobralenses participaram neste dia 31 de maio, da 40\u00aa edi\u00e7\u00e3o da Coroa\u00e7\u00e3o da imagem de Nossa Senhora no Arco de Nossa Senhora de F\u00e1tima. O evento celebra Jubileu de Esmeralda e neste ano trouxe como tema: \u201cCom Maria, unidos em ora\u00e7\u00e3o\u201d. O monumento do Arco de Nossa Senhora\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-01-at-15.01.32.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-01-at-15.01.32.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-01-at-15.01.32.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-01-at-15.01.32.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-01-at-15.01.32.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":9568,"url":"https:\/\/correiodasemana.com\/site\/festa-da-mae-rainha-atrai-fieis-para-uma-grande-celebracao\/","url_meta":{"origin":19943,"position":3},"title":"Festa da M\u00e3e Rainha atrai fi\u00e9is para uma grande celebra\u00e7\u00e3o","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"A programa\u00e7\u00e3o iniciou com uma carreata saindo da Par\u00f3quia do Patroc\u00ednio levando a acolhida dos peregrinos, terminando com a Coroa\u00e7\u00e3o de Nossa Senhora. \u201cUnidos ao Pai e Profeta, com a M\u00e3e Peregrina, cultivamos a nova terra Mariana\u201d foi o lema da festa\u00a0da M\u00e3e Rainha e Vencedora Tr\u00eas Vezes Admir\u00e1vel de\u2026","rel":"","context":"In &quot;Destaques&quot;","block_context":{"text":"Destaques","link":"https:\/\/correiodasemana.com\/site\/category\/destaques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29173,"url":"https:\/\/correiodasemana.com\/site\/abertura-do-mes-mariano-paroquias-celebram-despertar-com-maria\/","url_meta":{"origin":19943,"position":4},"title":"Abertura do M\u00eas Mariano: Par\u00f3quias celebram \u201cDespertar com Maria\u201d","author":"adminredacao","date":"Maio 6, 2024","format":false,"excerpt":"No raiar da \u00faltima quarta-feira, 1\u00ba de maio, algumas par\u00f3quias da Diocese de Sobral realizaram o \u201cDespertar com Maria\u201d onde fi\u00e9is cat\u00f3licos, devotos da virgem Maria participaram de programa\u00e7\u00e3o mariana em suas determinadas par\u00f3quias. O M\u00eas Mariano \u00e9 conhecido como m\u00eas dedicado a Virgem Maria. No dia 13 de maio,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Se-Catedral-de-Nossa-Senhora-da-Conceicao-1.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29437,"url":"https:\/\/correiodasemana.com\/site\/camara-municipal-de-sobral-realiza-homenagem-aos-40-anos-da-coroacao-de-nossa-senhora-no-arco\/","url_meta":{"origin":19943,"position":5},"title":"C\u00e2mara Municipal de Sobral realiza homenagem aos 40 anos da Coroa\u00e7\u00e3o de Nossa Senhora no Arco","author":"adminredacao","date":"Maio 27, 2024","format":false,"excerpt":"A C\u00e2mara Municipal de Sobral realizou uma Sess\u00e3o Solene em homenagem as Bodas de Esmeralda da Coroa\u00e7\u00e3o da imagem de Nossa Senhora no Arco de Nossa Senhora de F\u00e1tima nesta ter\u00e7a-feira, 21 de maio. O evento celebra neste ano quarenta anos de realiza\u00e7\u00e3o na Boullevard do Arco, espa\u00e7o sobralense tradicional\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Wedson-Araujo-comunidade-Shalom-e-vereador-Roberio-Cavalcante.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=19943"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19943\/revisions"}],"predecessor-version":[{"id":19951,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/19943\/revisions\/19951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/19950"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=19943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=19943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=19943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}