{"id":20069,"date":"2022-06-12T23:57:58","date_gmt":"2022-06-13T02:57:58","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20069"},"modified":"2022-06-12T23:57:58","modified_gmt":"2022-06-13T02:57:58","slug":"em-sobral-paroquia-do-patrocinio-celebra-solenemente-festa-do-divino-espirito-santo","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-sobral-paroquia-do-patrocinio-celebra-solenemente-festa-do-divino-espirito-santo\/","title":{"rendered":"Em Sobral, Par\u00f3quia do Patroc\u00ednio celebra solenemente festa do Divino Esp\u00edrito Santo"},"content":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) A Par\u00f3quia Nossa Senhora do Patroc\u00ednio, em Sobral, realizou entre os dias 26 de maio a 05 de junho a Festa do Divino Esp\u00edrito Santo na matriz, onde teve como tema: \u201cInspirada pelo Esp\u00edrito Santo, a comunidade partilha os dons e os bens\u201d.<br \/>\nDurante os nove dias, a Par\u00f3quia preparou-se profundamente para esta grande festa concluindo assim o tempo pascal, celebrada solenemente no Domingo de Pentecostes, dia este em que o Esp\u00edrito Santo desceu efusivamente sob Maria Sant\u00edssima e os Ap\u00f3stolos no Cen\u00e1culo. Diversos sacerdotes marcaram presen\u00e7a durante os noven\u00e1rios e a festa finalizou com prociss\u00e3o nas proximidades da matriz e em seguida, missa solene presidida por Dom Jos\u00e9 Luiz Gomes de Vasconcelos.<br \/>\nO Bispo Diocesano manifestou sua satisfa\u00e7\u00e3o por estar presente neste dia festivo com os seus diocesanos desta par\u00f3quia. Concelebrou com ele o P\u00e1roco e Vig\u00e1rio Geral da Diocese de Sobral, Pe. Agnaldo Tem\u00f3teo. \u201cSem o Esp\u00edrito Santo n\u00f3s n\u00e3o podemos dizer: Jesus \u00e9 o Senhor! \u00c9 o Esp\u00edrito Santo quem realiza tudo em todos. Assim como ele me chamou para ser bispo, chamou Pe. Agnaldo para ser presb\u00edtero, e chamou a todos pra ser crist\u00e3os, ele nos chama e continua derramando sobre n\u00f3s os seus dons e carismas. Realiza tudo em n\u00f3s. O Esp\u00edrito Santo \u00e9 o filho amado, amor que procede do pai e do filho, se manifesta atrav\u00e9s do amor\u201d. Disse Dom Vasconcelos \u00e0 assembl\u00e9ia durante a homilia.<br \/>\nO P\u00e1roco, Pe. Agnaldo agradeceu a todos os envolvidos na organiza\u00e7\u00e3o durante o per\u00edodo da festa, bem como aos noit\u00e1rios que se fizeram presentes, e a presen\u00e7a de Dom Vasconcelos no encerramento. O Pastor Diocesano ainda chamou aten\u00e7\u00e3o para a coleta diocesana em prol das v\u00edtimas das chuvas e enchentes em Pernambuco que haver\u00e1 no pr\u00f3ximo domingo, 12 de junho, dia este em que a igreja celebra a Solenidade da Sant\u00edssima Trindade. Toda a igreja particular da Diocese de Sobral estar\u00e1 realizando a coleta. Por fim, Dom Vasconcelos apagou o c\u00edrio pascal finalizando assim a P\u00e1scoa.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-20070\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-1-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-1-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-1-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-1.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-20071\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignleft size-medium wp-image-20072\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-3-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-3-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-3-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-3-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-3.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-20073\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-4-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-4-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-4-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-4-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-4.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-20074\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-5-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-5-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-5-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-5-768x512.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-5.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) A Par\u00f3quia Nossa Senhora do Patroc\u00ednio, em Sobral,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-20069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/SOLENIDADE-DE-PENTECOSTES-NA-IGREJA-DO-PATROCINIO-2.jpeg","jetpack-related-posts":[{"id":34183,"url":"https:\/\/correiodasemana.com\/site\/paroquia-de-nossa-senhora-do-patrocinio-celebra-festa-em-honra-ao-divino-espirito-santo\/","url_meta":{"origin":20069,"position":0},"title":"Par\u00f3quia de Nossa Senhora do Patroc\u00ednio celebra Festa em honra ao Divino Esp\u00edrito Santo","author":"adminredacao","date":"Junho 16, 2025","format":false,"excerpt":"De 29 de maio a 07 de junho, a comunidade paroquial da Par\u00f3quia de Nossa Senhora do Patroc\u00ednio celebrou com f\u00e9 e devo\u00e7\u00e3o os noven\u00e1rios em prepara\u00e7\u00e3o para a Festa do Divino Esp\u00edrito Santo na Igreja Matriz, com o tema: \u201cO Esp\u00edrito Santo vem em socorro de nossa fraqueza, pois\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-08-at-23.26.20.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-08-at-23.26.20.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-08-at-23.26.20.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-08-at-23.26.20.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-08-at-23.26.20.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35306,"url":"https:\/\/correiodasemana.com\/site\/devocao-e-esperanca-marcam-a-festa-de-nossa-senhora-do-patrocinio-em-sobral\/","url_meta":{"origin":20069,"position":1},"title":"Devo\u00e7\u00e3o e esperan\u00e7a marcam a Festa de Nossa Senhora do Patroc\u00ednio em Sobral","author":"adminredacao","date":"Agosto 25, 2025","format":false,"excerpt":"Entre os dias 7 e 17 de agosto, a Par\u00f3quia de Nossa Senhora do Patroc\u00ednio realizou os noven\u00e1rios em prepara\u00e7\u00e3o para a festa em honra \u00e0 sua excelsa padroeira, com o tema: \u201cPeregrinos de Esperan\u00e7a caminhando com Maria\u201d e o lema: \u201cMaria, ref\u00fagio dos pecadores\u201d. O termo Patroc\u00ednio refere-se a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/DSC_0881-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26359,"url":"https:\/\/correiodasemana.com\/site\/paroquia-de-nossa-senhora-do-patrocinio-celebra-138a-festa-da-padroeira\/","url_meta":{"origin":20069,"position":2},"title":"Par\u00f3quia de Nossa Senhora do Patroc\u00ednio celebra 138\u00aa festa da padroeira","author":"adminredacao","date":"Agosto 27, 2023","format":false,"excerpt":"Ap\u00f3s um itiner\u00e1rio de dez dias, de 10 a 20 de agosto, os paroquianos da Par\u00f3quia de Nossa Senhora do Patroc\u00ednio localizada no centro de Sobral participaram do encerramento da festa de sua excelsa padroeira, dia este em que a igreja no Brasil, celebra solenemente a Assun\u00e7\u00e3o de Maria aos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/DSC5582.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/DSC5582.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/DSC5582.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/08\/DSC5582.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10476,"url":"https:\/\/correiodasemana.com\/site\/regiao-episcopal-5\/","url_meta":{"origin":20069,"position":3},"title":"Regi\u00e3o Episcopal","author":"","date":"Janeiro 22, 2020","format":false,"excerpt":"Semin\u00e1rio de Vida no Esp\u00edrito Santo Dos dias 30 de janeiro a 02 de fevereiro, a Par\u00f3quia do Cristo Ressuscitado, em Sobral, estar\u00e1 promovendo o Semin\u00e1rio de Vida no Esp\u00edrito Santo para adultos. Ser\u00e3o dias de muita ora\u00e7\u00e3o para a renova\u00e7\u00e3o de nossa f\u00e9! Para mais informa\u00e7\u00f5es ligue (88) 31113348.\u2026","rel":"","context":"In &quot;Regi\u00e3o Episcopal&quot;","block_context":{"text":"Regi\u00e3o Episcopal","link":"https:\/\/correiodasemana.com\/site\/category\/regiao-episcopal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24918,"url":"https:\/\/correiodasemana.com\/site\/paroquia-do-patrocinio-ecc-comemora-40-anos-de-criacao\/","url_meta":{"origin":20069,"position":4},"title":"Par\u00f3quia do Patroc\u00ednio: ECC comemora 40 anos de cria\u00e7\u00e3o","author":"adminredacao","date":"Maio 29, 2023","format":false,"excerpt":"A Par\u00f3quia de Nossa Senhora do Patroc\u00ednio em Sobral celebrou neste domingo, 21\/05, os 40 anos de cria\u00e7\u00e3o do ECC (Encontro de Casais com Cristo), naquela par\u00f3quia onde realizam seu servi\u00e7o com muito amor. Em maio de 1983, gra\u00e7as ao empenho do saudoso Monsenhor Sabino, foi implantado o Encontro de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-26-at-13.34.13.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":28019,"url":"https:\/\/correiodasemana.com\/site\/solenidade-epifania-do-senhor-e-celebracao-dos-11-anos-de-fundacao-da-comunidade-catolica-mae-da-divina-providencia\/","url_meta":{"origin":20069,"position":5},"title":"Solenidade Epifania do Senhor e celebra\u00e7\u00e3o dos 11 anos de Funda\u00e7\u00e3o da Comunidade Cat\u00f3lica M\u00e3e da Divina Provid\u00eancia","author":"adminredacao","date":"Janeiro 15, 2024","format":false,"excerpt":"Com grande j\u00fabilo a Comunidade Cat\u00f3lica M\u00e3e da Divina Provid\u00eancia celebrou os 11 anos de sua funda\u00e7\u00e3o na Diocese de Sobral com a realiza\u00e7\u00e3o de uma Novena \u00e0 M\u00e3e da Divina Provid\u00eancia e teve a participa\u00e7\u00e3o especial dos nossos irm\u00e3os em situa\u00e7\u00e3o de rua. Uma Comunidade muito nova ainda, mas\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-13-at-22.04.30.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20069"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20069\/revisions"}],"predecessor-version":[{"id":20075,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20069\/revisions\/20075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/20071"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}