{"id":20091,"date":"2022-06-13T00:02:29","date_gmt":"2022-06-13T03:02:29","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20091"},"modified":"2022-06-13T00:23:46","modified_gmt":"2022-06-13T03:23:46","slug":"show-do-ivan-frota-fara-a-festa-dos-63-anos-da-fm-educadora-1075","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/show-do-ivan-frota-fara-a-festa-dos-63-anos-da-fm-educadora-1075\/","title":{"rendered":"Show do Ivan Frota far\u00e1 a festa  dos 63 anos da FM Educadora 107,5"},"content":{"rendered":"<p>J\u00e1 se foram 6 d\u00e9cadas no ar informando, educando e evangelizando. \u00c9 nesse clima que o programa Show do Ivan Frota far\u00e1 uma programa\u00e7\u00e3o especial para comemorar os 63 anos no ar, dia 21 de junho, uma ter\u00e7a-feira, das 7h \u00e0s 11h, no audit\u00f3rio da R\u00e1dio Rducadora, no Abrigo Cora\u00e7\u00e3o de Jesus. Teremos a participa\u00e7\u00e3o especial de Rosinha do Acordeon.<br \/>\nNa oportuinidade o programa Show do Ivan Frota homenagear\u00e1 as seguintes personalidades:<br \/>\nDom Jos\u00e9 Luiz Gomes de Vasconcelos, bispo de Sobral<br \/>\nPe. Lucas do Nascimento, diretor administrativo<br \/>\nDeputado Mo\u00e9sio Loiola, honra ao m\u00e9rito<br \/>\nCarlos Gomes Carneiro, ex-diretor<br \/>\nO Padre Lucas Moreira, diretor, agradece a presen\u00e7a de todos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 se foram 6 d\u00e9cadas no ar informando, educando e evangelizando. \u00c9 nesse clima que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-20091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/Ivan1.jpg","jetpack-related-posts":[{"id":20273,"url":"https:\/\/correiodasemana.com\/site\/radio-educadora-fm-1075-celebra-63-anos-de-criacao\/","url_meta":{"origin":20091,"position":0},"title":"R\u00e1dio Educadora FM 107,5 celebra 63 anos de cria\u00e7\u00e3o","author":"","date":"Junho 27, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Para celebrar o 63\u00ba anivers\u00e1rio da R\u00e1dio Educadora FM 107,5 houve uma programa\u00e7\u00e3o especial no p\u00e1tio da C\u00faria Diocesana na manh\u00e3 da \u00faltima ter\u00e7a-feira, dia 21 de junho, com o Show do Ivan Frota, homenagens, momento musical e anima\u00e7\u00e3o com Rosinha do Acordeon.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/06\/niver-radio-educadora.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8576,"url":"https:\/\/correiodasemana.com\/site\/radio-educadora-e-homenageada-por-seus-60-anos-no-programa-show-do-ivan-frota-no-becco-do-cotovelo\/","url_meta":{"origin":20091,"position":1},"title":"R\u00e1dio Educadora \u00e9 homenageada por seus 60 anos no programa Show do Ivan Frota no Becco do Cotovelo","author":"","date":"Agosto 6, 2019","format":false,"excerpt":"Funcion\u00e1rios e colaboradores que passaram pela emissora foram reconhecidos e homenageados pelo servi\u00e7o prestado e pertencentes \u00e0 hist\u00f3ria Com o objetivo de estender as comemora\u00e7\u00f5es referente aos 60 anos do anivers\u00e1rio de funda\u00e7\u00e3o da R\u00e1dio Educadora de Sobral, que aconteceu no dia 21 de junho, e homenagear mais pessoas que\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/08\/DSC_6124.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8310,"url":"https:\/\/correiodasemana.com\/site\/programa-show-do-ivan-frota-a-voz-do-becco-prestara-uma-homenagem-a-santa-casa-de-misericordia-de-sobral\/","url_meta":{"origin":20091,"position":2},"title":"Programa Show do Ivan Frota, a voz do Becco, prestar\u00e1 uma homenagem \u00e0 Santa Casa de Miseric\u00f3rdia de Sobral","author":"","date":"Julho 16, 2019","format":false,"excerpt":"Fazendo parte da programa\u00e7\u00e3o dos 246 anos da cidade de Sobral, o comunicador Ivan Frota, prestar\u00e1 uma homenagem aos 94 anos de exist\u00eancia da Santa Casa de Sobral O Diretor Geral da Santa Casa, Dr. Klebson Carvalho Soares convida os sobralenses a comparecer s\u00e1bado, dia 13 de julho, ao programa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-11-at-16.42.51.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-11-at-16.42.51.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-11-at-16.42.51.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/WhatsApp-Image-2019-07-11-at-16.42.51.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29634,"url":"https:\/\/correiodasemana.com\/site\/fm-educadora-comemora-65-anos-com-o-show-do-ivan-frota\/","url_meta":{"origin":20091,"position":3},"title":"FM Educadora comemora 65 anos com o Show do Ivan Frota","author":"adminredacao","date":"Junho 18, 2024","format":false,"excerpt":"O evento ser\u00e1 realizado dia 27\/06, quinta-feira, \u00e0s 09 horas da manh\u00e3, no audit\u00f3rio Dom Walfrido e contar\u00e1 com a participa\u00e7\u00e3o de todos os comunicadores da emissora. Para os presentes, teremos diversos sorteios e v\u00e1rias outras atra\u00e7\u00f5es. Convidamos todos os nossos ouvintes a participarem! O Diretor Padre Luca agradece a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-05-at-11.07.21.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":20181,"url":"https:\/\/correiodasemana.com\/site\/becco-ponto-com-89\/","url_meta":{"origin":20091,"position":4},"title":"Becco ponto Com","author":"","date":"Junho 19, 2022","format":false,"excerpt":"LIVRAI-NOS, SENHOR! 01. Do abandono do Becco do Cotovelo. 02. Do golpe dos politicos nos eleitores. 03. De um capit\u00e3o l\u00e1 e outro c\u00e1 em 2023. 04. Dos pastores ca\u00e7adores de votos, ui! 05. Das quadrilhas de pol\u00edticos este ano. 06. Do ensino paga e passa t\u00e3o fabricado. 07. Das\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/09\/Dr-Chico-Prado-Trofeu-Dom-Jose-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":11689,"url":"https:\/\/correiodasemana.com\/site\/morre-o-radialista-sobralense-ivan-moreira\/","url_meta":{"origin":20091,"position":5},"title":"Morre o radialista sobralense Ivan Moreira","author":"","date":"Julho 9, 2020","format":false,"excerpt":"Faleceu na manh\u00e3 desta quinta-feira, um dos mais conhecidos locutor esportivo da regi\u00e3o Norte do estado do Cear\u00e1, radialista Ivan Moreira, 63 anos.. Ivan Moreira comandava programas esportivos, atualmente na R\u00e1dio Tupinamb\u00e1 FM e R\u00e1dio Educadora do Nordeste AM. Ivan Moreira se destacou no mundo esportivo, atrav\u00e9s do esporte amador,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/DSC_7622.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20091"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20091\/revisions"}],"predecessor-version":[{"id":20092,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20091\/revisions\/20092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/20139"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}