{"id":20218,"date":"2022-06-20T00:00:13","date_gmt":"2022-06-20T03:00:13","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20218"},"modified":"2022-06-20T00:00:13","modified_gmt":"2022-06-20T03:00:13","slug":"semeadura-do-bem","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/semeadura-do-bem\/","title":{"rendered":"Semeadura do bem"},"content":{"rendered":"<p>A semeadura do bem \u00e9 tarefa e miss\u00e3o dos bons. Uma verdade que nos interpela a evitar a omiss\u00e3o e, especialmente, a expressar opini\u00f5es e ju\u00edzos na dire\u00e7\u00e3o do bem. Tristemente, na contram\u00e3o desse caminho, espanta o crescente sil\u00eancio dos bons, mesmo diante do agigantar-se dos maus. Semear o bem \u00e9 uma exigente labuta desigual, por se saber que o mal se espalha e contamina com uma impressionante velocidade. Mas, os semeadores do bem, fecundados pela serenidade e paci\u00eancia para colher os frutos a seu tempo, n\u00e3o devem se desanimar. S\u00e3o exigidos a pautar-se pela sabedoria da perseveran\u00e7a, pela intr\u00e9pida convic\u00e7\u00e3o de que o bem sempre vence o mal.<br \/>\nCompreende-se o sentido do magistral ensinamento de Jesus quando instru\u00eda seus disc\u00edpulos contando-lhes a par\u00e1bola do semeador que saiu a semear. As circunst\u00e2ncias diziam respeito \u00e0 qualidade da semente. Focalizava ainda a condi\u00e7\u00e3o de terrenos diferentes \u2013 pedregosos, cheios de espinhos, sem fundura suficiente \u2013 inviabilizando a semeadura que somente torna-se exitosa quando a terra \u00e9 boa. Jesus uniu a essa explicita\u00e7\u00e3o uma advert\u00eancia com a narra\u00e7\u00e3o de outra par\u00e1bola: a do joio e do trigo. Ao falar do Reino de Deus, sublinhou a boa semeadura feita no campo. Mas, conforme a par\u00e1bola, enquanto todos dormiam, veio o inimigo, semeou joio no meio do trigo. A par\u00e1bola conta que os oper\u00e1rios foram procurar o dono, surpresos, para informar o que havia ocorrido. Perguntaram: Senhor, n\u00e3o semeaste boa semente no teu campo? De onde veio o joio? O Senhor respondeu serenamente: algum inimigo fez isso. Os oper\u00e1rios quiseram arrancar o joio imediatamente, mas foram novamente instru\u00eddos com sabedoria e serenidade: arrancando o joio, poder-se-ia, indevidamente, perder o trigo. Em seguida, aconselhou deixar crescer um e outro, para tudo arrancar no momento certo da colheita.<br \/>\nO \u201cjoio\u201d no seu tempo devido ser\u00e1 arrancado, amarrado para ser queimado. O \u201ctrigo\u201d, fruto esperado, o bem, abarrotar\u00e1 os celeiros dos bons. O ensinamento da par\u00e1bola mostra que se caminha por uma linha muito t\u00eanue entre o bem e o mal. Uma linha t\u00e3o t\u00eanue que os n\u00e9scios e os incautos escorregam para o mal, convencidos de estar do lado do bem. Sobre essa falta de lucidez, o Mestre Jesus j\u00e1 advertia tratar-se de roubo e engano perpetrado pelo maligno, que deixa o cora\u00e7\u00e3o humano vazio das raz\u00f5es do bem. E o cora\u00e7\u00e3o vazio torna-se hospedagem de maquina\u00e7\u00f5es, tramas e artimanhas que buscam metas, aparentemente plaus\u00edveis, mas que na realidade s\u00e3o for\u00e7as para efetivar a destrui\u00e7\u00e3o. N\u00e3o apenas a destrui\u00e7\u00e3o dos outros, mas, cedo ou tarde, a pr\u00f3pria destrui\u00e7\u00e3o, de seus pr\u00f3ximos, de sua hist\u00f3ria e de seu patrim\u00f4nio.<br \/>\nO ensino magistral de Jesus clareia os indispens\u00e1veis entendimentos a respeito do que sublinha o Papa Francisco no cap\u00edtulo primeiro da sua Carta Enc\u00edclica sobre a Amizade Social, ao tratar das \u201csombras de um mundo fechado\u201d. As desastrosas consequ\u00eancias provocadas pelo distanciamento da semeadura do bem s\u00e3o evidentes. Dentre os preju\u00edzos est\u00e1 o aprisionamento de popula\u00e7\u00f5es em um provincianismo imobilizador, n\u00e3o permitindo enxergar horizontes mais largos, comprometendo a capacidade de olhar para o alto de uma montanha e ali divisar um horizonte iluminado para os sonhados dias melhores. Esses dias n\u00e3o vir\u00e3o dos paternalismos de pequenas e lisonjeadoras benesses, perpetuando atrasos e perpetrando irracionalidades \u201cvendidas\u201d como se fossem o caminho de um futuro melhor. Na verdade, essas irracionalidades s\u00e3o o \u201cjoio\u201d que tenta se camuflar no meio do \u201ctrigo\u201d. A colheita desse \u201cjoio\u201d \u00e9 um espantoso espectro de autofagia demolindo patrim\u00f4nios, heran\u00e7as, respeitabilidade de predecessores na hist\u00f3ria, tudo disfar\u00e7ado por um falso sentido de desenvolvimento.<br \/>\nEsse provincianismo tem sido fecundado e emoldurado pela t\u00e1tica autodestrutiva de tudo lan\u00e7ar no caos, achando, equivocadamente, que assim \u00e9 poss\u00edvel alcan\u00e7ar vit\u00f3ria, conquistar posses e riquezas. Mais perigoso ainda \u00e9 o fato de o \u00f3dio ser a lubrifica\u00e7\u00e3o dessa perversa engrenagem, ensandecendo aqueles que deveriam defender o direito e promover a justi\u00e7a. Compreende-se a urg\u00eancia de se investir em um novo humanismo integral, mobiliza\u00e7\u00e3o da Igreja Cat\u00f3lica para recompor o sentido da vida e efetivar uma ordem social, pol\u00edtica, econ\u00f4mica e cultural capaz de configurar uma sociedade mais justa, solid\u00e1ria e fraterna.<br \/>\nIndispens\u00e1vel \u00e9 labutar, operariamente, sempre e em todo lugar, na semeadura do bem para dissipar as sombras de um mundo fechado\u201d. Essas sombras, o \u201cjoio\u201d lan\u00e7ado no campo do \u201ctrigo\u201d, s\u00e3o muitas e precisam ser afrontadas com a ilumina\u00e7\u00e3o da semeadura do bem. No espectro dessas sombras, aten\u00e7\u00e3o especial seja dedicada ao enfrentamento da agressividade. H\u00e1 uma profus\u00e3o de formas ins\u00f3litas de hostilidades, com insultos, improp\u00e9rios, difama\u00e7\u00e3o, afrontas verbais, buscando destruir a imagem do semelhante. Essa agressividade apenas faz crescer a viol\u00eancia que destr\u00f3i vidas, o meio ambiente, patrim\u00f4nios e hist\u00f3rias, atrasando a colheita de bons frutos pela semeadura do bem.<br \/>\nDom Walmor Oliveira de Azevedo<br \/>\nArcebispo metropolitano de Belo Horizonte<br \/>\nPresidente da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A semeadura do bem \u00e9 tarefa e miss\u00e3o dos bons. Uma verdade que nos interpela&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[24,11],"tags":[],"class_list":["post-20218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-300x204.jpg",300,204,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-768x523.jpg",640,436,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",640,436,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",499,340,false]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/\" rel=\"category tag\">A voz do Pastor<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a>","tag_info":"Artigos","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":19203,"url":"https:\/\/correiodasemana.com\/site\/o-tempo-da-quaresma\/","url_meta":{"origin":20218,"position":0},"title":"O tempo da Quaresma","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"O tempo da Quaresma \u00e9 oferta da delicadeza de Deus, que chama seus filhos e filhas a buscar novos modos de viver, para qualificar a vida \u2013 que \u00e9 sempre dom. Importante lembrar: o tempo da vida corre aceleradamente, indom\u00e1vel, fazendo chegar novamente o per\u00edodo quaresmal, qualificado de espiritualidade e\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25664,"url":"https:\/\/correiodasemana.com\/site\/o-semeador-saiu-para-semear\/","url_meta":{"origin":20218,"position":1},"title":"O Semeador saiu para semear","author":"adminredacao","date":"Julho 17, 2023","format":false,"excerpt":"H\u00e1 poucos dias\u00a0tomou posse como Bispo de Camet\u00e1 Dom Ivanildo Oliveira Almeida. Seu lema episcopal \u00e9 \u201cEis que o semeador saiu a semear\u201d (Ecce exiit qui seminat seminare). \u00c9 a Igreja que cresce, e nossa Prov\u00edncia Eclesi\u00e1stica, assim como o Regional Norte II recebem com alegria este novo semeador da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33771,"url":"https:\/\/correiodasemana.com\/site\/queremos-ser-uma-igreja-que-avanca\/","url_meta":{"origin":20218,"position":2},"title":"\u201cQueremos ser uma Igreja que avan\u00e7a!\u201d","author":"adminredacao","date":"Maio 19, 2025","format":false,"excerpt":"Nestes \u00faltimos dias, a Igreja vivencia com alegria e expectativa os primeiros dias do pontificado do Papa Le\u00e3o XIV. Sua primeira apari\u00e7\u00e3o evidenciou as marcas de um homem sorridente, leve, pac\u00edfico e atento aos clamores da humanidade. Come\u00e7ou fazendo uma sauda\u00e7\u00e3o de paz e desejando que esta paz chegasse ao\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":19046,"url":"https:\/\/correiodasemana.com\/site\/russia-ataca-a-ucrania-e-papa-faz-apelo-de-paz\/","url_meta":{"origin":20218,"position":3},"title":"R\u00fassia ataca a Ucr\u00e2nia e Papa faz apelo de paz","author":"","date":"Fevereiro 27, 2022","format":false,"excerpt":"(Por Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Hoje, dia 24 de fevereiro o mundo acordou apreensivo com a not\u00edcia do ataque militar da R\u00fassia \u00e0 capital da Ucr\u00e2nia, em Kiev. O que era temido por muitos acabou acontecendo e o mundo est\u00e1 testemunhando uma nova guerra. De acordo com\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/GUERRA-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/GUERRA-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/GUERRA-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/GUERRA-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33990,"url":"https:\/\/correiodasemana.com\/site\/leao-xiv-na-audiencia-geral-a-palavra-de-deus-e-para-todos-mas-atua-diferente-em-cada-um\/","url_meta":{"origin":20218,"position":4},"title":"Le\u00e3o XIV na Audi\u00eancia Geral: a Palavra de Deus \u00e9 para todos, mas atua diferente em cada um","author":"adminredacao","date":"Junho 3, 2025","format":false,"excerpt":"Na sua primeira Audi\u00eancia Geral, o Papa retomou o ciclo de catequeses proposto por Francisco para refletir sobre as par\u00e1bolas. Le\u00e3o XIV escolheu aquela do semeador e afirmou que \u201cA Palavra de Jesus \u00e9 para todos, mas atua de uma forma diferente em cada pessoa\u201d, dependendo do solo encontrado, de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/Papa-Leao-XIV-audiencia-comunicacao.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/Papa-Leao-XIV-audiencia-comunicacao.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/Papa-Leao-XIV-audiencia-comunicacao.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/Papa-Leao-XIV-audiencia-comunicacao.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15097,"url":"https:\/\/correiodasemana.com\/site\/os-vastos-campos-da-evangelizacao\/","url_meta":{"origin":20218,"position":5},"title":"Os vastos campos da evangeliza\u00e7\u00e3o","author":"","date":"Dezembro 21, 2020","format":false,"excerpt":"Desde quando Jesus passou pelo mundo, h\u00e1 dois mil anos, a evangeliza\u00e7\u00e3o acontece. Uma tarefa \u00e1rdua e ininterrupta que Jesus pede a todos os seus seguidores: evangelizai. Impulsionados pelo IDE do Mestre, os disc\u00edpulos de todos os tempos s\u00e3o enviados a desbravar os vastos campos onde o Evangelho precisa ser\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20218"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20218\/revisions"}],"predecessor-version":[{"id":20219,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20218\/revisions\/20219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7687"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}