{"id":20301,"date":"2022-07-03T23:13:45","date_gmt":"2022-07-04T02:13:45","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20301"},"modified":"2022-07-03T23:13:45","modified_gmt":"2022-07-04T02:13:45","slug":"novo-equipamento-do-museu-do-eclipse-vai-aproximar-juventude-do-saber-cientifico","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/novo-equipamento-do-museu-do-eclipse-vai-aproximar-juventude-do-saber-cientifico\/","title":{"rendered":"Novo equipamento do Museu do Eclipse vai aproximar juventude do saber cient\u00edfico"},"content":{"rendered":"<p><strong><em>Com 26 experimentos para incentivar o conhecimento, o Centro Interativo de Ci\u00eancias foi inaugurado pela governadora Izolda Cela<\/em><\/strong><\/p>\n<p>Por Daniel Herculano &#8211; Comunica\u00e7\u00e3o Institucional\u00a0Texto &#8211; Thiago Gaspar e Carlos Gibaja\u00a0Fotos<\/p>\n<p>Sobral recebeu, nesta quinta-feira (30), sua mais nova atra\u00e7\u00e3o interativa, que funciona dentro da estrutura do Museu do Eclipse. \u00c9 o Centro Interativo de Ci\u00eancias, que proporciona uma experi\u00eancia imersiva e que vai entregar muito mais conhecimento cient\u00edfico aos seus visitantes. O evento de inaugura\u00e7\u00e3o contou com a presen\u00e7a da governadora Izolda Cela, recepcionada pela vice-prefeita de Sobral, Cristiane Coelho.<br \/>\nS\u00e3o 26 experimentos interativos com base na luz, parte de uma iniciativa de moderniza\u00e7\u00e3o dos espa\u00e7os cient\u00edficos e hist\u00f3ricos de Sobral. O espa\u00e7o prop\u00f5e uma experi\u00eancia mais din\u00e2mica para o p\u00fablico. \u201c\u00c9 uma alegria imensa estar aqui, e entregar um equipamento com tudo o que h\u00e1 de mais moderno e da melhor qualidade para garantir a intera\u00e7\u00e3o construtiva de aprendizagem. Que promova o interesse mesmo para aquelas pessoas que n\u00e3o t\u00eam conhecimento pr\u00e9vio de F\u00edsica e, assim, possa tamb\u00e9m despertar para as boas perguntas que a Ci\u00eancia pode responder\u201d, ressaltou a governadora Izolda Cela.<br \/>\nO Governo do Cear\u00e1 apoiou a moderniza\u00e7\u00e3o do equipamento ao realizar a aquisi\u00e7\u00e3o do novo maquin\u00e1rio do centro instalado no Museu do Eclipse, adquirido por meio da Secretaria da Ci\u00eancia, Tecnologia e Educa\u00e7\u00e3o Superior (Secitece). O investimento foi de cerca de R$ 5 milh\u00f5es, captados por meio do Programa de Moderniza\u00e7\u00e3o Tecnol\u00f3gica do Cear\u00e1 (Promotec II). Outros R$94 mil foram investidos pela Prefeitura de Sobral.<br \/>\nA vice-prefeita de Sobral, Cristiane Coelho, exaltou a capacidade n\u00e3o s\u00f3 de aprendizado, mas tur\u00edstica do equipamento. \u201cRecebemos com alegria esse museu interativo, onde nossos estudantes poder\u00e3o vir aqui fazer seus estudos e suas pesquisas. Mas, al\u00e9m disso, um lugar de fomentar a cultura e fomentar o turismo cient\u00edfico para nossa cidade e Regi\u00e3o Norte\u201d.<br \/>\nEntre os aparelhos adquiridos, destaque para o Holograma de Einstein, o Leitor de Bola de Cristal, o Quebra-Cabe\u00e7a a Laser e a Bicicleta de Relatividade. As atividades interativas incluem ainda a Harpa a Laser que, conectada a um sintetizador, produz som a partir da interrup\u00e7\u00e3o dos feixes de luz. Os outros equipamentos s\u00e3o: Raios de Luz 3D; M\u00e1quina do Olho; Holograma Especular; Luz Destilada; Intera\u00e7\u00e3o de Ondas; Capacetes de Difra\u00e7\u00e3o; Flu\u00eddo Birrefringente; Arco-\u00cdris da Areia; Microondas e Luz; Microfone Laser; Pong de Buraco Negro; Lente Gravitacional; Paradoxo dos G\u00eameos; \u00d3rbitas; Toque O In\u00edcio do Universo (Big-Bang); \u00d3ptica Ativa; Espelho Respirante; C\u00e2mera Infravermelha; Fotografia da Gota de \u00c1gua; Radiotelesc\u00f3pio e Empurr\u00e3o no Espa\u00e7o.<br \/>\nPara o secret\u00e1rio de Educa\u00e7\u00e3o de Sobral, Herbert Lima, o equipamento tamb\u00e9m vai para al\u00e9m das quest\u00f5es educacionais, pois aproximam os conceitos mais abstratos da popula\u00e7\u00e3o em geral. \u201cA parceria entre a Prefeitura de Sobral e o Governo do Cear\u00e1 permitiu a aquisi\u00e7\u00e3o de equipamentos e experimentos que vieram da Alemanha, desenvolvidos por uma empresa especializada na \u00e1rea de educa\u00e7\u00e3o cient\u00edfica. E assim vamos possibilitar aos estudantes experimentar uma s\u00e9rie de conceitos da Ci\u00eancia, principalmente esses conceitos t\u00e9cnicos que envolvem a luz, experimentos cient\u00edficos sobre \u00f3tica, ondulat\u00f3ria. Isso tem um significado importante porque vai compor o conjunto de equipamentos que fazem parte aqui do Parque da Luz. Agora temos o Planet\u00e1rio de Sobral, o Museu Hist\u00f3rico do Eclipse e, agora, o Centro Interativo para atender e disseminar cada vez mais a Ci\u00eancia\u201d, explica.<\/p>\n<p><strong>Promotec<\/strong><br \/>\nOs equipamentos se somam a outros j\u00e1 adquiridos por meio do Promotec para Sobral, como o projetor digital do Planet\u00e1rio de Sobral. Da marca alem\u00e3 Zeiss, o projetor utiliza intelig\u00eancia artificial e opera em terceira dimens\u00e3o com resolu\u00e7\u00e3o 4K.<br \/>\nEm sua segunda edi\u00e7\u00e3o, o programa tem promovido a moderniza\u00e7\u00e3o tecnol\u00f3gica em \u00e1reas estrat\u00e9gicas para o desenvolvimento do Estado, tais como seguran\u00e7a p\u00fablica, educa\u00e7\u00e3o, finan\u00e7as p\u00fablicas, meio ambiente e sa\u00fade, por meio da aquisi\u00e7\u00e3o de equipamentos e de servi\u00e7os de ponta. O Promotec \u00e9 coordenado pelo Governo do Cear\u00e1, por meio da Secitece.<br \/>\nFinalizando a entrega e visitando o equipamento, Izolda Cela pontuou a import\u00e2ncia da continuidade nos projetos em prol da popula\u00e7\u00e3o de Sobral e do Cear\u00e1. \u201cEquipamentos como esse se devem a uma a\u00e7\u00e3o de continuidade, de sustentabilidade e de uma boa pol\u00edtica. A pol\u00edtica que faz com que as obras, as a\u00e7\u00f5es e os projetos se expandam e ganhem mais qualidade, fiquem melhores para a cidade. E que fa\u00e7am o Cear\u00e1 brilhar cada vez mais\u201d, finalizou a governadora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 26 experimentos para incentivar o conhecimento, o Centro Interativo de Ci\u00eancias foi inaugurado pela&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-20301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/220630_MUSEU-DO-ECLIPSE-SOBRAL_TG2051-1536x1024-1.jpg","jetpack-related-posts":[{"id":29427,"url":"https:\/\/correiodasemana.com\/site\/poucas-e-boas-36\/","url_meta":{"origin":20301,"position":0},"title":"POUCAS E BOAS","author":"adminredacao","date":"Maio 27, 2024","format":false,"excerpt":"Eclipse de 19 Como quase todos sabem, o 29 de maio de 1919 ficou marcado na hist\u00f3ria de Sobral e da Ci\u00eancia gra\u00e7as \u00e0 comprova\u00e7\u00e3o neste munic\u00edpio da Teoria da Relatividade Geral, formulada pelo alem\u00e3o Albert Einstein (1879-1955), por ocasi\u00e3o do Eclipse Total do Sol. O fen\u00f4meno foi amplamente divulgado\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":33936,"url":"https:\/\/correiodasemana.com\/site\/106-anos-eclipse-sobral-relatividade-e-einstein\/","url_meta":{"origin":20301,"position":1},"title":"106 ANOS: Eclipse, Sobral, Relatividade e Einstein","author":"adminredacao","date":"Junho 3, 2025","format":false,"excerpt":"Como quase todos sabem, o 29 de maio de 1919 ficou marcado na hist\u00f3ria de Sobral e da Ci\u00eancia gra\u00e7as \u00e0 comprova\u00e7\u00e3o neste munic\u00edpio da Teoria da Relatividade Geral, formulada pelo alem\u00e3o Albert Einstein (1879-1955), por ocasi\u00e3o do Eclipse Total do Sol. O fen\u00f4meno foi amplamente divulgado por jornais sobralenses\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/artemisio-da-costa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":20782,"url":"https:\/\/correiodasemana.com\/site\/entregue-pela-governadora-izolda-cela-novo-restaurante-universitario-da-uva-em-sobral-oferta-quase-2-000-refeicoes-diarias\/","url_meta":{"origin":20301,"position":2},"title":"Entregue pela governadora Izolda Cela, novo restaurante universit\u00e1rio da UVA em Sobral oferta quase 2.000 refei\u00e7\u00f5es di\u00e1rias","author":"","date":"Agosto 29, 2022","format":false,"excerpt":"Isabella Campos- Ascom Casa Civil\u00a0Texto Na tarde desta quarta-feira, 24 de agosto de 2022, a governadora Izolda Cela esteve em Sobral para entregar o novo Restaurante Universit\u00e1rio (RU) do Campus Bet\u00e2nia da Universidade Estadual Vale do Acara\u00fa (UVA). Na ocasi\u00e3o, a governadora almo\u00e7ou ao lado dos estudantes e servidores da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/visita-isolda-na-uva-2-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10363,"url":"https:\/\/correiodasemana.com\/site\/novo-alto-do-cristo-em-sobral-e-inaugurado-pelo-governo-do-estado\/","url_meta":{"origin":20301,"position":3},"title":"Novo Alto do Cristo em Sobral \u00e9 inaugurado pelo Governo do Estado","author":"","date":"Janeiro 5, 2020","format":false,"excerpt":"O Governo do Estado do Cear\u00e1 entregou, nesta quinta-feira (26), a urbaniza\u00e7\u00e3o de um dos principais cart\u00f5es postais da cidade de Sobral, o Alto do Cristo. Entre outras autoridades, a inaugura\u00e7\u00e3o contou com a presen\u00e7a da vice-governadora Izolda Cela, representando o governador Camilo Santana; do prefeito de Sobral, Ivo Gomes;\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/01\/cartao22.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":19333,"url":"https:\/\/correiodasemana.com\/site\/cerimonia-de-transmissao-de-cargo-de-camilo-santana-para-izolda-cela-acontece-neste-sabado-2\/","url_meta":{"origin":20301,"position":4},"title":"Cerim\u00f4nia de transmiss\u00e3o de cargo de Camilo Santana para Izolda Cela acontece neste s\u00e1bado (2)","author":"","date":"Abril 3, 2022","format":false,"excerpt":"A solenidade de transmiss\u00e3o de cargo do governador Camilo Santana (PT) para a vice-governadora Izolda Cela (PDT) ocorre neste s\u00e1bado (2), \u00e0s 17 horas, no Pal\u00e1cio Aboli\u00e7\u00e3o, no Bairro Meireles, em Fortaleza. Antes da transmiss\u00e3o, Camilo Santana e Izolda Cela ir\u00e3o \u00e0 Assembleia Legislativa do Cear\u00e1 para as formalidades de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/Camilo-e-Izolda-Cela.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22623,"url":"https:\/\/correiodasemana.com\/site\/prefeitura-de-sobral-e-governo-do-ceara-inauguraram-diversas-obras\/","url_meta":{"origin":20301,"position":5},"title":"Prefeitura de Sobral e governo do Cear\u00e1 inauguraram diversas obras","author":"adminredacao","date":"Janeiro 8, 2023","format":false,"excerpt":"O prefeito Ivo Gomes e a governadora Izolda Cela realizaram, na sexta-feira (30\/12\/2022), uma s\u00e9rie de inaugura\u00e7\u00f5es em Sobral. A comitiva inaugurou a primeira etapa da internaliza\u00e7\u00e3o da rede el\u00e9trica do Centro Hist\u00f3rico de Sobral, o Centro de Educa\u00e7\u00e3o Infantil Guaracy Parente, no bairro Dom Expedito, o Parque da Esta\u00e7\u00e3o,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20301"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20301\/revisions"}],"predecessor-version":[{"id":20303,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20301\/revisions\/20303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/20302"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}