{"id":20344,"date":"2022-07-03T23:36:01","date_gmt":"2022-07-04T02:36:01","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20344"},"modified":"2022-07-03T23:36:01","modified_gmt":"2022-07-04T02:36:01","slug":"apos-69-anos-a-diocese-de-sobral-prepara-se-para-receber-imagem-peregrina-de-nossa-senhora-de-fatima","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/apos-69-anos-a-diocese-de-sobral-prepara-se-para-receber-imagem-peregrina-de-nossa-senhora-de-fatima\/","title":{"rendered":"Ap\u00f3s 69 anos, a Diocese de Sobral prepara-se para receber imagem peregrina de Nossa Senhora de F\u00e1tima"},"content":{"rendered":"<p>Pra\u00e7a da S\u00e9 ornamentada para acolher a imagem peregrina em 1953; Foto: Reprodu\u00e7\u00e3o<\/p>\n<p>(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana)<br \/>\nA Virgem Maria foi preservada do pecado, o anjo anunciou que ela seria a m\u00e3e do Salvador, ela diz \u201csim\u201d como consta no magn\u00edfica. J\u00e1 se tem not\u00edcia que os crist\u00e3os no s\u00e9culo II viviam essa devo\u00e7\u00e3o mariana. Depois desta data v\u00e1rios eventos na igreja foram celebrados. Por exemplo: Sistema lit\u00fargico e estudos. Chegando aos conc\u00edlios que afirmaram a venera\u00e7\u00e3o a Santa Maria. A Virgem Maria m\u00e3e do Salvador recebe v\u00e1rios t\u00edtulos, algo que hoje marca a comunidade eclesial. V\u00e1rias peregrina\u00e7\u00f5es foram realizadas, destacando-se em 1947, percorrendo toda a Europa pela primeira vez.<br \/>\nNesta a\u00e7\u00e3o mariana, exatamente em 1953 a Diocese de Sobral vive atividades mission\u00e1rias intensas sob a grande alegria e se preparou para receber a visita da imagem de Nossa Senhora de F\u00e1tima pelos Frades Franciscanos OFM, Serafim e Greg\u00f3rio (in memoriam) no dia 20 de outubro e terminaram no dia 31 do mesmo m\u00eas com enorme assist\u00eancia de fi\u00e9is e fruto espiritual nunca visto. Houve mais de 80 mil comunh\u00f5es. As prepara\u00e7\u00f5es foram feitas na Pra\u00e7a da S\u00e9 junto ao cruzeiro. (Livro de Tombo I: C\u00faria da Diocese de Sobral, p\u00e1g. 140; 1916-1959)<br \/>\nPara a gl\u00f3ria de Deus e alegria da comunidade eclesial que j\u00e1 sonhava com aquele t\u00e3o esperado e sonhado sinal de Deus, \u00e0s 17h30 do dia 1\u00ba de novembro de 1953, chegou por avi\u00e3o a imagem peregrina de Nossa Senhora de F\u00e1tima, trazida por Monsenhor Marques (in memoriam), Vig\u00e1rio do Bispado de Leiria em Portugal e por Pe. Francisco Leopoldo Demontier (in memoriam),\u00a0da Congrega\u00e7\u00e3o do PP dos doze cora\u00e7\u00f5es. Foi uma cena incompar\u00e1vel, cuja recep\u00e7\u00e3o, ocuparam-se os jornais de Fortaleza e Sobral. O jornal Correio da Semana pertencente a Diocese de Sobral publicou v\u00e1rias not\u00edcias deste acontecimento. (Ibden)<br \/>\nEste relato nos mostra quanta devo\u00e7\u00e3o e alegria a Deus pela intercess\u00e3o de Maria. Ap\u00f3s 69 anos, teremos novamente esta visita t\u00e3o bela da Imagem de Nossa Senhora \u00e0 Diocese de Sobral. Convidamos voc\u00ea devoto (a) de Maria, com t\u00edtulo de Nossa Senhora de F\u00e1tima para celebrar conosco esses dias de festa na cidade de Sobral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pra\u00e7a da S\u00e9 ornamentada para acolher a imagem peregrina em 1953; Foto: Reprodu\u00e7\u00e3o (Thais Helena&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20345,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-20344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/Igreja-da-Se-Catedral-1953.jpeg","jetpack-related-posts":[{"id":20426,"url":"https:\/\/correiodasemana.com\/site\/nossa-senhora-de-fatima-esta-de-volta\/","url_meta":{"origin":20344,"position":0},"title":"Nossa Senhora de F\u00e1tima est\u00e1 de volta&#8230;","author":"","date":"Julho 17, 2022","format":false,"excerpt":"A M\u00e3e de Deus e nossa, a Imaculada Concei\u00e7\u00e3o, sempre esteve e est\u00e1 entre n\u00f3s, mas, na Solenidade de Todos os Santos de 1953, dia 1\u00b0 de novembro, Sobral vivia um misto de f\u00e9, de alegria e de gratid\u00e3o! Dom Jos\u00e9 Tupinamb\u00e1 da Frota estava \u00e0 frente da grande Diocese\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/arco-de-sobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/arco-de-sobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/arco-de-sobral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/arco-de-sobral.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20605,"url":"https:\/\/correiodasemana.com\/site\/celebracoes-marcam-o-encerramento-da-peregrinacao-em-sobral\/","url_meta":{"origin":20344,"position":1},"title":"Celebra\u00e7\u00f5es marcam o encerramento da peregrina\u00e7\u00e3o em Sobral","author":"","date":"Agosto 1, 2022","format":false,"excerpt":"(Thais Helena \u2013 Reda\u00e7\u00e3o Correio da Semana) Os fi\u00e9is cat\u00f3licos participaram na noite do \u00faltimo s\u00e1bado, 23 de julho, da missa de encerramento da visita da imagem peregrina \u00e0 Sobral na Igreja Matriz de Nossa Senhora de F\u00e1tima. A imagem peregrina chegou \u00e0 Sobral no dia 16 de julho e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/igreja-peregrinacao-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16460,"url":"https:\/\/correiodasemana.com\/site\/sobral-sobral-40\/","url_meta":{"origin":20344,"position":2},"title":"Sobral, Sobral","author":"","date":"Maio 17, 2021","format":false,"excerpt":"QUANDO ALGU\u00c9M QUE A GENTE AMA MORRE, DEIXA DE VIVER ENTRE N\u00d3S E PASSA A VIVER DENTRO DE N\u00d3S !! MINHAS HIST\u00d3RIAS... COMO A VIRGEM MARIA MORREU ??? Neste m\u00eas de maio de 2021, em que o mundo comemora os 104 anos da primeira apari\u00e7\u00e3o de NOSSA SENHORA aos tr\u00eas\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/02\/artigo-carolino-radio.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29146,"url":"https:\/\/correiodasemana.com\/site\/paroquia-da-se-realiza-abertura-do-mes-mariano\/","url_meta":{"origin":20344,"position":3},"title":"Par\u00f3quia da S\u00e9 realiza abertura do M\u00eas Mariano","author":"adminredacao","date":"Maio 6, 2024","format":false,"excerpt":"A Santa Missa do 5\u00ba Domingo da P\u00e1scoa neste dia 28 de abril foi diferente na S\u00e9 Catedral de Nossa Senhora da Concei\u00e7\u00e3o. Em missa presidida por Dom Vasconcelos, foi realizada a abertura do m\u00eas mariano com a b\u00ean\u00e7\u00e3o e envio das imagens peregrinas, e os catequistas de todo o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-03-at-11.51.40.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":9568,"url":"https:\/\/correiodasemana.com\/site\/festa-da-mae-rainha-atrai-fieis-para-uma-grande-celebracao\/","url_meta":{"origin":20344,"position":4},"title":"Festa da M\u00e3e Rainha atrai fi\u00e9is para uma grande celebra\u00e7\u00e3o","author":"","date":"Outubro 28, 2019","format":false,"excerpt":"A programa\u00e7\u00e3o iniciou com uma carreata saindo da Par\u00f3quia do Patroc\u00ednio levando a acolhida dos peregrinos, terminando com a Coroa\u00e7\u00e3o de Nossa Senhora. \u201cUnidos ao Pai e Profeta, com a M\u00e3e Peregrina, cultivamos a nova terra Mariana\u201d foi o lema da festa\u00a0da M\u00e3e Rainha e Vencedora Tr\u00eas Vezes Admir\u00e1vel de\u2026","rel":"","context":"In &quot;Destaques&quot;","block_context":{"text":"Destaques","link":"https:\/\/correiodasemana.com\/site\/category\/destaques\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/10\/M%C3%A3e-Rainha-2019-3.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20465,"url":"https:\/\/correiodasemana.com\/site\/imagem-peregrina-de-nossa-senhora-de-fatima-estara-na-santa-casa-de-sobral-na-segunda-feira-18-07\/","url_meta":{"origin":20344,"position":5},"title":"Imagem Peregrina de Nossa Senhora de F\u00e1tima estar\u00e1 na Santa Casa de Sobral na segunda-feira (18\/07)","author":"","date":"Julho 17, 2022","format":false,"excerpt":"Com o tema \u201cSanta Maria, m\u00e3e da Eucaristia\u201d a programa\u00e7\u00e3o da peregrina\u00e7\u00e3o ser\u00e1 realizada de 16 a 24 de julho no munic\u00edpio de Sobral. A Santa Casa de Miseric\u00f3rdia de Sobral recebe na segunda-feira (18\/07) a imagem peregrina de Nossa Senhora de F\u00e1tima. Com o tema \u201cSanta Maria, m\u00e3e da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/peregrinacao-imagem.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/peregrinacao-imagem.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/peregrinacao-imagem.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/peregrinacao-imagem.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/07\/peregrinacao-imagem.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20344"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20344\/revisions"}],"predecessor-version":[{"id":20346,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20344\/revisions\/20346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/20345"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}