{"id":20866,"date":"2022-08-29T00:40:18","date_gmt":"2022-08-29T03:40:18","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=20866"},"modified":"2022-08-29T00:40:25","modified_gmt":"2022-08-29T03:40:25","slug":"ei-vi-o-senhor-mes-vocacional","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/ei-vi-o-senhor-mes-vocacional\/","title":{"rendered":"Ei vi o Senhor \u2013 M\u00eas Vocacional"},"content":{"rendered":"<p>Maria Madalena, segundo os te\u00f3logos, n\u00e3o \u00e9 a mulher que foi pega em adult\u00e9rio pronta para ser apedrejada, j\u00e1 que a Lei dava certo direito dela ser apedrejada porque estava cometendo adult\u00e9rio. Mas \u00e9 Maria de Magdala, a mulher de quem Jesus tinha expulsado 7 dem\u00f4nios.<br \/>\nO Senhor deseja sempre expulsar muitas coisas de nosso meio. \u00c0s vezes, n\u00f3s carregamos pesos como a inveja, o orgulho, a prepot\u00eancia, o medo, a vaidade (querendo o que n\u00e3o podemos), a ira, as revoltas, as saudades que nunca mais ser\u00e3o preenchidas e isso podemos chamar de esp\u00edritos maus. Os esp\u00edritos maus n\u00e3o s\u00e3o somente os esp\u00edritos dos dem\u00f4nios, mas \u00e9 todo e tudo aquilo que nos separa de Deus, que nos dispersa da presen\u00e7a e da vontade de Deus.<br \/>\nDiante desse ponto de vista, Maria Madalena era incapaz de ser a primeira pessoa a ver o Senhor ressuscitado. E olha para quem Jesus foi aparecer primeiro! Dessa forma, nessa narra\u00e7\u00e3o do sepulcro vazio, n\u00f3s contemplamos uma mulher que tinha ido ver o seu Senhor. Aqui vemos quem Jesus se transformou para Maria Madalena. Ela que era atormentada por sete dem\u00f4nios (o n\u00famero 7 na B\u00edblia \u00e9 sin\u00f4nimo de infinito). Ent\u00e3o n\u00e3o eram s\u00f3 sete, eram in\u00fameros. E ela n\u00e3o conseguia sair do lugar, ver sua dignidade. Ela era essa pessoa que se sentia incapaz.\u00a0 No entanto, quando ela encontrou Jesus, ele passou a ser o Senhor da sua vida.<br \/>\nEu pergunto: Quem \u00e9 o Senhor da sua vida? \u00c9 Jesus? \u00c9 Ele que manda na sua vida? \u00c9 Ele que diz \u201cvai\u201d e voc\u00ea vai? \u00c9 Ele que diz \u201cvem\u201d e voc\u00ea vem? Que diz \u201cfica\u201d e voc\u00ea fica? Que diz \u201csai\u201d e voc\u00ea sai? Que diz \u201cn\u00e3o compra\u201d e voc\u00ea n\u00e3o compra?<br \/>\nNesse sentido, Jesus passou a ser o Senhor de Maria Madalena. \u00c9 t\u00e3o tal que ela passou a ser seguidora de Jesus, porque ela n\u00e3o aguentou apenas ter recebido dele a gra\u00e7a de ter sido liberta de seus dem\u00f4nios. N\u00f3s tamb\u00e9m podemos ter um mal, sabe qual? O de querer s\u00f3 o que Jesus tem para n\u00f3s e n\u00e3o querer Ele para n\u00f3s. Podemos carregar dentro de n\u00f3s um peso muito grande de querer de Jesus s\u00f3 as curas, que minha vida esteja bem, que as doen\u00e7as n\u00e3o cheguem em mim nem na minha fam\u00edlia, nem em meus tios e nem no meu cachorro. Mas eu n\u00e3o quero Jesus na minha vida, n\u00e3o quero Jesus se metendo em nada\u00a0meu. Eu quero um Jesus que fique l\u00e1 e eu aqui, quando precisar dele eu vou e Ele me socorre. \u00c9 assim que deve ser?<br \/>\nQuando Maria Madalena foi liberta dos dem\u00f4nios, ela decidiu ser seguidora de Jesus e O seguiu at\u00e9 a cruz. Quem estava com Maria e Jo\u00e3o aos p\u00e9s da Cruz? Maria Madalena! Ela foi at\u00e9 o fim. Ficou com a M\u00e3e de Jesus at\u00e9 o fim. N\u00e3o desistiu, sentiu toda dor, fez um esc\u00e2ndalo quando Jesus foi crucificado, mas estava l\u00e1 e depois que Jesus morreu, quando ela tinha perdido o seu Senhor, sua refer\u00eancia, quando ela n\u00e3o sabia mais a quem seguir, ela ia ser banalizada. As pessoas iam perguntar a ela: \u201cCad\u00ea o teu Senhor? Aquele que foi pregado numa cruz?\u201d E essa era a noite na vida dela. Ela estava tomada de profunda dor. Mas n\u00e3o parou diante da dificuldade, mesmo sem saber que Jesus havia ressuscitado, ela foi velar o corpo do seu Senhor. Ela saiu de madrugada com Pedro e o disc\u00edpulo amado.<br \/>\nDe mulher possu\u00edda a mulher que anuncia a ressurrei\u00e7\u00e3o!<br \/>\nPor conseguinte, no momento em que ela ouviu a voz do Senhor lhe chamando pelo nome, ela acreditou que Ele havia ressuscitado e correu para anunciar. Ela \u00e9 a mulher que anuncia a ressurrei\u00e7\u00e3o! E Jesus foi a Pessoa que mais rompeu paradigmas e quebrou preconceitos. Maria, como mulher, era desprezada naquele tempo, n\u00e3o tinham privil\u00e9gios, entretanto, Jesus apareceu primeiro a ela. Assim, Maria passou de mulher possu\u00edda por v\u00e1rios dem\u00f4nios a mulher que anuncia a ressurrei\u00e7\u00e3o. Ela anuncia aos disc\u00edpulos e eles depois de receberem a visita de Jesus, tornam-se tamb\u00e9m anunciadores.<\/p>\n<p>Voc\u00ea quer ver Jesus? Esteja acordado!<\/p>\n<p>Francisco Adriano Silva<br \/>\nCofundador da Comunidade Filhos de Si\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maria Madalena, segundo os te\u00f3logos, n\u00e3o \u00e9 a mulher que foi pega em adult\u00e9rio pronta&#8230;<\/p>\n","protected":false},"author":1,"featured_media":65,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,87],"tags":[],"class_list":["post-20866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-filhos-de-siao"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg",1600,901,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9-300x169.jpg",300,169,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9-768x432.jpg",640,360,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9-1024x577.jpg",640,361,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg",1536,865,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg",1600,901,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg",1024,577,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg",540,304,false]},"author_info":{"info":[""]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/filhos-de-siao\/\" rel=\"category tag\">Filhos de Si\u00e3o<\/a>","tag_info":"Filhos de Si\u00e3o","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S\u00e9.jpg","jetpack-related-posts":[{"id":33194,"url":"https:\/\/correiodasemana.com\/site\/eis-que-faco-novas-todas-as-coisas\/","url_meta":{"origin":20866,"position":0},"title":"Eis que fa\u00e7o novas todas as coisas","author":"adminredacao","date":"Abril 7, 2025","format":false,"excerpt":"Na chamada mudan\u00e7a de \u00e9poca em que nos encontramos, \u00e9 frequente uma observa\u00e7\u00e3o a respeito dos mandamentos e as normas morais da vida crist\u00e3. Sobre os crist\u00e3os chega uma enxurrada de provoca\u00e7\u00f5es, dando conta que o mundo mudou, e muitas coisas antes consideradas como pecado deveriam ser admitidas com plena\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29537,"url":"https:\/\/correiodasemana.com\/site\/10-domingo-do-tempo-comum\/","url_meta":{"origin":20866,"position":1},"title":"10\u00b0 DOMINGO DO TEMPO COMUM\u00a0","author":"adminredacao","date":"Junho 10, 2024","format":false,"excerpt":"10\u00b0 Domingo do tempo Comum \u201cNo Senhor toda gra\u00e7a e reden\u00e7\u00e3o\u201d (Sl 129\/130) Celebramos neste domingo, o d\u00e9cimo deste tempo comum, ap\u00f3s termos celebrado as tr\u00eas solenidades que marcam este tempo que s\u00e3o: Sant\u00edssima Trindade, Corpus Christi e Sagrado Cora\u00e7\u00e3o de Jesus que celebramos na \u00faltima sexta-feira. Continuamos a celebrar\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30831,"url":"https:\/\/correiodasemana.com\/site\/para-valorizar-as-sementes-do-bem-plantadas-por-deus\/","url_meta":{"origin":20866,"position":2},"title":"Para valorizar as sementes do bem plantadas por Deus","author":"adminredacao","date":"Outubro 2, 2024","format":false,"excerpt":"Durante muitos s\u00e9culos Deus formou seu povo escolhido, dando-lhe leis e mandamentos justos, que proporcionaram a tantos homens e mulheres vislumbrarem a realiza\u00e7\u00e3o das promessas, na expectativa da plena realiza\u00e7\u00e3o do projeto do Senhor. Ao longo do caminho, muitas foram as li\u00e7\u00f5es e os corretivos feitos por Deus, atrav\u00e9s de\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":36732,"url":"https:\/\/correiodasemana.com\/site\/comunidade-catolica-filhos-de-siao-19\/","url_meta":{"origin":20866,"position":3},"title":"COMUNIDADE CAT\u00d3LICA FILHOS DE SI\u00c3O","author":"adminredacao","date":"Dezembro 11, 2025","format":false,"excerpt":"Perigos que pedem vigil\u00e2ncia! Com o tempo de caminhada, passamos a n\u00e3o perceber certos perigos. No entanto, precisamos ter muito cuidado para n\u00e3o perdermos a gra\u00e7a inicial do chamado de Deus. Inicio parafraseando nossa Fundadora, Vander L\u00facia:\u00a0\u201cEstamos vivendo os tempos de No\u00e9, e a arca est\u00e1 sendo constru\u00edda diante dos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":28692,"url":"https:\/\/correiodasemana.com\/site\/solenidade-de-sao-jose-2\/","url_meta":{"origin":20866,"position":4},"title":"SOLENIDADE DE S\u00c3O JOS\u00c9\u00a0","author":"adminredacao","date":"Mar\u00e7o 18, 2024","format":false,"excerpt":"Celebramos no pr\u00f3ximo dia 19 de mar\u00e7o de 2024 a Solenidade de S\u00e3o Jos\u00e9, patrono universal da Igreja, esposo da Virgem Maria e pai adotivo de Jesus. Lembramos de S\u00e3o Jos\u00e9 como o chefe de fam\u00edlia, e um pai cuidadoso e zeloso e fiel cumpridor das leis judaicas. No dia\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23984,"url":"https:\/\/correiodasemana.com\/site\/ressurreicao-e-vida\/","url_meta":{"origin":20866,"position":5},"title":"RESSURREI\u00c7\u00c3O E VIDA","author":"adminredacao","date":"Abril 11, 2023","format":false,"excerpt":"\u201cD\u00e1-me de beber uma \u00e1gua viva!\u201d \u201cEu sou a luz do mundo!\u201d \u201cEu sou a ressurrei\u00e7\u00e3o e a vida!\u201d Todos n\u00f3s, envolvidos na prepara\u00e7\u00e3o da P\u00e1scoa, somos chamados ao novo encontro com Jesus Cristo, nossa P\u00e1scoa, nossa esperan\u00e7a. A partir de \u00e2ngulos diferentes, todos caminhamos para ele, a fim de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=20866"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20866\/revisions"}],"predecessor-version":[{"id":20867,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/20866\/revisions\/20867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/65"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=20866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=20866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=20866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}