{"id":22595,"date":"2023-01-08T21:34:48","date_gmt":"2023-01-09T00:34:48","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=22595"},"modified":"2023-01-10T21:35:40","modified_gmt":"2023-01-11T00:35:40","slug":"lula-toma-posse-como-39o-presidente-da-republica","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/lula-toma-posse-como-39o-presidente-da-republica\/","title":{"rendered":"Lula toma posse como 39\u00ba Presidente da Rep\u00fablica"},"content":{"rendered":"<p><strong><em>Aos 77 anos, petista assume mandato pela 3\u00aa vez, com o desafio de pacificar o pa\u00eds e acabar com a fome em um cen\u00e1rio econ\u00f4mico incerto<\/em><\/strong><\/p>\n<p>O pernambucano, ex-sindicalista e fundador do Partido dos Trabalhadores Luiz In\u00e1cio Lula da Silva, 77 anos, assume pela 3\u00aa vez a Presid\u00eancia da Rep\u00fablica neste domingo, 1\u00ba de janeiro de 2023. Torna-se o 39\u00ba presidente da Rep\u00fablica Federativa do Brasil. O petista j\u00e1 havia assumido o cargo por 2 mandatos (2003-2010). Eleito em 2\u00ba turno com 50,9% dos votos v\u00e1lidos (60,3 milh\u00f5es de votos), Lula sobe a rampa do Pal\u00e1cio do Planalto com a miss\u00e3o de pacificar e reconciliar o pa\u00eds. Ele derrotou Jair Bolsonaro, que teve 49,1% dos votos (58,2 milh\u00f5es de votos). Foi a menor diferen\u00e7a entre 2 finalistas nas \u00faltimas 9 disputas presidenciais, desde 1989.<br \/>\nAo discursar \u00e0 na\u00e7\u00e3o depois de tomar posse perante o Congresso Nacional, Lula dever\u00e1 focar na tese de reconstru\u00e7\u00e3o do pa\u00eds deixado pelo governo Bolsonaro. Indicar\u00e1 que sua principal miss\u00e3o \u00e9 acabar com a fome extrema e enfatizar\u00e1 o car\u00e1ter social que pretende dar ao seu novo mandato. Janja espera 300 mil pessoas na posse de Lula em 1\u00ba de janeiro Tamb\u00e9m deve fazer um contraponto com o antecessor ao mostrar que o fortalecimento da democracia passa necessariamente pela pol\u00edtica. Deve ainda citar preocupa\u00e7\u00f5es com o desmatamento na Amaz\u00f4nia e prometer compromissos com solu\u00e7\u00f5es para mudan\u00e7as clim\u00e1ticas.<br \/>\nOs temas que dever\u00e3o ser abordados em seus discursos resumem parte do que o petista tem sinalizado como norteadores do seu novo governo. Lula demorou quase 2 meses inteiros para definir a composi\u00e7\u00e3o da Esplanada, que ter\u00e1 37 minist\u00e9rios. Aliados de Lula est\u00e3o contemplados com cargos na nova gest\u00e3o. Em busca de amplia\u00e7\u00e3o da sua base de apoio no Congresso e, consequentemente, de governabilidade, o petista abriu espa\u00e7o tamb\u00e9m para partidos que n\u00e3o o apoiaram nas elei\u00e7\u00f5es, mas que aderiram na montagem do novo governo. Ao todo, 9 partidos ter\u00e3o ministros: PT, PSB, PC do B, PDT, Psol, Rede, MDB, PSD e Uni\u00e3o Brasil. (Leia mais abaixo).<br \/>\nAntes mesmo de assumir o mandato, Lula j\u00e1 obteve uma vit\u00f3ria parcial, por\u00e9m importante, no Congresso. Conseguiu aprovar uma PEC (proposta de emenda \u00e0 Constitui\u00e7\u00e3o) que o autorizou a furar o teto de gastos em R$ 170 bilh\u00f5es. Assegurou, assim, recursos para os R$ 600 do Aux\u00edlio Brasil, que volta a se chamar Bolsa Fam\u00edlia. A mudan\u00e7a de nome ainda depender\u00e1 de aprova\u00e7\u00e3o no Congresso. O petista inicia seu governo em um cen\u00e1rio econ\u00f4mico incerto. A taxa de juros est\u00e1 alta, a infla\u00e7\u00e3o acima da meta e o crescimento global desacelera. O deficit da Uni\u00e3o em 2023 \u00e9 estimado em R$ 231,5 bilh\u00f5es&#8230;.<\/p>\n<p>Na pol\u00edtica, ter\u00e1 o desafio de reduzir a influ\u00eancia do bolsonarismo na oposi\u00e7\u00e3o ao seu governo. Para 34% dos eleitores, a administra\u00e7\u00e3o petista ser\u00e1 pior que a de Bolsonaro. Com Lula, toma posse tamb\u00e9m neste domingo como vice-presidente, o m\u00e9dico anestesista, ex-tucano e ex-governador de S\u00e3o Paulo, Geraldo Alckmin (PSB), 69 anos, um antigo advers\u00e1rio. A alian\u00e7a, constru\u00edda desde 2021, foi parte de um movimento para mostrar que um novo governo Lula n\u00e3o se restringiria ao PT e a partidos de esquerda. Houve tamb\u00e9m a inten\u00e7\u00e3o de amenizar a resist\u00eancia de setores mais conservadores, como o agroneg\u00f3cio e o mercado financeiro, e atrair eleitores que, tradicionalmente, n\u00e3o votariam no PT. Lula tamb\u00e9m ter\u00e1 ao seu lado a primeira-dama Ros\u00e2ngela Lula da Silva, a Janja. Atuante desde a pr\u00e9-campanha eleitoral, ela ganhou protagonismo e destaque depois da elei\u00e7\u00e3o de seu marido. Foi a respons\u00e1vel pela produ\u00e7\u00e3o da cerim\u00f4nia de posse e do \u201cFestival do Futuro\u201d, s\u00e9rie de shows que ser\u00e3o realizados ao longo deste domingo na Esplanada dos Minist\u00e9rios. O evento ficou conhecido popularmente como \u201cLulapalooza\u201d.<br \/>\nFonte: O Poder 360<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos 77 anos, petista assume mandato pela 3\u00aa vez, com o desafio de pacificar o&#8230;<\/p>\n","protected":false},"author":7,"featured_media":22596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-22595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/brasilia.jpg","jetpack-related-posts":[{"id":21484,"url":"https:\/\/correiodasemana.com\/site\/lula-e-eleito-presidente-da-republica-pela-terceira-vez\/","url_meta":{"origin":22595,"position":0},"title":"Lula \u00e9 eleito presidente da Rep\u00fablica pela terceira vez","author":"","date":"Novembro 6, 2022","format":false,"excerpt":"Da Reda\u00e7\u00e3o \/Fonte Ag\u00eancia Senado\u2039 Luiz In\u00e1cio Lula da Silva foi eleito no domingo (30 de outubro de 2022) presidente do Brasil com\u00a060.341.333 votos \u2014 o equivalente a 50,90% dos v\u00e1lidos. No dia 1\u00ba de janeiro de 2023, ele assume o terceiro mandato n\u00e3o consecutivo \u00e0 frente do Pal\u00e1cio do\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/lula-presidente.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/lula-presidente.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/11\/lula-presidente.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23114,"url":"https:\/\/correiodasemana.com\/site\/conselho-do-bndes-aprova-mercadante-como-novo-presidente\/","url_meta":{"origin":22595,"position":1},"title":"Conselho do BNDES aprova Mercadante como novo presidente","author":"","date":"Janeiro 26, 2023","format":false,"excerpt":"Nome do ex-ministro do governo Dilma Rousseff foi indicado por Luiz In\u00e1cio Lula da Silva antes da posse do Planalto; atua\u00e7\u00e3o do pol\u00edtico na campanha presidencial n\u00e3o feriu a Lei das Estatais, segundo ministro do TCU. O Conselho de Administra\u00e7\u00e3o do Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) aprovou\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/lula-e-mercadante770.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/lula-e-mercadante770.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/lula-e-mercadante770.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/lula-e-mercadante770.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23013,"url":"https:\/\/correiodasemana.com\/site\/brasil-e-argentina-estudam-criacao-de-moeda-unica\/","url_meta":{"origin":22595,"position":2},"title":"Brasil e Argentina estudam cria\u00e7\u00e3o de moeda \u00fanica","author":"","date":"Janeiro 23, 2023","format":false,"excerpt":"Ministro da Economia argentino afirmou ao \u201cFT\u201d que cria\u00e7\u00e3o de moeda \u00fanica ser\u00e1 analisada durante a visita do brasileiro ao pa\u00eds. Brasil e Argentina devem analisar a cria\u00e7\u00e3o de uma moeda comum do Mercosul (Mercado Comum do Sul) durante a visita do presidente Luiz In\u00e1cio Lula da Silva (PT) ao\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/file.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/file.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/file.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/file.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23298,"url":"https:\/\/correiodasemana.com\/site\/novo-congresso-toma-posse-nesta-quarta-1\/","url_meta":{"origin":22595,"position":3},"title":"Novo Congresso toma posse nesta quarta (1) fevereiro","author":"","date":"Fevereiro 1, 2023","format":false,"excerpt":"Nesta quarta-feira, 1\u00ba, inicia-se oficialmente a\u00a053\u00aa legislatura do\u00a0Congresso Nacional, com a posse de deputados federais e senadores eleitos e reeleitos no dia 2 de outubro do ano passado. Os primeiros exercer\u00e3o um mandato no quadri\u00eanio 2023-2027. Os integrantes da Casa Alta do Parlamento brasileiro, por sua vez, ter\u00e3o oito anos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/02\/imagem_materia.jfif_.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":32098,"url":"https:\/\/correiodasemana.com\/site\/prefeito-vice-e-vereadores-tomam-posse-para-mandato-2025-2028\/","url_meta":{"origin":22595,"position":4},"title":"Prefeito, vice e vereadores tomam posse para mandato 2025\/2028","author":"adminredacao","date":"Janeiro 15, 2025","format":false,"excerpt":"A C\u00e2mara de Vereadores de Sobral realizou, na tarde de quarta-feira (01\/01\/2025), no Plen\u00e1rio 05 de Julho, a solenidade de instala\u00e7\u00e3o da legislatura 2025-2028, compromisso e posse dos vereadores, prefeito e vice-prefeita eleitos em Sobral. O vereador Carlos do Calisto (PSB), mais votado no pleito de 2024, presidiu a mesa\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Prefeito-vice-prefeita-e-vereadores-empossados-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":27967,"url":"https:\/\/correiodasemana.com\/site\/educacao-e-cidadania-30\/","url_meta":{"origin":22595,"position":5},"title":"EDUCA\u00c7\u00c3O E CIDADANIA \u2022","author":"adminredacao","date":"Janeiro 8, 2024","format":false,"excerpt":"Diferen\u00e7a entre Voto Censit\u00e1rio e Voto Universal Existe o sufr\u00e1gio direto e o indireto. O sufr\u00e1gio direto \u00e9 o voto quando os eleitores escolhem seus representes diretamente. J\u00e1 o sufr\u00e1gio indireto \u00e9 quando o voto \u00e9 escolhido pelos representantes ou delegados do povo indiretamente. \u201cSufr\u00e1gio\u00a0\u00e9 o poder pol\u00edtico delegado aos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/02\/Salmito-Campos-1-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/22595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=22595"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/22595\/revisions"}],"predecessor-version":[{"id":22597,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/22595\/revisions\/22597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/22596"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=22595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=22595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=22595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}