{"id":23877,"date":"2023-04-11T10:13:24","date_gmt":"2023-04-11T13:13:24","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=23877"},"modified":"2023-04-11T10:13:24","modified_gmt":"2023-04-11T13:13:24","slug":"escola-sao-francisco-de-assis-faz-doacao-de-alimentos-roupas-e-materiais-de-higiene-para-o-orfanato-sao-francisco","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/escola-sao-francisco-de-assis-faz-doacao-de-alimentos-roupas-e-materiais-de-higiene-para-o-orfanato-sao-francisco\/","title":{"rendered":"Escola S\u00e3o Francisco de Assis faz doa\u00e7\u00e3o de alimentos, roupas e materiais de higiene para o Orfanato S\u00e3o Francisco"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-23878\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-300x199.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-1024x678.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-768x509.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-1536x1017.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_7999-2048x1357.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-23879\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-300x199.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-1024x678.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-768x509.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-1536x1017.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8004-2048x1356.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-23880\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-300x199.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-1024x678.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-768x509.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-1536x1017.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8007-2048x1356.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-23881\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-300x199.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-1024x678.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-768x509.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-1536x1017.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8015-2048x1356.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-23882\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-300x199.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-1024x678.jpg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-768x509.jpg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-1536x1017.jpg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018-2048x1356.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>A Escola S\u00e3o Francisco de Assis, realizou hoje no dia 05\/04, a entrega de alimentos, roupas, materiais de higiene para o Orfanato S\u00e3o Francisco de Assis, tendo como objetivo principal a arrecada\u00e7\u00e3o desses produtos para proporcionar as pessoas carentes e seus familiares uma alimenta\u00e7\u00e3o digna e desenvolvendo assim, um ato de solidariedade, amor e respeito com seu pr\u00f3ximo. O alimento \u00e9 direito de cada cidad\u00e3o, vindo a estabelecer e conduzi-los numa cidadania justa e participativa na democracia. O projeto foi realizado no Ensino Fundamental I e II, pelas professoras de Forma\u00e7\u00e3o Humana e Religiosa, tias Cleidenir e Elaine, juntamente com o Frei Gleison e com o objetivo de promover a Camapanha da Fraternidade de 2023 que tem como tema \u2018A fraternidade e a fome\u2019. Aproveitamos esse momento para agradecer as doa\u00e7\u00f5es feitas pelos alunos e familiares com muito amor e carinho. Doar \u00e9 um ato de amor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Escola S\u00e3o Francisco de Assis, realizou hoje no dia 05\/04, a entrega de alimentos,&#8230;<\/p>\n","protected":false},"author":7,"featured_media":23882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-23877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/DSC_8018.jpg","jetpack-related-posts":[{"id":27722,"url":"https:\/\/correiodasemana.com\/site\/escola-sao-francisco-de-assis-encerra-suas-atividades-escolares-e-deixa-um-legado-de-56-anos-de-historia\/","url_meta":{"origin":23877,"position":0},"title":"Escola S\u00e3o Francisco de Assis encerra suas atividades escolares e deixa um legado de 56 anos de hist\u00f3ria","author":"adminredacao","date":"Dezembro 19, 2023","format":false,"excerpt":"A comunidade educacional de Sobral foi surpreendida com o an\u00fancio do fechamento da Escola S\u00e3o Francisco de Assis (ESFA). Com 56 anos de hist\u00f3ria, a institui\u00e7\u00e3o comunicou na quarta-feira, 13 de dezembro, o encerramento de suas atividades escolares, marcando o fim de uma era para a educa\u00e7\u00e3o na cidade. A\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/esfasobral.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/esfasobral.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/esfasobral.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/esfasobral.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/12\/esfasobral.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":20699,"url":"https:\/\/correiodasemana.com\/site\/casa-viva-a-vida-celebra-22-anos-de-acolhimento-e-solidariedade-a-pacientes-oncologicos-da-santa-casa-de-sobral\/","url_meta":{"origin":23877,"position":1},"title":"Casa Viva a Vida celebra 22 anos de acolhimento e solidariedade a pacientes oncol\u00f3gicos da Santa Casa de Sobral","author":"","date":"Agosto 14, 2022","format":false,"excerpt":"Al\u00e9m de alimentos, materiais de higiene e limpeza, roupas tamb\u00e9m podem ser doadas para o projeto. A Casa Viva a Vida \u2013 servi\u00e7o social do Complexo Santa Casa de Miseric\u00f3rdia de Sobral - celebra nesta sexta-feira (12\/08) seus 22 anos de exist\u00eancia. O projeto nasceu do desejo de proporcionar estadia\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/santa-casa-2-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/santa-casa-2-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/08\/santa-casa-2-1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":35836,"url":"https:\/\/correiodasemana.com\/site\/jantar-beneficente-em-prol-da-casa-sao-francisco-reune-mais-de-400-pessoas\/","url_meta":{"origin":23877,"position":2},"title":"Jantar beneficente em prol da Casa S\u00e3o Francisco re\u00fane mais de 400 pessoas","author":"adminredacao","date":"Outubro 13, 2025","format":false,"excerpt":"Institui\u00e7\u00e3o acolhe crian\u00e7as de 0 a 6 anos em situa\u00e7\u00e3o de vulnerabilidade social Em clima de alegria e fraternidade, a Comunidade Cat\u00f3lica Shalom em Sobral realizou, na noite desta quinta-feira, 9 de outubro, o Jantar Sua M\u00e3o \u00e9 Abrigo, em prol da Casa S\u00e3o Francisco, institui\u00e7\u00e3o que acolhe crian\u00e7as de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/10\/IMG_3490-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24381,"url":"https:\/\/correiodasemana.com\/site\/alunos-da-escola-sao-francisco-de-assis-visitam-o-jornal-correio-da-semana\/","url_meta":{"origin":23877,"position":3},"title":"Alunos da Escola S\u00e3o Francisco de Assis visitam o Jornal Correio da Semana","author":"adminredacao","date":"Maio 1, 2023","format":false,"excerpt":"Nesta quinta-feira (27), alunos da escola s\u00e3o Francisco de Assis fizeram uma visita ao jornal mais antigo em circula\u00e7\u00e3o do estado do Cear\u00e1. Eles puderam conhecer um pouco da produ\u00e7\u00e3o das mat\u00e9rias, conversaram com o rep\u00f3rter fotogr\u00e1fico Macildo Brito e conheceram um pouco da hist\u00f3ria centen\u00e1ria do jornal. Os estudantes\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/colegio-jornal-125x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11569,"url":"https:\/\/correiodasemana.com\/site\/abrigo-de-criancas-lanca-campanha-apadrinhar-para-amar-hoje\/","url_meta":{"origin":23877,"position":4},"title":"Abrigo de crian\u00e7as lan\u00e7a campanha \u201cApadrinhar para Amar Hoje\u201d","author":"","date":"Julho 2, 2020","format":false,"excerpt":"Campanha visa contribuir para a manuten\u00e7\u00e3o da Casa S\u00e3o Francisco, que acolhe crian\u00e7as de 0 a 6 anos em situa\u00e7\u00e3o de risco social. Por Socorro Mouta Voc\u00ea j\u00e1 parou para imaginar quanta diferen\u00e7a R$ 2,00 reais podem fazer na vida de quem muito precisa? Para as crian\u00e7as da Casa S\u00e3o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-06-30-at-09.57.50.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-06-30-at-09.57.50.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-06-30-at-09.57.50.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/07\/WhatsApp-Image-2020-06-30-at-09.57.50.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10694,"url":"https:\/\/correiodasemana.com\/site\/santa-casa-de-misericordia-de-sobral-oficializa-parceria-com-colegios-particulares-e-lanca-projeto-filhos-da-misericordia\/","url_meta":{"origin":23877,"position":5},"title":"Santa Casa de Miseric\u00f3rdia de Sobral oficializa parceria com col\u00e9gios particulares e lan\u00e7a Projeto Filhos da Miseric\u00f3rdia","author":"","date":"Fevereiro 3, 2020","format":false,"excerpt":"Representantes do\u00a0Col\u00e9gio Luciano Feij\u00e3o,\u00a0Col\u00e9gio Jos\u00e9 Rom\u00e3o\u00a0e\u00a0Escola S\u00e3o Francisco de Assis\u00a0participaram de cerim\u00f4nia de entrega de bolsas de estudos integrais para filhos de funcion\u00e1rios. Assessoria de Comunica\u00e7\u00e3o do Complexo SCMS A Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) realizou na sexta-feira (24\/01) o lan\u00e7amento do\u00a0Projeto Filhos da Miseric\u00f3rdia, com a entrega\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Foto-principal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Foto-principal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Foto-principal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/02\/Foto-principal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/23877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=23877"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/23877\/revisions"}],"predecessor-version":[{"id":23883,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/23877\/revisions\/23883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/23882"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=23877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=23877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=23877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}