{"id":26335,"date":"2023-08-27T21:54:20","date_gmt":"2023-08-28T00:54:20","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=26335"},"modified":"2023-08-27T21:54:20","modified_gmt":"2023-08-28T00:54:20","slug":"filhos-de-siao-7","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/filhos-de-siao-7\/","title":{"rendered":"Filhos de Si\u00e3o"},"content":{"rendered":"<p><strong>O grande an\u00fancio: Deus \u00e9 amor<\/strong><\/p>\n<p>Eu li recentemente que o \u00f3bvio tamb\u00e9m precisa ser dito, ent\u00e3o vou come\u00e7ar dizendo que: Deus te ama!<br \/>\nNa exorta\u00e7\u00e3o Christus Vivit, o Papa nos diz que esta \u00e9 uma verdade que n\u00e3o pode nunca ser silenciada, quantas vezes forem poss\u00edveis, oportuna e inoportunamente, deve ser dita e lembrada. Esse an\u00fancio se converte em tr\u00eas grandes verdades e n\u00f3s vamos falar sobre cada uma delas.<br \/>\n1\u00aa Verdade: Deus \u00e9 amor<br \/>\nOuvimos tanto que \u00e0s vezes esquecemos de acreditar. Mas em toda e qualquer circunst\u00e2ncia voc\u00ea \u00e9 infinitamente amado. Na Palavra de Deus, podemos contemplar uma \u201ccarta aberta\u201d de amor. Em cada livro, Ele encontra um jeito de se declarar e o Papa nos diz que \u00e9: \u201cpara ver se com alguma dessas palavras Ele consegue chegar no nosso cora\u00e7\u00e3o\u201d.<br \/>\nEm algumas situa\u00e7\u00f5es, o Senhor se apresenta como um Pai carinhoso que brinca com seus filhos colocando-os no colo. Em outras, como uma m\u00e3e que \u00e9 incapaz de esquecer seus filhos ou como um apaixonado que \u00e9 capaz de tatuar o nome da pessoa amada na palma da m\u00e3o. E em muitas outras, Ele simplesmente declara o seu amor fiel, bondoso, forte, paciente. \u201cAme-te com amor eterno\u201d (Jr 31).<br \/>\nDeus n\u00e3o s\u00f3 o enxerga, Ele o v\u00ea. Ele consegue contemplar sua beleza. \u201c\u00c9s precioso aos meus olhos, te estimo e te amo\u201d (Is 43). Deus presta aten\u00e7\u00e3o em voc\u00ea! Ele v\u00ea quando voc\u00ea ri por fora e chora por dentro, quando se sente s\u00f3 ou insuficiente. Deus lembra de voc\u00ea porque te ama! Ele n\u00e3o fica remoendo seus erros ou pecados. O amor de Deus te liberta. \u00c9 um amor real, verdadeiro e concreto.<br \/>\nNosso cofundador nos disse esses dias que Deus n\u00e3o parou s\u00f3 em dizer que nos ama, Ele provou. Ele nos deu Jesus e aqui entramos na segunda verdade.<br \/>\n2\u00aa Verdade: Cristo salva<br \/>\nPor que Cristo salva? Por amor! Um amor t\u00e3o grande que o fez ir at\u00e9 o extremo da cruz. Mas Ele continua a salvar a sua vida se voc\u00ea assim o deixar. Ele o salva dos seus pecados, da solid\u00e3o, do vazio, carrega-o nos ombros se for preciso.<br \/>\nNingu\u00e9m ou pecado algum pode tirar de voc\u00ea a dignidade que o amor de Cristo lhe d\u00e1. Sempre o deixa come\u00e7ar de novo e de cabe\u00e7a erguida. Porque o ama, Ele te salva e no seu abra\u00e7o transforma a sua vida. Esse amor \u00e9 maior que suas inconst\u00e2ncias, fraquezas, medos, pecados, mas \u00e9 atrav\u00e9s de tudo isso que Ele quer escrever uma hist\u00f3ria de amor. Ele sempre encontra um jeito de levantar, como disse \u00e0quele jovem j\u00e1 morto, hoje Ele diz tamb\u00e9m pra voc\u00ea: \u201cJovem eu ordeno, levanta-te\u201d.<br \/>\nJovem, n\u00e3o fique no ch\u00e3o! N\u00e3o se compare! N\u00e3o se despreze! A forma do mundo \u00e9 deformada, voc\u00ea n\u00e3o \u00e9 uma \u201ccoisa\u201d. Voc\u00ea vale a vida do Filho de Deus. Olhe para Jesus na cruz de bra\u00e7os abertos, coberto de sangue s\u00f3 para que voc\u00ea seja salvo e livre. Isso n\u00e3o foi s\u00f3 h\u00e1 2 mil anos, Ele te faz livre todos os dias. E quando voc\u00ea for buscar a reconcilia\u00e7\u00e3o, o perd\u00e3o na confiss\u00e3o, olhe para a cruz de novo.<br \/>\nO Padre Uli disse recentemente em uma de suas homilias que: \u201cN\u00e3o h\u00e1 pecado que resista ao sangue de Jesus\u201d. Por isso, deixe esse sangue purificar voc\u00ea. Na confiss\u00e3o, voc\u00ea se esvazia de uma \u00e1gua imunda que s\u00e3o os seus pecados e sai cheio da miseric\u00f3rdia de Deus que \u00e9 a \u00e1gua da vida, e aqui n\u00f3s entramos na terceira verdade.<br \/>\n3\u00aa Verdade: Cristo vive<br \/>\nJesus ressuscitou! N\u00e3o foi um evento que acabou. Ele vive e anda conosco, como prometeu.<br \/>\nO mal n\u00e3o o vence e tamb\u00e9m na sua vida o mal n\u00e3o tem a \u00faltima palavra, porque Jesus, nosso Salvador, Aquele que vive, quer triunfar em voc\u00ea. Nos nossos Estatutos, n\u00f3s aprendemos que o Domingo da Ressurrei\u00e7\u00e3o n\u00e3o tardar\u00e1, toda noite tem o seu dia. Portanto, n\u00e3o precisa se desesperar, porque Jesus, pela for\u00e7a da sua ressurrei\u00e7\u00e3o, \u00e9 o vivente eterno, fonte de nossa esperan\u00e7a. Foi Ele que quis nos amar, salvar-nos e nos dar vida em abund\u00e2ncia.<br \/>\nVoc\u00ea percebe que n\u00f3s falamos do Pai e do Filho? Mas e o Esp\u00edrito Santo? A Trindade n\u00e3o se divide, Onde um est\u00e1, todos est\u00e3o. E nessa realidade, \u00e9 o Esp\u00edrito Santo que torna poss\u00edvel voc\u00ea receber esse grande an\u00fancio e \u00e9 Ele que mant\u00e9m viva a experi\u00eancia da salva\u00e7\u00e3o.<br \/>\nO Esp\u00edrito Santo enche o cora\u00e7\u00e3o do Ressuscitado e de l\u00e1 se derrama como uma fonte. \u00c0 medida que voc\u00ea se abre para ser amado, salvo e vivo, o Esp\u00edrito lhe introduz no cora\u00e7\u00e3o de Jesus. Por isso, pe\u00e7a ao Esp\u00edrito Santo todos os dias a gra\u00e7a de n\u00e3o esquecer que \u00e9 amado por Deus. N\u00e3o vai lhe arrancar peda\u00e7os. \u00c9 pelo Esp\u00edrito Santo que aprendemos a amar. S\u00f3 pelo Espirito Santo sua sede ser\u00e1 saciada.<br \/>\nAfinal, o vazio, a solid\u00e3o, a tristeza, tudo isso \u00e9 sede do amor de Deus. \u00c9 como se voc\u00ea sofresse com uma enxaqueca horr\u00edvel e eu estivesse lhe oferecendo a cura para sempre. O rem\u00e9dio para dentro, vem de dentro. Eu n\u00e3o sei quais s\u00e3o suas feridas no amor, se com seu pai, com sua m\u00e3e, com seus amigos, ou se tem a ver com seus relacionamentos, eu n\u00e3o sei o qu\u00ea ou quem o feriu, mas eu conhe\u00e7o quem pode cur\u00e1-las e transform\u00e1-las. Eles o amaram da mesma forma que foram amados, ou como disseram para eles que o amor deveria ser, mas Deus o ama como voc\u00ea merece ser amado, porque Ele \u00e9 o pr\u00f3prio amor.<br \/>\nL\u00edvia Rosaly Carvalho da Cunha<br \/>\nConsagrada na Comunidade de Vida Filhos de Si\u00e3o<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O grande an\u00fancio: Deus \u00e9 amor Eu li recentemente que o \u00f3bvio tamb\u00e9m precisa ser&#8230;<\/p>\n","protected":false},"author":7,"featured_media":7752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,87],"tags":[],"class_list":["post-26335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-filhos-de-siao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se\u0301.jpg","jetpack-related-posts":[{"id":24537,"url":"https:\/\/correiodasemana.com\/site\/cenaculo-filhos-de-siao-cristo-ressuscitou-alegria-em-siao\/","url_meta":{"origin":26335,"position":0},"title":"Cen\u00e1culo Filhos de Si\u00e3o: Cristo Ressuscitou. Alegria em Si\u00e3o!","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"Cristo ressuscitou, aleluia! Verdadeiramente ressuscitou! E que alegria, pois estamos comemorando a oitava de nossas promessas vocacionais no Carisma Filhos de Si\u00e3o. Alegria em Si\u00e3o Meditemos a partir de Sofonias 3, 14-20, este trecho apresenta um hino festivo, de alegria em Si\u00e3o. O profeta vem nos anunciar que Senhor revogou\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/th-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":26601,"url":"https:\/\/correiodasemana.com\/site\/filhos-de-siao-11\/","url_meta":{"origin":26335,"position":1},"title":"FILHOS DE SI\u00c3O","author":"adminredacao","date":"Setembro 25, 2023","format":false,"excerpt":"Ora\u00e7\u00e3o Contemplativa do Filho de Si\u00e3o Contemplar n\u00e3o depende dos olhos, mas do cora\u00e7\u00e3o A contempla\u00e7\u00e3o \u00e9 uma forma de ora\u00e7\u00e3o. Contemplar, diz o Papa Francisco, n\u00e3o \u00e9 um modo de fazer, mas um modo de ser. Quando se trata de ora\u00e7\u00e3o, \u00e9 o nosso modo de rezar e de\u2026","rel":"","context":"In &quot;Agenda Uninta&quot;","block_context":{"text":"Agenda Uninta","link":"https:\/\/correiodasemana.com\/site\/category\/agenda-uninta\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":27279,"url":"https:\/\/correiodasemana.com\/site\/comunidade-catolica-filhos-de-siao-2\/","url_meta":{"origin":26335,"position":2},"title":"COMUNIDADE CAT\u00d3LICA FILHOS DE SI\u00c3O","author":"adminredacao","date":"Novembro 20, 2023","format":false,"excerpt":"N\u00e3o vos conformeis com este mundo Aquilo que mais atrai \u00e9 ouvir algu\u00e9m encontrado, o testemunho de uma pessoa que foi achada, que se conformou \u00e0 vontade de Deus. Voc\u00ea \u00e9 encontrado na vida? \u00c9 capaz de dizer achei o \u201cmeu lugar no mundo\u201d, na sociedade? Olhe para si mesmo.\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25330,"url":"https:\/\/correiodasemana.com\/site\/filhos-de-siao-4\/","url_meta":{"origin":26335,"position":3},"title":"Filhos de Si\u00e3o","author":"adminredacao","date":"Junho 19, 2023","format":false,"excerpt":"Jesus \u00e9 o Senhor A verdade revelada Algumas verdades s\u00e3o reveladas para n\u00f3s durante o SVES, a verdade de Deus para n\u00f3s. A come\u00e7ar pelo amor divino, que supera todas as coisas e nos constrange. Depois, ouvimos que, por amor, o Pai enviou Seu Filho para nos salvar do pecado.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Igreja_Se%CC%81.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":36122,"url":"https:\/\/correiodasemana.com\/site\/comunidade-catolica-filhos-de-siao-15\/","url_meta":{"origin":26335,"position":4},"title":"Comunidade Cat\u00f3lica Filhos de Si\u00e3o","author":"adminredacao","date":"Novembro 3, 2025","format":false,"excerpt":"Conselhos Evang\u00e9licos \u201cDesde que eu o encontrei, um grande tesouro encontrei\u2026 Seu amor me conquistou, sou feliz!\u201d Todos sabemos o que \u00e9 um conselho: costumamos procurar algu\u00e9m mais velho, mais vivido, para nos orientar em algo. Embora muitas vezes n\u00e3o queiramos ouvir os \u201cconselhos\u201d dos nossos pais, por exemplo, precisamos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/cropped-Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":20656,"url":"https:\/\/correiodasemana.com\/site\/ano-jubilar-eis-o-tempo-favoravel\/","url_meta":{"origin":26335,"position":5},"title":"Ano Jubilar: Eis o tempo favor\u00e1vel","author":"","date":"Agosto 8, 2022","format":false,"excerpt":"Somos convidados a testemunhar Jesus Cristo por meio da nossa f\u00e9 atrav\u00e9s do Carisma Filhos de Si\u00e3o\u2026 O tempo \u00e9 favor\u00e1vel para agradecermos ao passado e fazermos mem\u00f3ria da nossa hist\u00f3ria, da nossa vida e da nossa caminhada. Vamos viver com alegria o presente! Vamos pedir for\u00e7as a Deus para\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Igreja_S%C3%A9.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/26335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=26335"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/26335\/revisions"}],"predecessor-version":[{"id":26336,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/26335\/revisions\/26336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7752"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=26335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=26335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=26335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}