{"id":27285,"date":"2023-11-20T17:19:45","date_gmt":"2023-11-20T20:19:45","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=27285"},"modified":"2023-11-20T17:19:45","modified_gmt":"2023-11-20T20:19:45","slug":"de-olho-na-lingua-71","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-71\/","title":{"rendered":"DE OLHO NA L\u00cdNGUA"},"content":{"rendered":"<p>DE OLHO NA L\u00cdNGUA<br \/>\nProf. Ant\u00f4nio da Costa (Jornal Correio da Semana &#8211; Sobral-CE &#8211; S\u00e1bado &#8211; 18.11.23)<\/p>\n<p>\u00c9 verdade que o verbo rigorosamente correto \u00e9 \u201cagilitar\u201d e n\u00e3o \u201cagilizar\u201d?<br \/>\n\u00c9 verdade, embora agilizar j\u00e1 esteja consagrado. Hoje, todavia, se pedirmos que algu\u00e9m \u201cagilite\u201d um processo, certamente seremos olhados de \u201cesguelha\u201d. Injustamente, mas seremos olhados de \u201cesguelha\u201d. \u00c9 a evolu\u00e7\u00e3o&#8230;<br \/>\n\u201cDe esguelha\u201d ou \u201cde esgueia\u201d?<br \/>\nDe esguelha, evidentemente, ainda que muitos prefiram olhar de \u201cesgueia\u201d, como j\u00e1 ouvimos. Ningu\u00e9m abre um \u201ctaio\u201d no dedo, mas, sim, um talho. \u00c9 comum haver a troca do \u201clh\u201d por \u201ci\u201d. Vejamos: paia\u00e7o (palha\u00e7o), veio (velho), paia (palha), etc. Trata-se de influ\u00eancia africana.<br \/>\nCom palavras no plural uso \u201ca ser\u201d ou \u201ca serem\u201d?<br \/>\nDo jeito que voc\u00ea achar melhor. Exs.: Os presidentes definir\u00e3o as medidas a ser (ou a serem) tomadas; As crian\u00e7as a ser (ou a serem) matriculadas chegam a cem; O secret\u00e1rio se viu praticamente impossibilitado de agilizar o andamento dos decretos a ser (ou a serem) assinados pelo governador.<br \/>\nIsso vale tamb\u00e9m para a nega\u00e7\u00e3o: Todos beberam, a n\u00e3o ser (ou a n\u00e3o serem) os policiais; Ningu\u00e9m ficou b\u00eabado (ou b\u00eabedo), a n\u00e3o ser (ou a n\u00e3o sermos) n\u00f3s.<br \/>\n\u201cN\u00e3o queremos denegrir sua imagem\u201d ou \u201cN\u00e3o queremos denigrir sua imagem\u201d<br \/>\nAmbas corretas. Denegrir e denigrir s\u00e3o formas variantes ou sincr\u00e9ticas. Ali\u00e1s, \u00e9 bom que saibamos que essas palavras n\u00e3o devem ser usadas. Atualmente elas s\u00e3o tachadas de discriminat\u00f3rias. J\u00e1 pensou&#8230;<br \/>\n\u201cNada a ver\u201d ou \u201cNada que ver\u201d?<br \/>\nNo Portugu\u00eas contempor\u00e2neo podemos usar as duas formas. Os puristas recomendam \u201cnada que ver\u201d. \u201cNada a ver\u201d \u00e9 galicismo (mania dos franceses).<br \/>\n\u201cDe maneiras que\u201d, \u201cDe formas que\u201d, \u201cDe modos que\u201d, \u201cDe sortes que\u201d<br \/>\nAs locu\u00e7\u00f5es conjuntivas s\u00e3o usadas corretamente no singular. Assim: \u201cde maneira que\u201d, \u201cde forma que\u201d, \u201cde modo que\u201d, \u201cde sorte que\u201d, etc.<br \/>\n\u201cFazem trinta anos que isso aconteceu\u201d?<br \/>\nO verbo \u201cfazer\u201d indicando tempo decorrido \u00e9 impessoal. Isto \u00e9: n\u00e3o vai para o plural. A forma correta \u00e9: \u201cFaz trinta anos que isso aconteceu\u201d.<br \/>\nMulato (Etimologia)<br \/>\nMulato \u00e9 um termo que designa a pessoa que \u00e9 descendente de negros africanos e brancos europeus. Inicialmente o termo era tamb\u00e9m aplicado para designar mesti\u00e7os. Mulatos podem apresentar os mais variados perfis fenot\u00edpicos e culturais. Mesti\u00e7os s\u00e3o pessoas que descendem de duas ou mais etnias diferentes. No Brasil os mesti\u00e7os s\u00e3o chamados de pardos.<br \/>\nExistem terminologias tradicionais: mulatos &#8211; para descendentes de brancos e negros; caboclos e mamelucos &#8211; para descendentes de brancos e ind\u00edgenas; cafuzos: para descendentes de negros e ind\u00edgenas.<br \/>\nMulata<br \/>\nNa l\u00edngua espanhola referia-se ao filhote macho do cruzamento de cavalo com jumenta ou de jumento com \u00e9gua. A enorme carga pejorativa \u00e9 ainda maior quando se diz \u201cmulata tipo exporta\u00e7\u00e3o\u201d, reiterando a vis\u00e3o do corpo da mulher negra como mercadoria. A palavra remete \u00e0 ideia de sedu\u00e7\u00e3o, sensualidade.<br \/>\nS\u00edntese<br \/>\nMulato: cruzamento de cavalo com jumenta ou cruzamento de \u00e9gua com jumento. Resulta o animal h\u00edbrido burro (asno). A burra (ou mula) n\u00e3o procria.<br \/>\n\u201cA L\u00edngua n\u00e3o se escraviza ao sentido origin\u00e1rio das palavras\u201d (De Celso Pedro Luft, do livro \u201cO romance das palavras\u201d.<br \/>\n(*) Professor Ant\u00f4nio da Costa \u00e9 graduado em Letras Plenas, com Especializa\u00e7\u00e3o em L\u00edngua Portuguesa e Literatura, na Universidade Estadual Vale do Acara\u00fa (UVA). Contatos: (088) 99373-7724.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DE OLHO NA L\u00cdNGUA Prof. Ant\u00f4nio da Costa (Jornal Correio da Semana &#8211; Sobral-CE &#8211;&#8230;<\/p>\n","protected":false},"author":7,"featured_media":17923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[11,12],"tags":[],"class_list":["post-27285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-de-olho-na-lingua"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg",180,200,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/de-olho-na-lingua\/\" rel=\"category tag\">De olho na l\u00edngua<\/a>","tag_info":"De olho na l\u00edngua","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/DE-OLHO-NA-LIN-GUA-Antonio-da-Costa.jpg","jetpack-related-posts":[{"id":34966,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-130\/","url_meta":{"origin":27285,"position":0},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Agosto 4, 2025","format":false,"excerpt":"\u00c9 verdade que o verbo rigorosamente correto \u00e9 \u201cagilitar\u201d e n\u00e3o \u201cagilizar\u201d? \u00c9 verdade, embora agilizar j\u00e1 esteja consagrado. Hoje, todavia, se pedirmos que algu\u00e9m \u201cagilite\u201d um processo, certamente seremos olhados de \u201cesguelha\u201d. Injustamente, mas seremos olhados de \u201cesguelha\u201d. \u00c9 a evolu\u00e7\u00e3o\u2026 \u201cDe esguelha\u201d ou \u201cde esgueia\u201d? De esguelha, evidentemente,\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8750,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-8\/","url_meta":{"origin":27285,"position":1},"title":"De Olho na L\u00edngua","author":"","date":"Agosto 17, 2019","format":false,"excerpt":"Mascote \u00e9 sobrecomum ou comum de dois? Nossos principais dicion\u00e1rios e o Vocabul\u00e1rio Ortogr\u00e1fico da Academia Brasileira de Letras (ABL) consideram mascote um substantivo sobrecomum. Ou seja: a mascote \u00e9 uma palavra feminina que serve aos dois sexos. Acredito que a forma masculina esteja consagrada e deva ser aceita. Mascote\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/divisoes-da-gramatica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":32496,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-115\/","url_meta":{"origin":27285,"position":2},"title":"De Olho na L\u00edngua","author":"adminredacao","date":"Fevereiro 10, 2025","format":false,"excerpt":"\u201cDar uma pensada \/ Dar uma verificada S\u00f3 porque podemos dar uma olhada, dar uma chamada e tamb\u00e9m dar uma passada, muitos acham que tamb\u00e9m podem dar uma \u201cpensada\u201d ou dar uma \u201cverificada\u201d. Na fala di\u00e1ria podemos at\u00e9 usar quase sem muito problema: Vou dar uma pensada no assunto ou\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":27962,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-75\/","url_meta":{"origin":27285,"position":3},"title":"De Olho Na L\u00edngua","author":"adminredacao","date":"Janeiro 8, 2024","format":false,"excerpt":"\u201cEstou comprometido\u201d ou \u201cEstou compromissado\u201d? O partic\u00edpio \u00e9 comprometido porque deriva do verbo comprometer, e n\u00e3o do substantivo compromisso. \u00c9 comprometido, da mesma forma que remeter \u00e9 remetido, e n\u00e3o remessido; proteger \u00e9 protegido, e n\u00e3o protessido; cometer \u00e9 cometido. Ex.: O nosso prefeito sempre esteve compromissado com a verdade.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10927,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-32\/","url_meta":{"origin":27285,"position":4},"title":"De Olho na L\u00edngua","author":"","date":"Fevereiro 25, 2020","format":false,"excerpt":"Feito nas coxas \u201cNas coxas\u201d \u00e9 uma express\u00e3o idiom\u00e1tica brasileira. Quando se diz que alguma coisa foi feita nas coxas, isso significa que essa coisa \u201cfoi feita apressadamente, grosseiramente, sem capricho e mal feita\u201d. Vejamos um exemplo da express\u00e3o numa frase: Joaquim, o relat\u00f3rio que voc\u00ea apresentou n\u00e3o estava bom.\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/escrevendo-uma-letra-na-ma%CC%81quina-de-escrever-do-vintage-47570680.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27446,"url":"https:\/\/correiodasemana.com\/site\/de-olho-na-lingua-72\/","url_meta":{"origin":27285,"position":5},"title":"De Olho Na Lingua","author":"adminredacao","date":"Dezembro 4, 2023","format":false,"excerpt":"\u201cTemos repelentes, lanternas e etc.\u201d Diga-se: \u201cTemos repelentes, lanternas, e etc. Etc. \u00e9 a abreviatura de etcetera, aportuguesamento da express\u00e3o latina \u201cet caetera\u201d. Por isso apresenta ponto final. O significado de etc. \u00e9 \u201ce outras coisas mais\u201d. Ou seja, a conjun\u00e7\u00e3o \u201ce\u201d j\u00e1 est\u00e1 inclu\u00edda no significado da abreviatura. Dessa\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=27285"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27285\/revisions"}],"predecessor-version":[{"id":27286,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27285\/revisions\/27286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/17923"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=27285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=27285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=27285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}