{"id":27917,"date":"2024-01-05T11:10:00","date_gmt":"2024-01-05T14:10:00","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=27917"},"modified":"2024-01-05T11:10:00","modified_gmt":"2024-01-05T14:10:00","slug":"escandalos-farisaicos","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/escandalos-farisaicos\/","title":{"rendered":"ESC\u00c2NDALOS FARISAICOS!"},"content":{"rendered":"<p>Para Jesus n\u00e3o era esc\u00e2ndalo. Para os fariseus que n\u00e3o gostavam de Jesus muita coisa que ele dizia e fazia, era vista como esc\u00e2ndalo! Achavam que Jesus estava desafiando a Lei Mosaica. Fan\u00e1ticos veem pecado e esc\u00e2ndalo onde n\u00e3o h\u00e1, e veem gra\u00e7a, cura e revela\u00e7\u00e3o onde tamb\u00e9m n\u00e3o h\u00e1. \u00c9 uma grande gra\u00e7a o sujeito saber distinguir o que \u00e9, e o que n\u00e3o \u00e9 nem nunca foi! Jesus deixou a pecadora cuidar dos p\u00e9s e dos cabelos dele e, s\u00f3 depois, perdoou o pecado dela. Deu tempo para ela decidir. Mas n\u00e3o proibiu o gesto da \u2018pecadora\u2019. Deixou tocar por ela! Aos olhos dos fariseus aquilo era um esc\u00e2ndalo. At\u00e9 perguntaram se Jesus realmente conhecia aquela mulher! Agora alguns fariseus modernos veem esc\u00e2ndalo nos acolhimentos do Papa Cat\u00f3lico. Confundem acolhimento com sacramento! Sacramento \u00e9 muito mais que acolhimento! Respeitar e querer bem uma pessoa n\u00e3o \u00e9 o mesmo que casar com ela. Para a Igreja h\u00e1 uma grande diferen\u00e7a! Uma coisa n\u00e3o leva necessariamente \u00e0 outra. Em Mt 25, 31-46 h\u00e1 promessa de C\u00e9u para quem se importa com os outros e consequ\u00eancias dr\u00e1sticas para quem n\u00e3o se importa com os outros. Inclusive quem calunia e vive julgando os outros (Mt 7,1-6). Isto tamb\u00e9m pode levar algu\u00e9m para o inferno!<br \/>\nA igreja se importa com quem ainda est\u00e1 em pecado e, por isso mesmo, ela explica porqu\u00ea n\u00e3o lhe d\u00e1 todos os sacramentos que ele pede. N\u00e3o \u00e9 poss\u00edvel sem mudan\u00e7a de vida!<br \/>\nMas nossa Igreja n\u00e3o lhe nega a ben\u00e7\u00e3o, porque BENEDIRE, (aben\u00e7oar) \u00e9 dizer coisas boas aos outros, inclusive ao pecador. Por isso n\u00e3o \u00e9 sacramento mas \u00e9 ben\u00e7\u00e3o . Para quem estudou a Doutrina da Gra\u00e7a, dar ben\u00e7\u00e3o (bene dire) \u00e9 dizer coisas boas para quem ainda n\u00e3o consegue se converter. Mas existe uma gra\u00e7a latente no cora\u00e7\u00e3o de quem pede alguma ben\u00e7\u00e3o . Ningu\u00e9m sabe quando e como a gra\u00e7a atua em cada pessoa. S\u00e3o Paulo e Santo Agostinho n\u00e3o sabiam se um dia se converteriam. Mas Deus sabia! Deus os estava preparando! No tempo certo eles aceitaram Jesus.<br \/>\nEu n\u00e3o aben\u00e7oaria nem diria coisas boas a um traficante ou a um sujeito que matou a esposa. Ele n\u00e3o faz por merecer nenhum sacramento. Mas, se este sujeito expiar o seu pecado e depois provar que fez penit\u00eancia, sim, ele pode ser aben\u00e7oado por nossa Igreja. Sua v\u00edtima inocente provavelmente est\u00e1 no C\u00e9u e viu seu arrependimento.<br \/>\nMotivo? Um sacramento \u00e9 muito mais do que uma ben\u00e7\u00e3o. Na Igreja existe esta distin\u00e7\u00e3o! A Igreja n\u00e3o d\u00e1 o sacramento para quem n\u00e3o consegue viv\u00ea-lo. Mas d\u00e1 a ben\u00e7\u00e3o para quem pede alguma chance e algum di\u00e1logo. Jesus sempre dialogou com quem quis conversar com Ele. Mas com os maldosos fariseus de cora\u00e7\u00e3o endurecido n\u00e3o houve como conversar. Eles se aproximavam para julga-lo e deturpar tudo o que ele dizia!<br \/>\nEst\u00e3o fazendo exatamente isto com o Papa. E o triste \u00e9 que alguns desses detratores s\u00e3o cat\u00f3licos de comunh\u00e3o di\u00e1ria! Mas decidiram ele est\u00e1 errado e que eles est\u00e3o certos! Ser\u00e1 que est\u00e3o? Leram toda a B\u00edblia ou s\u00f3 as frases que lhes interessa citar? Gostam ou n\u00e3o gostam do Papa? Aceitam ou n\u00e3o aceitam as catequeses dele?<br \/>\nEu sei a raz\u00e3o porque alguns cat\u00f3licos o rejeitam. J\u00e1 escreveram isto na minha p\u00e1gina\u2026<br \/>\nAcham que o Papa est\u00e1 indo longe demais com suas prega\u00e7\u00f5es! Para eles soa como comunismo. Mas se lessem os evangelhos com seriedade descobririam que \u00e9 CRISTIANISMO da melhor qualidade!\u201d<br \/>\nPadre Zezinho<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Jesus n\u00e3o era esc\u00e2ndalo. Para os fariseus que n\u00e3o gostavam de Jesus muita coisa&#8230;<\/p>\n","protected":false},"author":7,"featured_media":7687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[24,11],"tags":[],"class_list":["post-27917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":25283,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-celebra-11o-aniversario-de-ordenacao-episcopal\/","url_meta":{"origin":27917,"position":0},"title":"Dom Vasconcelos celebra 11\u00ba anivers\u00e1rio de Ordena\u00e7\u00e3o Episcopal","author":"adminredacao","date":"Junho 19, 2023","format":false,"excerpt":"No dia 11 de junho, Dom Jos\u00e9 Luiz Gomes de Vasconcelos celebrou o d\u00e9cimo primeiro anivers\u00e1rio de sua Ordena\u00e7\u00e3o Episcopal. A Santa Missa em a\u00e7\u00e3o de gra\u00e7as por ocasi\u00e3o desta data importante foi na S\u00c9 Catedral de Nossa Senhora da Concei\u00e7\u00e3o, em Sobral. Concelebrou com ele, o p\u00e1roco e cura\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-13-at-21.18.57-3.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33799,"url":"https:\/\/correiodasemana.com\/site\/domingo-do-bom-pastor-dom-vasconcelos-convida-fieis-a-renovarem-a-fe-e-a-rezarem-pelo-novo-pontifice\/","url_meta":{"origin":27917,"position":1},"title":"Domingo do Bom Pastor: Dom Vasconcelos convida fieis a renovarem a f\u00e9 e a rezarem pelo novo Pont\u00edfice","author":"adminredacao","date":"Maio 19, 2025","format":false,"excerpt":"No \u00faltimo dia 11 de maio, a Igreja Cat\u00f3lica celebrou o 4\u00ba Domingo da P\u00e1scoa, mais conhecido como Domingo do Bom Pastor. Dom Vasconcelos presidiu a Santa Missa na S\u00e9 Catedral de Sobral, onde na oportunidade rendeu gra\u00e7as pela elei\u00e7\u00e3o do novo pont\u00edfice, Papa Le\u00e3o XIV. A santa eucaristia foi\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-16-at-15.51.50.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16630,"url":"https:\/\/correiodasemana.com\/site\/unidade-tarefa-crista\/","url_meta":{"origin":27917,"position":2},"title":"UNIDADE: TAREFA CRIST\u00c3","author":"","date":"Maio 31, 2021","format":false,"excerpt":"Neste mundo cada vez mais dividido, marcado pelos esfacelamentos da cultura contempor\u00e2nea, polariza\u00e7\u00f5es e extremismos, a recomposi\u00e7\u00e3o da unidade, sem pretens\u00e3o de uniformidade, \u00e9 tarefa cidad\u00e3. Sublinhe-se: a constru\u00e7\u00e3o da unidade \u00e9 essencialmente tarefa crist\u00e3, pois remete a uma amorosa ora\u00e7\u00e3o nascida do cora\u00e7\u00e3o de Jesus, dirigida a seu Pai\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28690,"url":"https:\/\/correiodasemana.com\/site\/somos-amigos-do-senhor\/","url_meta":{"origin":27917,"position":3},"title":"SOMOS AMIGOS DO SENHOR","author":"adminredacao","date":"Mar\u00e7o 18, 2024","format":false,"excerpt":"Dando mais um passo nas reflex\u00f5es que temos feito sobre a Campanha da Fraternidade (CF) 2024, cujo tema \u00e9 Fraternidade a Amizade Social, queremos expor alguns textos b\u00edblicos que iluminam as nossas realidades. De um modo mais espec\u00edfico, a passagem que orienta as reflex\u00f5es desta CF \u00e9 Mt 23,1-12. Dessa\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":28500,"url":"https:\/\/correiodasemana.com\/site\/esmola-e-caridade-2\/","url_meta":{"origin":27917,"position":4},"title":"ESMOLA E CARIDADE\u00a0","author":"adminredacao","date":"Fevereiro 27, 2024","format":false,"excerpt":"A Quaresma nos proporciona um caminho de renova\u00e7\u00e3o da vida crist\u00e3. Somos convidados a acolher a for\u00e7a da Palavra de Deus e comprometer-nos com os passos dados na ora\u00e7\u00e3o, na penit\u00eancia, na caridade e na fraternidade, acolhendo o apelo forte da presente Campanha da Fraternidade \u00e0 amizade social, com a\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33114,"url":"https:\/\/correiodasemana.com\/site\/na-casa-da-parabola\/","url_meta":{"origin":27917,"position":5},"title":"Na casa da Par\u00e1bola","author":"adminredacao","date":"Mar\u00e7o 31, 2025","format":false,"excerpt":"As par\u00e1bolas contadas por Jesus partem de situa\u00e7\u00f5es cotidianas vividas pelas pessoas, assim como de uma apurada observa\u00e7\u00e3o da natureza, onde comparecem animais e plantas. As chamadas par\u00e1bolas da miseric\u00f3rdia, do cap\u00edtulo quinze do Evangelho de S\u00e3o Lucas, referem-se a uma ovelha perdida, uma moeda perdida e um filho perdido!\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=27917"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27917\/revisions"}],"predecessor-version":[{"id":27918,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/27917\/revisions\/27918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7687"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=27917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=27917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=27917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}