{"id":28880,"date":"2024-04-02T09:42:53","date_gmt":"2024-04-02T12:42:53","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=28880"},"modified":"2024-04-02T09:42:53","modified_gmt":"2024-04-02T12:42:53","slug":"catedral-de-sobral-recebe-milhares-de-fieis-durante-semana-santa-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/catedral-de-sobral-recebe-milhares-de-fieis-durante-semana-santa-2\/","title":{"rendered":"Catedral de Sobral recebe milhares de fi\u00e9is durante Semana Santa"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-28880 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/catedral-de-sobral-recebe-milhares-de-fieis-durante-semana-santa-2\/dada\/'><img loading=\"lazy\" width=\"813\" height=\"248\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/dada.jpg\" class=\"attachment-full size-full\" alt=\"dada\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/dada.jpg 813w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/dada-300x92.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/dada-768x234.jpg 768w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>Domingo de Ramos<\/strong><br \/>\nCom a Solenidade do Domingo de Ramos e da Paix\u00e3o do Senhor, adentramos na Semana Santa. Na manh\u00e3 de domingo, 24 de mar\u00e7o, os olhos e as express\u00f5es de f\u00e9 voltaram-se para o Santu\u00e1rio S\u00e3o Francisco de Assis em Sobral.<br \/>\nIn\u00fameras pessoas participaram da solene ben\u00e7\u00e3o de Ramos presidida por Dom Jos\u00e9 Luiz Gomes de Vasconcelos, bispo diocesano. Teve como concelebrantes: Pe. Jos\u00e9 Canafistula (Berg), p\u00e1roco da Par\u00f3quia da S\u00e9 e Cura da Catedral; Pe. Denilson de Sousa, reitor do Semin\u00e1rio maior de Filosofia S\u00e3o Jo\u00e3o Paulo II e vig\u00e1rio paroquial da Par\u00f3quia da S\u00e9; Frei S\u00e9rgio Viana, reitor do Santu\u00e1rio S\u00e3o Francisco e Pe. Livandro Monteiro, da comunidade Shalom. Os sacerdotes foram auxiliados pelo di\u00e1cono permanente, C\u00e2ndido Aguiar.<br \/>\nAp\u00f3s a aclama\u00e7\u00e3o do primeiro evangelho, todos sa\u00edram em prociss\u00e3o com destino \u00e0 S\u00e9 Catedral animando a caminhada com os ramos e cantando: \u201cHosana ao filho de Davi!\u201d, assim como fizeram os filhos dos hebreus saudando Jesus que entrava em Jerusal\u00e9m. A prociss\u00e3o fez um pequeno percurso at\u00e9 chegar na igreja m\u00e3e, onde in\u00fameros fi\u00e9is j\u00e1 aguardavam a prociss\u00e3o para dar continuidade a celebra\u00e7\u00e3o eucar\u00edstica que teve como destaque a proclama\u00e7\u00e3o do evangelho que relembra a paix\u00e3o e morte de Jesus Cristo.<br \/>\n\u201cCom essa solenidade iniciamos a semana santa, contemplamos um duplo mist\u00e9rio, a entrada de Jesus em Jerusal\u00e9m e a sua paix\u00e3o. Jesus percorreu a todos os lugares fazendo milagres, todos sabiam que ele era o Messias, e reconheciam nele o Messias, mas nem todos o acolhiam. A mesma multid\u00e3o que gritava: \u201cHosana ao filho de Davi\u201d, deixou Pilatos o crucificar, quando disseram: crucifica-o!\u201d, disse o bispo diocesano em homilia.<br \/>\nDom Vasconcelos exortou os fi\u00e9is a viverem uma verdadeira Semana Santa, deixando de lado as festividades e viagens, para que procurassem viver com profundidade n\u00e3o s\u00f3 os atos, mas o mist\u00e9rio desta semana maior.<\/p>\n<div id='gallery-2' class='gallery galleryid-28880 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/catedral-de-sobral-recebe-milhares-de-fieis-durante-semana-santa-2\/afaa\/'><img loading=\"lazy\" width=\"813\" height=\"160\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/afaa.jpg\" class=\"attachment-full size-full\" alt=\"afaa\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/afaa.jpg 813w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/afaa-300x59.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/afaa-768x151.jpg 768w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>Segunda-feira Santa<\/strong><br \/>\nNa segunda-feira da Semana Santa, 25 de mar\u00e7o, o evangelho relembra o gesto de Maria, irm\u00e3 de L\u00e1zaro, que lava os p\u00e9s de Jesus com perfume de nardo e os enxuga com seu cabelo. A partir deste momento, Jesus vai se preparando para a sua paix\u00e3o e morte atrav\u00e9s dos acontecimentos com seus amigos e ap\u00f3stolos. \u201cMaria, tomando quase meio litro de perfume de nardo puro e muito caro, ungiu os p\u00e9s de Jesus e enxugou-os com seus cabelos. A casa inteira ficou cheia do perfume do b\u00e1lsamo.\u201d (Jo\u00e3o 12,1-3) Na S\u00e9 Catedral, Dom Vasconcelos presidiu a santa missa. Concelebrou o p\u00e1roco e Cura da Catedral, Pe. Berg, auxiliados pelo di\u00e1cono permanente, C\u00e2ndido Aguiar. Mesmo com forte chuva, os fi\u00e9is participaram da celebra\u00e7\u00e3o eucar\u00edstica. O p\u00e1roco, Pe. Berg, animou o povo fazendo o convite para participarem efetivamente dos atos lit\u00fargicos da semana santa, sobretudo, o tr\u00edduo pascal. Foram distribu\u00eddos in\u00fameros folders com a programa\u00e7\u00e3o completa.<\/p>\n<div id='gallery-3' class='gallery galleryid-28880 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/catedral-de-sobral-recebe-milhares-de-fieis-durante-semana-santa-2\/ggg\/'><img loading=\"lazy\" width=\"813\" height=\"160\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg\" class=\"attachment-full size-full\" alt=\"ggg\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg 813w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-300x59.jpg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-768x151.jpg 768w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>Ter\u00e7a-feira Santa<\/strong><br \/>\nNa celebra\u00e7\u00e3o eucar\u00edstica desta ter\u00e7a-feira santa, 26 de mar\u00e7o, o evangelho apresentou a passagem de Jesus anunciando aos disc\u00edpulos que um deles haveria de o trair. E Jesus diz a Judas Iscariotes para executar logo o que ele tinha que fazer.<br \/>\nEm homilia, Dom Vasconcelos falou que Judas foi excomungado da presen\u00e7a de Jesus. \u201cJudas ao se retirar n\u00e3o saiu apenas do local onde estava com Jesus, mas saiu da comunh\u00e3o com Jesus. Ele saiu a noite, na escurid\u00e3o, mergulhou nas trevas, n\u00e3o tem mais a luz porque a luz \u00e9 Jesus\u201d, disse. Ap\u00f3s a santa missa, os presentes sa\u00edram em prociss\u00e3o para a Via Sacra P\u00fablica realizada nas resid\u00eancias localizadas pr\u00f3ximo a Catedral. Dom Vasconcelos, Pe. Berg, Pe. Denilson de Sousa e o di\u00e1cono C\u00e2ndido Aguiar, conduziram o ato com momentos de medita\u00e7\u00e3o com a \u201cVia Sacra das m\u00e3os\u201d, fazendo analogia a cada esta\u00e7\u00e3o, sobre as atitudes pessoais de cada presente, tornando-se um momento forte de espiritualidade e contri\u00e7\u00e3o.<br \/>\nDestaca-se a primeira esta\u00e7\u00e3o, que aconteceu na casa do p\u00e1roco em\u00e9rito da Par\u00f3quia da S\u00e9, Monsenhor Gon\u00e7alo de Pinho Gomes, que recebeu os sacerdotes e o povo com bastante alegria e emo\u00e7\u00e3o. A medita\u00e7\u00e3o das esta\u00e7\u00f5es da via sacra seguiu pelas ruas: 23 de setembro (conhecida como Rua da Palha), Cordeiro de Andrade e Galdino Gondim.<br \/>\nA \u00faltima esta\u00e7\u00e3o foi meditada na porta central da Catedral, onde o bispo e demais sacerdotes findaram com a ben\u00e7\u00e3o final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domingo de Ramos Com a Solenidade do Domingo de Ramos e da Paix\u00e3o do Senhor,&#8230;<\/p>\n","protected":false},"author":7,"featured_media":28883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-28880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg",813,160,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-300x59.jpg",300,59,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-768x151.jpg",640,126,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg",640,126,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg",813,160,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg",813,160,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg",813,160,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg-540x160.jpg",540,160,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack-related-posts":[{"id":19501,"url":"https:\/\/correiodasemana.com\/site\/domingo-de-ramos-abre-oficialmente-a-semana-santa-na-diocese-de-sobral\/","url_meta":{"origin":28880,"position":0},"title":"Domingo de Ramos abre oficialmente a Semana Santa na Diocese de Sobral","author":"","date":"Abril 17, 2022","format":false,"excerpt":"Thais Helena (Reda\u00e7\u00e3o Correio da Semana) - No dia 10 de abril, a igreja cat\u00f3lica celebrou solenemente o Domingo de Ramos e da Paix\u00e3o do Senhor, dia em que marca a abertura da Semana Santa relembrando a entrada triunfal de Jesus em Jerusal\u00e9m e a multid\u00e3o se re\u00fane para aclam\u00e1-lo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/04\/missa-domingo-3.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":23887,"url":"https:\/\/correiodasemana.com\/site\/domingo-de-ramos-solenidade-recorda-a-entrada-triunfal-de-jesus-em-jerusalem\/","url_meta":{"origin":28880,"position":1},"title":"Domingo de Ramos: Solenidade recorda a entrada triunfal de Jesus em Jerusal\u00e9m","author":"adminredacao","date":"Abril 11, 2023","format":false,"excerpt":"Aclamado pelos judeus, Jesus entrou em Jerusal\u00e9m montado em um jumento. Com louvores, a multid\u00e3o cobria com ramos, os caminhos para que Jesus pudesse passar, enquanto gritavam: \u201cHosana ao filho de Davi. Bendito o que vem em nome do Senhor\u201d (Lc 19, 38; Mt 21, 9). Em Sobral, os fi\u00e9is\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-08-at-14.39.07-1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-08-at-14.39.07-1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-08-at-14.39.07-1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-08-at-14.39.07-1.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/04\/WhatsApp-Image-2023-04-08-at-14.39.07-1.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":33460,"url":"https:\/\/correiodasemana.com\/site\/semana-santa-e-marcada-por-fe-devocao-e-participacao-intensa-dos-fieis-na-catedral-de-sobral\/","url_meta":{"origin":28880,"position":2},"title":"Semana Santa \u00e9 marcada por f\u00e9, devo\u00e7\u00e3o e participa\u00e7\u00e3o intensa dos fi\u00e9is na Catedral de Sobral","author":"adminredacao","date":"Abril 23, 2025","format":false,"excerpt":"Domingo de Ramos Na Solenidade do Domingo de Ramos e da Paix\u00e3o do Senhor, os cat\u00f3licos no mundo inteiro revivem a entrada triunfal de Jesus em Jerusal\u00e9m, montado em um jumentinho com toda sua humildade. As pessoas o reconhecem e gritam: Hosana ao filho de Davi! Ao amanhecer do \u00faltimo\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/domingo-de-ramos-4.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":23227,"url":"https:\/\/correiodasemana.com\/site\/frei-sergio-viana-e-o-novo-reitor-do-santuario-sao-francisco-em-sobral\/","url_meta":{"origin":28880,"position":3},"title":"Frei S\u00e9rgio Viana \u00e9 o novo reitor do Santu\u00e1rio S\u00e3o Francisco em Sobral","author":"adminredacao","date":"Janeiro 31, 2023","format":false,"excerpt":"Na alegria de receber um novo reitor, os fi\u00e9is estiveram no Santu\u00e1rio S\u00e3o Francisco de Assis em Sobral na tarde deste s\u00e1bado (21\/01) para a Santa Missa de Posse Can\u00f4nica de Frei S\u00e9rgio Viana. A celebra\u00e7\u00e3o foi presidida pelo bispo diocesano de Sobral, Dom Jos\u00e9 Luiz Gomes de Vasconcelos. A\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/frei-sergio-viana-2.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":38125,"url":"https:\/\/correiodasemana.com\/site\/da-entrada-em-jerusalem-a-ressurreicao-celebracoes-na-se-catedral-reunem-fe-e-tradicao-na-semana-santa\/","url_meta":{"origin":28880,"position":4},"title":"Da entrada em Jerusal\u00e9m \u00e0 Ressurrei\u00e7\u00e3o: Celebra\u00e7\u00f5es na S\u00e9 Catedral re\u00fanem f\u00e9 e tradi\u00e7\u00e3o na Semana Santa","author":"adminredacao","date":"Abril 13, 2026","format":false,"excerpt":"Solenidade do Domingo de Ramos marca o in\u00edcio da Semana Maior da Igreja Cat\u00f3lica Mais do que um rito lit\u00fargico, o Domingo de Ramos, celebrado no \u00faltimo dia 29 de mar\u00e7o, marcou o in\u00edcio da Semana Santa e convidou os fi\u00e9is a percorrerem, com o cora\u00e7\u00e3o aberto, o caminho da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/Domingo-de-Ramos-9-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19170,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-celebra-santa-missa-de-posse-canonica-do-novo-reitor-do-santuario-sao-francisco-em-sobral\/","url_meta":{"origin":28880,"position":5},"title":"Dom Vasconcelos celebra Santa Missa de Posse Can\u00f4nica do novo Reitor do Santu\u00e1rio S\u00e3o Francisco em Sobral","author":"","date":"Mar\u00e7o 14, 2022","format":false,"excerpt":"Thais Helena (Reda\u00e7\u00e3o Correio da Semana) \u2013 O Santu\u00e1rio S\u00e3o Francisco de Assis em Sobral h\u00e1 exatamente um m\u00eas acolheu o seu novo reitor, Frei Alexandre Veloso. Mas, somente no \u00faltimo domingo (06), foi realizada a Santa Missa de Posse Can\u00f4nica presidida pelo Bispo Diocesano de Sobral, Dom Jos\u00e9 Luiz\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/03\/FREI-DIOCESE-4.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/04\/ggg.jpg","_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/28880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=28880"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/28880\/revisions"}],"predecessor-version":[{"id":28884,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/28880\/revisions\/28884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/28883"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=28880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=28880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=28880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}