{"id":29422,"date":"2024-05-27T10:46:23","date_gmt":"2024-05-27T13:46:23","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=29422"},"modified":"2024-05-27T10:46:23","modified_gmt":"2024-05-27T13:46:23","slug":"em-fortaleza-lbv-abre-posto-de-arrecadacao-em-prol-do-rs","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-fortaleza-lbv-abre-posto-de-arrecadacao-em-prol-do-rs\/","title":{"rendered":"Em Fortaleza, LBV abre posto de arrecada\u00e7\u00e3o em prol do RS"},"content":{"rendered":"<p><strong>A Institui\u00e7\u00e3o j\u00e1 enviou mais de 350 toneladas de doa\u00e7\u00f5es ao Rio Grande do Sul em resposta \u00e0s chuvas<\/strong><\/p>\n<p>A Legi\u00e3o da Boa Vontade, por meio de sua campanha LBV \u2014 SOS Calamidades, intensifica seus esfor\u00e7os humanit\u00e1rios em um grande mutir\u00e3o nacional com volunt\u00e1rios para receber doa\u00e7\u00f5es em suas unidades no Brasil.<br \/>\nAt\u00e9 o momento, mais de 350 toneladas de suprimentos j\u00e1 foram angariadas e enviadas para o RS. Al\u00e9m dos itens essenciais, lindas cartinhas feitas pelas crian\u00e7as da Escola da LBV na capital paulista est\u00e3o sendo enviadas, buscando levar um pouco de conforto \u00e0s fam\u00edlias ga\u00fachas em meio a essa trag\u00e9dia.<br \/>\nAs doa\u00e7\u00f5es arrecadadas na Unidade da LBV em Fortaleza v\u00e3o ter o apoio da Azul Linhas A\u00e9reas e Correios que far\u00e1 o transporte das mesmas e entregues imediatamente \u00e0 Defesa Civil de Glorinha, no Rio Grande do Sul, em apoio \u00e0s v\u00edtimas das chuvas.<br \/>\nJunte-se a n\u00f3s e fa\u00e7a parte dessa for\u00e7a-tarefa para prestar assist\u00eancia humanit\u00e1ria \u00e0s comunidades mais afetadas. Cada gesto de solidariedade faz a diferen\u00e7a.<\/p>\n<p>O QUE DOAR:<br \/>\n&#8211; Itens de limpeza (sab\u00e3o, \u00e1gua sanit\u00e1ria, \u00e1lcool, desinfetante e detergente)<br \/>\n&#8211; Itens de higiene pessoal (sabonete, creme dental, escova de dentes, absorvente \u00edntimo, shampoo e condicionador)<br \/>\n&#8211; Alimentos n\u00e3o perec\u00edveis<br \/>\n&#8211; \u00c1gua pot\u00e1vel engarrafada<br \/>\n&#8211; Roupas de cama (len\u00e7\u00f3is, cobertores e toalhas)<br \/>\n&#8211; Roupas em bom estado (feminino, masculino e infantil)<br \/>\n&#8211; Ra\u00e7\u00f5es para animais<br \/>\n&#8211; Fraldas descart\u00e1veis<\/p>\n<p>\ud83d\udccd POSTOS DE ARRECADA\u00c7\u00c3O EM FORTALEZA:<br \/>\nRua Alziro Zarur,275- Vila Manoel S\u00e1tiro, das 8h \u00e0s 17h.<br \/>\nInforma\u00e7\u00f5es: (85) 3484-3533.<\/p>\n<p>DOA\u00c7\u00d5ES VIA PIX SOLID\u00c1RIO:<br \/>\nE-mail: ajude@lbv.org.br<\/p>\n<p>ENTREGA DAS DOA\u00c7\u00d5ES:<br \/>\nAcompanhe a entrega dos donativos acessando @lbvbrasil no Facebook e no Instagram.<\/p>\n<p>SOLIDARIEDADE:<br \/>\nA Legi\u00e3o da Boa Vontade tamb\u00e9m se solidariza e ora por todas as pessoas e fam\u00edlias afetadas pelas chuvas e por todo povo do Rio Grande do Sul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Institui\u00e7\u00e3o j\u00e1 enviou mais de 350 toneladas de doa\u00e7\u00f5es ao Rio Grande do Sul&#8230;<\/p>\n","protected":false},"author":7,"featured_media":29423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-29422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Posto-de-arrecadacao-LBV.jpeg","jetpack-related-posts":[{"id":14798,"url":"https:\/\/correiodasemana.com\/site\/celebrar-o-natal-e-tambem-ajudar-as-familias-mais-vulneraveis-que-sofrem-com-os-efeitos-da-pandemia-do-novo-coronavirus\/","url_meta":{"origin":29422,"position":0},"title":"Celebrar o Natal \u00e9 tamb\u00e9m ajudar as fam\u00edlias mais vulner\u00e1veis que sofrem com os efeitos da pandemia do novo coronav\u00edrus","author":"","date":"Novembro 30, 2020","format":false,"excerpt":"Campanha de Natal da LBV no estado do Cear\u00e1 pretende arrecadar\u00a056 toneladas de doa\u00e7\u00f5es A fome voltou a crescer no Brasil, segundo a \u201cPesquisa de Or\u00e7amentos Familiares 2017-2018: An\u00e1lise da Seguran\u00e7a Alimentar no Brasil\u201d, do Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE), divulgada em 17\/9\/2020. De acordo com o documento,\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/11\/Anuncio1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":31749,"url":"https:\/\/correiodasemana.com\/site\/caravana-do-bem-lbv-inicia-entrega-de-cestas-de-alimentos-a-familias-em-vulnerabilidade-social-no-ceara\/","url_meta":{"origin":29422,"position":1},"title":"Caravana do Bem! LBV inicia entrega de cestas de alimentos a fam\u00edlias em vulnerabilidade social no Cear\u00e1","author":"adminredacao","date":"Dezembro 10, 2024","format":false,"excerpt":"A Legi\u00e3o da Boa Vontade est\u00e1 iniciando a entrega das cestas de alimentos n\u00e3o perec\u00edveis arrecadadas por meio de sua tradicional campanha Natal Permanente da LBV \u2014 Jesus, o P\u00e3o Nosso de cada dia! As doa\u00e7\u00f5es est\u00e3o sendo entregues a fam\u00edlias em vulnerabilidade social que, ao longo do ano, participaram\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/WhatsApp-Image-2024-12-09-at-10.06.43.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15398,"url":"https:\/\/correiodasemana.com\/site\/combater-a-fome-conter-a-covid-19-e-levar-esperanca-a-milhares-de-familias-sao-algumas-das-realizacoes-da-lbv-em-2020\/","url_meta":{"origin":29422,"position":2},"title":"Combater a fome, conter a Covid-19 e levar esperan\u00e7a a milhares de fam\u00edlias s\u00e3o algumas das realiza\u00e7\u00f5es da LBV em 2020","author":"","date":"Janeiro 18, 2021","format":false,"excerpt":"Mais de tr\u00eas milh\u00f5es de quilos em doa\u00e7\u00f5es foram entregues pela Institui\u00e7\u00e3o nas cinco regi\u00f5es do pa\u00eds 2020: um ano de grandes desafios para pessoas no mundo inteiro. No Brasil, n\u00e3o foi diferente. Al\u00e9m de causar milhares de mortes, a pandemia do novo coronav\u00edrus tamb\u00e9m afetou fortemente a vida das\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/01\/amaresermada.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28852,"url":"https:\/\/correiodasemana.com\/site\/a-educacao-transforma-sonhos-em-realidade\/","url_meta":{"origin":29422,"position":3},"title":"A Educa\u00e7\u00e3o transforma sonhos em realidade","author":"adminredacao","date":"Abril 2, 2024","format":false,"excerpt":"No Cear\u00e1, institui\u00e7\u00e3o entrega kits pedag\u00f3gicos para crian\u00e7as em situa\u00e7\u00e3o de pobreza e vulnerabilidade social Alimenta\u00e7\u00e3o e material escolar s\u00e3o fortes aliados para um bom desempenho escolar, por isso, \u00e9 fundamental a realiza\u00e7\u00e3o de a\u00e7\u00f5es efetivas que garantam os direitos b\u00e1sicos de crian\u00e7as e jovens em situa\u00e7\u00e3o de vulnerabilidade social.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/01\/Ministerio-da-Educacao-Fonte-ARCH-Consultoria-Educacional-.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19705,"url":"https:\/\/correiodasemana.com\/site\/o-valor-de-um-sim\/","url_meta":{"origin":29422,"position":4},"title":"O valor de um \u201cSim\u201d","author":"","date":"Maio 8, 2022","format":false,"excerpt":"SIM \u00e9 uma palavra t\u00e3o simples, por\u00e9m, com diversos significados. Um \u201csim\u201d pode mudar um estado de \u00e2nimo, mudar planos, at\u00e9 mesmo atitudes, assim como pode transformar vidas de diferentes formas. E quanto \u00e0queles que dependem de um \u201csim\u201d para sobreviver? Quanto vale ter algu\u00e9m que zela por n\u00f3s? Enquanto\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/05\/LBV-Diga_Sim-2022-a4v-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24788,"url":"https:\/\/correiodasemana.com\/site\/vivencias-que-inspiram-com-a-ajuda-da-lbv-mae-atendida-conseguiu-realizar-o-sonho-de-concluir-a-sua-graduacao\/","url_meta":{"origin":29422,"position":5},"title":"Viv\u00eancias que inspiram! Com a ajuda da LBV, m\u00e3e atendida conseguiu realizar o sonho de concluir a sua gradua\u00e7\u00e3o.","author":"adminredacao","date":"Maio 21, 2023","format":false,"excerpt":"A felicidade de ser m\u00e3e\u00a0traz consigo\u00a0al\u00e9m, de todas as alegrias e realiza\u00e7\u00f5es da maternidade, grandes desafios, n\u00e3o s\u00f3 com a cria\u00e7\u00e3o e acompanhamento de uma crian\u00e7a, mas tamb\u00e9m com autoestima e muitas vezes a abdica\u00e7\u00e3o de um sonho, como os estudos. Em\u00a0Fortaleza\/CE,\u00a0Edna dos Santos,\u00a0m\u00e3e atendida pela\u00a0Legi\u00e3o da Boa Vontade\u00a0(LBV),\u00a0tinha o\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_5560_0.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_5560_0.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_5560_0.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/img_5560_0.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=29422"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29422\/revisions"}],"predecessor-version":[{"id":29424,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29422\/revisions\/29424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/29423"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=29422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=29422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=29422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}