{"id":29874,"date":"2024-07-08T23:23:45","date_gmt":"2024-07-09T02:23:45","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=29874"},"modified":"2024-07-08T23:23:45","modified_gmt":"2024-07-09T02:23:45","slug":"bispos-recem-nomeados-participam-de-encontro-em-brasilia","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/bispos-recem-nomeados-participam-de-encontro-em-brasilia\/","title":{"rendered":"Bispos rec\u00e9m nomeados participam de encontro em Bras\u00edlia"},"content":{"rendered":"<p>A Comiss\u00e3o Episcopal para os Minist\u00e9rios Ordenados e a Vida Consagrada da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB) promoveu de 1\u00ba a 5 de julho o Encontro dos Bispos de Recente Nomea\u00e7\u00e3o. O encontro reuniu 22 bispos j\u00e1 ordenados e ainda a serem ordenados que foram nomeados de setembro de 2023 a junho deste ano.<br \/>\nDa Diocese de Sobral esteve presente Monsenhor Agnaldo Tem\u00f3teo, bispo eleito para a diocese de Garanhuns\/PE, nomeado pelo Papa Francisco no dia 14 de maio.<br \/>\nDurante o encontro, os bispos aprofundaram os seguintes temas: a organiza\u00e7\u00e3o da CNBB, o bispo e a sua miss\u00e3o, Campanhas (Fraternidade e Evangeliza\u00e7\u00e3o), sa\u00fade integral, o bispo no c\u00f3digo de direito can\u00f4nico, regimento e estatuto da CNBB, prote\u00e7\u00e3o de menores, apresenta\u00e7\u00e3o das Comiss\u00f5es, Lei Geral de Prote\u00e7\u00e3o de Dados, gest\u00e3o eclesial.<br \/>\nComo parte da programa\u00e7\u00e3o, os bispos visitaram na quarta-feira, 03 de julho, a Nunciatura Apost\u00f3lica do Brasil, onde foram acolhidos pelo n\u00fancio, Dom Giambattista Diquattro.<br \/>\nNo pr\u00f3ximo dia 16 de julho, Monsenhor Agnaldo ser\u00e1 sagrado bispo em Sobral. E no dia 6 de agosto, tomar\u00e1 posse como 12\u00ba bispo diocesano de Garanhuns\/CE.<\/p>\n<p>Tha\u00eds Helena &#8211; Jornalista &#8211; Jornal Correio da Semana<\/p>\n<p><a href=\"https:\/\/correiodasemana.com\/site\/bispos-recem-nomeados-participam-de-encontro-em-brasilia\/whatsapp-image-2024-07-05-at-17-13-39-1\/\" rel=\"attachment wp-att-29876\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-29876\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1.jpeg\" alt=\"\" width=\"1393\" height=\"1516\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1.jpeg 1393w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1-276x300.jpeg 276w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1-941x1024.jpeg 941w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1-768x836.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1-1024x1114.jpeg 1024w\" sizes=\"(max-width: 1393px) 100vw, 1393px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/bispos-recem-nomeados-participam-de-encontro-em-brasilia\/whatsapp-image-2024-07-05-at-17-13-38\/\" rel=\"attachment wp-att-29875\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-29875\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.38.jpeg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.38.jpeg 1280w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.38-300x225.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.38-1024x768.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.38-768x576.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/bispos-recem-nomeados-participam-de-encontro-em-brasilia\/whatsapp-image-2024-07-05-at-17-13-39\/\" rel=\"attachment wp-att-29877\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-29877\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39.jpeg\" alt=\"\" width=\"1440\" height=\"1567\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39.jpeg 1440w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-276x300.jpeg 276w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-941x1024.jpeg 941w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-768x836.jpeg 768w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1412x1536.jpeg 1412w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.39-1024x1114.jpeg 1024w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/a> <a href=\"https:\/\/correiodasemana.com\/site\/bispos-recem-nomeados-participam-de-encontro-em-brasilia\/whatsapp-image-2024-07-05-at-17-13-40\/\" rel=\"attachment wp-att-29878\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-29878\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg\" alt=\"\" width=\"1536\" height=\"1023\" srcset=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg 1536w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-300x200.jpeg 300w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-1024x682.jpeg 1024w, https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-768x512.jpeg 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Episcopal para os Minist\u00e9rios Ordenados e a Vida Consagrada da Confer\u00eancia Nacional dos&#8230;<\/p>\n","protected":false},"author":7,"featured_media":29878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-29874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg",1536,1023,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-150x150.jpeg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-300x200.jpeg",300,200,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-768x512.jpeg",640,427,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-1024x682.jpeg",640,426,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg",1536,1023,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg",1536,1023,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-1024x682.jpeg",1024,682,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40-540x340.jpeg",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-05-at-17.13.40.jpeg","jetpack-related-posts":[{"id":24574,"url":"https:\/\/correiodasemana.com\/site\/nomeado-o-quarto-bispo-da-diocese-de-quixada-ce\/","url_meta":{"origin":29874,"position":0},"title":"Nomeado o quarto Bispo da Diocese de Quixad\u00e1 (CE)","author":"adminredacao","date":"Maio 14, 2023","format":false,"excerpt":"Fonte: CNBB O Papa Francisco nomeou, nesta quarta-feira, 10 de maio, o novo bispo da diocese de Quixad\u00e1 (CE). O eleito \u00e9 o padre Aur\u00e9lio Pinto de Sousa, atualmente p\u00e1roco da par\u00f3quia Nossa Senhora da Assun\u00e7\u00e3o, em Vi\u00e7osa do Cear\u00e1 (CE). Ele pertence ao clero da diocese de Tiangu\u00e1 (CE).\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/345609777_1683046505457363_1097920028478859531_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/345609777_1683046505457363_1097920028478859531_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/345609777_1683046505457363_1097920028478859531_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/345609777_1683046505457363_1097920028478859531_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11170,"url":"https:\/\/correiodasemana.com\/site\/papa-acolhe-renuncia-de-dom-murilo-krieger-e-nomeia-novo-arcebispo-para-salvador-ba\/","url_meta":{"origin":29874,"position":1},"title":"Papa acolhe ren\u00fancia de dom Murilo Krieger e nomeia novo arcebispo para Salvador (BA)","author":"","date":"Mar\u00e7o 18, 2020","format":false,"excerpt":"O Papa Francisco acolheu, nesta quarta-feira, 11 de mar\u00e7o, o pedido de ren\u00fancia apresentado por dom Murilo Sebasti\u00e3o Ramos Krieger ao governo pastoral da arquidiocese S\u00e3o Salvador da Bahia, a S\u00e9 Primacial do Brasil. No mesmo ato, o Santo Padre nomeou arcebispo para a mesma arquidiocese o cardeal Sergio da\u2026","rel":"","context":"In &quot;Igreja&quot;","block_context":{"text":"Igreja","link":"https:\/\/correiodasemana.com\/site\/category\/igreja\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Destaque_Agradecimento_DomMurilo.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Destaque_Agradecimento_DomMurilo.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Destaque_Agradecimento_DomMurilo.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Destaque_Agradecimento_DomMurilo.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/03\/Destaque_Agradecimento_DomMurilo.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25371,"url":"https:\/\/correiodasemana.com\/site\/eleitos-os-membros-para-a-comissao-episcopal-para-a-comunicacao-social-da-cnbb\/","url_meta":{"origin":29874,"position":2},"title":"Eleitos os membros para a Comiss\u00e3o Episcopal para a Comunica\u00e7\u00e3o Social da CNBB","author":"adminredacao","date":"Junho 26, 2023","format":false,"excerpt":"Fonte: CNBB O Conselho Permanente da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB) elegeu os membros que ir\u00e3o compor a Comiss\u00e3o Episcopal para a Comunica\u00e7\u00e3o Social da CNBB,\u00a0que atualmente \u00e9 presidida pelo bispo de Campo Limpo\u00a0(SP), dom Valdir Jos\u00e9 de Castro, eleito na 60\u00aa Assembleia Geral da CNBB, realizada em\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-21-at-14.07.23.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25640,"url":"https:\/\/correiodasemana.com\/site\/papa-francisco-acolhe-pedido-de-renuncia-de-dom-jaime-vieira-rocha-e-nomeia-novo-arcebispo-de-natal\/","url_meta":{"origin":29874,"position":3},"title":"PAPA FRANCISCO ACOLHE PEDIDO DE REN\u00daNCIA DE DOM JAIME VIEIRA ROCHA E NOMEIA NOVO ARCEBISPO DE NATAL","author":"adminredacao","date":"Julho 11, 2023","format":false,"excerpt":"O Papa Francisco acolheu, nesta quarta-feira, 5 de julho, o pedido de ren\u00fancia apresentado por dom Jaime Vieira Rocha ao governo pastoral da arquidiocese de Natal (RN). Foi nomedo para suceder a dom Jaime o atual bispo de Bom Jesus da Lapa (BA), dom Jo\u00e3o Santos Cardoso. A Presid\u00eancia da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/Destaque-Portal-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/Destaque-Portal-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/Destaque-Portal-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/Destaque-Portal-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/07\/Destaque-Portal-1.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25300,"url":"https:\/\/correiodasemana.com\/site\/papa-aceita-renuncia-de-dom-saburido-e-nomeia-dom-paulo-jackson-para-olinda-e-recife\/","url_meta":{"origin":29874,"position":4},"title":"Papa aceita ren\u00fancia de Dom Saburido e nomeia Dom Paulo Jackson para Olinda e Recife","author":"adminredacao","date":"Junho 19, 2023","format":false,"excerpt":"Fonte: CNBB O Papa Francisco acolheu, nesta quarta-feira, 14 de junho, o pedido de ren\u00fancia apresentado por dom Ant\u00f4nio Fernando Saburido ao governo pastoral da arquidiocese de Olinda e Recife (PE). E nomeou como novo arcebispo dom Paulo Jackson N\u00f3brega de Sousa, atualmente bispo de Garanhuns (PE) e segundo-vice-presidente da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/Destaque-Portal-2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/Destaque-Portal-2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/Destaque-Portal-2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/Destaque-Portal-2.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/06\/Destaque-Portal-2.png?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":31421,"url":"https:\/\/correiodasemana.com\/site\/o-regional-sul-4-da-cnbb-ganhou-duas-novas-arquidioceses\/","url_meta":{"origin":29874,"position":5},"title":"O Regional Sul 4 da CNBB  ganhou duas novas Arquidioceses","author":"adminredacao","date":"Novembro 18, 2024","format":false,"excerpt":"O Papa Francisco anunciou nesta ter\u00e7a-feira, 5 de novembro, a reestrutura\u00e7\u00e3o da Prov\u00edncia Eclesi\u00e1stica (arquidiocese) de Florian\u00f3polis (SC) com a cria\u00e7\u00e3o de duas novas prov\u00edncias eclesi\u00e1sticas: Joinville (SC) e Chapec\u00f3 (SC). O Santo Padre atribuiu \u00e0 nova arquidiocese de Joinville as dioceses sufrag\u00e2neas de Blumenau e Rio do Sul e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/Novas-pronvincias.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/Novas-pronvincias.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/Novas-pronvincias.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/11\/Novas-pronvincias.png?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=29874"}],"version-history":[{"count":2,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29874\/revisions"}],"predecessor-version":[{"id":29880,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/29874\/revisions\/29880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/29878"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=29874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=29874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=29874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}