{"id":30107,"date":"2024-07-29T16:58:52","date_gmt":"2024-07-29T19:58:52","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=30107"},"modified":"2024-07-29T16:58:52","modified_gmt":"2024-07-29T19:58:52","slug":"homilia-de-dom-vasconcelos-na-ocasiao-da-ordenacao-episcopal-do-monsenhor-agnaldo-temoteo-da-silveira-2","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/homilia-de-dom-vasconcelos-na-ocasiao-da-ordenacao-episcopal-do-monsenhor-agnaldo-temoteo-da-silveira-2\/","title":{"rendered":"Homilia de Dom Vasconcelos na ocasi\u00e3o da Ordena\u00e7\u00e3o Episcopal do Monsenhor Agnaldo Tem\u00f3teo da Silveira"},"content":{"rendered":"<p>Sobral, CE, 16 de julho de 2024<\/p>\n<p>Car\u00edssimos irm\u00e3os e irm\u00e3s, neste dia em que a Igreja celebra a Festa de N. Sra. do Monte Carmelo, somos convidados com ela a subir \u00e0 montanha do Profeta Elias para fazermos uma bel\u00edssima experi\u00eancia de Deus. \u201cConsideremos atentamente o minist\u00e9rio que vai ser confiado na Igreja a este nosso irm\u00e3o por obra e gra\u00e7a do Esp\u00edrito Santo de Deus.<br \/>\nJesus Cristo, nosso Senhor, enviado pelo Pai para salvar o g\u00eanero humano, enviou por sua vez os doze Ap\u00f3stolos ao mundo, a fim de que, cheios do Esp\u00edrito Santo, anunciassem o Evangelho, santificassem e conduzissem todos os povos, reunindo-os num s\u00f3 rebanho.<br \/>\nPara que este minist\u00e9rio permanecesse at\u00e9 o fim dos tempos, os Ap\u00f3stolos escolheram colaboradores, aos quais pela imposi\u00e7\u00e3o das m\u00e3os, que confere a plenitude do sacramento da Ordem, comunicaram o dom do Esp\u00edrito Santo, recebido de Cristo.<br \/>\nAssim, ao longo das gera\u00e7\u00f5es, este dom inicial foi sempre transmitido pela sucess\u00e3o ininterrupta dos Bispos, e a obra do salvador se prolonga e cresce at\u00e9 os nossos dias.<br \/>\nNo Bispo com os seus presb\u00edteros est\u00e1 presente o pr\u00f3prio Cristo, Senhor e Pont\u00edfice eterno. Pelo minist\u00e9rio do Bispo \u00e9 Cristo quem continua a proclamar o Evangelho e a distribuir aos que creem os sacramentos da f\u00e9. Pela solicitude paternal do Bispo, \u00e9 Cristo que incorpora novos membros \u00e0 Igreja. Pela sabedoria e prud\u00eancia do Bispo, \u00e9 Cristo que nos conduz nesta peregrina\u00e7\u00e3o terrena, at\u00e9 a felicidade eterna.1\u201d<br \/>\nA voca\u00e7\u00e3o crist\u00e3 espec\u00edfica, seja para o episcopado, para o presbiterado, para o diaconado ou para a vida consagrada, n\u00e3o \u00e9 uma escolha humana, muito menos uma carreira profissional, \u00e9 sim, um chamado divino. A todos Jesus diz: \u201cN\u00e3o fostes v\u00f3s que me escolhestes, fui eu quem vos escolhi.\u201d (Jo 15,16)<br \/>\nNingu\u00e9m estuda para ser Bispo, aprende a ser Bispo depois que \u00e9 nomeado e ordenado. Ningu\u00e9m pode ser um bom Bispo sem antes ser um bom crist\u00e3o e um bom padre. Entre os bons crist\u00e3os padres, Jesus escolhe livremente, como fizera com os ap\u00f3stolos em rela\u00e7\u00e3o aos seus numerosos disc\u00edpulos, \u00e0queles que ele quis.<br \/>\nSer Bispo n\u00e3o \u00e9 uma honra, \u00e9 um servi\u00e7o, e um servi\u00e7o exigente. Exige desapego total: desapego de sua terra natal, de suas poss\u00edveis posses, de seus familiares, enfim, da sua pr\u00f3pria vida,<br \/>\nMonsenhor Agnaldo \u00e9 um bom crist\u00e3o e um bom padre. Todos os que o conhecem encontram nele um Bom Pastor. Sentiremos sua falta. Sentiremos falta daquele padre inteligente, objetivo na condu\u00e7\u00e3o das reuni\u00f5es, determinado na forma\u00e7\u00e3o dos leigos, competente no ensinamento da doutrina da f\u00e9, na apresenta\u00e7\u00e3o da Palavra de Deus; aglutinador na organiza\u00e7\u00e3o dos padres na Regi\u00e3o episcopal, s\u00e1bio nas interven\u00e7\u00f5es nas reuni\u00f5es do Conselho Presbiteral e Col\u00e9gio dos Consultores.<br \/>\nNunca nos esqueceremos daquele padre simples, que veste camiseta de santo de padroeiro no dia a dia, que percorre as ruas da cidade \u00e0 noite alimentando os famintos que dormem nas ruas, daquele padre zeloso para com o templo, a casa de Deus. Aquele padre cujo sim \u00e9 sim, cujo n\u00e3o \u00e9 n\u00e3o. Daquele padre que conseguiu tornar sua Par\u00f3quia, com seus diversos grupos de pastorais, movimentos e servi\u00e7os, ricos e pobres, numa grande fam\u00edlia, que prima por viver \u00e0 fraternidade. As missas terminam e as pessoas n\u00e3o querem ir para casa, sentem prazer em prolongar a ceia eucar\u00edstica numa grande confraterniza\u00e7\u00e3o, quase todos os domingos.<br \/>\nPadre Agnaldo escolheu como lema de sua ordena\u00e7\u00e3o episcopal uma frase pronunciada por Sim\u00e3o Pedro dirigida \u00e0 Jesus, quando este o chamou para a miss\u00e3o.<br \/>\nComo ouvimos no Evangelho proclamado, Jesus encontrou Sim\u00e3o Pedro com seu irm\u00e3o Andr\u00e9 numa bela manh\u00e3 consertando \u00e0s redes ap\u00f3s uma pesca infrut\u00edfera. Jesus sobe na barca de Pedro, dela prega para a multid\u00e3o e depois diz \u00e0 Sim\u00e3o: \u201cDuc in altum!\u201d \u201cAvan\u00e7a para \u00e1guas mais profundas! Lan\u00e7a as redes \u00e0 direita da barca!\u201d que palavras ousadas ditas por um carpinteiro ou mesmo por um rabino judeu!<br \/>\nSim\u00e3o Pedro, pescador experiente, estranhou e reagiu, por\u00e9m com humildade: \u201cMestre, n\u00f3s trabalhamos a noite inteira e nada pescamos. Mas, em \u2018aten\u00e7\u00e3o \u00e0 tua palavra\u2019, vou lan\u00e7ar as redes.\u201d<br \/>\nSim\u00e3o Pedro poderia ter dito a Jesus: Mestre, sei que sabes muitas coisas e \u00e9s um bom pregador, mas \u00e9s um carpinteiro de Nazar\u00e9! Queres me ensinar a pescar? \u00c9 o mesmo que querer \u201censinar pai nosso a vig\u00e1rio!\u201d (talvez esta seja uma das mais dif\u00edceis miss\u00f5es de um Bispo \u201censinar pai nosso a vig\u00e1rio\u201d, muitos sempre acham que j\u00e1 sabem tudo e quase nunca est\u00e3o dispostos a aprender com a humildade de Sim\u00e3o Pedro). \u201cIn verbo tuo!\u201d Em \u2018aten\u00e7\u00e3o \u00e0 tua Palavra\u2019, vou lan\u00e7ar as redes.\u201d Foi a resposta de Pedro. Foi a frase que tocou o cora\u00e7\u00e3o deste sacerdote escolhido para o episcopado.<br \/>\nO que teria levado Padre Agnaldo escolher esta frase como lema do seu minist\u00e9rio episcopal? Certamente, um total abandono nas m\u00e3os do Mestre Jesus! Um total abandono \u00e0 vontade do Senhor! \u00c9 a mesma resposta que o profeta Isaias deu a Deus com outras palavras: \u201cAqui estou! Envia-me!\u201d como ouvimos na primeira leitura desta santa missa.<br \/>\nVou revelar-lhes um segredo: o Padre Agnaldo gosta de viajar em suas merecidas f\u00e9rias. Conhece muitos lugares. Todavia, nunca foi a Garanhuns. O que sabe de Garanhuns para onde est\u00e1 sendo enviado?<br \/>\nSabe que h\u00e1 67 anos atr\u00e1s um irm\u00e3o seu, sacerdote formado no presbit\u00e9rio desta Diocese foi nomeado Bispo: Dom Francisco Expedito Lopes. Sabe que Dom Expedito depois de uma curta perman\u00eancia em Oeiras no Piau\u00ed, como primeiro Bispo daquela Diocese, foi transferido para Garanhuns PE. Dom Expedito foi o s\u00e9timo Bispo da Diocese de Garanhuns. Deparou-se ele com um sacerdote que vivia uma vida irregular. O Pe. Hosana estava amasiado com uma mulher, gerava filhos com ela, a obrigava a abortar os filhos, n\u00e3o permitia que ela se confessasse com outro padre que n\u00e3o fosse ele! Que terr\u00edvel! Exortou o pobre sacerdote. Advertiu-o! Sem sucesso! No cumprimento do seu dever Dom Expedito o suspendeu de Ordem e o Padre Hosana furioso assassinou seu Bispo com tr\u00eas tiros de revolver no dia 02de julho de 1957.<br \/>\nDom Expedito n\u00e3o morreu na hora, foi socorrido no Hospital onde pronunciou suas \u00faltimas palavras, anotadas por seu secret\u00e1rio o Pe. Ac\u00e1cio Rodrigues Alves, futuro primeiro Bispo de Palmares, de saudosa mem\u00f3ria. Antes de morrer Dom Expedito perdoou seu algoz com as seguintes palavras: \u201cMeu Deus, tende piedade deste pobre sacerdote, n\u00e3o permitas que ele vos torne a ofender. Por ele eu ofere\u00e7o \u00e0 minha vida\u201d. Disse ainda: \u201cMeu Deus, perdoai todos os meus pecados, os esquecidos e os mal acusados.\u201d E concluiu: \u201cMeu Deus, vos ofere\u00e7o a minha vida pela Diocese de Garanhuns, pelo seu Clero e pelos seus seminaristas.\u201d<\/p>\n<p>Sua vida \u00e9 um testemunho. Bispo dos pobres. Bispo de cora\u00e7\u00e3o mariano. Bispo de muitas virtudes. Bispo do perd\u00e3o.<br \/>\nA Diocese de Garanhuns abriu um processo de canoniza\u00e7\u00e3o de Dom Francisco Expedito Lopes e todos n\u00f3s rezamos para um dia o vermos na gl\u00f3ria dos altares.<br \/>\nO Padre Agnaldo sabe ainda que no dia 08 de julho de 2015, anivers\u00e1rio natal\u00edcio de Dom Expedito Lopes, o Santo Padre o Papa Francisco nomeou a mim, proveniente do Clero de Garanhuns, l\u00e1 onde Dom Expedito est\u00e1 sepultado, tamb\u00e9m como s\u00e9timo Bispo. S\u00e9timo Bispo da Diocesano de Sobral.<br \/>\nSoube enfim, recentemente, que o mesmo Papa Francisco o nomeou Bispo para a Diocese de Garanhuns, Pernambuco.<\/p>\n<p>O que Deus quer dizer com tudo isto? N\u00e3o sabemos. S\u00f3 Ele sabe.<br \/>\nEm minha reflex\u00e3o, penso que em tudo h\u00e1 um bom prop\u00f3sito de Deus. Deus quis neste m\u00eas do precios\u00edssimo Sangue de Nosso Senhor Jesus Cristo, selar com estas duas Dioceses irm\u00e3s, um la\u00e7o de sangue. Sangue que \u00e9 vida. Vida doada, vida oferecida. Selar esta uni\u00e3o com uma troca de \u201cDons\u201d. Isto tudo \u00e9 uma forma pedag\u00f3gica de Deus para redimir a Diocese de Garanhuns.<br \/>\nDar de presente \u00e0 Diocese de Sobral um Bispo do clero de Garanhuns, devolver, digamos assim, \u00e0 Sobral um Bispo, e agora enviar um novo Bispo, filho da Diocese de Sobral para Garanhuns trat\u00e1-lo como os bons filhos devem tratar um bom pai, para que, sob o seu cajado, ser conduzida \u00e0s alegrias eternas. \u201ccomo s\u00e3o belos, os p\u00e9s do mensageiro da paz, caminhando&#8230;\u201d nas colinas verdejantes de Garanhuns! Deus permita que assim seja!<\/p>\n<p>Para concluir, dirijo-me a ti irm\u00e3o car\u00edssimo:<br \/>\nN\u00e3o tenhas medo. Em aten\u00e7\u00e3o \u00e0 palavra do nosso Mestre Jesus avan\u00e7a para as \u00e1guas mais profundas e lan\u00e7a as redes! \u201cPrega a Palavra de Deus, quer agrade, quer desagrade. Admoesta com paci\u00eancia e desejo de ensinar. Orando e oferecendo o sacrif\u00edcio pelo povo que te foi confiado, procura haurir copiosamente da plenitude do Cristo as riquezas da gra\u00e7a.\u201d<br \/>\nDesejo que continues a ser \u201cum Pastor com o cheiro das ovelhas\u201d. \u201cAma com amor de Pai e de irm\u00e3o todos aqueles que Deus te confiou, especialmente os Presb\u00edteros e Di\u00e1conos, teus colaboradores no servi\u00e7o de Cristo; e tamb\u00e9m os pobres e doentes, os peregrinos e aprisionados.\u201d<br \/>\nExorta os fi\u00e9is a colaborarem contigo na miss\u00e3o apost\u00f3lica, na constru\u00e7\u00e3o de uma Igreja em sa\u00edda, mission\u00e1ria, pobre, serva, samaritana. Mostra zelo incans\u00e1vel pelos que ainda n\u00e3o pertencem ao rebanho de Cristo, para que o Cristianismo cres\u00e7a, \u201cn\u00e3o por propaganda, nem por proselitismo, mas por atra\u00e7\u00e3o\u201d como nos tem ensinado os dois \u00faltimos Papas.<br \/>\n\u201cVela, enfim, por todo o rebanho dos fi\u00e9is a cujo servi\u00e7o te coloca o Esp\u00edrito Santo, para reger a Igreja de Deus: em nome do Pai de quem \u00e9s imagem entre os fi\u00e9is; em nome do Filho, cuja miss\u00e3o de mestre, sacerdote e pastor, exerces; e em nome do Esp\u00edrito Santo, que d\u00e1 vida \u00e0 Igreja de Cristo, e fortalece a nossa fraqueza\u201d.<\/p>\n<p>Em aten\u00e7\u00e3o \u00e0 Palavra do Mestre Jesus, n\u00e3o hesites em lan\u00e7ar as redes!<br \/>\nNossa Senhora do Carmo, rogai por n\u00f3s!<br \/>\nAssim seja! Am\u00e9m!<\/p>\n<div id='gallery-1' class='gallery galleryid-30107 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/homilia-de-dom-vasconcelos-na-ocasiao-da-ordenacao-episcopal-do-monsenhor-agnaldo-temoteo-da-silveira-2\/dom-vasoncelos-homilia-2-3\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/DOM-VASONCELOS-HOMILIA-2-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"DOM VASONCELOS HOMILIA (2)\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Sobral, CE, 16 de julho de 2024 Car\u00edssimos irm\u00e3os e irm\u00e3s, neste dia em que&#8230;<\/p>\n","protected":false},"author":7,"featured_media":79,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[24,11],"tags":[],"class_list":["post-30107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-300x167.jpg",300,167,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses-768x427.jpg",640,356,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",640,356,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",800,445,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg",540,300,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/\" rel=\"category tag\">A voz do Pastor<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a>","tag_info":"Artigos","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":24068,"url":"https:\/\/correiodasemana.com\/site\/o-ressuscitado-vive-entre-nos\/","url_meta":{"origin":30107,"position":0},"title":"O RESSUSCITADO VIVE ENTRE N\u00d3S","author":"adminredacao","date":"Abril 17, 2023","format":false,"excerpt":"\u201cO Ressuscitado vive entre n\u00f3s. Am\u00e9m, aleluia! N\u00e3o temais, irm\u00e3os, eu estive morto, mas agora vivo, vivo para sempre. Am\u00e9m. N\u00e3o temais, irm\u00e3os, eu sou o primeiro, \u00faltimo tamb\u00e9m, eu sou o vivente. Am\u00e9m. N\u00e3o temais, irm\u00e3os, tenho em m\u00e3os as chaves que da morte foram, hoje s\u00e3o vit\u00f3ria. Am\u00e9m.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30022,"url":"https:\/\/correiodasemana.com\/site\/homilia-de-dom-vasconcelos-na-ocasiao-da-ordenacao-episcopal-do-monsenhor-agnaldo-temoteo-da-silveira\/","url_meta":{"origin":30107,"position":1},"title":"Homilia de Dom Vasconcelos na ocasi\u00e3o da Ordena\u00e7\u00e3o Episcopal do Monsenhor Agnaldo Tem\u00f3teo da Silveira","author":"adminredacao","date":"Julho 22, 2024","format":false,"excerpt":"Sobral, CE, 16 de julho de 2024 Car\u00edssimos irm\u00e3os e irm\u00e3s, neste dia em que a Igreja celebra a Festa de N. Sra. do Monte Carmelo, somos convidados com ela a subir \u00e0 montanha do Profeta Elias para fazermos uma bel\u00edssima experi\u00eancia de Deus. \u201cConsideremos atentamente o minist\u00e9rio que vai\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":33595,"url":"https:\/\/correiodasemana.com\/site\/tempo-de-discernimento-e-obediencia\/","url_meta":{"origin":30107,"position":2},"title":"Tempo de discernimento e obedi\u00eancia","author":"adminredacao","date":"Maio 5, 2025","format":false,"excerpt":"Ap\u00f3s a Ressurrei\u00e7\u00e3o e Ascens\u00e3o de Jesus e a descida do Esp\u00edrito Santo, no Pentecostes, come\u00e7ou a maravilhosa aventura da Igreja, chamada por Deus e atuar como sal, luz e fermento na sociedade. Os Atos dos Ap\u00f3stolos retratam a vida das primeiras Comunidades, com os percal\u00e7os havidos no confronto com\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29780,"url":"https:\/\/correiodasemana.com\/site\/pedro-paulo-e-francisco-2\/","url_meta":{"origin":30107,"position":3},"title":"Pedro, Paulo e Francisco","author":"adminredacao","date":"Julho 1, 2024","format":false,"excerpt":"Neste dia 29, encerrando as festividades do m\u00eas junino, celebramos a festa de S\u00e3o Pedro. No calend\u00e1rio lit\u00fargico, desde o s\u00e9culo III, a Igreja une na mesma celebra\u00e7\u00e3o S\u00e3o Pedro e S\u00e3o Paulo. No caso do Brasil, esta solenidade \u00e9 transferida para o domingo seguinte. Portanto, no domingo (30), celebramos\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":25484,"url":"https:\/\/correiodasemana.com\/site\/pedro-paulo-e-francisco\/","url_meta":{"origin":30107,"position":4},"title":"Pedro, Paulo e Francisco","author":"adminredacao","date":"Julho 1, 2023","format":false,"excerpt":"No \u00faltimo dia 29, encerrando as festividades do m\u00eas junino, celebramos a festa de S\u00e3o Pedro. No calend\u00e1rio lit\u00fargico, desde o s\u00e9culo III, a Igreja une na mesma celebra\u00e7\u00e3o S\u00e3o Pedro e S\u00e3o Paulo. No caso do Brasil, esta solenidade \u00e9 transferida para o domingo seguinte. Portanto, neste domingo (02),\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2019\/07\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":38748,"url":"https:\/\/correiodasemana.com\/site\/solenidade-de-pentecostes\/","url_meta":{"origin":30107,"position":5},"title":"Solenidade de Pentecostes","author":"adminredacao","date":"Junho 4, 2026","format":false,"excerpt":"A Solenidade de Pentecostes para n\u00f3s \u00e9 um marco do qual vemos a Igreja que \u00e9 sustentada e animada pelo Dom e pela For\u00e7a do Esp\u00edrito Santo. A palavra Pentecostes vem do grego,\u00a0pentekost\u00e9, \u00e9 o\u00a0quinquag\u00e9simo\u00a0dia ap\u00f3s a P\u00e1scoa. Comemoramos nesta solenidade o envio do Esp\u00edrito Santo \u00e0 Igreja. A partir\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/12\/festa-santa-luzia-com-dom-Vasconcelos-5-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=30107"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30107\/revisions"}],"predecessor-version":[{"id":30110,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30107\/revisions\/30110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/79"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=30107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=30107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=30107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}