{"id":30162,"date":"2024-07-29T17:16:31","date_gmt":"2024-07-29T20:16:31","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=30162"},"modified":"2024-07-29T17:16:31","modified_gmt":"2024-07-29T20:16:31","slug":"paroquia-de-nossa-senhora-da-saude-em-frecheirinha-tem-novo-paroco-e-vigario-paroquial","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/paroquia-de-nossa-senhora-da-saude-em-frecheirinha-tem-novo-paroco-e-vigario-paroquial\/","title":{"rendered":"Par\u00f3quia de Nossa Senhora da Sa\u00fade em Frecheirinha, tem novo p\u00e1roco e vig\u00e1rio paroquial"},"content":{"rendered":"<div id='gallery-1' class='gallery galleryid-30162 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/paroquia-de-nossa-senhora-da-saude-em-frecheirinha-tem-novo-paroco-e-vigario-paroquial\/frecheirinha-5\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Frecheirinha (5)\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/paroquia-de-nossa-senhora-da-saude-em-frecheirinha-tem-novo-paroco-e-vigario-paroquial\/frecheirinha-6\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-6-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Frecheirinha (6)\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Na noite da \u00faltima quarta-feira, 24 de julho, Dom Vasconcelos deu posse ao novo p\u00e1roco da Par\u00f3quia de Nossa Senhora da Sa\u00fade em Frecheirinha, Pe. Em\u00eddio Moura, e apresentou o novo vig\u00e1rio paroquial, Pe. Renato Welton. A celebra\u00e7\u00e3o eucar\u00edstica com rito de posse can\u00f4nica aconteceu na igreja matriz e contou com a concelebra\u00e7\u00e3o de Dom Agnaldo Tem\u00f3teo, bispo eleito de Garanhuns\/PE e padres diocesanos.<br \/>\nA provis\u00e3o can\u00f4nica foi lida pelo vig\u00e1rio geral, Monsenhor Nonato Timb\u00f3. Padre Em\u00eddio \u00e9 o 22\u00ba p\u00e1roco e chega para dar continuidade aos trabalhos pastorais exercidos por Padre J\u00falio Nascimento, ex-p\u00e1roco. Contar\u00e1 com a contribui\u00e7\u00e3o dos vig\u00e1rios paroquiais: Pe. Renato Welton e Pe. Maur\u00edlio Xavier, que exerce trabalho pastoral na quase \u00e1rea pastoral de S\u00e3o Francisco de Assis em Uba\u00fana.<br \/>\nNa aclama\u00e7\u00e3o do evangelho, o novo p\u00e1roco recebeu do bispo o livro dos evangelhos, recordando que uma das fun\u00e7\u00f5es do presb\u00edtero \u00e9 o an\u00fancio da palavra; e posteriormente, proclamou o evangelho.<br \/>\nEm um dos trechos da homilia, Dom Vasconcelos recordou que o evangelho do dia relembra a peregrina\u00e7\u00e3o de Jesus por diversos lugares para proclamar a palavra da salva\u00e7\u00e3o. \u201c\u00c9 sempre algo desafiador quando Deus nos chama para uma nova miss\u00e3o. A igreja \u00e9 essencialmente mission\u00e1ria, ela existe para anunciar o evangelho a toda criatura, e Jesus percorria cidades e aldeias, por isso ele n\u00e3o parava.<br \/>\nPortanto, o sacerdote deve atrair multid\u00f5es, n\u00e3o em torno de si, mas em torno da palavra. Ele deve comunicar Cristo, deve ser outro Cristo\u201d, disse.<br \/>\nAp\u00f3s a homilia, o rito de posse can\u00f4nica deu continuidade com a entrega dos s\u00edmbolos: chave da igreja, estola roxa, instrumentos para o batismo e chave do sacr\u00e1rio.<br \/>\nA comunidade paroquial acolheu os novos pastores com palavras fraternas e ressaltou que a partir deste dia, eles s\u00e3o como membros de cada fam\u00edlia que pertence aquela par\u00f3quia. O novo vig\u00e1rio enfatizou que est\u00e1 dispon\u00edvel para colaborar com os trabalhos pastorais ao lado do p\u00e1roco, Pe. Em\u00eddio, e pediu ora\u00e7\u00f5es pela nova miss\u00e3o.<br \/>\nJ\u00e1 o p\u00e1roco, ressaltou que ir\u00e1 preservar tr\u00eas miss\u00f5es: f\u00e9 no que se refere na confian\u00e7a em Deus, e ir\u00e1 rezar e pedir ao Senhor que derrame em nos cora\u00e7\u00f5es a confian\u00e7a que n\u00e3o precisa de entendimento. A segunda miss\u00e3o, falar sobre a compreens\u00e3o da f\u00e9, se dedicar\u00e1 a propagar a palavra; e a terceira ser\u00e1 a miss\u00e3o de reunir, estar unido. \u201cQuero manter acesa a chama da f\u00e9 unindo as pessoas, e \u00e9 por isso que a igreja \u00e9 uma chama da f\u00e9 unida a comunh\u00e3o\u201d, completou.<\/p>\n<p>Thais Helena &#8211; Jornalista \u2013 Jornal Correio da Semana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite da \u00faltima quarta-feira, 24 de julho, Dom Vasconcelos deu posse ao novo p\u00e1roco&#8230;<\/p>\n","protected":false},"author":7,"featured_media":30163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-30162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5.jpeg",1600,1066,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-150x150.jpeg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-300x200.jpeg",300,200,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-768x512.jpeg",640,427,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-1024x682.jpeg",640,426,true],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-1536x1023.jpeg",1536,1023,true],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5.jpeg",1600,1066,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-1024x682.jpeg",1024,682,true],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5-540x340.jpeg",540,340,true]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/atualidade\/\" rel=\"category tag\">Atualidade<\/a>","tag_info":"Atualidade","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/Frecheirinha-5.jpeg","jetpack-related-posts":[{"id":30147,"url":"https:\/\/correiodasemana.com\/site\/em-uruoca-padre-aristides-toma-posse-como-novo-administrador-paroquial-da-paroquia-de-nossa-senhora-do-livramento\/","url_meta":{"origin":30162,"position":0},"title":"Em Uruoca, Padre Aristides toma posse como novo administrador paroquial da Par\u00f3quia de Nossa Senhora do Livramento","author":"adminredacao","date":"Julho 29, 2024","format":false,"excerpt":"Os paroquianos da Par\u00f3quia dedicada \u00e0 Nossa Senhora do Livramento em Uruoca, conheceram no \u00faltimo dia 25 de julho, quinta-feira, o novo administrador paroquial, Pe. Aristides Carneiro, durante Santa Missa com Rito de Posse Can\u00f4nica presidida por Dom Vasconcelos na igreja matriz. O sacerdote \u00e9 o quarto administrador paroquial desta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-27-at-15.54.11.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":26402,"url":"https:\/\/correiodasemana.com\/site\/novo-paroco-e-vigario-paroquial-sao-empossados-na-catedral\/","url_meta":{"origin":30162,"position":1},"title":"Novo p\u00e1roco e vig\u00e1rio paroquial  s\u00e3o empossados na Catedral","author":"adminredacao","date":"Setembro 4, 2023","format":false,"excerpt":"Uma nova hist\u00f3ria inicia para os paroquianos da Par\u00f3quia de Nossa Senhora da Concei\u00e7\u00e3o - S\u00c9 Catedral, igreja matriz de Sobral. Na noite de ter\u00e7a-feira, 29\/08, o povo acolheu o novo p\u00e1roco e cura da Catedral, Pe. Jos\u00e9 Canaf\u00edstula Gomes e o vig\u00e1rio paroquial, Pe. Ant\u00f4nio Denilson de Sousa. Nesta\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/09\/11-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29659,"url":"https:\/\/correiodasemana.com\/site\/capela-de-santa-terezinha-em-lisieux-acolhe-pe-antonio-jose-como-vigario-paroquial\/","url_meta":{"origin":30162,"position":2},"title":"Capela de Santa Terezinha em Lisieux, acolhe Pe. Ant\u00f4nio Jos\u00e9 como vig\u00e1rio paroquial","author":"adminredacao","date":"Junho 18, 2024","format":false,"excerpt":"No \u00faltimo domingo, em 16 de junho, Dom Vasconcelos esteve no distrito de Lisieux para presidir a Santa Missa e apresentar aos paroquianos o Pe. Ant\u00f4nio Jos\u00e9 Viana Monte, como novo vig\u00e1rio paroquial, onde ir\u00e1 contribuir com os trabalhos da capela dedicada a Santa Terezinha localizada naquela comunidade. O sacerdote\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-17-at-10.59.02.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":30861,"url":"https:\/\/correiodasemana.com\/site\/em-ubauna-criacao-da-quase-paroquia-de-sao-francisco-de-assis-marca-festa-do-padroeiro\/","url_meta":{"origin":30162,"position":3},"title":"Em Uba\u00fana, cria\u00e7\u00e3o da quase-par\u00f3quia de S\u00e3o Francisco de Assis marca festa do padroeiro","author":"adminredacao","date":"Outubro 2, 2024","format":false,"excerpt":"Com o aumento da popula\u00e7\u00e3o desta pequena por\u00e7\u00e3o do povo de Deus, foi criada na noite da \u00faltima quinta-feira, 26 de setembro, durante a missa do terceiro dia da festa do padroeiro, a quase-par\u00f3quia de S\u00e3o Francisco de Assis no distrito de Uba\u00fana, pertencente ao munic\u00edpio de Corea\u00fa. Este territ\u00f3rio\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/10\/DSC_5023.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":28282,"url":"https:\/\/correiodasemana.com\/site\/dom-vasconcelos-apresenta-a-paroquia-de-acarau-novo-paroco-e-vigario-paroquial\/","url_meta":{"origin":30162,"position":4},"title":"Dom Vasconcelos apresenta \u00e0 Par\u00f3quia de Acara\u00fa novo p\u00e1roco e vig\u00e1rio paroquial","author":"adminredacao","date":"Fevereiro 6, 2024","format":false,"excerpt":"Em solene celebra\u00e7\u00e3o eucar\u00edstica na Festa da Apresenta\u00e7\u00e3o do Senhor no templo, nesta sexta-feira, 02 de fevereiro, Dom Vasconcelos apresentou o novo p\u00e1roco, Pe. Jo\u00e3o Vasconcelos, e o vig\u00e1rio paroquial, Pe. Adalberto Menezes, \u00e0 comunidade paroquial de Acara\u00fa. Padre Jo\u00e3o Vasconcelos j\u00e1 fez parte da regi\u00e3o quando foi p\u00e1roco da\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-02-05-at-16.35.32.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":30284,"url":"https:\/\/correiodasemana.com\/site\/paroquia-de-sao-francisco-em-caicara-prea-tem-novo-administrador-e-vigario-paroquial\/","url_meta":{"origin":30162,"position":5},"title":"Par\u00f3quia de S\u00e3o Francisco em Cai\u00e7ara\/Pre\u00e1, tem novo administrador e vig\u00e1rio paroquial","author":"adminredacao","date":"Agosto 3, 2024","format":false,"excerpt":"A comunidade paroquial da Par\u00f3quia de S\u00e3o Francisco de Assis localizada no distrito de Cai\u00e7ara\/Pre\u00e1, no mun\u00edcipio de Cruz, participou na \u00faltima quinta-feira, 1\u00ba de agosto, da Santa Missa de Apresenta\u00e7\u00e3o do novo administrador paroquial, Pe. F\u00e1bio Nascimento e do vig\u00e1rio paroquial, Pe. Marcos Ribeiro. Os presb\u00edteros j\u00e1 exercem trabalhos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/08\/Posse-em-Caicara-4-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=30162"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30162\/revisions"}],"predecessor-version":[{"id":30165,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/30162\/revisions\/30165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/30163"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=30162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=30162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=30162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}