{"id":32081,"date":"2025-01-15T15:41:20","date_gmt":"2025-01-15T18:41:20","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=32081"},"modified":"2025-01-15T15:43:24","modified_gmt":"2025-01-15T18:43:24","slug":"novos-diretores-da-santa-casa-de-sobral-sao-apresentados-em-reuniao-extraordinaria","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/novos-diretores-da-santa-casa-de-sobral-sao-apresentados-em-reuniao-extraordinaria\/","title":{"rendered":"Novos diretores da Santa Casa de Sobral s\u00e3o apresentados em reuni\u00e3o extraordin\u00e1ria"},"content":{"rendered":"<p>Na tarde da quinta-feira (02\/01), foram apresentados os novos diretores da Santa Casa de Miseric\u00f3rdia de Sobral em uma reuni\u00e3o extraordin\u00e1ria que reuniu coordenadores de enfermagem, m\u00e9dicos e administrativos. Os m\u00e9dicos Jos\u00e9 Ueides Fechine J\u00fanior e Lizandro de Andrade Teles assumiram, respectivamente, os cargos de diretor-geral e diretor t\u00e9cnico da institui\u00e7\u00e3o.<br \/>\nA apresenta\u00e7\u00e3o foi conduzida pela nova secret\u00e1ria da Sa\u00fade de Sobral, Dra. Michelle Alves Vasconcelos Ponte, que introduziu a din\u00e2mica inicial dos pr\u00f3ximos tr\u00eas meses de interven\u00e7\u00e3o administrativa. \u201cA nova gest\u00e3o da prefeitura de Sobral vai ouvir e buscar solucionar todas as demandas poss\u00edveis\u201d, afirmou Dra. Michele, destacando o compromisso com a efici\u00eancia e a humaniza\u00e7\u00e3o nos servi\u00e7os de sa\u00fade.<br \/>\nEmocionado com sua nova fun\u00e7\u00e3o, Dr. Jos\u00e9 Ueides, pediatra neonatologista, destacou a import\u00e2ncia do trabalho em equipe para o sucesso da gest\u00e3o hospitalar. \u201cAbra\u00e7o essa miss\u00e3o com muita responsabilidade e conto com o apoio de todos para seguirmos caminhando na miss\u00e3o da Santa Casa\u201d, declarou.<br \/>\nDr. Lizandro, tamb\u00e9m pediatra neonatologista, agora diretor t\u00e9cnico, ressaltou a relev\u00e2ncia da Santa Casa como refer\u00eancia em sa\u00fade para mais de 50 munic\u00edpios da regi\u00e3o norte do Cear\u00e1. \u201cAgrade\u00e7o a confian\u00e7a e reafirmo meu compromisso com a excel\u00eancia e o cuidado que caracterizam esta institui\u00e7\u00e3o\u201d, disse.<br \/>\nA escolha dos novos diretores da Santa Casa de Sobral foi realizada pela nova gest\u00e3o da cidade, sob a lideran\u00e7a do prefeito eleito Oscar Rodrigues, visando o fortalecimento e o desenvolvimento da institui\u00e7\u00e3o. A nova gest\u00e3o busca assegurar que o hospital continue sendo um pilar de refer\u00eancia na sa\u00fade, n\u00e3o s\u00f3 para Sobral, mas tamb\u00e9m para a popula\u00e7\u00e3o de toda a regi\u00e3o norte do estado do Cear\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde da quinta-feira (02\/01), foram apresentados os novos diretores da Santa Casa de Miseric\u00f3rdia&#8230;<\/p>\n","protected":false},"author":7,"featured_media":32082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-32081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/01\/Novos-diretores-Santa-Casa-Sobral.jpeg","jetpack-related-posts":[{"id":13240,"url":"https:\/\/correiodasemana.com\/site\/associacao-da-santa-casa-de-misericordia-de-sobral-realiza-assembleia-geral-ordinaria\/","url_meta":{"origin":32081,"position":0},"title":"Associa\u00e7\u00e3o da Santa Casa de Miseric\u00f3rdia de Sobral realiza Assembleia Geral Ordin\u00e1ria","author":"","date":"Agosto 31, 2020","format":false,"excerpt":"\u00a0 Ascom Complexo SCMS O Bispo Diocesano e Provedor da Santa Casa de Miseric\u00f3rdia de Sobral, (SCMS) Dom Jos\u00e9 Luiz Gomes Vasconcelos, presidiu nesta ter\u00e7a-feira (25\/08) a Assembleia Geral Ordin\u00e1ria da Associa\u00e7\u00e3o Beneficente da Santa Casa de Miseric\u00f3rdia de Sobral, evento que ocorre anualmente. Este ano a reuni\u00e3o foi realizada\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Assembleia-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Assembleia-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Assembleia-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/08\/Assembleia-1.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":35543,"url":"https:\/\/correiodasemana.com\/site\/novo-conselho-gestor-da-santa-casa-de-sobral-realiza-primeira-reuniao-com-perspectivas-positivas-para-o-futuro\/","url_meta":{"origin":32081,"position":1},"title":"Novo Conselho Gestor da Santa Casa de Sobral realiza primeira reuni\u00e3o com perspectivas positivas para o futuro","author":"adminredacao","date":"Setembro 15, 2025","format":false,"excerpt":"O novo Conselho Gestor da Santa Casa de Miseric\u00f3rdia de Sobral reuniu-se na manh\u00e3 desta sexta-feira, 12 de setembro, para a primeira reuni\u00e3o da nova equipe. Na pauta, foi apresentada ao conselho a atual realidade da institui\u00e7\u00e3o, ap\u00f3s o retorno da Santa Casa de Miseric\u00f3rdia \u00e0 associa\u00e7\u00e3o, agora sob a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-12-at-17.35.53.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":16963,"url":"https:\/\/correiodasemana.com\/site\/diretor-da-santa-casa-de-misericordia-de-sobral-participa-de-reuniao-com-ministro-da-saude\/","url_meta":{"origin":32081,"position":2},"title":"Diretor da Santa Casa de Miseric\u00f3rdia de Sobral participa de reuni\u00e3o com Ministro da Sa\u00fade","author":"","date":"Julho 12, 2021","format":false,"excerpt":"O balan\u00e7o dos servi\u00e7os prestados pela Institui\u00e7\u00e3o filantr\u00f3pica aos 55 munic\u00edpios da Regi\u00e3o Norte do estado do Cear\u00e1 foi apresentado ao Ministro. O diretor-geral da Santa Casa de Miseric\u00f3rdia de Sobral Dr. Klebson Carvalho, participou de uma reuni\u00e3o com o Ministro da Sa\u00fade Marcelo Queiroga, nesta quarta-feira (30\/06) em Bras\u00edlia.\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Reuniao-MS.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Reuniao-MS.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Reuniao-MS.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Reuniao-MS.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/07\/Reuniao-MS.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16668,"url":"https:\/\/correiodasemana.com\/site\/em-assembleia-ordinaria-virtual-novo-conselho-fiscal-do-complexo-santa-casa-de-misericordia-de-sobral-e-eleito\/","url_meta":{"origin":32081,"position":3},"title":"Em Assembleia Ordin\u00e1ria virtual, novo conselho fiscal do Complexo Santa Casa de Miseric\u00f3rdia de Sobral \u00e9 eleito","author":"","date":"Junho 7, 2021","format":false,"excerpt":"Encontro virtual contou com a participa\u00e7\u00e3o do bispo da diocese de Sobral e provedor do Complexo SCMS, Dom Jos\u00e9 Luiz Gomes de Vasconcelos, al\u00e9m de toda dire\u00e7\u00e3o-geral da institui\u00e7\u00e3o, associados e convidados. Ascom Complexo SCMS Com o objetivo de continuar o desenvolvimento dos processos administrativos do Complexo Santa Casa de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/06\/Assembleia-Virtual.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15135,"url":"https:\/\/correiodasemana.com\/site\/conselho-fiscal-do-complexo-santa-casa-de-misericordia-de-sobral-se-reune-para-avaliar-indicadores-do-hospital-do-coracao\/","url_meta":{"origin":32081,"position":4},"title":"Conselho Fiscal do Complexo Santa Casa de Miseric\u00f3rdia de Sobral se re\u00fane para avaliar indicadores do Hospital do Cora\u00e7\u00e3o","author":"","date":"Dezembro 21, 2020","format":false,"excerpt":"Os membros do Conselho tamb\u00e9m visitaram as novas instala\u00e7\u00f5es do Centro Cir\u00fargico da unidade. Com o objetivo de fiscalizar atos administrativos, com a verifica\u00e7\u00e3o do cumprimento de deveres legais e estatut\u00e1rios, o Complexo Santa Casa de Miseric\u00f3rdia de Sobral conta com um Conselho Fiscal. Na tarde da sexta-feira (11\/12) os\u2026","rel":"","context":"In &quot;Santa Casa&quot;","block_context":{"text":"Santa Casa","link":"https:\/\/correiodasemana.com\/site\/category\/santa-casa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Foto-1-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Foto-1-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Foto-1-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2020\/12\/Foto-1-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18690,"url":"https:\/\/correiodasemana.com\/site\/em-sessao-solene-santa-casa-de-sobral-empossa-novo-diretor-clinico-da-instituicao\/","url_meta":{"origin":32081,"position":5},"title":"Em sess\u00e3o solene, Santa Casa de Sobral empossa novo diretor cl\u00ednico da institui\u00e7\u00e3o","author":"","date":"Janeiro 30, 2022","format":false,"excerpt":"Dr. Elson Arruda Linhares assume o cargo pelos pr\u00f3ximos dois anos junto \u00e0 diretoria administrativa da institui\u00e7\u00e3o. Ascom Complexo SCMS A Santa Casa de Miseric\u00f3rdia de Sobral (SCMS) realizou nesta quarta-feira (26\/01) a posse do novo diretor cl\u00ednico da institui\u00e7\u00e3o, Dr. Elson Arruda Linhares. O m\u00e9dico foi eleito pelos demais\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/foto-sta-casa-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/foto-sta-casa-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/foto-sta-casa-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2022\/01\/foto-sta-casa-2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/32081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=32081"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/32081\/revisions"}],"predecessor-version":[{"id":32083,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/32081\/revisions\/32083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/32082"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=32081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=32081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=32081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}