{"id":33547,"date":"2025-04-29T12:46:41","date_gmt":"2025-04-29T15:46:41","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=33547"},"modified":"2025-04-29T12:46:41","modified_gmt":"2025-04-29T15:46:41","slug":"em-tempo-274","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/em-tempo-274\/","title":{"rendered":"EM TEMPO \u2022"},"content":{"rendered":"<p>Vestibular da UVA com notas do Enem<br \/>\nA Universidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es at\u00e9 o dia 6 de maio para Vestibular 2025.2, com aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem). Ser\u00e3o aceitas as pontua\u00e7\u00f5es das dez \u00faltimas edi\u00e7\u00f5es, realizadas entre 2015 e 2024.<br \/>\nS\u00e3o ofertadas 1.134 vagas, distribu\u00eddas da seguinte forma: 854 vagas para os cursos de gradua\u00e7\u00e3o da UVA nos campi de Sobral, 80 para Acara\u00fa, 80 para Camocim e 120 para S\u00e3o Benedito. Acesse o site ww2.uva.ce.gov.br para outras informa\u00e7\u00f5es sobre o processo seletivo.<\/p>\n<p>Mostras no Museu da Imagem e do Som<br \/>\nEm celebra\u00e7\u00e3o ao m\u00eas dos povos ind\u00edgenas, Museu da Imagem e do Som Chico Albuquerque (MIS) estreia neste 26 de abril, em Fortaleza,exposi\u00e7\u00f5es \u201cHiromi Nagakura at\u00e9 a Amaz\u00f4nia com Ailton Krenak\u201d e \u201cRe-floresta\u201d, obra audiovisual da artista Roberta Carvalho.<br \/>\nEvento de lan\u00e7amento, com show da cantora Brisa Flow, ocorre na pra\u00e7a do MIS, \u00e0s 17h, com presen\u00e7as das curadoras Angela Pappiani e Eliza Otsuka, da exposi\u00e7\u00e3o de Nagakura; Gabriela Moulin, diretora executiva do Instituto Tomie Ohtake; e da artista Roberta Carvalho.<\/p>\n<p>Cordel de despedida do Papa Francisco<\/p>\n<div id='gallery-1' class='gallery galleryid-33547 gallery-columns-6 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/correiodasemana.com\/site\/em-tempo-274\/cordel-adeus-papa-francisco\/'><img loading=\"lazy\" width=\"150\" height=\"150\" src=\"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/Cordel-Adeus-Papa-Francisco-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Cordel Adeus Papa Francisco\" loading=\"lazy\" decoding=\"async\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Cordelista Kl\u00e9visson Viana \u00e9 autor do cordel e da ilustra\u00e7\u00e3o da capa<br \/>\nPoeta cordelista cearense Kl\u00e9visson Viana fez uma homenagem ao Papa Francisco, que faleceu no dia 21 de abril, com um cordel de despedida. \u201cAdeus ao Papa Francisco\u201d fala sobre a trajet\u00f3ria do Santo Padre e destaca as contribui\u00e7\u00f5es do primeiro papa latino-americano.<br \/>\nKl\u00e9visson Viana, multiartista e mestre da Cultura do Cear\u00e1, relata que o pont\u00edfice foi um divisor de \u00e1guas na hist\u00f3ria da Igreja Cat\u00f3lica. \u201cPor sua simplicidade\/Era um farol da verdade\/ Que iluminava os lares\u201d, diz um trecho do cordel, impresso pela editora Tupynanquim.<\/p>\n<p>Entre Capas &#8211; Uma viagem pela hist\u00f3ria<br \/>\nEntre as fontes para saber mais da hist\u00f3ria, uma de ineg\u00e1vel import\u00e2ncia \u00e9 o jornalismo. Neste sentido, em um convite para mergulho nos epis\u00f3dios que marcaram o estado, foi aberta a exposi\u00e7\u00e3o \u201cEntre Capas &#8211; Uma viagem pela hist\u00f3ria do Cear\u00e1 com o Di\u00e1rio do Nordeste\u201d.<br \/>\nA mostra re\u00fane reprodu\u00e7\u00f5es de 39 capas hist\u00f3ricas do jornal, at\u00e9 16 de maio, no Espa\u00e7o Cultural Arandu, em Caucaia. A iniciativa integra comemora\u00e7\u00f5es do centen\u00e1rio do empres\u00e1rio Edson Queiroz e evidencia um dos seus principais legados no \u00e2mbito da comunica\u00e7\u00e3o.<\/p>\n<p>Livro \u201cAldeota\u201d de J\u00e1der de Carvalho<br \/>\nEditora e livraria independente Subst\u00e2nsia promoveu debate em Fortaleza sobre a obra \u201cAldeota\u201d, do jornalista e escritor J\u00e1der de Carvalho. Grande romance do s\u00e9culo XX da literatura cearense, o livro foi rec\u00e9m reeditado e publicado pela Universidade Federal do Cear\u00e1.<br \/>\nIntitulado \u201cEncontros de Literatura Cearense\u201d, o evento reuniu na sala 1 do Cinema do Drag\u00e3o do Mar, na Praia de Iracema, dia 23 de abril, a escritora, vice-diretora da Editora UFC e colunista do O Povo, Juliana Diniz, e o jornalista e doutor em Mem\u00f3ria Social Tiago Coutinho.<\/p>\n<p>Dica da Coluna<br \/>\nLeia o Blog do Edilson (www.blogdoedilson.com.br): Cultura, educa\u00e7\u00e3o, pol\u00edtica e utilidade p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vestibular da UVA com notas do Enem A Universidade Estadual Vale do Acara\u00fa (UVA) recebe&#8230;<\/p>\n","protected":false},"author":7,"featured_media":18025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11,36],"tags":[],"class_list":["post-33547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos","category-em-tempo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2021\/11\/Edilson-Silva.jpg","jetpack-related-posts":[{"id":33337,"url":"https:\/\/correiodasemana.com\/site\/uva-abre-processo-seletivo-para-vestibular-2025-2-com-reaproveitamento-da-nota-do-enem\/","url_meta":{"origin":33547,"position":0},"title":"UVA abre Processo Seletivo para Vestibular 2025.2 com reaproveitamento da nota do ENEM","author":"adminredacao","date":"Abril 14, 2025","format":false,"excerpt":"A Universidade Estadual Vale do Acara\u00fa - UVA abriu inscri\u00e7\u00f5es para o Processo Seletivo do Vestibular 2025.2 por meio da Comiss\u00e3o Executiva de Processos Seletivos - CEPS, com aproveitamento do resultado do ENEM. Neste processo seletivo, ser\u00e3o ofertadas 1.134 vagas, distribu\u00eddas da seguinte forma: 854 vagas para os cursos de\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/UVA-Universidade-Vale-do-Acarau-Sobral-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":29582,"url":"https:\/\/correiodasemana.com\/site\/uva-oferta-1-134-vagas-para-o-vestibular-2024-2-use-a-nota-do-enem\/","url_meta":{"origin":33547,"position":1},"title":"UVA oferta 1.134 vagas para o Vestibular 2024.2. Use a nota do ENEM","author":"adminredacao","date":"Junho 10, 2024","format":false,"excerpt":"A Universidade Estadual Vale do Acara\u00fa (UVA), atrav\u00e9s da Comiss\u00e3o Executiva de Processos Seletivos (Ceps), est\u00e1 com inscri\u00e7\u00f5es abertas para o Processo Seletivo do Vestibular 2024.2 com o aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem). O prazo vai at\u00e9 23 de junho, pelo site https:\/\/vestibular.uvanet.br. Para este\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Fachada-da-UVA.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Fachada-da-UVA.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/06\/Fachada-da-UVA.jpeg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":29296,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-226\/","url_meta":{"origin":33547,"position":2},"title":"EM TEMPO \u2022","author":"adminredacao","date":"Maio 20, 2024","format":false,"excerpt":"Vestibular UVA com nota do Enem Universidade Estadual Vale do Acara\u00fa (UVA) recebe inscri\u00e7\u00f5es, at\u00e9 23 de junho, para Processo Seletivo do Vestibular 2024.2 com aproveitamento do resultado do Exame Nacional do Ensino M\u00e9dio (Enem), com 1.134 vagas em Sobral, S\u00e3o Benedito, Camocim e Acara\u00fa. Os candidatos dever\u00e3o anexar, no\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Tercia-Montenegro-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Tercia-Montenegro-150x150.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Tercia-Montenegro-150x150.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Tercia-Montenegro-150x150.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2024\/05\/Tercia-Montenegro-150x150.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":35201,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-290\/","url_meta":{"origin":33547,"position":3},"title":"Em Tempo","author":"adminredacao","date":"Agosto 17, 2025","format":false,"excerpt":"Mestrado em Ci\u00eancia da Informa\u00e7\u00e3o UFC O Programa de P\u00f3s-Gradua\u00e7\u00e3o em Ci\u00eancia da Informa\u00e7\u00e3o da Universidade Federal do Cear\u00e1 (UFC) receber\u00e1 inscri\u00e7\u00f5es, at\u00e9 o dia 31 de agosto, para o seu mestrado acad\u00eamico, com \u00e1rea de concentra\u00e7\u00e3o em Representa\u00e7\u00e3o e Media\u00e7\u00e3o da Informa\u00e7\u00e3o e do Conhecimento. Conforme o edital, s\u00e3o\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/lula-camilo-e-elmano-premio-MEC.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/lula-camilo-e-elmano-premio-MEC.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/lula-camilo-e-elmano-premio-MEC.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/08\/lula-camilo-e-elmano-premio-MEC.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37959,"url":"https:\/\/correiodasemana.com\/site\/uva-abre-processo-seletivo-do-vestibular-2026-2-com-nota-do-enem-curso-de-psicologia-passa-a-ser-ofertado\/","url_meta":{"origin":33547,"position":4},"title":"UVA abre Processo Seletivo do Vestibular 2026.2 com nota do ENEM; curso de Psicologia passa a ser ofertado","author":"adminredacao","date":"Abril 11, 2026","format":false,"excerpt":"A Universidade Estadual Vale do Acara\u00fa (UVA) anuncia a abertura do Processo Seletivo do Vestibular 2026.2 para ingresso no ensino superior, por meio da nota do Exame Nacional do Ensino M\u00e9dio (ENEM), ampliando as oportunidades de acesso \u00e0 gradua\u00e7\u00e3o para estudantes de toda a regi\u00e3o. A sele\u00e7\u00e3o permite que candidatos\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-20-at-08.54.13.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":33482,"url":"https:\/\/correiodasemana.com\/site\/em-tempo-273\/","url_meta":{"origin":33547,"position":5},"title":"Em Tempo","author":"adminredacao","date":"Abril 23, 2025","format":false,"excerpt":"Livro sobre hist\u00f3ria da fam\u00edlia Santana Museu da Fotografia Fortaleza recebeu, na noite de 16 de abril, lan\u00e7amento do fotolivro \u201cReter Tudo ou Quanta Maravilha do Dia a Dia Que Passou\u201d. Com 256 p\u00e1ginas e publicada pelo selo Lux, a obra foi semifinalista do Pr\u00eamio Jabuti 2024 na categoria Projeto\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/ricardo-guilherme.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/ricardo-guilherme.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/ricardo-guilherme.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/04\/ricardo-guilherme.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33547"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33547\/revisions"}],"predecessor-version":[{"id":33549,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33547\/revisions\/33549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/18025"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=33547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=33547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=33547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}