{"id":33595,"date":"2025-05-05T14:10:24","date_gmt":"2025-05-05T17:10:24","guid":{"rendered":"https:\/\/correiodasemana.com\/site\/?p=33595"},"modified":"2025-05-05T14:10:24","modified_gmt":"2025-05-05T17:10:24","slug":"tempo-de-discernimento-e-obediencia","status":"publish","type":"post","link":"https:\/\/correiodasemana.com\/site\/tempo-de-discernimento-e-obediencia\/","title":{"rendered":"Tempo de discernimento e obedi\u00eancia"},"content":{"rendered":"<p>Ap\u00f3s a Ressurrei\u00e7\u00e3o e Ascens\u00e3o de Jesus e a descida do Esp\u00edrito Santo, no Pentecostes, come\u00e7ou a maravilhosa aventura da Igreja, chamada por Deus e atuar como sal, luz e fermento na sociedade. Os Atos dos Ap\u00f3stolos retratam a vida das primeiras Comunidades, com os percal\u00e7os havidos no confronto com os costumes, legisla\u00e7\u00e3o e pr\u00e1tica religiosa existentes na Palestina daquele tempo. Depois, especialmente atrav\u00e9s do minist\u00e9rio de Paulo, ampliaram-se os horizontes e os problemas afloraram. Tratava-se do ambiente hel\u00eanico e romano, com h\u00e1bitos e cultura diferentes. Trata-se de adequar-se a cada ambiente, sem perder a originalidade da gra\u00e7a do cristianismo, tarefa que acompanha a Igreja no correr dos s\u00e9culos.<br \/>\nJ\u00e1 na Sagrada Escritura e na Hist\u00f3ria da Igreja, o Esp\u00edrito Santo abriu sempre as portas para o reconhecimento sincero das faltas existentes nas pessoas, sabedores que somos da santidade da Igreja, malgrado os nossos pecados pessoais, comunit\u00e1rios e sociais. De fato, ela \u00e9 santa, pois \u201cCristo tamb\u00e9m amou a Igreja e se entregou por ela, a fim de santificar pela palavra aquela que ele purifica pelo banho da \u00e1gua. Pois ele quis apresent\u00e1-la a si mesmo toda bela, sem mancha nem ruga ou qualquer reparo, mas santa e sem defeito\u201d (Ef 5,26-27). Os pecados s\u00e3o nossos, e o Senhor quer deles purificar-nos. A Igreja \u00e9 santa, mas feita de pecadores, que somos n\u00f3s! Se assim n\u00e3o fosse e a Igreja tivesse sido criada como uma associa\u00e7\u00e3o de pessoas, at\u00e9 interessadas no Evangelho, n\u00e3o teria subsistido! Ela se mant\u00e9m porque o Senhor est\u00e1 no meio de n\u00f3s! Mist\u00e9rio da Miseric\u00f3rdia de Deus!<br \/>\nO confronto da Igreja nascente com os poderes religiosos e pol\u00edticos ent\u00e3o reinantes nos trouxe uma magn\u00edfica experi\u00eancia, cujos reflexos podem multiplicar-se tamb\u00e9m hoje, com edificantes consequ\u00eancias. \u201cOs guardas levaram os ap\u00f3stolos e os apresentaram ao Sin\u00e9drio. O sumo sacerdote come\u00e7ou a interrog\u00e1-los: \u2018N\u00e3o vos proibimos expressamente de ensinar nesse nome? Apesar disso, enchestes a cidade de Jerusal\u00e9m com a vossa doutrina. E ainda quereis nos responsabilizar pela morte desse homem!\u2019 Ent\u00e3o Pedro e os outros ap\u00f3stolos responderam: \u2018\u00c9 preciso obedecer a Deus antes que aos homens. O Deus de nossos pais suscitou Jesus, a quem v\u00f3s matastes, pregando-o numa cruz. Deus, por\u00e9m, por seu poder, o exaltou, tornando-o Chefe e Salvador, para propiciar a Israel a convers\u00e3o e o perd\u00e3o dos seus pecados. E disso somos testemunhas, n\u00f3s e o Esp\u00edrito Santo, que Deus concedeu \u00e0queles que lhe obedecem\u2019. Quando ouviram isto, ficaram furiosos e queriam mat\u00e1-los\u201d (At 5,27-33).<br \/>\nN\u00f3s fomos criados por Deus e a ele devemos dar contas de nossa caminhada nesta terra e das decis\u00f5es que tomamos. Antes de sermos membros de qualquer sociedade organizada nesta terra, temos uma dignidade fundante de nossa exist\u00eancia, e esta vem de Deus e seu plano infinito de amor, com o qual quer que vivamos nesta terra e numa eternidade feliz. Passa na frente do Estado ou dos Governos a liberdade religiosa e o dever de respeitar as pessoas, em suas decis\u00f5es de consci\u00eancia. Por isso, sistemas sociais e pol\u00edticos vieram \u00e0 tona e depois se esva\u00edram, mas a Igreja, com todos os limites dos homens e mulheres que a comp\u00f5em, permanece firme est\u00e1vel, solidamente alicer\u00e7ada na Rocha que \u00e9 Cristo. Um dos sinais mais impressionantes da solidez da Igreja \u00e9 o minist\u00e9rio de Pedro e seus sucessores, chamados a proclamar que se deve obedecer antes a Deus do que aos homens. E \u00e9 um verdadeiro milagre que percorre a hist\u00f3ria o fato de o Esp\u00edrito Santo ter sempre algu\u00e9m misteriosamente preparado para ser Papa.<br \/>\nIndependentemente da idade, nacionalidade, forma\u00e7\u00e3o ou cultura, impressiona fortemente a n\u00f3s e ao mundo a fidelidade dos que s\u00e3o respons\u00e1veis pela elei\u00e7\u00e3o de um Papa, como estamos vivendo agora, ao acolherem e a ele fazerem plena unidade e prestarem obedi\u00eancia, sabendo que sua palavra e minist\u00e9rio confirmam os irm\u00e3os, segundo a promessa do Senhor: \u201cEu, por\u00e9m, orei por ti, para que tua f\u00e9 n\u00e3o desfale\u00e7a. E tu, uma vez convertido, confirma os teus irm\u00e3os\u201d (Lc 22,32).<br \/>\nPara obedecer antes a Deus do que aos homens, faz parte da vida da Igreja o discernimento, com o qual se buscam fontes seguras: a Palavra da Escritura, as inspira\u00e7\u00f5es de Deus acolhidas com serenidade na ora\u00e7\u00e3o e o conselho dos irm\u00e3os e irm\u00e3s. Da\u00ed o respeito que nos cabe ter diante de realidades t\u00e3o s\u00e9rias, com que a Igreja busca o discernimento dos passos a serem dados no an\u00fancio do Evangelho.<br \/>\nE a Igreja vive a sua miss\u00e3o num mundo pluralista e desafiador, quanto \u00e0s convic\u00e7\u00f5es religiosas, pol\u00edticas e culturais, devendo responder com esp\u00edrito de humildade, aliado \u00e0 grande paix\u00e3o pela verdade, que \u00e9 Jesus Cristo. Sabemos que os pr\u00f3ximos dias ser\u00e3o tamb\u00e9m de grandes provoca\u00e7\u00f5es a um testemunho fiel do Evangelho sobre toda a Igreja, vindas das mais diversificadas correntes de pensamento e opini\u00e3o, pelo que confiamos na fervorosa ora\u00e7\u00e3o de todo o Povo de Deus, para que sejamos mais fi\u00e9is a Deus do que aos homens (cf. At 2,27-33). Rezemos muito pela realiza\u00e7\u00e3o do Conclave, sabendo que Deus tem preparado aquele que s\u00f3 ele sabe e, estamos convictos, ser\u00e1 o Papa para este tempo, pois Deus n\u00e3o abandona a sua Igreja. A certeza vem do Evangelho: \u201cEu te digo: tu \u00e9s Pedro, e sobre esta pedra edificarei a minha Igreja, e as for\u00e7as do Inferno n\u00e3o poder\u00e3o venc\u00ea-la. Eu te darei as chaves do Reino dos C\u00e9us: tudo o que ligares na terra ser\u00e1 ligado nos c\u00e9us, e tudo o que desligares na terra ser\u00e1 desligado nos c\u00e9us\u201d (Mt 16,18-19).<br \/>\nNo entanto, n\u00e3o s\u00f3 no governo da Igreja faz-se necess\u00e1rio obedecer antes a Deus do que aos homens. O discernimento h\u00e1 de acompanhar os jovens em suas op\u00e7\u00f5es de vida, o matrim\u00f4nio nas decis\u00f5es sobre os filhos e a educa\u00e7\u00e3o dos mesmos, os homens e mulheres que t\u00eam responsabilidades na vida p\u00fablica nas escolhas e na execu\u00e7\u00e3o das pol\u00edticas p\u00fablicas!<br \/>\nO Esp\u00edrito Santo nos conceda o mesmo ardor e a coragem das primeiras comunidades crist\u00e3s, para sermos sinais de Deus para o nosso tempo e o nosso mundo. Maria, M\u00e3e da Igreja e Rainha dos Ap\u00f3stolos, interceda por n\u00f3s!<\/p>\n<p>Dom Alberto Taveira Corr\u00eaa\u00a0 &#8211; Arcebispo de Bel\u00e9m do Par\u00e1 (PA)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a Ressurrei\u00e7\u00e3o e Ascens\u00e3o de Jesus e a descida do Esp\u00edrito Santo, no Pentecostes,&#8230;<\/p>\n","protected":false},"author":7,"featured_media":7687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[24,11],"tags":[],"class_list":["post-33595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-voz-do-pastor","category-artigos"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"thumbnail":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-150x150.jpg",150,150,true],"medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-300x204.jpg",300,204,true],"medium_large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses-768x523.jpg",640,436,true],"large":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",640,436,false],"1536x1536":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"2048x2048":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-featured":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",1000,681,false],"covernews-medium":["https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg",499,340,false]},"author_info":{"info":["adminredacao"]},"category_info":"<a href=\"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/\" rel=\"category tag\">A voz do Pastor<\/a> <a href=\"https:\/\/correiodasemana.com\/site\/category\/artigos\/\" rel=\"category tag\">Artigos<\/a>","tag_info":"Artigos","comment_count":"0","jetpack_featured_media_url":"https:\/\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg","jetpack-related-posts":[{"id":28841,"url":"https:\/\/correiodasemana.com\/site\/a-graca-da-pascoa\/","url_meta":{"origin":33595,"position":0},"title":"A GRA\u00c7A DA P\u00c1SCOA","author":"adminredacao","date":"Abril 2, 2024","format":false,"excerpt":"Com a alegria que \u00e9 fruto do Esp\u00edrito Santo, estamos celebrando a P\u00e1scoa de Nosso Senhor Jesus Cristo. Todos somos convidados a participar intensamente do Tr\u00edduo Pascal. A P\u00e1scoa da Ceia, com a Missa da Ceia do Senhor, abre-nos o cora\u00e7\u00e3o para a entrega total do Senhor, no dom da\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24499,"url":"https:\/\/correiodasemana.com\/site\/intencao-de-oracao-do-papa-os-movimentos-eclesiais-sao-um-dom-sao-a-riqueza-da-igreja\/","url_meta":{"origin":33595,"position":1},"title":"INTEN\u00c7\u00c3O DE ORA\u00c7\u00c3O DO PAPA: OS MOVIMENTOS ECLESIAIS S\u00c3O UM DOM, S\u00c3O A RIQUEZA DA IGREJA","author":"adminredacao","date":"Maio 8, 2023","format":false,"excerpt":"Fonte: CNBB Neste m\u00eas de maio, a inten\u00e7\u00e3o de ora\u00e7\u00e3o \u00e9 pelos movimentos e grupos eclesiais. Na mensagem divulgada em v\u00eddeo, Francisco afirma que \u201cos movimentos renovam a Igreja com a sua capacidade de di\u00e1logo a servi\u00e7o da miss\u00e3o evangelizadora\u201d. A inten\u00e7\u00e3o convida a rezar para que \u201cos movimentos e\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/capa-movimentos-intencao-papa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/capa-movimentos-intencao-papa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/capa-movimentos-intencao-papa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2023\/05\/capa-movimentos-intencao-papa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":34195,"url":"https:\/\/correiodasemana.com\/site\/solenidade-de-pentecostes-reune-fieis-na-catedral-em-jubileu-das-novas-comunidades\/","url_meta":{"origin":33595,"position":2},"title":"Solenidade de Pentecostes re\u00fane fi\u00e9is na Catedral em Jubileu das Novas Comunidades","author":"adminredacao","date":"Junho 16, 2025","format":false,"excerpt":"A Igreja Cat\u00f3lica celebrou, neste domingo, 08, em todo o mundo, a Solenidade de Pentecostes. Dom Vasconcelos presidiu a Santa Missa na S\u00e9 Catedral de Nossa Senhora da Concei\u00e7\u00e3o pela manh\u00e3, onde, na ocasi\u00e3o, tamb\u00e9m foi celebrado o Jubileu das Novas Comunidades. Ao celebrar a Solenidade de Pentecostes, recordamos a\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-09-at-17.32.34.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-09-at-17.32.34.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-09-at-17.32.34.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-09-at-17.32.34.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-09-at-17.32.34.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":24873,"url":"https:\/\/correiodasemana.com\/site\/nas-asas-do-espirito\/","url_meta":{"origin":33595,"position":3},"title":"NAS ASAS DO ESP\u00cdRITO","author":"adminredacao","date":"Maio 29, 2023","format":false,"excerpt":"Celebramos com grande alegria, fruto do Esp\u00edrito, a Solenidade de Pentecostes. Nossa Igreja olha para frente e para o alto, como desejamos meditar e rezar na Grande Vig\u00edlia, preparada com carinho por tantas pessoas que a ela se dedicaram. No Pentecostes, a Igreja saiu \u00e0 vida p\u00fablica, come\u00e7ando pelas ruas\u2026","rel":"","context":"In &quot;Atualidade&quot;","block_context":{"text":"Atualidade","link":"https:\/\/correiodasemana.com\/site\/category\/atualidade\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37260,"url":"https:\/\/correiodasemana.com\/site\/2o-domingo-do-tempo-comum\/","url_meta":{"origin":33595,"position":4},"title":"2\u00ba Domingo do Tempo Comum\u00a0","author":"adminredacao","date":"Fevereiro 7, 2026","format":false,"excerpt":"Cardeal Orani Jo\u00e3o Tempesta Arcebispo do Rio de Janeiro (RJ) \u201cEis o\u00a0Cordeiro de Deus, que tira o pecado do mundo\u201d (Jo 1,29) Celebramos nesse domingo o segundo desse Tempo Comum. Na Segunda-feira, dia 12 de janeiro, iniciamos a primeira semana do Tempo Comum e neste domingo celebramos o segundo domingo\u2026","rel":"","context":"In &quot;A voz do Pastor&quot;","block_context":{"text":"A voz do Pastor","link":"https:\/\/correiodasemana.com\/site\/category\/a-voz-do-pastor\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/Dom-Vasconcelos-posses.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20009,"url":"https:\/\/correiodasemana.com\/site\/a-nos-descei-divina-luz\/","url_meta":{"origin":33595,"position":5},"title":"A n\u00f3s descei Divina Luz","author":"","date":"Junho 6, 2022","format":false,"excerpt":"Neste domingo, a Igreja celebra a grande solenidade de Pentecostes, recordando, assim, a efus\u00e3o do Esp\u00edrito Santo sobre a Igreja primitiva, em Jerusal\u00e9m, cinquenta dias ap\u00f3s a P\u00e1scoa. \u00c9 no livro dos Atos dos Ap\u00f3stolos que S\u00e3o Lucas descreve os primeiros raios da aurora da Igreja. O sopro do Esp\u00edrito\u2026","rel":"","context":"In &quot;Artigos&quot;","block_context":{"text":"Artigos","link":"https:\/\/correiodasemana.com\/site\/category\/artigos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/correiodasemana.com\/site\/wp-content\/uploads\/2018\/02\/editorial-cs.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/comments?post=33595"}],"version-history":[{"count":1,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33595\/revisions"}],"predecessor-version":[{"id":33596,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/posts\/33595\/revisions\/33596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media\/7687"}],"wp:attachment":[{"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/media?parent=33595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/categories?post=33595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/correiodasemana.com\/site\/wp-json\/wp\/v2\/tags?post=33595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}